{"id":29328,"date":"2026-03-04T14:55:28","date_gmt":"2026-03-04T13:55:28","guid":{"rendered":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/?post_type=product&#038;p=29328"},"modified":"2026-03-05T09:50:18","modified_gmt":"2026-03-05T08:50:18","slug":"spazio-positivo-centro-educativo-e-di-benessere-per-bambini-e-famiglie","status":"publish","type":"product","link":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/spazio-positivo-centro-educativo-e-di-benessere-per-bambini-e-famiglie\/","title":{"rendered":"Spazio Positivo \u2013 Centro Educativo e di Benessere per Bambini e Famiglie"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"29328\" class=\"elementor elementor-29328\">\n\t\t\t\t<div class=\"elementor-element elementor-element-657270c e-flex e-con-boxed e-con e-parent\" data-id=\"657270c\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-536908a e-con-full e-flex e-con e-child\" data-id=\"536908a\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-da75c0c elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"da75c0c\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" fetchpriority=\"high\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2026\/03\/Logo-Spazio-Positivo.png\" class=\"attachment-full size-full wp-image-29335\" alt=\"\" srcset=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2026\/03\/Logo-Spazio-Positivo.png 500w, https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2026\/03\/Logo-Spazio-Positivo-480x480.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 500px, 100vw\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a5d5467 elementor-widget elementor-widget-text-editor\" data-id=\"a5d5467\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Spazio Positivo<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a87572e elementor-widget elementor-widget-text-editor\" data-id=\"a87572e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Centro Educativo e di Benessere <br \/>per Bambini e Famiglie a Milano (San Siro)<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c2c2dfa e-con-full e-flex e-con e-child\" data-id=\"c2c2dfa\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4591b43 elementor-widget elementor-widget-spacer\" data-id=\"4591b43\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1cca0b3 elementor-hidden-desktop e-flex e-con-boxed e-con e-parent\" data-id=\"1cca0b3\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-5fbb1c2 e-con-full e-flex e-con e-child\" data-id=\"5fbb1c2\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c0beb2f elementor-widget elementor-widget-text-editor\" data-id=\"c0beb2f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Chi siamo<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-892d8af elementor-widget elementor-widget-text-editor\" data-id=\"892d8af\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Spazio Positivo \u00e8 un centro polifunzionale per bambini e famiglie situato nel cuore del quartiere San Siro a Milano. <br \/>\u00c8 un\u2019Impresa Sociale senza scopo di lucro nata per promuovere benessere psicologico, educativo e sociale, offrendo attivit\u00e0 e servizi pensati per sostenere la genitorialit\u00e0 e creare opportunit\u00e0 inclusive per il territorio.<\/p><p>La missione \u00e8 semplice e potente: creare un luogo accogliente dove bambini e genitori possano crescere, trovare sostegno e sentirsi parte di una comunit\u00e0 attiva e solidale.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-70fe5e5 e-con-full e-flex e-con e-child\" data-id=\"70fe5e5\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6edf3ab elementor-widget elementor-widget-spacer\" data-id=\"6edf3ab\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-eacd23e e-con-full e-flex e-con e-child\" data-id=\"eacd23e\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-58f42c3 elementor-widget elementor-widget-text-editor\" data-id=\"58f42c3\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Attivit\u00e0 e Corsi per Bambini e Famiglie<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c3ae43d elementor-widget elementor-widget-text-editor\" data-id=\"c3ae43d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>1. Psicomotricit\u00e0, Movimento e Gioco<\/strong><br>Gruppi di psicomotricit\u00e0 educatica progettati per sostenere lo sviluppo del bambino sul piano emotivo, relazionale, motorio e cognitivo.<br>Le proposte si basano su: <strong>apprendimento non formale,<\/strong><strong> life skills riconosciute dalla pedagogia contemporanea, <\/strong><strong>gioco e movimento come basi fondamentali per il neurosviluppo.<\/strong><\/p>\n<p>I corsi sono rivolti anche ai bambini nella fascia 12-36 mesi<\/p>\n<p><strong>2. Capoeira, Danzaterapia e altre discipline<\/strong><br>Discipline artistiche e corporee che combinano: <strong>movimento, ritmo, gioco e consapevolezza corporea.<\/strong><br>Corsi e cicli di incontri condotti da professionisti. Movimento, ritmo e gioco sono utilizzati come strumenti di crescita.<\/p>\n<p><strong>3. Laboratori Creativi del Weekend<\/strong><br>Ogni mese vengono organizzati laboratori tematici come: <strong>attivit\u00e0 artistiche e riciclo creativo, ceramica, stanze sensoriali immersive, percorsi esperienziali<\/strong><br>Materiali selezionati, personale esperto, formato e competente. Non i soliti lavoretti ma vere e proprie esperienze pianificate, studiate e guidate da esperti.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2a03b56 e-con-full elementor-hidden-tablet e-flex e-con e-child\" data-id=\"2a03b56\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4bc1e28 elementor-widget elementor-widget-spacer\" data-id=\"4bc1e28\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-50d3222 e-con-full e-flex e-con e-child\" data-id=\"50d3222\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5a18b9d elementor-widget elementor-widget-text-editor\" data-id=\"5a18b9d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>4. Eventi per Famiglie<\/strong><br \/>Per condividere momenti di qualit\u00e0 e sostenere la genitorialit\u00e0 (con particolare attenzione per le neo-mamme).<br \/><strong>\u2665 pigiama party per adolescenti e bambini grandi<\/strong><br \/><strong>\u2665 cinemino dei neonati<\/strong><br \/><strong>\u2665 spettacoli per famiglie in piccoli gruppi, rivolti anche e soprattutto ai pi\u00f9 piccoli<\/strong><br \/><strong>\u2665 attivit\u00e0 speciali a tema<\/strong><\/p><p>Lo scopo non \u00e8 quello di fare intrattenimento ma di creare momenti condivisi che ci portino ad uscire dalle mura di casa, in un ambiente sicuro e dedicato a genitori e figli, nel quale i bambini possono essere bambini.<\/p><p><strong>5. Sostegno alla Genitorialit\u00e0<\/strong><br \/>Un pilastro fondamentale del progetto. <br \/>Spazio Positivo offre:<br \/><strong>\u2665 incontri tematici con psicologi, educatori e professionisti<\/strong><br \/><strong>\u2665 laboratori genitore\u2013bambino<\/strong><br \/><strong>\u2665 gruppi di auto-sostegno tra neomamme e genitori con figli neurodivergenti<\/strong><\/p><p>L&#8217;obiettivo \u00e8 aiutare i genitori a riconoscere risorse, costruire consapevolezza, prevenire stress e burn-out, favorire il supporto comunitario.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-96d5a42 e-con-full elementor-hidden-mobile e-flex e-con e-child\" data-id=\"96d5a42\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1b7a1cb elementor-widget elementor-widget-spacer\" data-id=\"1b7a1cb\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-49d1227 e-con-full e-flex e-con e-child\" data-id=\"49d1227\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e03eb97 elementor-widget elementor-widget-spacer\" data-id=\"e03eb97\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f3d73f6 e-con-full e-flex e-con e-child\" data-id=\"f3d73f6\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e9d64b3 elementor-widget elementor-widget-text-editor\" data-id=\"e9d64b3\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La Struttura<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8b33c43 elementor-widget elementor-widget-text-editor\" data-id=\"8b33c43\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Gli ambienti sono progettati per accogliere bambini e adulti in modo sicuro e accogliente.<br \/>La nostra sala d&#8217;attesa permette ai genitori di rimanere nella struttura durante i corsi dedicati ai bambini e condividere il proprio tempo con altri caregivers. Siamo dotati di spogliatoi con bagno per bambini e fasciatoio. Il centro \u00e8 totalmente accessibile anche in carrozzina (in quel caso \u00e8 per\u00f2 necessario avvisare ed entrare dal passo carraio).<br \/>Lo spazio \u00e8 condiviso in sinergia con ASD Capoeira Milano ETS, con cui viene portata avanti una visione di comunit\u00e0 aperta e inclusiva.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c8f43d5 elementor-widget-divider--view-line_icon elementor-view-default elementor-widget-divider--element-align-center elementor-widget elementor-widget-divider\" data-id=\"c8f43d5\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon elementor-divider__element\">\n\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-hand-holding-heart\" viewBox=\"0 0 576 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M275.3 250.5c7 7.4 18.4 7.4 25.5 0l108.9-114.2c31.6-33.2 29.8-88.2-5.6-118.8-30.8-26.7-76.7-21.9-104.9 7.7L288 36.9l-11.1-11.6C248.7-4.4 202.8-9.2 172 17.5c-35.3 30.6-37.2 85.6-5.6 118.8l108.9 114.2zm290 77.6c-11.8-10.7-30.2-10-42.6 0L430.3 402c-11.3 9.1-25.4 14-40 14H272c-8.8 0-16-7.2-16-16s7.2-16 16-16h78.3c15.9 0 30.7-10.9 33.3-26.6 3.3-20-12.1-37.4-31.6-37.4H192c-27 0-53.1 9.3-74.1 26.3L71.4 384H16c-8.8 0-16 7.2-16 16v96c0 8.8 7.2 16 16 16h356.8c14.5 0 28.6-4.9 40-14L564 377c15.2-12.1 16.4-35.3 1.3-48.9z\"><\/path><\/svg><\/div>\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-348a1cc elementor-widget elementor-widget-text-editor\" data-id=\"348a1cc\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La Filosofia di Spazio Positivo<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8e88a34 elementor-widget elementor-widget-text-editor\" data-id=\"8e88a34\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Spazio Positivo non \u00e8 solo un centro per bambini: \u00e8 un luogo che mette al centro relazioni, crescita, comunit\u00e0 e benessere emotivo.<\/p><p>I valori guida sono:<br \/><strong>\u2665 Inclusione:<\/strong> ogni famiglia \u00e8 la benvenuta<br \/><strong>\u2665 Benessere psicologico:<\/strong> sostegno al delicato equilibrio emotivo di bambini e genitori<br \/><strong>\u2665 Comunit\u00e0:<\/strong> creare reti di supporto reciproco<br \/><strong>\u2665 Gioco come linguaggio dell\u2019infanzia<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-fe0f0d0 e-con-full e-flex e-con e-child\" data-id=\"fe0f0d0\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f274520 elementor-widget-tablet__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"f274520\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Perch\u00e9 Scegliere Spazio Positivo<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8d3f2cf elementor-widget elementor-widget-text-editor\" data-id=\"8d3f2cf\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u2665 approccio integrato educativo\u2013motorio\u2013relazionale<br \/>\u2665 professionisti qualificati dell\u2019infanzia e del movimento<br \/>\u2665 attivit\u00e0 adatte a diverse fasce d\u2019et\u00e0<br \/>\u2665 gruppi divisi per fasce di et\u00e0 ristrette<br \/>\u2665 ambiente sicuro e familiare<br \/>\u2665 focus su genitorialit\u00e0 consapevole e inclusiva<br \/>\u2665 materiali e setting selezionati per le necessit\u00e0 dei bambini<br \/>\u2665 incontri, corsi, percorsi anche per la fascia 0-3 anni<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-226897c e-con-full e-flex e-con e-child\" data-id=\"226897c\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ee304cd elementor-widget elementor-widget-spacer\" data-id=\"ee304cd\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7c65d13 elementor-hidden-tablet elementor-hidden-mobile e-flex e-con-boxed e-con e-parent\" data-id=\"7c65d13\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-e8a112a e-con-full e-flex e-con e-child\" data-id=\"e8a112a\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9cda021 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"9cda021\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" fetchpriority=\"high\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2026\/03\/Logo-Spazio-Positivo.png\" class=\"attachment-full size-full wp-image-29335\" alt=\"\" srcset=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2026\/03\/Logo-Spazio-Positivo.png 500w, https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2026\/03\/Logo-Spazio-Positivo-480x480.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 500px, 100vw\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9ae40ea elementor-widget elementor-widget-text-editor\" data-id=\"9ae40ea\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Chi siamo<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2c66ff9 elementor-widget elementor-widget-text-editor\" data-id=\"2c66ff9\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Spazio Positivo \u00e8 un centro polifunzionale per bambini e famiglie situato nel cuore del quartiere San Siro a Milano. <br \/>\u00c8 un\u2019Impresa Sociale senza scopo di lucro nata per promuovere benessere psicologico, educativo e sociale, offrendo attivit\u00e0 e servizi pensati per sostenere la genitorialit\u00e0 e creare opportunit\u00e0 inclusive per il territorio.<\/p><p>La missione \u00e8 semplice e potente: creare un luogo accogliente dove bambini e genitori possano crescere, trovare sostegno e sentirsi parte di una comunit\u00e0 attiva e solidale.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-fdde0e6 e-con-full e-flex e-con e-child\" data-id=\"fdde0e6\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a99b364 elementor-widget elementor-widget-spacer\" data-id=\"a99b364\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5e53926 e-con-full e-flex e-con e-child\" data-id=\"5e53926\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a7d9319 elementor-widget elementor-widget-text-editor\" data-id=\"a7d9319\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Attivit\u00e0 e Corsi per Bambini e Famiglie<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-41629de elementor-widget elementor-widget-text-editor\" data-id=\"41629de\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>1. Psicomotricit\u00e0, Movimento e Gioco<\/strong><br>Gruppi di psicomotricit\u00e0 educatica progettati per sostenere lo sviluppo del bambino sul piano emotivo, relazionale, motorio e cognitivo.<br>Le proposte si basano su: <strong>apprendimento non formale,<\/strong><strong> life skills riconosciute dalla pedagogia contemporanea, <\/strong><strong>gioco e movimento come basi fondamentali per il neurosviluppo.<\/strong><\/p>\n<p>I corsi sono rivolti anche ai bambini nella fascia 12-36 mesi<\/p>\n<p><strong>2. Capoeira, Danzaterapia e altre discipline<\/strong><br>Discipline artistiche e corporee che combinano: <strong>movimento, ritmo, gioco e consapevolezza corporea.<\/strong><br>Corsi e cicli di incontri condotti da professionisti. Movimento, ritmo e gioco sono utilizzati come strumenti di crescita.<\/p>\n<p><strong>3. Laboratori Creativi del Weekend<\/strong><br>Ogni mese vengono organizzati laboratori tematici come: <strong>attivit\u00e0 artistiche e riciclo creativo, ceramica, stanze sensoriali immersive, percorsi esperienziali<\/strong><br>Materiali selezionati, personale esperto, formato e competente. Non i soliti lavoretti ma vere e proprie esperienze pianificate, studiate e guidate da esperti.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b1578bc e-con-full e-flex e-con e-child\" data-id=\"b1578bc\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0e4afec elementor-widget elementor-widget-text-editor\" data-id=\"0e4afec\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>4. Eventi per Famiglie<\/strong><br \/>Per condividere momenti di qualit\u00e0 e sostenere la genitorialit\u00e0 (con particolare attenzione per le neo-mamme).<br \/><strong>\u2665 pigiama party per adolescenti e bambini grandi<\/strong><br \/><strong>\u2665 cinemino dei neonati<\/strong><br \/><strong>\u2665 spettacoli per famiglie in piccoli gruppi, rivolti anche e soprattutto ai pi\u00f9 piccoli<\/strong><br \/><strong>\u2665 attivit\u00e0 speciali a tema<\/strong><\/p><p>Lo scopo non \u00e8 quello di fare intrattenimento ma di creare momenti condivisi che ci portino ad uscire dalle mura di casa, in un ambiente sicuro e dedicato a genitori e figli, nel quale i bambini possono essere bambini.<\/p><p><strong>5. Sostegno alla Genitorialit\u00e0<\/strong><br \/>Un pilastro fondamentale del progetto. <br \/>Spazio Positivo offre:<br \/><strong>\u2665 incontri tematici con psicologi, educatori e professionisti<\/strong><br \/><strong>\u2665 laboratori genitore\u2013bambino<\/strong><br \/><strong>\u2665 gruppi di auto-sostegno tra neomamme e genitori con figli neurodivergenti<\/strong><\/p><p>L&#8217;obiettivo \u00e8 aiutare i genitori a riconoscere risorse, costruire consapevolezza, prevenire stress e burn-out, favorire il supporto comunitario.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-17822e9 e-con-full e-flex e-con e-child\" data-id=\"17822e9\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7ab3a32 elementor-widget elementor-widget-spacer\" data-id=\"7ab3a32\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-78913fa e-con-full e-flex e-con e-child\" data-id=\"78913fa\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b0d3827 elementor-widget elementor-widget-spacer\" data-id=\"b0d3827\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-cec94be e-con-full e-flex e-con e-child\" data-id=\"cec94be\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2d17321 elementor-widget elementor-widget-text-editor\" data-id=\"2d17321\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La Struttura<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5430c5e elementor-widget elementor-widget-text-editor\" data-id=\"5430c5e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Gli ambienti sono progettati per accogliere bambini e adulti in modo sicuro e accogliente.<br \/>La nostra sala d&#8217;attesa permette ai genitori di rimanere nella struttura durante i corsi dedicati ai bambini e condividere il proprio tempo con altri caregivers. Siamo dotati di spogliatoi con bagno per bambini e fasciatoio. Il centro \u00e8 totalmente accessibile anche in carrozzina (in quel caso \u00e8 per\u00f2 necessario avvisare ed entrare dal passo carraio).<br \/>Lo spazio \u00e8 condiviso in sinergia con ASD Capoeira Milano ETS, con cui viene portata avanti una visione di comunit\u00e0 aperta e inclusiva.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-992200d elementor-widget-divider--view-line_icon elementor-view-default elementor-widget-divider--element-align-center elementor-widget elementor-widget-divider\" data-id=\"992200d\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon elementor-divider__element\">\n\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-hand-holding-heart\" viewBox=\"0 0 576 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M275.3 250.5c7 7.4 18.4 7.4 25.5 0l108.9-114.2c31.6-33.2 29.8-88.2-5.6-118.8-30.8-26.7-76.7-21.9-104.9 7.7L288 36.9l-11.1-11.6C248.7-4.4 202.8-9.2 172 17.5c-35.3 30.6-37.2 85.6-5.6 118.8l108.9 114.2zm290 77.6c-11.8-10.7-30.2-10-42.6 0L430.3 402c-11.3 9.1-25.4 14-40 14H272c-8.8 0-16-7.2-16-16s7.2-16 16-16h78.3c15.9 0 30.7-10.9 33.3-26.6 3.3-20-12.1-37.4-31.6-37.4H192c-27 0-53.1 9.3-74.1 26.3L71.4 384H16c-8.8 0-16 7.2-16 16v96c0 8.8 7.2 16 16 16h356.8c14.5 0 28.6-4.9 40-14L564 377c15.2-12.1 16.4-35.3 1.3-48.9z\"><\/path><\/svg><\/div>\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-502dae0 elementor-widget elementor-widget-text-editor\" data-id=\"502dae0\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La Filosofia di Spazio Positivo<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7904517 elementor-widget elementor-widget-text-editor\" data-id=\"7904517\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Spazio Positivo non \u00e8 solo un centro per bambini: \u00e8 un luogo che mette al centro relazioni, crescita, comunit\u00e0 e benessere emotivo.<\/p><p>I valori guida sono:<br \/><strong>\u2665 Inclusione:<\/strong> ogni famiglia \u00e8 la benvenuta<br \/><strong>\u2665 Benessere psicologico:<\/strong> sostegno al delicato equilibrio emotivo di bambini e genitori<br \/><strong>\u2665 Comunit\u00e0:<\/strong> creare reti di supporto reciproco<br \/><strong>\u2665 Gioco come linguaggio dell\u2019infanzia<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6713397 e-con-full e-flex e-con e-child\" data-id=\"6713397\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7ac9f56 elementor-widget elementor-widget-text-editor\" data-id=\"7ac9f56\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Perch\u00e9 Scegliere Spazio Positivo<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-48073fa elementor-widget elementor-widget-text-editor\" data-id=\"48073fa\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u2665 approccio integrato educativo\u2013motorio\u2013relazionale<br \/>\u2665 professionisti qualificati dell\u2019infanzia e del movimento<br \/>\u2665 attivit\u00e0 adatte a diverse fasce d\u2019et\u00e0<br \/>\u2665 gruppi divisi per fasce di et\u00e0 ristrette<br \/>\u2665 ambiente sicuro e familiare<br \/>\u2665 focus su genitorialit\u00e0 consapevole e inclusiva<br \/>\u2665 materiali e setting selezionati per le necessit\u00e0 dei bambini<br \/>\u2665 incontri, corsi, percorsi anche per la fascia 0-3 anni<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a6574ba e-con-full e-flex e-con e-child\" data-id=\"a6574ba\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-faf9bd3 elementor-widget elementor-widget-spacer\" data-id=\"faf9bd3\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c936404 e-flex e-con-boxed e-con e-parent\" data-id=\"c936404\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e3d6d65 elementor-widget-mobile__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"e3d6d65\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Agevolazioni riservate agli associati<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9091bbf e-flex e-con-boxed e-con e-parent\" data-id=\"9091bbf\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-84f2649 e-con-full e-flex e-con e-child\" data-id=\"84f2649\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8d75c43 elementor-widget elementor-widget-text-editor\" data-id=\"8d75c43\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tSpazio Positivo\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d3bc5af elementor-widget-tablet__width-initial elementor-widget-mobile__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"d3bc5af\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Centro Educativo e di Benessere per Bambini e Famiglie<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-25426ca elementor-widget-divider--view-line_icon elementor-view-default elementor-widget-divider--element-align-center elementor-widget elementor-widget-divider\" data-id=\"25426ca\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon elementor-divider__element\">\n\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-hand-holding-heart\" viewBox=\"0 0 576 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M275.3 250.5c7 7.4 18.4 7.4 25.5 0l108.9-114.2c31.6-33.2 29.8-88.2-5.6-118.8-30.8-26.7-76.7-21.9-104.9 7.7L288 36.9l-11.1-11.6C248.7-4.4 202.8-9.2 172 17.5c-35.3 30.6-37.2 85.6-5.6 118.8l108.9 114.2zm290 77.6c-11.8-10.7-30.2-10-42.6 0L430.3 402c-11.3 9.1-25.4 14-40 14H272c-8.8 0-16-7.2-16-16s7.2-16 16-16h78.3c15.9 0 30.7-10.9 33.3-26.6 3.3-20-12.1-37.4-31.6-37.4H192c-27 0-53.1 9.3-74.1 26.3L71.4 384H16c-8.8 0-16 7.2-16 16v96c0 8.8 7.2 16 16 16h356.8c14.5 0 28.6-4.9 40-14L564 377c15.2-12.1 16.4-35.3 1.3-48.9z\"><\/path><\/svg><\/div>\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e482ddb elementor-widget elementor-widget-text-editor\" data-id=\"e482ddb\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Contatti<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5368572 elementor-widget elementor-widget-text-editor\" data-id=\"5368572\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Via Gianicolo, 20 (Citofono 99) &#8211; 20148 Milano (Zona San Siro)<br \/><strong>Tel:<\/strong> <a href=\"tel:+393514421288\">351 4421288<\/a><br \/><b>Mail: <\/b><a href=\"mailto:info@spaziopositivoimpresasociale.it\">info@spaziopositivoimpresasociale.it<\/a><br \/><strong>Sito web:<\/strong> <a href=\"https:\/\/www.spaziopositivoimpresasociale.it\/\">www.spaziopositivoimpresasociale.it<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-284e9ae e-con-full e-flex e-con e-child\" data-id=\"284e9ae\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c59c5de elementor-widget elementor-widget-spacer\" data-id=\"c59c5de\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6a84804 e-con-full e-flex e-con e-parent\" data-id=\"6a84804\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d2913ab elementor-widget elementor-widget-text-editor\" data-id=\"d2913ab\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><div id=\"gmw-single-object-locations-wrapper-254\" class=\"gmw-element-wrapper gmw-single-location-wrapper gmw-sl-wrapper gmw-sl-single-post-wrapper post gmw-sl-multiple-locations\" object_type=\"post\" object_id=\"\"  style=\"width:100%\"><div class=\"gmw-sl-map-wrapper\"><div id=\"gmw-map-wrapper-254\" class=\"gmw-map-wrapper  sl single_location \" style=\"width:100%;height:400px;\"> <span id=\"gmw-resize-map-toggle-254\" class=\"gmw-resize-map-toggle gmw-icon-resize-full\" style=\"display:none;\" title=\"Resize map\"><\/span> <div id=\"gmw-map-loader-254\" class=\"gmw-map-loader\"><\/div> <div id=\"gmw-map-254\" class=\"gmw-map sl single_location\" style=\"width:100%; height:100%\" data-map_id=\"254\" data-prefix=\"sl\" data-map_type=\"single_location\" data-icons_usage=\"global\"><\/div> <\/div><\/div><\/div><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-dafbb09 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile e-flex e-con-boxed e-con e-parent\" data-id=\"dafbb09\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-42e6aa4 elementor-widget elementor-widget-text-editor\" data-id=\"42e6aa4\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>&lt;div style= &#8220;display: none&#8221;&gt;<\/p><p><br \/>Gent.mi,<br \/>Con la presente invio il testo per la Landing Page relativa al nostro Centro &#8220;Spazio Positivo&#8221; per la newsletter.<br \/>Allego immagini da inserire (in caso di minori abbiamo liberatorie e possono essere tutte pubblicate se legate a noi). Per qualsiasi dubbio contattatemi pure.<\/p><p>\u2b50 Spazio Positivo \u2013 Centro Educativo e di Benessere per Bambini e Famiglie a Milano (San Siro)<\/p><p><br \/>Indirizzo: Via Gianicolo 20, Milano &#8211; Citofono 99<br \/>Email: info@spaziopositivoimpresasociale.it<br \/>Telefono: 351 442 1288<br \/>Sito web: https:\/\/www.spaziopositivoimpresasociale.it\/<\/p><p>Spazio Positivo \u00e8 un centro polifunzionale per bambini e famiglie situato nel cuore del quartiere San Siro a Milano. \u00c8 un\u2019Impresa Sociale senza scopo di lucro nata per promuovere benessere psicologico, educativo e sociale, offrendo attivit\u00e0 e servizi pensati per sostenere la genitorialit\u00e0 e creare opportunit\u00e0 inclusive per il territorio.<\/p><p>La missione \u00e8 semplice e potente: creare un luogo accogliente dove bambini e genitori possano crescere, trovare sostegno e sentirsi parte di una comunit\u00e0 attiva e solidale.<\/p><p>? Attivit\u00e0 e Corsi per Bambini e Famiglie<\/p><p>1. Psicomotricit\u00e0, Movimento e Gioco<\/p><p>Gruppi di psicomotricit\u00e0 educatica progettati per sostenere lo sviluppo del bambino sul piano emotivo, relazionale, motorio e cognitivo.<br \/>Le proposte si basano su:<\/p><p>&#8211; apprendimento non formale<br \/>&#8211; life skills riconosciute dalla pedagogia contemporanea<br \/>&#8211; gioco e movimento come basi fondamentali per il neurosviluppo<\/p><p>I corsi sono rivolti anche ai bambini nella fascia 12-36 mesi<\/p><p>2. Capoeira, Danzaterapia e altre discipline<br \/>Discipline artistiche e corporee che combinano:<\/p><p>movimento<br \/>ritmo<br \/>gioco<br \/>consapevolezza corporea<br \/>Corsi e cicli di incontri condotti da professionisti. Movimento, ritmo e gioco sono utilizzati come strumenti di crescita.<br \/>\u200b<br \/>3. Laboratori Creativi del Weekend<br \/>Ogni mese vengono organizzati laboratori tematici come:<\/p><p>attivit\u00e0 artistiche e riciclo creativo<br \/>ceramica<br \/>stanze sensoriali immersive<br \/>percorsi esperienziali<br \/>Materiali selezionati, personale esperto, formato e competente. Non i soliti lavoretti ma vere e proprie esperienze pianificate, studiate e guidate da esperti.<\/p><p>4. Eventi per Famiglie<br \/>Per condividere momenti di qualit\u00e0 e sostenere la genitorialit\u00e0 (con particolare attenzione per le neo-mamme)<\/p><p>&#8211; pigiama party per adolescenti e bambini grandi <br \/>&#8211; cinemino dei neonati<br \/>&#8211; spettacoli per famiglie in piccoli gruppi, rivolti anche e soprattutto ai pi\u00f9 piccoli<br \/>&#8211; attivit\u00e0 speciali a tema<\/p><p>Lo scopo non \u00e8 quello di fare intrattenimento ma di creare momenti condivisi che ci portino ad uscire dalle mura di casa, in un ambiente sicuro e decicato a genitori e figli, nel quale i bambini possono essere bambini.<\/p><p>5. Sostegno alla Genitorialit\u00e0<br \/>Un pilastro fondamentale del progetto. Spazio Positivo offre:<\/p><p>&#8211; incontri tematici con psicologi, educatori e professionisti<br \/>&#8211; laboratori genitore\u2013bambino<br \/>&#8211; gruppi di auto-sostegno tra neomamme e genitori con figli neurodivergenti<\/p><p>L&#8217;obiettivo \u00e8 aiutare i genitori a riconoscere risorse, costruire consapevolezza, prevenire stress e burn-out, favorire il supporto comunitario.<\/p><p>? La Struttura<\/p><p>Ci troviamo in via Gianicolo 20, Milano, all\u2019interno del quartiere San Siro.<br \/>Gli ambienti sono progettati per accogliere bambini e adulti in modo sicuro e accogliente.<\/p><p>La nostra sala d&#8217;attesa permette ai genitori di rimanere nella struttura durante i corsi dedicati ai bambini e condividere il proprio tempo con altri caregivers. Siamo dotati di spogliatoi con bagno per bambini e fasciatoio. Il centro \u00e8 totalmente accessibile anche in carrozzina (in quel caso \u00e8 per\u00f2 necessario avvisare ed entrare dal passo carraio).<\/p><p>Lo spazio \u00e8 condiviso in sinergia con ASD Capoeira Milano ETS, con cui viene portata avanti una visione di comunit\u00e0 aperta e inclusiva.<\/p><p>? La Filosofia di Spazio Positivo<br \/>Spazio Positivo non \u00e8 solo un centro per bambini: \u00e8 un luogo che mette al centro relazioni, crescita, comunit\u00e0 e benessere emotivo.<\/p><p>I valori guida sono:<\/p><p>Inclusione: ogni famiglia \u00e8 la benvenuta<br \/>Benessere psicologico: sostegno al delicato equilibrio emotivo di bambini e genitori<br \/>Comunit\u00e0: creare reti di supporto reciproco<br \/>Gioco come linguaggio dell\u2019infanzia<\/p><p>? Perch\u00e9 Scegliere Spazio Positivo<br \/>approccio integrato educativo\u2013motorio\u2013relazionale<br \/>professionisti qualificati dell\u2019infanzia e del movimento<br \/>attivit\u00e0 adatte a diverse fasce d\u2019et\u00e0<br \/>gruppi divisi per fasce di et\u00e0 ristrette<br \/>ambiente sicuro e familiare<br \/>focus su genitorialit\u00e0 consapevole e inclusiva<br \/>materiali e setting selezionati per le necessit\u00e0 dei bambini<br \/>incontri, corsi, percorsi anche per la fascia 0-3 anni<\/p><p>\u00a0<\/p><p><br \/>Centri educativi, imprese sociali per famiglie, centri polifunzionali per bambini, centri per le famiglie, spazi accoglienti per genitori e figli,<\/p><p>Centro educativo, impresa sociale per famiglie, centro polifunzionale per bambini, benessere psicologico infanzia, promozione benessere sociale famiglie, comunit\u00e0 attiva e solidale, attivit\u00e0 inclusive per bambini, centro per la famiglia, spazio accogliente per genitori e figli, corsi per bambini, psicomotricit\u00e0 educativa, corsi movimento e gioco bambini, neurosviluppo infantile attraverso il gioco, attivit\u00e0 fascia 12-36 mesi, corsi capoeira per bambini, danzaterapia per l&#8217;infanzia, consapevolezza corporea per piccoli, laboratori creativi weekend, laboratori ceramica per bambini, stanze sensoriali immersive, percorsi esperienziali per l&#8217;infanzia, attivit\u00e0 artistiche, riciclo creativo, eventi per famiglie, cinema per neonati, pigiama party per adolescenti, spettacoli per la prima infanzia, attivit\u00e0 per neo-mamme, tempo libero di qualit\u00e0 genitori e figli, esperienze guidate da esperti per bambini, ambiente sicuro per il gioco infantile, sostegno alla genitorialit\u00e0, incontri con psicologi per genitori, laboratori genitore-bambino, gruppi aiuto neomamme, supporto genitori figli neurodivergenti, prevenzione burn-out genitoriale, consapevolezza educativa, corsi per genitori consapevoli, rete di supporto comunitario per famiglie, educatori qualificati dell&#8217;infanzia, benessere emotivo infantile,<\/p><p>\u00a0<\/p><p><br \/>Centri educativi a Milano, imprese sociali per famiglie a Milano, centri polifunzionali per bambini a Milano, centri per le famiglie a Milano, spazi accoglienti per genitori e figli a Milano, centro educativo a Milano, impresa sociale per famiglie a Milano, centro polifunzionale per bambini a Milano, benessere psicologico infanzia a Milano, promozione benessere sociale famiglie a Milano, comunit\u00e0 attiva e solidale a Milano, attivit\u00e0 inclusive per bambini a Milano, centro per la famiglia a Milano, spazio accogliente per genitori e figli a Milano, corsi per bambini a Milano, psicomotricit\u00e0 educativa a Milano, corsi movimento e gioco bambini a Milano, neurosviluppo infantile attraverso il gioco a Milano, attivit\u00e0 fascia 12-36 mesi a Milano, corsi capoeira per bambini a Milano, danzaterapia per l&#8217;infanzia a Milano, consapevolezza corporea per piccoli a Milano, laboratori creativi weekend a Milano, laboratori ceramica per bambini a Milano, stanze sensoriali immersive a Milano, percorsi esperienziali per l&#8217;infanzia a Milano, attivit\u00e0 artistiche a Milano, riciclo creativo a Milano, eventi per famiglie a Milano, cinema per neonati a Milano, pigiama party per adolescenti a Milano, spettacoli per la prima infanzia a Milano, attivit\u00e0 per neo-mamme a Milano, tempo libero di qualit\u00e0 genitori e figli a Milano, esperienze guidate da esperti per bambini a Milano, ambiente sicuro per il gioco infantile a Milano, sostegno alla genitorialit\u00e0 a Milano, incontri con psicologi per genitori a Milano, laboratori genitore-bambino a Milano, gruppi aiuto neomamme a Milano, supporto genitori figli neurodivergenti a Milano, prevenzione burn-out genitoriale a Milano, consapevolezza educativa a Milano, corsi per genitori consapevoli a Milano, rete di supporto comunitario per famiglie a Milano, educatori qualificati dell&#8217;infanzia a Milano, benessere emotivo infantile a Milano.<\/p><p>Centro educativo a San Siro, impresa sociale per famiglie a San Siro, centro polifunzionale per bambini a San Siro, benessere psicologico infanzia a San Siro, promozione benessere sociale famiglie a San Siro, comunit\u00e0 attiva e solidale a San Siro, attivit\u00e0 inclusive per bambini a San Siro, centro per la famiglia a San Siro, spazio accogliente per genitori e figli a San Siro, corsi per bambini a San Siro, psicomotricit\u00e0 educativa a San Siro, corsi movimento e gioco bambini a San Siro, neurosviluppo infantile attraverso il gioco a San Siro, attivit\u00e0 fascia 12-36 mesi a San Siro, corsi capoeira per bambini a San Siro, danzaterapia per l&#8217;infanzia a San Siro, consapevolezza corporea per piccoli a San Siro, laboratori creativi weekend a San Siro, laboratori ceramica per bambini a San Siro, stanze sensoriali immersive a San Siro, percorsi esperienziali per l&#8217;infanzia a San Siro, attivit\u00e0 artistiche a San Siro, riciclo creativo a San Siro, eventi per famiglie a San Siro, cinema per neonati a San Siro, pigiama party per adolescenti a San Siro, spettacoli per la prima infanzia a San Siro, attivit\u00e0 per neo-mamme a San Siro, tempo libero di qualit\u00e0 genitori e figli a San Siro, esperienze guidate da esperti per bambini a San Siro, ambiente sicuro per il gioco infantile a San Siro, sostegno alla genitorialit\u00e0 a San Siro, incontri con psicologi per genitori a San Siro, laboratori genitore-bambino a San Siro, gruppi aiuto neomamme a San Siro, supporto genitori figli neurodivergenti a San Siro, prevenzione burn-out genitoriale a San Siro, consapevolezza educativa a San Siro, corsi per genitori consapevoli a San Siro, rete di supporto comunitario per famiglie a San Siro, educatori qualificati dell&#8217;infanzia a San Siro, benessere emotivo infantile a San Siro.<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>&lt;\/div&gt;<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<div style=\"display: none;\">\n<p>Gent.mi,<br \/>\nCon la presente invio il testo per la Landing Page relativa al nostro Centro &#8220;Spazio Positivo&#8221; per la newsletter.<br \/>\nAllego immagini da inserire (in caso di minori abbiamo liberatorie e possono essere tutte pubblicate se legate a noi). Per qualsiasi dubbio contattatemi pure.<\/p>\n<p>\u2b50 Spazio Positivo \u2013 Centro Educativo e di Benessere per Bambini e Famiglie a Milano (San Siro)<\/p>\n<p>Indirizzo: Via Gianicolo 20, Milano &#8211; Citofono 99<br \/>\nEmail: info@spaziopositivoimpresasociale.it<br \/>\nTelefono: 351 442 1288<br \/>\nSito web: https:\/\/www.spaziopositivoimpresasociale.it\/<\/p>\n<p>Spazio Positivo \u00e8 un centro polifunzionale per bambini e famiglie situato nel cuore del quartiere San Siro a Milano. \u00c8 un\u2019Impresa Sociale senza scopo di lucro nata per promuovere benessere psicologico, educativo e sociale, offrendo attivit\u00e0 e servizi pensati per sostenere la genitorialit\u00e0 e creare opportunit\u00e0 inclusive per il territorio.<\/p>\n<p>La missione \u00e8 semplice e potente: creare un luogo accogliente dove bambini e genitori possano crescere, trovare sostegno e sentirsi parte di una comunit\u00e0 attiva e solidale.<\/p>\n<p>? Attivit\u00e0 e Corsi per Bambini e Famiglie<\/p>\n<p>1. Psicomotricit\u00e0, Movimento e Gioco<\/p>\n<p>Gruppi di psicomotricit\u00e0 educatica progettati per sostenere lo sviluppo del bambino sul piano emotivo, relazionale, motorio e cognitivo.<br \/>\nLe proposte si basano su:<\/p>\n<p>&#8211; apprendimento non formale<br \/>\n&#8211; life skills riconosciute dalla pedagogia contemporanea<br \/>\n&#8211; gioco e movimento come basi fondamentali per il neurosviluppo<\/p>\n<p>I corsi sono rivolti anche ai bambini nella fascia 12-36 mesi<\/p>\n<p>2. Capoeira, Danzaterapia e altre discipline<br \/>\nDiscipline artistiche e corporee che combinano:<\/p>\n<p>movimento<br \/>\nritmo<br \/>\ngioco<br \/>\nconsapevolezza corporea<br \/>\nCorsi e cicli di incontri condotti da professionisti. Movimento, ritmo e gioco sono utilizzati come strumenti di crescita.<br \/>\n\u200b<br \/>\n3. Laboratori Creativi del Weekend<br \/>\nOgni mese vengono organizzati laboratori tematici come:<\/p>\n<p>attivit\u00e0 artistiche e riciclo creativo<br \/>\nceramica<br \/>\nstanze sensoriali immersive<br \/>\npercorsi esperienziali<br \/>\nMateriali selezionati, personale esperto, formato e competente. Non i soliti lavoretti ma vere e proprie esperienze pianificate, studiate e guidate da esperti.<\/p>\n<p>4. Eventi per Famiglie<br \/>\nPer condividere momenti di qualit\u00e0 e sostenere la genitorialit\u00e0 (con particolare attenzione per le neo-mamme)<\/p>\n<p>&#8211; pigiama party per adolescenti e bambini grandi<br \/>\n&#8211; cinemino dei neonati<br \/>\n&#8211; spettacoli per famiglie in piccoli gruppi, rivolti anche e soprattutto ai pi\u00f9 piccoli<br \/>\n&#8211; attivit\u00e0 speciali a tema<\/p>\n<p>Lo scopo non \u00e8 quello di fare intrattenimento ma di creare momenti condivisi che ci portino ad uscire dalle mura di casa, in un ambiente sicuro e decicato a genitori e figli, nel quale i bambini possono essere bambini.<\/p>\n<p>5. Sostegno alla Genitorialit\u00e0<br \/>\nUn pilastro fondamentale del progetto. Spazio Positivo offre:<\/p>\n<p>&#8211; incontri tematici con psicologi, educatori e professionisti<br \/>\n&#8211; laboratori genitore\u2013bambino<br \/>\n&#8211; gruppi di auto-sostegno tra neomamme e genitori con figli neurodivergenti<\/p>\n<p>L&#8217;obiettivo \u00e8 aiutare i genitori a riconoscere risorse, costruire consapevolezza, prevenire stress e burn-out, favorire il supporto comunitario.<\/p>\n<p>? La Struttura<\/p>\n<p>Ci troviamo in via Gianicolo 20, Milano, all\u2019interno del quartiere San Siro.<br \/>\nGli ambienti sono progettati per accogliere bambini e adulti in modo sicuro e accogliente.<\/p>\n<p>La nostra sala d&#8217;attesa permette ai genitori di rimanere nella struttura durante i corsi dedicati ai bambini e condividere il proprio tempo con altri caregivers. Siamo dotati di spogliatoi con bagno per bambini e fasciatoio. Il centro \u00e8 totalmente accessibile anche in carrozzina (in quel caso \u00e8 per\u00f2 necessario avvisare ed entrare dal passo carraio).<\/p>\n<p>Lo spazio \u00e8 condiviso in sinergia con ASD Capoeira Milano ETS, con cui viene portata avanti una visione di comunit\u00e0 aperta e inclusiva.<\/p>\n<p>? La Filosofia di Spazio Positivo<br \/>\nSpazio Positivo non \u00e8 solo un centro per bambini: \u00e8 un luogo che mette al centro relazioni, crescita, comunit\u00e0 e benessere emotivo.<\/p>\n<p>I valori guida sono:<\/p>\n<p>Inclusione: ogni famiglia \u00e8 la benvenuta<br \/>\nBenessere psicologico: sostegno al delicato equilibrio emotivo di bambini e genitori<br \/>\nComunit\u00e0: creare reti di supporto reciproco<br \/>\nGioco come linguaggio dell\u2019infanzia<\/p>\n<p>? Perch\u00e9 Scegliere Spazio Positivo<br \/>\napproccio integrato educativo\u2013motorio\u2013relazionale<br \/>\nprofessionisti qualificati dell\u2019infanzia e del movimento<br \/>\nattivit\u00e0 adatte a diverse fasce d\u2019et\u00e0<br \/>\ngruppi divisi per fasce di et\u00e0 ristrette<br \/>\nambiente sicuro e familiare<br \/>\nfocus su genitorialit\u00e0 consapevole e inclusiva<br \/>\nmateriali e setting selezionati per le necessit\u00e0 dei bambini<br \/>\nincontri, corsi, percorsi anche per la fascia 0-3 anni<\/p>\n<p>Centri educativi, imprese sociali per famiglie, centri polifunzionali per bambini, centri per le famiglie, spazi accoglienti per genitori e figli,<\/p>\n<p>Centro educativo, impresa sociale per famiglie, centro polifunzionale per bambini, benessere psicologico infanzia, promozione benessere sociale famiglie, comunit\u00e0 attiva e solidale, attivit\u00e0 inclusive per bambini, centro per la famiglia, spazio accogliente per genitori e figli, corsi per bambini, psicomotricit\u00e0 educativa, corsi movimento e gioco bambini, neurosviluppo infantile attraverso il gioco, attivit\u00e0 fascia 12-36 mesi, corsi capoeira per bambini, danzaterapia per l&#8217;infanzia, consapevolezza corporea per piccoli, laboratori creativi weekend, laboratori ceramica per bambini, stanze sensoriali immersive, percorsi esperienziali per l&#8217;infanzia, attivit\u00e0 artistiche, riciclo creativo, eventi per famiglie, cinema per neonati, pigiama party per adolescenti, spettacoli per la prima infanzia, attivit\u00e0 per neo-mamme, tempo libero di qualit\u00e0 genitori e figli, esperienze guidate da esperti per bambini, ambiente sicuro per il gioco infantile, sostegno alla genitorialit\u00e0, incontri con psicologi per genitori, laboratori genitore-bambino, gruppi aiuto neomamme, supporto genitori figli neurodivergenti, prevenzione burn-out genitoriale, consapevolezza educativa, corsi per genitori consapevoli, rete di supporto comunitario per famiglie, educatori qualificati dell&#8217;infanzia, benessere emotivo infantile,<\/p>\n<p>Centri educativi a Milano, imprese sociali per famiglie a Milano, centri polifunzionali per bambini a Milano, centri per le famiglie a Milano, spazi accoglienti per genitori e figli a Milano, centro educativo a Milano, impresa sociale per famiglie a Milano, centro polifunzionale per bambini a Milano, benessere psicologico infanzia a Milano, promozione benessere sociale famiglie a Milano, comunit\u00e0 attiva e solidale a Milano, attivit\u00e0 inclusive per bambini a Milano, centro per la famiglia a Milano, spazio accogliente per genitori e figli a Milano, corsi per bambini a Milano, psicomotricit\u00e0 educativa a Milano, corsi movimento e gioco bambini a Milano, neurosviluppo infantile attraverso il gioco a Milano, attivit\u00e0 fascia 12-36 mesi a Milano, corsi capoeira per bambini a Milano, danzaterapia per l&#8217;infanzia a Milano, consapevolezza corporea per piccoli a Milano, laboratori creativi weekend a Milano, laboratori ceramica per bambini a Milano, stanze sensoriali immersive a Milano, percorsi esperienziali per l&#8217;infanzia a Milano, attivit\u00e0 artistiche a Milano, riciclo creativo a Milano, eventi per famiglie a Milano, cinema per neonati a Milano, pigiama party per adolescenti a Milano, spettacoli per la prima infanzia a Milano, attivit\u00e0 per neo-mamme a Milano, tempo libero di qualit\u00e0 genitori e figli a Milano, esperienze guidate da esperti per bambini a Milano, ambiente sicuro per il gioco infantile a Milano, sostegno alla genitorialit\u00e0 a Milano, incontri con psicologi per genitori a Milano, laboratori genitore-bambino a Milano, gruppi aiuto neomamme a Milano, supporto genitori figli neurodivergenti a Milano, prevenzione burn-out genitoriale a Milano, consapevolezza educativa a Milano, corsi per genitori consapevoli a Milano, rete di supporto comunitario per famiglie a Milano, educatori qualificati dell&#8217;infanzia a Milano, benessere emotivo infantile a Milano.<\/p>\n<p>Centro educativo a San Siro, impresa sociale per famiglie a San Siro, centro polifunzionale per bambini a San Siro, benessere psicologico infanzia a San Siro, promozione benessere sociale famiglie a San Siro, comunit\u00e0 attiva e solidale a San Siro, attivit\u00e0 inclusive per bambini a San Siro, centro per la famiglia a San Siro, spazio accogliente per genitori e figli a San Siro, corsi per bambini a San Siro, psicomotricit\u00e0 educativa a San Siro, corsi movimento e gioco bambini a San Siro, neurosviluppo infantile attraverso il gioco a San Siro, attivit\u00e0 fascia 12-36 mesi a San Siro, corsi capoeira per bambini a San Siro, danzaterapia per l&#8217;infanzia a San Siro, consapevolezza corporea per piccoli a San Siro, laboratori creativi weekend a San Siro, laboratori ceramica per bambini a San Siro, stanze sensoriali immersive a San Siro, percorsi esperienziali per l&#8217;infanzia a San Siro, attivit\u00e0 artistiche a San Siro, riciclo creativo a San Siro, eventi per famiglie a San Siro, cinema per neonati a San Siro, pigiama party per adolescenti a San Siro, spettacoli per la prima infanzia a San Siro, attivit\u00e0 per neo-mamme a San Siro, tempo libero di qualit\u00e0 genitori e figli a San Siro, esperienze guidate da esperti per bambini a San Siro, ambiente sicuro per il gioco infantile a San Siro, sostegno alla genitorialit\u00e0 a San Siro, incontri con psicologi per genitori a San Siro, laboratori genitore-bambino a San Siro, gruppi aiuto neomamme a San Siro, supporto genitori figli neurodivergenti a San Siro, prevenzione burn-out genitoriale a San Siro, consapevolezza educativa a San Siro, corsi per genitori consapevoli a San Siro, rete di supporto comunitario per famiglie a San Siro, educatori qualificati dell&#8217;infanzia a San Siro, benessere emotivo infantile a San Siro.<\/p>\n<\/div>\n","protected":false},"featured_media":29329,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":""},"product_brand":[],"product_cat":[3688,3689,161,3687,26,27,5772,29],"product_tag":[7151,3548,7135,7129,7148,7161,7126,7071,7121,7120,7123,7130,7125,7145,7128,7138,7157,7136,7133,3308,7158,7137,7160,7150,7144,7154,7124,7119,7152,7140,7139,7153,7134,7142,7146,7156,7127,7132,7159,7143,4171,7122,7131,7147,7141,7155,7149],"class_list":{"0":"post-29328","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-assistenza-alla-genitorialita","7":"product_cat-centri-assistenza-per-le-famiglie","8":"product_cat-psicologi","9":"product_cat-psicomotricita","10":"product_cat-salute","11":"product_cat-servizi","12":"product_cat-spazi-per-bambini-e-genitori","13":"product_cat-sport-tempo-libero","14":"product_tag-ambiente-sicuro-per-il-gioco-infantile","15":"product_tag-attivita-artistiche","16":"product_tag-attivita-fascia-12-36-mesi","17":"product_tag-attivita-inclusive-per-bambini","18":"product_tag-attivita-per-neo-mamme","19":"product_tag-benessere-emotivo-infantile","20":"product_tag-benessere-psicologico-infanzia","21":"product_tag-centri-educativi","22":"product_tag-centri-per-le-famiglie","23":"product_tag-centri-polifunzionali-per-bambini","24":"product_tag-centro-educativo","25":"product_tag-centro-per-la-famiglia","26":"product_tag-centro-polifunzionale-per-bambini","27":"product_tag-cinema-per-neonati","28":"product_tag-comunita-attiva-e-solidale","29":"product_tag-consapevolezza-corporea-per-piccoli","30":"product_tag-consapevolezza-educativa","31":"product_tag-corsi-capoeira-per-bambini","32":"product_tag-corsi-movimento-e-gioco-bambini","33":"product_tag-corsi-per-bambini","34":"product_tag-corsi-per-genitori-consapevoli","35":"product_tag-danzaterapia-per-linfanzia","36":"product_tag-educatori-qualificati-dellinfanzia","37":"product_tag-esperienze-guidate-da-esperti-per-bambini","38":"product_tag-eventi-per-famiglie","39":"product_tag-gruppi-aiuto-neomamme","40":"product_tag-impresa-sociale-per-famiglie","41":"product_tag-imprese-sociali-per-famiglie","42":"product_tag-incontri-con-psicologi-per-genitori","43":"product_tag-laboratori-ceramica-per-bambini","44":"product_tag-laboratori-creativi-weekend","45":"product_tag-laboratori-genitore-bambino","46":"product_tag-neurosviluppo-infantile-attraverso-il-gioco","47":"product_tag-percorsi-esperienziali-per-linfanzia","48":"product_tag-pigiama-party-per-adolescenti","49":"product_tag-prevenzione-burn-out-genitoriale","50":"product_tag-promozione-benessere-sociale-famiglie","51":"product_tag-psicomotricita-educativa","52":"product_tag-rete-di-supporto-comunitario-per-famiglie","53":"product_tag-riciclo-creativo","54":"product_tag-sostegno-alla-genitorialita","55":"product_tag-spazi-accoglienti-per-genitori-e-figli","56":"product_tag-spazio-accogliente-per-genitori-e-figli","57":"product_tag-spettacoli-per-la-prima-infanzia","58":"product_tag-stanze-sensoriali-immersive","59":"product_tag-supporto-genitori-figli-neurodivergenti","60":"product_tag-tempo-libero-di-qualita-genitori-e-figli","62":"first","63":"instock","64":"shipping-taxable","65":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Spazio Positivo \u2013 Centro Educativo e di Benessere per Bambini e Famiglie - Cral Policlinico di Milano<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/spazio-positivo-centro-educativo-e-di-benessere-per-bambini-e-famiglie\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Spazio Positivo \u2013 Centro Educativo e di Benessere per Bambini e Famiglie - Cral Policlinico di Milano\" \/>\n<meta property=\"og:description\" content=\"Gent.mi, Con la presente invio il testo per la Landing Page relativa al nostro Centro &quot;Spazio Positivo&quot; per la newsletter. Allego immagini da inserire (in caso di minori abbiamo liberatorie e possono essere tutte pubblicate se legate a noi). Per qualsiasi dubbio contattatemi pure.  \u2b50 Spazio Positivo \u2013 Centro Educativo e di Benessere per Bambini e Famiglie a Milano (San Siro)  Indirizzo: Via Gianicolo 20, Milano - Citofono 99 Email: info@spaziopositivoimpresasociale.it Telefono: 351 442 1288 Sito web: https:\/\/www.spaziopositivoimpresasociale.it\/  Spazio Positivo \u00e8 un centro polifunzionale per bambini e famiglie situato nel cuore del quartiere San Siro a Milano. \u00c8 un\u2019Impresa Sociale senza scopo di lucro nata per promuovere benessere psicologico, educativo e sociale, offrendo attivit\u00e0 e servizi pensati per sostenere la genitorialit\u00e0 e creare opportunit\u00e0 inclusive per il territorio.  La missione \u00e8 semplice e potente: creare un luogo accogliente dove bambini e genitori possano crescere, trovare sostegno e sentirsi parte di una comunit\u00e0 attiva e solidale.  ? Attivit\u00e0 e Corsi per Bambini e Famiglie  1. Psicomotricit\u00e0, Movimento e Gioco  Gruppi di psicomotricit\u00e0 educatica progettati per sostenere lo sviluppo del bambino sul piano emotivo, relazionale, motorio e cognitivo. Le proposte si basano su:  - apprendimento non formale - life skills riconosciute dalla pedagogia contemporanea - gioco e movimento come basi fondamentali per il neurosviluppo  I corsi sono rivolti anche ai bambini nella fascia 12-36 mesi  2. Capoeira, Danzaterapia e altre discipline Discipline artistiche e corporee che combinano:  movimento ritmo gioco consapevolezza corporea Corsi e cicli di incontri condotti da professionisti. Movimento, ritmo e gioco sono utilizzati come strumenti di crescita. \u200b 3. Laboratori Creativi del Weekend Ogni mese vengono organizzati laboratori tematici come:  attivit\u00e0 artistiche e riciclo creativo ceramica stanze sensoriali immersive percorsi esperienziali Materiali selezionati, personale esperto, formato e competente. Non i soliti lavoretti ma vere e proprie esperienze pianificate, studiate e guidate da esperti.  4. Eventi per Famiglie Per condividere momenti di qualit\u00e0 e sostenere la genitorialit\u00e0 (con particolare attenzione per le neo-mamme)  - pigiama party per adolescenti e bambini grandi - cinemino dei neonati - spettacoli per famiglie in piccoli gruppi, rivolti anche e soprattutto ai pi\u00f9 piccoli - attivit\u00e0 speciali a tema  Lo scopo non \u00e8 quello di fare intrattenimento ma di creare momenti condivisi che ci portino ad uscire dalle mura di casa, in un ambiente sicuro e decicato a genitori e figli, nel quale i bambini possono essere bambini.  5. Sostegno alla Genitorialit\u00e0 Un pilastro fondamentale del progetto. Spazio Positivo offre:  - incontri tematici con psicologi, educatori e professionisti - laboratori genitore\u2013bambino - gruppi di auto-sostegno tra neomamme e genitori con figli neurodivergenti  L&#039;obiettivo \u00e8 aiutare i genitori a riconoscere risorse, costruire consapevolezza, prevenire stress e burn-out, favorire il supporto comunitario.  ? La Struttura  Ci troviamo in via Gianicolo 20, Milano, all\u2019interno del quartiere San Siro. Gli ambienti sono progettati per accogliere bambini e adulti in modo sicuro e accogliente.  La nostra sala d&#039;attesa permette ai genitori di rimanere nella struttura durante i corsi dedicati ai bambini e condividere il proprio tempo con altri caregivers. Siamo dotati di spogliatoi con bagno per bambini e fasciatoio. Il centro \u00e8 totalmente accessibile anche in carrozzina (in quel caso \u00e8 per\u00f2 necessario avvisare ed entrare dal passo carraio).  Lo spazio \u00e8 condiviso in sinergia con ASD Capoeira Milano ETS, con cui viene portata avanti una visione di comunit\u00e0 aperta e inclusiva.  ? La Filosofia di Spazio Positivo Spazio Positivo non \u00e8 solo un centro per bambini: \u00e8 un luogo che mette al centro relazioni, crescita, comunit\u00e0 e benessere emotivo.  I valori guida sono:  Inclusione: ogni famiglia \u00e8 la benvenuta Benessere psicologico: sostegno al delicato equilibrio emotivo di bambini e genitori Comunit\u00e0: creare reti di supporto reciproco Gioco come linguaggio dell\u2019infanzia  ? Perch\u00e9 Scegliere Spazio Positivo approccio integrato educativo\u2013motorio\u2013relazionale professionisti qualificati dell\u2019infanzia e del movimento attivit\u00e0 adatte a diverse fasce d\u2019et\u00e0 gruppi divisi per fasce di et\u00e0 ristrette ambiente sicuro e familiare focus su genitorialit\u00e0 consapevole e inclusiva materiali e setting selezionati per le necessit\u00e0 dei bambini incontri, corsi, percorsi anche per la fascia 0-3 anni  Centri educativi, imprese sociali per famiglie, centri polifunzionali per bambini, centri per le famiglie, spazi accoglienti per genitori e figli,  Centro educativo, impresa sociale per famiglie, centro polifunzionale per bambini, benessere psicologico infanzia, promozione benessere sociale famiglie, comunit\u00e0 attiva e solidale, attivit\u00e0 inclusive per bambini, centro per la famiglia, spazio accogliente per genitori e figli, corsi per bambini, psicomotricit\u00e0 educativa, corsi movimento e gioco bambini, neurosviluppo infantile attraverso il gioco, attivit\u00e0 fascia 12-36 mesi, corsi capoeira per bambini, danzaterapia per l&#039;infanzia, consapevolezza corporea per piccoli, laboratori creativi weekend, laboratori ceramica per bambini, stanze sensoriali immersive, percorsi esperienziali per l&#039;infanzia, attivit\u00e0 artistiche, riciclo creativo, eventi per famiglie, cinema per neonati, pigiama party per adolescenti, spettacoli per la prima infanzia, attivit\u00e0 per neo-mamme, tempo libero di qualit\u00e0 genitori e figli, esperienze guidate da esperti per bambini, ambiente sicuro per il gioco infantile, sostegno alla genitorialit\u00e0, incontri con psicologi per genitori, laboratori genitore-bambino, gruppi aiuto neomamme, supporto genitori figli neurodivergenti, prevenzione burn-out genitoriale, consapevolezza educativa, corsi per genitori consapevoli, rete di supporto comunitario per famiglie, educatori qualificati dell&#039;infanzia, benessere emotivo infantile,  Centri educativi a Milano, imprese sociali per famiglie a Milano, centri polifunzionali per bambini a Milano, centri per le famiglie a Milano, spazi accoglienti per genitori e figli a Milano, centro educativo a Milano, impresa sociale per famiglie a Milano, centro polifunzionale per bambini a Milano, benessere psicologico infanzia a Milano, promozione benessere sociale famiglie a Milano, comunit\u00e0 attiva e solidale a Milano, attivit\u00e0 inclusive per bambini a Milano, centro per la famiglia a Milano, spazio accogliente per genitori e figli a Milano, corsi per bambini a Milano, psicomotricit\u00e0 educativa a Milano, corsi movimento e gioco bambini a Milano, neurosviluppo infantile attraverso il gioco a Milano, attivit\u00e0 fascia 12-36 mesi a Milano, corsi capoeira per bambini a Milano, danzaterapia per l&#039;infanzia a Milano, consapevolezza corporea per piccoli a Milano, laboratori creativi weekend a Milano, laboratori ceramica per bambini a Milano, stanze sensoriali immersive a Milano, percorsi esperienziali per l&#039;infanzia a Milano, attivit\u00e0 artistiche a Milano, riciclo creativo a Milano, eventi per famiglie a Milano, cinema per neonati a Milano, pigiama party per adolescenti a Milano, spettacoli per la prima infanzia a Milano, attivit\u00e0 per neo-mamme a Milano, tempo libero di qualit\u00e0 genitori e figli a Milano, esperienze guidate da esperti per bambini a Milano, ambiente sicuro per il gioco infantile a Milano, sostegno alla genitorialit\u00e0 a Milano, incontri con psicologi per genitori a Milano, laboratori genitore-bambino a Milano, gruppi aiuto neomamme a Milano, supporto genitori figli neurodivergenti a Milano, prevenzione burn-out genitoriale a Milano, consapevolezza educativa a Milano, corsi per genitori consapevoli a Milano, rete di supporto comunitario per famiglie a Milano, educatori qualificati dell&#039;infanzia a Milano, benessere emotivo infantile a Milano.  Centro educativo a San Siro, impresa sociale per famiglie a San Siro, centro polifunzionale per bambini a San Siro, benessere psicologico infanzia a San Siro, promozione benessere sociale famiglie a San Siro, comunit\u00e0 attiva e solidale a San Siro, attivit\u00e0 inclusive per bambini a San Siro, centro per la famiglia a San Siro, spazio accogliente per genitori e figli a San Siro, corsi per bambini a San Siro, psicomotricit\u00e0 educativa a San Siro, corsi movimento e gioco bambini a San Siro, neurosviluppo infantile attraverso il gioco a San Siro, attivit\u00e0 fascia 12-36 mesi a San Siro, corsi capoeira per bambini a San Siro, danzaterapia per l&#039;infanzia a San Siro, consapevolezza corporea per piccoli a San Siro, laboratori creativi weekend a San Siro, laboratori ceramica per bambini a San Siro, stanze sensoriali immersive a San Siro, percorsi esperienziali per l&#039;infanzia a San Siro, attivit\u00e0 artistiche a San Siro, riciclo creativo a San Siro, eventi per famiglie a San Siro, cinema per neonati a San Siro, pigiama party per adolescenti a San Siro, spettacoli per la prima infanzia a San Siro, attivit\u00e0 per neo-mamme a San Siro, tempo libero di qualit\u00e0 genitori e figli a San Siro, esperienze guidate da esperti per bambini a San Siro, ambiente sicuro per il gioco infantile a San Siro, sostegno alla genitorialit\u00e0 a San Siro, incontri con psicologi per genitori a San Siro, laboratori genitore-bambino a San Siro, gruppi aiuto neomamme a San Siro, supporto genitori figli neurodivergenti a San Siro, prevenzione burn-out genitoriale a San Siro, consapevolezza educativa a San Siro, corsi per genitori consapevoli a San Siro, rete di supporto comunitario per famiglie a San Siro, educatori qualificati dell&#039;infanzia a San Siro, benessere emotivo infantile a San Siro.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/spazio-positivo-centro-educativo-e-di-benessere-per-bambini-e-famiglie\/\" \/>\n<meta property=\"og:site_name\" content=\"Cral Policlinico di Milano\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-05T08:50:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2026\/03\/logo_Spazio-Positivo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"15 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/spazio-positivo-centro-educativo-e-di-benessere-per-bambini-e-famiglie\/\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/spazio-positivo-centro-educativo-e-di-benessere-per-bambini-e-famiglie\/\",\"name\":\"Spazio Positivo \u2013 Centro Educativo e di Benessere per Bambini e Famiglie - Cral Policlinico di Milano\",\"isPartOf\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/spazio-positivo-centro-educativo-e-di-benessere-per-bambini-e-famiglie\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/spazio-positivo-centro-educativo-e-di-benessere-per-bambini-e-famiglie\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2026\/03\/logo_Spazio-Positivo.jpg\",\"datePublished\":\"2026-03-04T13:55:28+00:00\",\"dateModified\":\"2026-03-05T08:50:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/spazio-positivo-centro-educativo-e-di-benessere-per-bambini-e-famiglie\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/spazio-positivo-centro-educativo-e-di-benessere-per-bambini-e-famiglie\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/spazio-positivo-centro-educativo-e-di-benessere-per-bambini-e-famiglie\/#primaryimage\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2026\/03\/logo_Spazio-Positivo.jpg\",\"contentUrl\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2026\/03\/logo_Spazio-Positivo.jpg\",\"width\":300,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/spazio-positivo-centro-educativo-e-di-benessere-per-bambini-e-famiglie\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/negozio\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Spazio Positivo \u2013 Centro Educativo e di Benessere per Bambini e Famiglie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/#website\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/\",\"name\":\"Cral Policlinico di Milano\",\"description\":\"Area Convenzioni\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Spazio Positivo \u2013 Centro Educativo e di Benessere per Bambini e Famiglie - Cral Policlinico di Milano","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/spazio-positivo-centro-educativo-e-di-benessere-per-bambini-e-famiglie\/","og_locale":"it_IT","og_type":"article","og_title":"Spazio Positivo \u2013 Centro Educativo e di Benessere per Bambini e Famiglie - Cral Policlinico di Milano","og_description":"Gent.mi, Con la presente invio il testo per la Landing Page relativa al nostro Centro \"Spazio Positivo\" per la newsletter. Allego immagini da inserire (in caso di minori abbiamo liberatorie e possono essere tutte pubblicate se legate a noi). Per qualsiasi dubbio contattatemi pure.  \u2b50 Spazio Positivo \u2013 Centro Educativo e di Benessere per Bambini e Famiglie a Milano (San Siro)  Indirizzo: Via Gianicolo 20, Milano - Citofono 99 Email: info@spaziopositivoimpresasociale.it Telefono: 351 442 1288 Sito web: https:\/\/www.spaziopositivoimpresasociale.it\/  Spazio Positivo \u00e8 un centro polifunzionale per bambini e famiglie situato nel cuore del quartiere San Siro a Milano. \u00c8 un\u2019Impresa Sociale senza scopo di lucro nata per promuovere benessere psicologico, educativo e sociale, offrendo attivit\u00e0 e servizi pensati per sostenere la genitorialit\u00e0 e creare opportunit\u00e0 inclusive per il territorio.  La missione \u00e8 semplice e potente: creare un luogo accogliente dove bambini e genitori possano crescere, trovare sostegno e sentirsi parte di una comunit\u00e0 attiva e solidale.  ? Attivit\u00e0 e Corsi per Bambini e Famiglie  1. Psicomotricit\u00e0, Movimento e Gioco  Gruppi di psicomotricit\u00e0 educatica progettati per sostenere lo sviluppo del bambino sul piano emotivo, relazionale, motorio e cognitivo. Le proposte si basano su:  - apprendimento non formale - life skills riconosciute dalla pedagogia contemporanea - gioco e movimento come basi fondamentali per il neurosviluppo  I corsi sono rivolti anche ai bambini nella fascia 12-36 mesi  2. Capoeira, Danzaterapia e altre discipline Discipline artistiche e corporee che combinano:  movimento ritmo gioco consapevolezza corporea Corsi e cicli di incontri condotti da professionisti. Movimento, ritmo e gioco sono utilizzati come strumenti di crescita. \u200b 3. Laboratori Creativi del Weekend Ogni mese vengono organizzati laboratori tematici come:  attivit\u00e0 artistiche e riciclo creativo ceramica stanze sensoriali immersive percorsi esperienziali Materiali selezionati, personale esperto, formato e competente. Non i soliti lavoretti ma vere e proprie esperienze pianificate, studiate e guidate da esperti.  4. Eventi per Famiglie Per condividere momenti di qualit\u00e0 e sostenere la genitorialit\u00e0 (con particolare attenzione per le neo-mamme)  - pigiama party per adolescenti e bambini grandi - cinemino dei neonati - spettacoli per famiglie in piccoli gruppi, rivolti anche e soprattutto ai pi\u00f9 piccoli - attivit\u00e0 speciali a tema  Lo scopo non \u00e8 quello di fare intrattenimento ma di creare momenti condivisi che ci portino ad uscire dalle mura di casa, in un ambiente sicuro e decicato a genitori e figli, nel quale i bambini possono essere bambini.  5. Sostegno alla Genitorialit\u00e0 Un pilastro fondamentale del progetto. Spazio Positivo offre:  - incontri tematici con psicologi, educatori e professionisti - laboratori genitore\u2013bambino - gruppi di auto-sostegno tra neomamme e genitori con figli neurodivergenti  L'obiettivo \u00e8 aiutare i genitori a riconoscere risorse, costruire consapevolezza, prevenire stress e burn-out, favorire il supporto comunitario.  ? La Struttura  Ci troviamo in via Gianicolo 20, Milano, all\u2019interno del quartiere San Siro. Gli ambienti sono progettati per accogliere bambini e adulti in modo sicuro e accogliente.  La nostra sala d'attesa permette ai genitori di rimanere nella struttura durante i corsi dedicati ai bambini e condividere il proprio tempo con altri caregivers. Siamo dotati di spogliatoi con bagno per bambini e fasciatoio. Il centro \u00e8 totalmente accessibile anche in carrozzina (in quel caso \u00e8 per\u00f2 necessario avvisare ed entrare dal passo carraio).  Lo spazio \u00e8 condiviso in sinergia con ASD Capoeira Milano ETS, con cui viene portata avanti una visione di comunit\u00e0 aperta e inclusiva.  ? La Filosofia di Spazio Positivo Spazio Positivo non \u00e8 solo un centro per bambini: \u00e8 un luogo che mette al centro relazioni, crescita, comunit\u00e0 e benessere emotivo.  I valori guida sono:  Inclusione: ogni famiglia \u00e8 la benvenuta Benessere psicologico: sostegno al delicato equilibrio emotivo di bambini e genitori Comunit\u00e0: creare reti di supporto reciproco Gioco come linguaggio dell\u2019infanzia  ? Perch\u00e9 Scegliere Spazio Positivo approccio integrato educativo\u2013motorio\u2013relazionale professionisti qualificati dell\u2019infanzia e del movimento attivit\u00e0 adatte a diverse fasce d\u2019et\u00e0 gruppi divisi per fasce di et\u00e0 ristrette ambiente sicuro e familiare focus su genitorialit\u00e0 consapevole e inclusiva materiali e setting selezionati per le necessit\u00e0 dei bambini incontri, corsi, percorsi anche per la fascia 0-3 anni  Centri educativi, imprese sociali per famiglie, centri polifunzionali per bambini, centri per le famiglie, spazi accoglienti per genitori e figli,  Centro educativo, impresa sociale per famiglie, centro polifunzionale per bambini, benessere psicologico infanzia, promozione benessere sociale famiglie, comunit\u00e0 attiva e solidale, attivit\u00e0 inclusive per bambini, centro per la famiglia, spazio accogliente per genitori e figli, corsi per bambini, psicomotricit\u00e0 educativa, corsi movimento e gioco bambini, neurosviluppo infantile attraverso il gioco, attivit\u00e0 fascia 12-36 mesi, corsi capoeira per bambini, danzaterapia per l'infanzia, consapevolezza corporea per piccoli, laboratori creativi weekend, laboratori ceramica per bambini, stanze sensoriali immersive, percorsi esperienziali per l'infanzia, attivit\u00e0 artistiche, riciclo creativo, eventi per famiglie, cinema per neonati, pigiama party per adolescenti, spettacoli per la prima infanzia, attivit\u00e0 per neo-mamme, tempo libero di qualit\u00e0 genitori e figli, esperienze guidate da esperti per bambini, ambiente sicuro per il gioco infantile, sostegno alla genitorialit\u00e0, incontri con psicologi per genitori, laboratori genitore-bambino, gruppi aiuto neomamme, supporto genitori figli neurodivergenti, prevenzione burn-out genitoriale, consapevolezza educativa, corsi per genitori consapevoli, rete di supporto comunitario per famiglie, educatori qualificati dell'infanzia, benessere emotivo infantile,  Centri educativi a Milano, imprese sociali per famiglie a Milano, centri polifunzionali per bambini a Milano, centri per le famiglie a Milano, spazi accoglienti per genitori e figli a Milano, centro educativo a Milano, impresa sociale per famiglie a Milano, centro polifunzionale per bambini a Milano, benessere psicologico infanzia a Milano, promozione benessere sociale famiglie a Milano, comunit\u00e0 attiva e solidale a Milano, attivit\u00e0 inclusive per bambini a Milano, centro per la famiglia a Milano, spazio accogliente per genitori e figli a Milano, corsi per bambini a Milano, psicomotricit\u00e0 educativa a Milano, corsi movimento e gioco bambini a Milano, neurosviluppo infantile attraverso il gioco a Milano, attivit\u00e0 fascia 12-36 mesi a Milano, corsi capoeira per bambini a Milano, danzaterapia per l'infanzia a Milano, consapevolezza corporea per piccoli a Milano, laboratori creativi weekend a Milano, laboratori ceramica per bambini a Milano, stanze sensoriali immersive a Milano, percorsi esperienziali per l'infanzia a Milano, attivit\u00e0 artistiche a Milano, riciclo creativo a Milano, eventi per famiglie a Milano, cinema per neonati a Milano, pigiama party per adolescenti a Milano, spettacoli per la prima infanzia a Milano, attivit\u00e0 per neo-mamme a Milano, tempo libero di qualit\u00e0 genitori e figli a Milano, esperienze guidate da esperti per bambini a Milano, ambiente sicuro per il gioco infantile a Milano, sostegno alla genitorialit\u00e0 a Milano, incontri con psicologi per genitori a Milano, laboratori genitore-bambino a Milano, gruppi aiuto neomamme a Milano, supporto genitori figli neurodivergenti a Milano, prevenzione burn-out genitoriale a Milano, consapevolezza educativa a Milano, corsi per genitori consapevoli a Milano, rete di supporto comunitario per famiglie a Milano, educatori qualificati dell'infanzia a Milano, benessere emotivo infantile a Milano.  Centro educativo a San Siro, impresa sociale per famiglie a San Siro, centro polifunzionale per bambini a San Siro, benessere psicologico infanzia a San Siro, promozione benessere sociale famiglie a San Siro, comunit\u00e0 attiva e solidale a San Siro, attivit\u00e0 inclusive per bambini a San Siro, centro per la famiglia a San Siro, spazio accogliente per genitori e figli a San Siro, corsi per bambini a San Siro, psicomotricit\u00e0 educativa a San Siro, corsi movimento e gioco bambini a San Siro, neurosviluppo infantile attraverso il gioco a San Siro, attivit\u00e0 fascia 12-36 mesi a San Siro, corsi capoeira per bambini a San Siro, danzaterapia per l'infanzia a San Siro, consapevolezza corporea per piccoli a San Siro, laboratori creativi weekend a San Siro, laboratori ceramica per bambini a San Siro, stanze sensoriali immersive a San Siro, percorsi esperienziali per l'infanzia a San Siro, attivit\u00e0 artistiche a San Siro, riciclo creativo a San Siro, eventi per famiglie a San Siro, cinema per neonati a San Siro, pigiama party per adolescenti a San Siro, spettacoli per la prima infanzia a San Siro, attivit\u00e0 per neo-mamme a San Siro, tempo libero di qualit\u00e0 genitori e figli a San Siro, esperienze guidate da esperti per bambini a San Siro, ambiente sicuro per il gioco infantile a San Siro, sostegno alla genitorialit\u00e0 a San Siro, incontri con psicologi per genitori a San Siro, laboratori genitore-bambino a San Siro, gruppi aiuto neomamme a San Siro, supporto genitori figli neurodivergenti a San Siro, prevenzione burn-out genitoriale a San Siro, consapevolezza educativa a San Siro, corsi per genitori consapevoli a San Siro, rete di supporto comunitario per famiglie a San Siro, educatori qualificati dell'infanzia a San Siro, benessere emotivo infantile a San Siro.","og_url":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/spazio-positivo-centro-educativo-e-di-benessere-per-bambini-e-famiglie\/","og_site_name":"Cral Policlinico di Milano","article_modified_time":"2026-03-05T08:50:18+00:00","og_image":[{"width":300,"height":300,"url":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2026\/03\/logo_Spazio-Positivo.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"15 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/spazio-positivo-centro-educativo-e-di-benessere-per-bambini-e-famiglie\/","url":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/spazio-positivo-centro-educativo-e-di-benessere-per-bambini-e-famiglie\/","name":"Spazio Positivo \u2013 Centro Educativo e di Benessere per Bambini e Famiglie - Cral Policlinico di Milano","isPartOf":{"@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/#website"},"primaryImageOfPage":{"@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/spazio-positivo-centro-educativo-e-di-benessere-per-bambini-e-famiglie\/#primaryimage"},"image":{"@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/spazio-positivo-centro-educativo-e-di-benessere-per-bambini-e-famiglie\/#primaryimage"},"thumbnailUrl":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2026\/03\/logo_Spazio-Positivo.jpg","datePublished":"2026-03-04T13:55:28+00:00","dateModified":"2026-03-05T08:50:18+00:00","breadcrumb":{"@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/spazio-positivo-centro-educativo-e-di-benessere-per-bambini-e-famiglie\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/spazio-positivo-centro-educativo-e-di-benessere-per-bambini-e-famiglie\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/spazio-positivo-centro-educativo-e-di-benessere-per-bambini-e-famiglie\/#primaryimage","url":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2026\/03\/logo_Spazio-Positivo.jpg","contentUrl":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2026\/03\/logo_Spazio-Positivo.jpg","width":300,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/spazio-positivo-centro-educativo-e-di-benessere-per-bambini-e-famiglie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/negozio\/"},{"@type":"ListItem","position":3,"name":"Spazio Positivo \u2013 Centro Educativo e di Benessere per Bambini e Famiglie"}]},{"@type":"WebSite","@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/#website","url":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/","name":"Cral Policlinico di Milano","description":"Area Convenzioni","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/product\/29328","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/comments?post=29328"}],"version-history":[{"count":32,"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/product\/29328\/revisions"}],"predecessor-version":[{"id":29375,"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/product\/29328\/revisions\/29375"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/media\/29329"}],"wp:attachment":[{"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/media?parent=29328"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/product_brand?post=29328"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/product_cat?post=29328"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/product_tag?post=29328"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}