{"id":22507,"date":"2025-09-10T11:57:02","date_gmt":"2025-09-10T09:57:02","guid":{"rendered":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/?post_type=product&#038;p=22507"},"modified":"2025-09-26T09:57:34","modified_gmt":"2025-09-26T07:57:34","slug":"s-e-i-skin","status":"publish","type":"product","link":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/s-e-i-skin\/","title":{"rendered":"S.E.I. Skin"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"22507\" class=\"elementor elementor-22507\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c9845e9 e-con-full e-flex e-con e-parent\" data-id=\"c9845e9\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-3eacc87 e-con-full e-flex e-con e-child\" data-id=\"3eacc87\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-98ad4cd elementor-widget elementor-widget-spacer\" data-id=\"98ad4cd\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e652008 e-con-full e-flex e-con e-child\" data-id=\"e652008\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9f2fc3c elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"9f2fc3c\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" fetchpriority=\"high\" decoding=\"async\" width=\"1920\" height=\"580\" src=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/09\/SEI-Skinbc.png\" class=\"attachment-full size-full wp-image-22774\" alt=\"\" srcset=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/09\/SEI-Skinbc.png 1920w, https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/09\/SEI-Skinbc-1280x387.png 1280w, https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/09\/SEI-Skinbc-980x296.png 980w, https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/09\/SEI-Skinbc-480x145.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) and (max-width: 1280px) 1280px, (min-width: 1281px) 1920px, 100vw\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8a65de0 elementor-hidden-desktop e-flex e-con-boxed e-con e-parent\" data-id=\"8a65de0\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-9eb1dbc e-flex e-con-boxed e-con e-child\" data-id=\"9eb1dbc\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-91b6d90 elementor-widget elementor-widget-text-editor\" data-id=\"91b6d90\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Chi siamo<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-15d8f16 elementor-widget elementor-widget-text-editor\" data-id=\"15d8f16\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>S.E.I. SKIN nasce dalla visione di Sonia, una professionista del mondo dell\u2019estetica e del benessere, di unire la propria esperienza a quella delle figlie Eleonora, fashion designer, ed Irene, User Experience Designer, nel creare un\u2019<strong>esperienza unica ed irripetibile di skincare di lusso affiancata ad una consulenza personalizzata e altamente formata<\/strong>.<\/p><p><strong>Qualit\u00e0<\/strong>, <strong>innovazione<\/strong> e <strong>ricerca<\/strong> sono le chiavi motrici che portano alla rigorosa selezione dei Brand proposti, che vengono sempre <strong>testati a lungo<\/strong> nel nostro Istituto prima di essere proposti al grande pubblico. Solo quello che <strong>altamente effettivo<\/strong> entra a far parte della nostra selezione dei marchi.<\/p><p><span style=\"font-size: 14px;\">Ogni esperienza \u00e8 <\/span><strong style=\"font-size: 14px;\">personalizzata<\/strong><span style=\"font-size: 14px;\"> e <\/span><strong style=\"font-size: 14px;\">curata nel dettaglio<\/strong><span style=\"font-size: 14px;\"> per offrire una Beauty Routine di prodotti che portino risultati <\/span><strong style=\"font-size: 14px;\">reali<\/strong><span style=\"font-size: 14px;\"> e <\/span><strong style=\"font-size: 14px;\">tangibili<\/strong><span style=\"font-size: 14px;\">. Coccoliamo i nostri clienti, guidandoli con la corretta applicazione dei prodotti, beauty pills ad hoc, trucchi dell\u2019 esperta e richieste personalizzate.<\/span><\/p><p><strong>La consulenza personalizzata gratuita che offriamo \u00e8 un plus che doniamo ad ogni cliente per raggiungere i propri obbiettivi.<\/strong><\/p><p>Il profondo desiderio di Sonia di regalare ad ogni persona la <strong>beauty routine ideale<\/strong>, mettendo a frutto tutta la sua esperienza, porta alla creazione di S.E.I. Skin.<\/p><p>Anagramma delle iniziali delle fondatrici, S.E.I. SKIN \u00e8 un\u2019azienda nata dall\u2019<strong>amore della condivisione<\/strong>, dal credo nelle grandi capacit\u00e0 di ciascuna delle fondatrici, dove nella diversit\u00e0 dei tre cerchi d\u2019oro si crea una sinergia vincente.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-eb93435 elementor-widget__width-inherit elementor-widget elementor-widget-image\" data-id=\"eb93435\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1359\" height=\"904\" src=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/09\/sei.jpg\" class=\"attachment-full size-full wp-image-22775\" alt=\"\" srcset=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/09\/sei.jpg 1359w, https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/09\/sei-1280x851.jpg 1280w, https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/09\/sei-980x652.jpg 980w, https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/09\/sei-480x319.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) and (max-width: 1280px) 1280px, (min-width: 1281px) 1359px, 100vw\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b5abbfa elementor-hidden-tablet elementor-hidden-mobile e-flex e-con-boxed e-con e-parent\" data-id=\"b5abbfa\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-b497bed e-con-full e-flex e-con e-child\" data-id=\"b497bed\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6f531cd elementor-widget elementor-widget-text-editor\" data-id=\"6f531cd\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Chi siamo<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bc249ec elementor-widget elementor-widget-text-editor\" data-id=\"bc249ec\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>S.E.I. SKIN nasce dalla visione di Sonia, una professionista del mondo dell\u2019estetica e del benessere, di unire la propria esperienza a quella delle figlie Eleonora, fashion designer, ed Irene, User Experience Designer, nel creare un\u2019<strong>esperienza unica ed irripetibile di skincare di lusso affiancata ad una consulenza personalizzata e altamente formata<\/strong>.<\/p><p><strong>Qualit\u00e0<\/strong>, <strong>innovazione<\/strong> e <strong>ricerca<\/strong> sono le chiavi motrici che portano alla rigorosa selezione dei Brand proposti, che vengono sempre <strong>testati a lungo<\/strong> nel nostro Istituto prima di essere proposti al grande pubblico. Solo quello che <strong>altamente effettivo<\/strong> entra a far parte della nostra selezione dei marchi.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-177f558 e-con-full e-flex e-con e-child\" data-id=\"177f558\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e386609 e-con-full e-flex e-con e-child\" data-id=\"e386609\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d646944 elementor-widget elementor-widget-text-editor\" data-id=\"d646944\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-size: 14px;\">Ogni esperienza \u00e8 <\/span><strong style=\"font-size: 14px;\">personalizzata<\/strong><span style=\"font-size: 14px;\"> e <\/span><strong style=\"font-size: 14px;\">curata nel dettaglio<\/strong><span style=\"font-size: 14px;\"> per offrire una Beauty Routine di prodotti che portino risultati <\/span><strong style=\"font-size: 14px;\">reali<\/strong><span style=\"font-size: 14px;\"> e <\/span><strong style=\"font-size: 14px;\">tangibili<\/strong><span style=\"font-size: 14px;\">. Coccoliamo i nostri clienti, guidandoli con la corretta applicazione dei prodotti, beauty pills ad hoc, trucchi dell\u2019 esperta e richieste personalizzate.<\/span><\/p><p><strong>La consulenza personalizzata gratuita che offriamo \u00e8 un plus che doniamo ad ogni cliente per raggiungere i propri obbiettivi.<\/strong><\/p><p>Il profondo desiderio di Sonia di regalare ad ogni persona la <strong>beauty routine ideale<\/strong>, mettendo a frutto tutta la sua esperienza, porta alla creazione di S.E.I. Skin.<\/p><p>Anagramma delle iniziali delle fondatrici, S.E.I. SKIN \u00e8 un\u2019azienda nata dall\u2019<strong>amore della condivisione<\/strong>, dal credo nelle grandi capacit\u00e0 di ciascuna delle fondatrici, dove nella diversit\u00e0 dei tre cerchi d\u2019oro si crea una sinergia vincente.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-99ba861 e-con-full elementor-hidden-desktop elementor-hidden-tablet e-flex e-con e-parent\" data-id=\"99ba861\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-9fb103d e-flex e-con-boxed e-con e-child\" data-id=\"9fb103d\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-55be08a elementor-widget elementor-widget-spacer\" data-id=\"55be08a\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3889545 e-flex e-con-boxed e-con e-child\" data-id=\"3889545\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-48178bc elementor-widget elementor-widget-text-editor\" data-id=\"48178bc\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Per gli associati<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b88e839 elementor-widget elementor-widget-text-editor\" data-id=\"b88e839\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Prenota ora una consulenza gratuita su SEISKIN: scopri qual \u00e8 la skincare perfetta per te e quali prodotti acquistare.<br \/>&#8211;<br \/>Usa il codice <strong>MAGIASKIN<\/strong> per un <strong>10% di sconto<\/strong> illimitato su ogni acquisto.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3d68379 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"3d68379\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/seiskin.com\/discount\/MAGIASKIN\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Clicca il bottone e inizia ora<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-42c08a4 e-con-full elementor-hidden-mobile e-flex e-con e-parent\" data-id=\"42c08a4\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-4e48c7e e-con-full e-flex e-con e-child\" data-id=\"4e48c7e\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d27b5bb elementor-widget elementor-widget-spacer\" data-id=\"d27b5bb\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a92d2e6 e-con-full e-flex e-con e-child\" data-id=\"a92d2e6\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4b0c546 elementor-widget elementor-widget-text-editor\" data-id=\"4b0c546\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Per gli associati<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cb90ad3 elementor-widget elementor-widget-text-editor\" data-id=\"cb90ad3\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Prenota ora una consulenza gratuita su SEISKIN: scopri qual \u00e8 la skincare perfetta per te e quali prodotti acquistare.<br \/>&#8211;<br \/>Usa il codice <strong>MAGIASKIN<\/strong> per un <strong>10% di sconto<\/strong> illimitato su ogni acquisto.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9dce8ff elementor-align-center elementor-widget elementor-widget-button\" data-id=\"9dce8ff\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/seiskin.com\/discount\/MAGIASKIN\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Clicca il bottone e inizia ora<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2eadf9e e-con-full elementor-hidden-mobile elementor-hidden-desktop elementor-hidden-tablet e-flex e-con e-parent\" data-id=\"2eadf9e\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-3709a78 e-con-full e-flex e-con e-child\" data-id=\"3709a78\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-da0fb38 elementor-widget elementor-widget-spacer\" data-id=\"da0fb38\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7812d52 e-con-full e-flex e-con e-child\" data-id=\"7812d52\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c5c1d4c elementor-widget elementor-widget-text-editor\" data-id=\"c5c1d4c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Per gli associati<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b6f2fe1 elementor-widget elementor-widget-text-editor\" data-id=\"b6f2fe1\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Usa il codice <strong>MAGIASKIN<\/strong> per un <strong>10% di sconto<\/strong> illimitato su ogni acquisto<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b1eb558 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"b1eb558\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/seiskin.com\/discount\/MAGIASKIN\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Clicca il bottone e inizia ora<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-cbe9932 elementor-hidden-desktop e-flex e-con-boxed e-con e-parent\" data-id=\"cbe9932\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-0c94065 e-con-full e-flex e-con e-child\" data-id=\"0c94065\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-c6351c0 e-con-full e-flex e-con e-child\" data-id=\"c6351c0\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-299d425 elementor-widget elementor-widget-spacer\" data-id=\"299d425\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-364182a e-con-full e-flex e-con e-child\" data-id=\"364182a\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c5b395b elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"c5b395b\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1920\" height=\"550\" src=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/09\/SEI-Skin-nor.png\" class=\"attachment-full size-full wp-image-22795\" alt=\"\" srcset=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/09\/SEI-Skin-nor.png 1920w, https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/09\/SEI-Skin-nor-1280x367.png 1280w, https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/09\/SEI-Skin-nor-980x281.png 980w, https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/09\/SEI-Skin-nor-480x138.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) and (max-width: 1280px) 1280px, (min-width: 1281px) 1920px, 100vw\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9d3e88d elementor-widget elementor-widget-text-editor\" data-id=\"9d3e88d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Contattaci ora<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1081de9 elementor-widget elementor-widget-text-editor\" data-id=\"1081de9\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #151515;\">Per maggiori info chiamaci al<\/span><br \/><span style=\"color: #151515;\"><a style=\"color: #151515;\" href=\"tel:+393289518292\"><strong>3289518292<\/strong><\/a><\/span><\/p><p><span style=\"color: #151515;\">Oppure scrivici una mail<\/span><br \/><span style=\"color: #151515;\"><a style=\"color: #151515;\" href=\"mailto:info@seiskin.com\"><strong>info@seiskin.com<\/strong><\/a><\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-232a875 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"232a875\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6c9bacb elementor-widget elementor-widget-text-editor\" data-id=\"6c9bacb\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Entra nel nostro mondo, visita il sito<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3bfecae elementor-widget elementor-widget-text-editor\" data-id=\"3bfecae\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #151515;\"><a style=\"color: #151515;\" href=\"https:\/\/seiskin.com\/\">www.seiskin.com<\/a><\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9740553 elementor-hidden-tablet elementor-hidden-mobile e-flex e-con-boxed e-con e-parent\" data-id=\"9740553\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-e72db1e e-con-full e-flex e-con e-child\" data-id=\"e72db1e\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-48eafa7 e-con-full e-flex e-con e-child\" data-id=\"48eafa7\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c00634d elementor-widget elementor-widget-spacer\" data-id=\"c00634d\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a4fd785 e-con-full e-flex e-con e-child\" data-id=\"a4fd785\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-eed3ff1 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"eed3ff1\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1920\" height=\"550\" src=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/09\/SEI-Skin-nor.png\" class=\"attachment-full size-full wp-image-22795\" alt=\"\" srcset=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/09\/SEI-Skin-nor.png 1920w, https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/09\/SEI-Skin-nor-1280x367.png 1280w, https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/09\/SEI-Skin-nor-980x281.png 980w, https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/09\/SEI-Skin-nor-480x138.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) and (max-width: 1280px) 1280px, (min-width: 1281px) 1920px, 100vw\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2208f6d elementor-widget elementor-widget-text-editor\" data-id=\"2208f6d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Contattaci ora<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ef96cc4 elementor-widget elementor-widget-text-editor\" data-id=\"ef96cc4\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #151515;\">Per maggiori info chiamaci al<\/span><br \/><span style=\"color: #151515;\"><a style=\"color: #151515;\" href=\"tel:+393289518292\"><strong>3289518292<\/strong><\/a><\/span><\/p><p><span style=\"color: #151515;\">Oppure scrivici una mail<\/span><br \/><span style=\"color: #151515;\"><a style=\"color: #151515;\" href=\"mailto:info@seiskin.com\"><strong>info@seiskin.com<\/strong><\/a><\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d0c02a3 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"d0c02a3\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dfab51c elementor-widget elementor-widget-text-editor\" data-id=\"dfab51c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tEntra nel nostro mondo, visita il sito\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-308f967 elementor-widget elementor-widget-text-editor\" data-id=\"308f967\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #151515;\"><a style=\"color: #151515;\" href=\"https:\/\/seiskin.com\/\">www.seiskin.com<\/a><\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-35280c17 elementor-section-content-middle elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"35280c17\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-281640f3\" data-id=\"281640f3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d9cf00f elementor-widget elementor-widget-text-editor\" data-id=\"d9cf00f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tContatti\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3a5304e2 elementor-shape-circle e-grid-align-left elementor-grid-0 elementor-widget elementor-widget-social-icons\" data-id=\"3a5304e2\" data-element_type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-facebook elementor-repeater-item-1539373\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Facebook<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-facebook\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M504 256C504 119 393 8 256 8S8 119 8 256c0 123.78 90.69 226.38 209.25 245V327.69h-63V256h63v-54.64c0-62.15 37-96.48 93.67-96.48 27.14 0 55.52 4.84 55.52 4.84v61h-31.28c-30.8 0-40.41 19.12-40.41 38.73V256h68.78l-11 71.69h-57.78V501C413.31 482.38 504 379.78 504 256z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-twitter elementor-repeater-item-8913cb9\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Twitter<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-twitter\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M459.37 151.716c.325 4.548.325 9.097.325 13.645 0 138.72-105.583 298.558-298.558 298.558-59.452 0-114.68-17.219-161.137-47.106 8.447.974 16.568 1.299 25.34 1.299 49.055 0 94.213-16.568 130.274-44.832-46.132-.975-84.792-31.188-98.112-72.772 6.498.974 12.995 1.624 19.818 1.624 9.421 0 18.843-1.3 27.614-3.573-48.081-9.747-84.143-51.98-84.143-102.985v-1.299c13.969 7.797 30.214 12.67 47.431 13.319-28.264-18.843-46.781-51.005-46.781-87.391 0-19.492 5.197-37.36 14.294-52.954 51.655 63.675 129.3 105.258 216.365 109.807-1.624-7.797-2.599-15.918-2.599-24.04 0-57.828 46.782-104.934 104.934-104.934 30.213 0 57.502 12.67 76.67 33.137 23.715-4.548 46.456-13.32 66.599-25.34-7.798 24.366-24.366 44.833-46.132 57.827 21.117-2.273 41.584-8.122 60.426-16.243-14.292 20.791-32.161 39.308-52.628 54.253z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-youtube elementor-repeater-item-3255c55\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Youtube<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-youtube\" viewBox=\"0 0 576 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M549.655 124.083c-6.281-23.65-24.787-42.276-48.284-48.597C458.781 64 288 64 288 64S117.22 64 74.629 75.486c-23.497 6.322-42.003 24.947-48.284 48.597-11.412 42.867-11.412 132.305-11.412 132.305s0 89.438 11.412 132.305c6.281 23.65 24.787 41.5 48.284 47.821C117.22 448 288 448 288 448s170.78 0 213.371-11.486c23.497-6.321 42.003-24.171 48.284-47.821 11.412-42.867 11.412-132.305 11.412-132.305s0-89.438-11.412-132.305zm-317.51 213.508V175.185l142.739 81.205-142.739 81.201z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6bf9a244\" data-id=\"6bf9a244\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-50cc269b elementor-widget elementor-widget-text-editor\" data-id=\"50cc269b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div id=\"gmw-single-location-wrapper-379\" class=\"gmw-element-wrapper gmw-single-location-wrapper gmw-sl-wrapper gmw-sl-single-post-wrapper post \" object_type=\"post\" object_id=\"22507\"  style=\"width:100%\"><div class=\"gmw-sl-map-wrapper gmw-sl-element\"><div id=\"gmw-map-wrapper-379\" class=\"gmw-map-wrapper  sl single_location \" style=\"width:100%;height:300px;\"> <span id=\"gmw-resize-map-toggle-379\" class=\"gmw-resize-map-toggle gmw-icon-resize-full\" style=\"display:none;\" title=\"Resize map\"><\/span> <div id=\"gmw-map-loader-379\" class=\"gmw-map-loader\"><\/div> <div id=\"gmw-map-379\" class=\"gmw-map sl single_location\" style=\"width:100%; height:100%\" data-map_id=\"379\" data-prefix=\"sl\" data-map_type=\"single_location\" data-icons_usage=\"global\"><\/div> <\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6f7bc900 elementor-widget elementor-widget-text-editor\" data-id=\"6f7bc900\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><div id=\"gmw-single-object-locations-wrapper-504\" class=\"gmw-element-wrapper gmw-single-location-wrapper gmw-sl-wrapper gmw-sl-single-post-wrapper post gmw-sl-multiple-locations\" object_type=\"post\" object_id=\"\"  style=\"width:100%\"><div class=\"gmw-sl-map-wrapper\"><div id=\"gmw-map-wrapper-504\" class=\"gmw-map-wrapper  sl single_location \" style=\"width:100%;height:350px;\"> <span id=\"gmw-resize-map-toggle-504\" class=\"gmw-resize-map-toggle gmw-icon-resize-full\" style=\"display:none;\" title=\"Resize map\"><\/span> <div id=\"gmw-map-loader-504\" class=\"gmw-map-loader\"><\/div> <div id=\"gmw-map-504\" class=\"gmw-map sl single_location\" style=\"width:100%; height:100%\" data-map_id=\"504\" data-prefix=\"sl\" data-map_type=\"single_location\" data-icons_usage=\"global\"><\/div> <\/div><\/div><\/div><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<div style=\"display: none;\">\n<p>S.E.I. SKIN nasce dalla visione di Sonia, una professionista del mondo dell\u2019estetica e del benessere, di unire la propria esperienza a quella delle figlie Eleonora, fashion designer, ed Irene, User Experience Designer, nel creare un\u2019esperienza unica ed irripetibile di skincare di lusso affiancata ad una consulenza personalizzata e altamente formata.<br \/>\nQualit\u00e0, innovazione e ricerca sono le chiavi motrici che portano alla rigorosa selezione dei Brand proposti, che vengono sempre testati a lungo nel nostro Istituto prima di essere proposti al grande pubblico. Solo quello che altamente effettivo entra a far parte della nostra selezione dei marchi.<br \/>\nOgni esperienza \u00e8 personalizzata e curata nel dettaglio per offrire una Beauty Routine di prodotti che portino risultati reali e tangibili. Coccoliamo i nostri clienti, guidandoli con la corretta applicazione dei prodotti, beauty pills ad hoc, trucchi dell\u2019 esperta e richieste personalizzate. La consulenza personalizzata gratuita che offriamo \u00e8 un plus che doniamo ad ogni cliente per raggiungere i propri obbiettivi.+ Il profondo desiderio di Sonia di regalare ad ogni persona la beauty routine ideale, mettendo a frutto tutta la sua esperienza, porta alla creazione di S.E.I. Skin.<br \/>\nAnagramma delle iniziali delle fondatrici, S.E.I. SKIN \u00e8 un\u2019azienda nata dall\u2019amore della condivisione, dal credo nelle grandi capacit\u00e0 di ciascuna delle fondatrici, dove nella diversit\u00e0 dei tre cerchi d\u2019oro si crea una sinergia vincente.<\/p>\n<p>estetica e benessere, skincare, cura della pelle, cura del viso, consulenza della pelle, Beauty Routine, skincare Routine, prodotti per skincare, prodotti estetici, creme per viso, creme per la pelle del viso, prodotti per il viso, prodotti per la pelle del viso, creme per il corpo, creme per la pelle del corpo, prodotti per il corpo, prodotti per la pelle del corpo, Creme antiaging, Creme stimolanti, Creme nutrienti, prodotti per i Capelli, cura dei Capelli,<\/p>\n<p>vendita di prodotti per skincare, vendita di prodotti estetici, vendita di creme per il viso, vendita di creme per la pelle del viso, vendita di prodotti per il viso, vendita di prodotti per la pelle del viso, vendita di creme per il corpo, vendita di creme per la pelle del corpo, vendita di prodotti per il corpo, vendita di prodotti per la pelle del corpo, vendita di Creme antiaging, vendita di Creme stimolanti, vendita di Creme nutrienti, vendita di prodotti per i Capelli,<\/p>\n<p>vendita online di prodotti per skincare, vendita online di prodotti estetici, vendita online di creme per il viso, vendita online di creme per la pelle del viso, vendita online di prodotti per il viso, vendita online di prodotti per la pelle del viso, vendita online di creme per il corpo, vendita online di creme per la pelle del corpo, vendita online di prodotti per il corpo, vendita online di prodotti per la pelle del corpo, vendita online di Creme antiaging, vendita online di Creme stimolanti, vendita online di Creme nutrienti, vendita online di prodotti per i Capelli,<\/p>\n<p>negozio online di prodotti per skincare, negozio online di prodotti estetici, negozio online di creme per il viso, negozio online di creme per la pelle del viso, negozio online di prodotti per il viso, negozio online di prodotti per la pelle del viso, negozio online di creme per il corpo, negozio online di creme per la pelle del corpo, negozio online di prodotti per il corpo, negozio online di prodotti per la pelle del corpo, negozio online di Creme antiaging, negozio online di Creme stimolanti, negozio online di Creme nutrienti, negozio online di prodotti per i Capelli,<\/p>\n<p>shop online di prodotti per skincare, shop online di prodotti estetici, shop online di creme per il viso, shop online di creme per la pelle del viso, shop online di prodotti per il viso, shop online di prodotti per la pelle del viso, shop online di creme per il corpo, shop online di creme per la pelle del corpo, shop online di prodotti per il corpo, shop online di prodotti per la pelle del corpo, shop online di Creme antiaging, shop online di Creme stimolanti, shop online di Creme nutrienti, shop online di prodotti per i Capelli,<\/p>\n<\/div>\n","protected":false},"featured_media":22508,"comment_status":"open","ping_status":"closed","template":"elementor_header_footer","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":""},"product_brand":[],"product_cat":[58,20,49,518,263,28],"product_tag":[4688,4687,4698,4700,4695,4696,4693,4692,4699,2916,600,4099,4686,4691,850,598,849,4697,4694,4690,4711,4713,4707,4703,4708,4704,4712,4702,4714,4709,4705,4710,4706,4701,1343,4689],"class_list":{"0":"post-22507","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-benessere","7":"product_cat-benessere-e-bellezza","8":"product_cat-cosmetici","9":"product_cat-cosmetici-shopping","10":"product_cat-shop-online","11":"product_cat-shopping","12":"product_tag-beauty-routine","13":"product_tag-consulenza-della-pelle","14":"product_tag-creme-antiaging","15":"product_tag-creme-nutrienti","16":"product_tag-creme-per-il-corpo","17":"product_tag-creme-per-la-pelle-del-corpo","18":"product_tag-creme-per-la-pelle-del-viso","19":"product_tag-creme-per-viso","20":"product_tag-creme-stimolanti","21":"product_tag-cura-dei-capelli","22":"product_tag-cura-del-viso","23":"product_tag-cura-della-pelle","24":"product_tag-estetica-e-benessere","25":"product_tag-prodotti-estetici","26":"product_tag-prodotti-per-i-capelli","27":"product_tag-prodotti-per-il-corpo","28":"product_tag-prodotti-per-il-viso","29":"product_tag-prodotti-per-la-pelle-del-corpo","30":"product_tag-prodotti-per-la-pelle-del-viso","31":"product_tag-prodotti-per-skincare","32":"product_tag-shop-online-di-creme-antiaging","33":"product_tag-shop-online-di-creme-nutrienti","34":"product_tag-shop-online-di-creme-per-il-corpo","35":"product_tag-shop-online-di-creme-per-il-viso","36":"product_tag-shop-online-di-creme-per-la-pelle-del-corpo","37":"product_tag-shop-online-di-creme-per-la-pelle-del-viso","38":"product_tag-shop-online-di-creme-stimolanti","39":"product_tag-shop-online-di-prodotti-estetici","40":"product_tag-shop-online-di-prodotti-per-i-capelli","41":"product_tag-shop-online-di-prodotti-per-il-corpo","42":"product_tag-shop-online-di-prodotti-per-il-viso","43":"product_tag-shop-online-di-prodotti-per-la-pelle-del-corpo","44":"product_tag-shop-online-di-prodotti-per-la-pelle-del-viso","45":"product_tag-shop-online-di-prodotti-per-skincare","46":"product_tag-skincare","47":"product_tag-skincare-routine","49":"first","50":"instock","51":"shipping-taxable","52":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>S.E.I. Skin - Cral Policlinico di Milano<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/s-e-i-skin\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"S.E.I. Skin - Cral Policlinico di Milano\" \/>\n<meta property=\"og:description\" content=\"S.E.I. SKIN nasce dalla visione di Sonia, una professionista del mondo dell\u2019estetica e del benessere, di unire la propria esperienza a quella delle figlie Eleonora, fashion designer, ed Irene, User Experience Designer, nel creare un\u2019esperienza unica ed irripetibile di skincare di lusso affiancata ad una consulenza personalizzata e altamente formata. Qualit\u00e0, innovazione e ricerca sono le chiavi motrici che portano alla rigorosa selezione dei Brand proposti, che vengono sempre testati a lungo nel nostro Istituto prima di essere proposti al grande pubblico. Solo quello che altamente effettivo entra a far parte della nostra selezione dei marchi. Ogni esperienza \u00e8 personalizzata e curata nel dettaglio per offrire una Beauty Routine di prodotti che portino risultati reali e tangibili. Coccoliamo i nostri clienti, guidandoli con la corretta applicazione dei prodotti, beauty pills ad hoc, trucchi dell\u2019 esperta e richieste personalizzate. La consulenza personalizzata gratuita che offriamo \u00e8 un plus che doniamo ad ogni cliente per raggiungere i propri obbiettivi.+ Il profondo desiderio di Sonia di regalare ad ogni persona la beauty routine ideale, mettendo a frutto tutta la sua esperienza, porta alla creazione di S.E.I. Skin. Anagramma delle iniziali delle fondatrici, S.E.I. SKIN \u00e8 un\u2019azienda nata dall\u2019amore della condivisione, dal credo nelle grandi capacit\u00e0 di ciascuna delle fondatrici, dove nella diversit\u00e0 dei tre cerchi d\u2019oro si crea una sinergia vincente.  estetica e benessere, skincare, cura della pelle, cura del viso, consulenza della pelle, Beauty Routine, skincare Routine, prodotti per skincare, prodotti estetici, creme per viso, creme per la pelle del viso, prodotti per il viso, prodotti per la pelle del viso, creme per il corpo, creme per la pelle del corpo, prodotti per il corpo, prodotti per la pelle del corpo, Creme antiaging, Creme stimolanti, Creme nutrienti, prodotti per i Capelli, cura dei Capelli,  vendita di prodotti per skincare, vendita di prodotti estetici, vendita di creme per il viso, vendita di creme per la pelle del viso, vendita di prodotti per il viso, vendita di prodotti per la pelle del viso, vendita di creme per il corpo, vendita di creme per la pelle del corpo, vendita di prodotti per il corpo, vendita di prodotti per la pelle del corpo, vendita di Creme antiaging, vendita di Creme stimolanti, vendita di Creme nutrienti, vendita di prodotti per i Capelli,  vendita online di prodotti per skincare, vendita online di prodotti estetici, vendita online di creme per il viso, vendita online di creme per la pelle del viso, vendita online di prodotti per il viso, vendita online di prodotti per la pelle del viso, vendita online di creme per il corpo, vendita online di creme per la pelle del corpo, vendita online di prodotti per il corpo, vendita online di prodotti per la pelle del corpo, vendita online di Creme antiaging, vendita online di Creme stimolanti, vendita online di Creme nutrienti, vendita online di prodotti per i Capelli,  negozio online di prodotti per skincare, negozio online di prodotti estetici, negozio online di creme per il viso, negozio online di creme per la pelle del viso, negozio online di prodotti per il viso, negozio online di prodotti per la pelle del viso, negozio online di creme per il corpo, negozio online di creme per la pelle del corpo, negozio online di prodotti per il corpo, negozio online di prodotti per la pelle del corpo, negozio online di Creme antiaging, negozio online di Creme stimolanti, negozio online di Creme nutrienti, negozio online di prodotti per i Capelli,  shop online di prodotti per skincare, shop online di prodotti estetici, shop online di creme per il viso, shop online di creme per la pelle del viso, shop online di prodotti per il viso, shop online di prodotti per la pelle del viso, shop online di creme per il corpo, shop online di creme per la pelle del corpo, shop online di prodotti per il corpo, shop online di prodotti per la pelle del corpo, shop online di Creme antiaging, shop online di Creme stimolanti, shop online di Creme nutrienti, shop online di prodotti per i Capelli,\" \/>\n<meta property=\"og:url\" content=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/s-e-i-skin\/\" \/>\n<meta property=\"og:site_name\" content=\"Cral Policlinico di Milano\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-26T07:57:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/09\/Logo-siti-sei-skin-skincare.png\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/s-e-i-skin\/\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/s-e-i-skin\/\",\"name\":\"S.E.I. Skin - Cral Policlinico di Milano\",\"isPartOf\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/s-e-i-skin\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/s-e-i-skin\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/09\/Logo-siti-sei-skin-skincare.png\",\"datePublished\":\"2025-09-10T09:57:02+00:00\",\"dateModified\":\"2025-09-26T07:57:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/s-e-i-skin\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/s-e-i-skin\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/s-e-i-skin\/#primaryimage\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/09\/Logo-siti-sei-skin-skincare.png\",\"contentUrl\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/09\/Logo-siti-sei-skin-skincare.png\",\"width\":300,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/s-e-i-skin\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/negozio\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"S.E.I. Skin\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/#website\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/\",\"name\":\"Cral Policlinico di Milano\",\"description\":\"Area Convenzioni\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"S.E.I. Skin - Cral Policlinico di Milano","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/s-e-i-skin\/","og_locale":"it_IT","og_type":"article","og_title":"S.E.I. Skin - Cral Policlinico di Milano","og_description":"S.E.I. SKIN nasce dalla visione di Sonia, una professionista del mondo dell\u2019estetica e del benessere, di unire la propria esperienza a quella delle figlie Eleonora, fashion designer, ed Irene, User Experience Designer, nel creare un\u2019esperienza unica ed irripetibile di skincare di lusso affiancata ad una consulenza personalizzata e altamente formata. Qualit\u00e0, innovazione e ricerca sono le chiavi motrici che portano alla rigorosa selezione dei Brand proposti, che vengono sempre testati a lungo nel nostro Istituto prima di essere proposti al grande pubblico. Solo quello che altamente effettivo entra a far parte della nostra selezione dei marchi. Ogni esperienza \u00e8 personalizzata e curata nel dettaglio per offrire una Beauty Routine di prodotti che portino risultati reali e tangibili. Coccoliamo i nostri clienti, guidandoli con la corretta applicazione dei prodotti, beauty pills ad hoc, trucchi dell\u2019 esperta e richieste personalizzate. La consulenza personalizzata gratuita che offriamo \u00e8 un plus che doniamo ad ogni cliente per raggiungere i propri obbiettivi.+ Il profondo desiderio di Sonia di regalare ad ogni persona la beauty routine ideale, mettendo a frutto tutta la sua esperienza, porta alla creazione di S.E.I. Skin. Anagramma delle iniziali delle fondatrici, S.E.I. SKIN \u00e8 un\u2019azienda nata dall\u2019amore della condivisione, dal credo nelle grandi capacit\u00e0 di ciascuna delle fondatrici, dove nella diversit\u00e0 dei tre cerchi d\u2019oro si crea una sinergia vincente.  estetica e benessere, skincare, cura della pelle, cura del viso, consulenza della pelle, Beauty Routine, skincare Routine, prodotti per skincare, prodotti estetici, creme per viso, creme per la pelle del viso, prodotti per il viso, prodotti per la pelle del viso, creme per il corpo, creme per la pelle del corpo, prodotti per il corpo, prodotti per la pelle del corpo, Creme antiaging, Creme stimolanti, Creme nutrienti, prodotti per i Capelli, cura dei Capelli,  vendita di prodotti per skincare, vendita di prodotti estetici, vendita di creme per il viso, vendita di creme per la pelle del viso, vendita di prodotti per il viso, vendita di prodotti per la pelle del viso, vendita di creme per il corpo, vendita di creme per la pelle del corpo, vendita di prodotti per il corpo, vendita di prodotti per la pelle del corpo, vendita di Creme antiaging, vendita di Creme stimolanti, vendita di Creme nutrienti, vendita di prodotti per i Capelli,  vendita online di prodotti per skincare, vendita online di prodotti estetici, vendita online di creme per il viso, vendita online di creme per la pelle del viso, vendita online di prodotti per il viso, vendita online di prodotti per la pelle del viso, vendita online di creme per il corpo, vendita online di creme per la pelle del corpo, vendita online di prodotti per il corpo, vendita online di prodotti per la pelle del corpo, vendita online di Creme antiaging, vendita online di Creme stimolanti, vendita online di Creme nutrienti, vendita online di prodotti per i Capelli,  negozio online di prodotti per skincare, negozio online di prodotti estetici, negozio online di creme per il viso, negozio online di creme per la pelle del viso, negozio online di prodotti per il viso, negozio online di prodotti per la pelle del viso, negozio online di creme per il corpo, negozio online di creme per la pelle del corpo, negozio online di prodotti per il corpo, negozio online di prodotti per la pelle del corpo, negozio online di Creme antiaging, negozio online di Creme stimolanti, negozio online di Creme nutrienti, negozio online di prodotti per i Capelli,  shop online di prodotti per skincare, shop online di prodotti estetici, shop online di creme per il viso, shop online di creme per la pelle del viso, shop online di prodotti per il viso, shop online di prodotti per la pelle del viso, shop online di creme per il corpo, shop online di creme per la pelle del corpo, shop online di prodotti per il corpo, shop online di prodotti per la pelle del corpo, shop online di Creme antiaging, shop online di Creme stimolanti, shop online di Creme nutrienti, shop online di prodotti per i Capelli,","og_url":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/s-e-i-skin\/","og_site_name":"Cral Policlinico di Milano","article_modified_time":"2025-09-26T07:57:34+00:00","og_image":[{"width":300,"height":300,"url":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/09\/Logo-siti-sei-skin-skincare.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/s-e-i-skin\/","url":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/s-e-i-skin\/","name":"S.E.I. Skin - Cral Policlinico di Milano","isPartOf":{"@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/#website"},"primaryImageOfPage":{"@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/s-e-i-skin\/#primaryimage"},"image":{"@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/s-e-i-skin\/#primaryimage"},"thumbnailUrl":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/09\/Logo-siti-sei-skin-skincare.png","datePublished":"2025-09-10T09:57:02+00:00","dateModified":"2025-09-26T07:57:34+00:00","breadcrumb":{"@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/s-e-i-skin\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/s-e-i-skin\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/s-e-i-skin\/#primaryimage","url":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/09\/Logo-siti-sei-skin-skincare.png","contentUrl":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/09\/Logo-siti-sei-skin-skincare.png","width":300,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/s-e-i-skin\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/negozio\/"},{"@type":"ListItem","position":3,"name":"S.E.I. Skin"}]},{"@type":"WebSite","@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/#website","url":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/","name":"Cral Policlinico di Milano","description":"Area Convenzioni","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/product\/22507","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/comments?post=22507"}],"version-history":[{"count":66,"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/product\/22507\/revisions"}],"predecessor-version":[{"id":22892,"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/product\/22507\/revisions\/22892"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/media\/22508"}],"wp:attachment":[{"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/media?parent=22507"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/product_brand?post=22507"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/product_cat?post=22507"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/product_tag?post=22507"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}