{"id":21781,"date":"2025-07-21T12:27:13","date_gmt":"2025-07-21T10:27:13","guid":{"rendered":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/?post_type=product&#038;p=21781"},"modified":"2026-03-20T16:23:34","modified_gmt":"2026-03-20T15:23:34","slug":"lifetrend-group","status":"publish","type":"product","link":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/lifetrend-group\/","title":{"rendered":"LifeTrend Group"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"21781\" class=\"elementor elementor-21781\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7f4ebc8 e-flex e-con-boxed e-con e-parent\" data-id=\"7f4ebc8\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-94eaf61 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"94eaf61\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" fetchpriority=\"high\" decoding=\"async\" width=\"2000\" height=\"523\" src=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/07\/LifeTrend-logo-colore.png\" class=\"attachment-full size-full wp-image-25704\" alt=\"\" srcset=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/07\/LifeTrend-logo-colore.png 2000w, https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/07\/LifeTrend-logo-colore-1280x335.png 1280w, https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/07\/LifeTrend-logo-colore-980x256.png 980w, https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/07\/LifeTrend-logo-colore-480x126.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) and (max-width: 1280px) 1280px, (min-width: 1281px) 2000px, 100vw\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0216223 elementor-hidden-desktop e-flex e-con-boxed e-con e-parent\" data-id=\"0216223\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-d6802b6 e-flex e-con-boxed e-con e-child\" data-id=\"d6802b6\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3c1c9a4 elementor-widget elementor-widget-text-editor\" data-id=\"3c1c9a4\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #1ca474;\">Chi<\/span> siamo<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d232c15 elementor-widget elementor-widget-text-editor\" data-id=\"d232c15\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>LifeTrend Group nasce dall\u2019esperienza di un team di consulenti specializzati nel ramo vita. Il fondatore, Massimo Meldoli, dopo oltre vent\u2019anni nel settore assicurativo, ha scelto di dedicarsi alla consulenza e alla gestione del risparmio per clienti Retail e Corporate.<\/p><p>Ascolto, dialogo e relazione sono al centro di ogni percorso, con l\u2019obiettivo di costruire fiducia, proteggere ci\u00f2 che conta davvero e accompagnare i clienti nel raggiungimento dei loro progetti, coniugando redditivit\u00e0 e sicurezza del capitale.<\/p><p>Grazie alla collaborazione con Allianz Milano Moscova, Aladiah Broker ed Energon, LifeTrend Group offre soluzioni di elevata qualit\u00e0, chiare, efficaci e personalizzate, affermandosi come punto di riferimento per i propri clienti.<\/p><p>LT Financial Club \u00e8 l\u2019headquarter del Gruppo e il cuore della community: uno spazio esclusivo dedicato a eventi, talk e incontri con Opinion Leader, dove prendono forma esperienze che uniscono benessere, performance e visione, spaziando da Sport &amp; Wellness a Business, Food, Fashion e Art.<\/p><p>Professionalit\u00e0, Affidabilit\u00e0 e Trasparenza guidano da sempre il nostro operato.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-43feceb e-flex e-con-boxed e-con e-child\" data-id=\"43feceb\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;slideshow&quot;,&quot;background_slideshow_gallery&quot;:[{&quot;id&quot;:25705,&quot;url&quot;:&quot;https:\\\/\\\/convenzioni.cralnetwork.it\\\/cralmangiagalli\\\/wp-content\\\/uploads\\\/sites\\\/30\\\/2025\\\/07\\\/lt.jpg&quot;},{&quot;id&quot;:25703,&quot;url&quot;:&quot;https:\\\/\\\/convenzioni.cralnetwork.it\\\/cralmangiagalli\\\/wp-content\\\/uploads\\\/sites\\\/30\\\/2025\\\/07\\\/MG_5127-1-1-scaled.jpg&quot;},{&quot;id&quot;:25702,&quot;url&quot;:&quot;https:\\\/\\\/convenzioni.cralnetwork.it\\\/cralmangiagalli\\\/wp-content\\\/uploads\\\/sites\\\/30\\\/2025\\\/07\\\/MG_4958-1-1-scaled.jpg&quot;},{&quot;id&quot;:25701,&quot;url&quot;:&quot;https:\\\/\\\/convenzioni.cralnetwork.it\\\/cralmangiagalli\\\/wp-content\\\/uploads\\\/sites\\\/30\\\/2025\\\/07\\\/MG_4829-1-1-scaled.jpg&quot;},{&quot;id&quot;:25700,&quot;url&quot;:&quot;https:\\\/\\\/convenzioni.cralnetwork.it\\\/cralmangiagalli\\\/wp-content\\\/uploads\\\/sites\\\/30\\\/2025\\\/07\\\/lt2.jpg&quot;}],&quot;background_slideshow_slide_duration&quot;:2000,&quot;background_slideshow_transition_duration&quot;:200,&quot;background_slideshow_ken_burns&quot;:&quot;yes&quot;,&quot;background_slideshow_loop&quot;:&quot;yes&quot;,&quot;background_slideshow_slide_transition&quot;:&quot;fade&quot;,&quot;background_slideshow_ken_burns_zoom_direction&quot;:&quot;in&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0cf7be9 elementor-widget elementor-widget-spacer\" data-id=\"0cf7be9\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-97eda7a elementor-hidden-tablet elementor-hidden-mobile e-flex e-con-boxed e-con e-parent\" data-id=\"97eda7a\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-c2eecb1 e-con-full e-flex e-con e-child\" data-id=\"c2eecb1\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-904f2d8 elementor-widget elementor-widget-text-editor\" data-id=\"904f2d8\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #1ca474;\">Chi<\/span> siamo<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e366876 elementor-widget elementor-widget-text-editor\" data-id=\"e366876\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>LifeTrend Group nasce dall\u2019esperienza di un team di consulenti specializzati nel ramo vita. Il fondatore, Massimo Meldoli, dopo oltre vent\u2019anni nel settore assicurativo, ha scelto di dedicarsi alla consulenza e alla gestione del risparmio per clienti Retail e Corporate.<\/p><p>Ascolto, dialogo e relazione sono al centro di ogni percorso, con l\u2019obiettivo di costruire fiducia, proteggere ci\u00f2 che conta davvero e accompagnare i clienti nel raggiungimento dei loro progetti, coniugando redditivit\u00e0 e sicurezza del capitale.<\/p><p>Grazie alla collaborazione con Allianz Milano Moscova, Aladiah Broker ed Energon, LifeTrend Group offre soluzioni di elevata qualit\u00e0, chiare, efficaci e personalizzate, affermandosi come punto di riferimento per i propri clienti.<\/p><p>LT Financial Club \u00e8 l\u2019headquarter del Gruppo e il cuore della community: uno spazio esclusivo dedicato a eventi, talk e incontri con Opinion Leader, dove prendono forma esperienze che uniscono benessere, performance e visione, spaziando da Sport &amp; Wellness a Business, Food, Fashion e Art.<\/p><p>Professionalit\u00e0, Affidabilit\u00e0 e Trasparenza guidano da sempre il nostro operato.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-81d471e e-con-full e-flex e-con e-child\" data-id=\"81d471e\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;slideshow&quot;,&quot;background_slideshow_gallery&quot;:[{&quot;id&quot;:25705,&quot;url&quot;:&quot;https:\\\/\\\/convenzioni.cralnetwork.it\\\/cralmangiagalli\\\/wp-content\\\/uploads\\\/sites\\\/30\\\/2025\\\/07\\\/lt.jpg&quot;},{&quot;id&quot;:25703,&quot;url&quot;:&quot;https:\\\/\\\/convenzioni.cralnetwork.it\\\/cralmangiagalli\\\/wp-content\\\/uploads\\\/sites\\\/30\\\/2025\\\/07\\\/MG_5127-1-1-scaled.jpg&quot;},{&quot;id&quot;:25702,&quot;url&quot;:&quot;https:\\\/\\\/convenzioni.cralnetwork.it\\\/cralmangiagalli\\\/wp-content\\\/uploads\\\/sites\\\/30\\\/2025\\\/07\\\/MG_4958-1-1-scaled.jpg&quot;},{&quot;id&quot;:25701,&quot;url&quot;:&quot;https:\\\/\\\/convenzioni.cralnetwork.it\\\/cralmangiagalli\\\/wp-content\\\/uploads\\\/sites\\\/30\\\/2025\\\/07\\\/MG_4829-1-1-scaled.jpg&quot;},{&quot;id&quot;:25700,&quot;url&quot;:&quot;https:\\\/\\\/convenzioni.cralnetwork.it\\\/cralmangiagalli\\\/wp-content\\\/uploads\\\/sites\\\/30\\\/2025\\\/07\\\/lt2.jpg&quot;}],&quot;background_slideshow_slide_duration&quot;:2000,&quot;background_slideshow_transition_duration&quot;:200,&quot;background_slideshow_ken_burns&quot;:&quot;yes&quot;,&quot;background_slideshow_loop&quot;:&quot;yes&quot;,&quot;background_slideshow_slide_transition&quot;:&quot;fade&quot;,&quot;background_slideshow_ken_burns_zoom_direction&quot;:&quot;in&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7de61c3 elementor-widget elementor-widget-spacer\" data-id=\"7de61c3\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2176ce12 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2176ce12\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2ab6ac26\" data-id=\"2ab6ac26\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-32925d65 elementor-widget elementor-widget-text-editor\" data-id=\"32925d65\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Agevolazioni riservate agli associati<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-a148228 e-flex e-con-boxed e-con e-parent\" data-id=\"a148228\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-5b1419f e-con-full e-flex e-con e-child\" data-id=\"5b1419f\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-70035c5 elementor-widget elementor-widget-text-editor\" data-id=\"70035c5\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Contatti<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a72af51 elementor-widget elementor-widget-text-editor\" data-id=\"a72af51\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>LifeTrend Group<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-780f030 elementor-widget elementor-widget-text-editor\" data-id=\"780f030\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Via Mecenate 76,<br \/>20138 Milano<\/p><p><strong>Mail: <\/strong><a href=\"mailto:info@lifetrendgroup.it\">info@lifetrendgroup.it<\/a><br \/><strong>Cell: <\/strong>\u202d<a href=\"tel:+393336863989\">333 6863989\u202c<\/a><\/p><p><strong>Sito web: <\/strong><a href=\"https:\/\/lifetrendgroup.it\/\">lifetrendgroup.it<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-96ffe68 e-con-full e-flex e-con e-child\" data-id=\"96ffe68\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f099b74 elementor-widget elementor-widget-text-editor\" data-id=\"f099b74\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><div id=\"gmw-single-location-wrapper-360\" class=\"gmw-element-wrapper gmw-single-location-wrapper gmw-sl-wrapper gmw-sl-single-post-wrapper post \" object_type=\"post\" object_id=\"21781\"  style=\"width:100%\"><div class=\"gmw-sl-map-wrapper gmw-sl-element\"><div id=\"gmw-map-wrapper-360\" class=\"gmw-map-wrapper  sl single_location \" style=\"width:100%;height:300px;\"> <span id=\"gmw-resize-map-toggle-360\" class=\"gmw-resize-map-toggle gmw-icon-resize-full\" style=\"display:none;\" title=\"Resize map\"><\/span> <div id=\"gmw-map-loader-360\" class=\"gmw-map-loader\"><\/div> <div id=\"gmw-map-360\" class=\"gmw-map sl single_location\" style=\"width:100%; height:100%\" data-map_id=\"360\" data-prefix=\"sl\" data-map_type=\"single_location\" data-icons_usage=\"global\"><\/div> <\/div><\/div><\/div><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5a3e3428 elementor-section-content-middle elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5a3e3428\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2d0e1403\" data-id=\"2d0e1403\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1b178b1e elementor-widget elementor-widget-text-editor\" data-id=\"1b178b1e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tContatti\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3fa8812f elementor-shape-circle e-grid-align-left elementor-grid-0 elementor-widget elementor-widget-social-icons\" data-id=\"3fa8812f\" data-element_type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-facebook elementor-repeater-item-1539373\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Facebook<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-facebook\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M504 256C504 119 393 8 256 8S8 119 8 256c0 123.78 90.69 226.38 209.25 245V327.69h-63V256h63v-54.64c0-62.15 37-96.48 93.67-96.48 27.14 0 55.52 4.84 55.52 4.84v61h-31.28c-30.8 0-40.41 19.12-40.41 38.73V256h68.78l-11 71.69h-57.78V501C413.31 482.38 504 379.78 504 256z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-twitter elementor-repeater-item-8913cb9\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Twitter<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-twitter\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M459.37 151.716c.325 4.548.325 9.097.325 13.645 0 138.72-105.583 298.558-298.558 298.558-59.452 0-114.68-17.219-161.137-47.106 8.447.974 16.568 1.299 25.34 1.299 49.055 0 94.213-16.568 130.274-44.832-46.132-.975-84.792-31.188-98.112-72.772 6.498.974 12.995 1.624 19.818 1.624 9.421 0 18.843-1.3 27.614-3.573-48.081-9.747-84.143-51.98-84.143-102.985v-1.299c13.969 7.797 30.214 12.67 47.431 13.319-28.264-18.843-46.781-51.005-46.781-87.391 0-19.492 5.197-37.36 14.294-52.954 51.655 63.675 129.3 105.258 216.365 109.807-1.624-7.797-2.599-15.918-2.599-24.04 0-57.828 46.782-104.934 104.934-104.934 30.213 0 57.502 12.67 76.67 33.137 23.715-4.548 46.456-13.32 66.599-25.34-7.798 24.366-24.366 44.833-46.132 57.827 21.117-2.273 41.584-8.122 60.426-16.243-14.292 20.791-32.161 39.308-52.628 54.253z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-youtube elementor-repeater-item-3255c55\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Youtube<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-youtube\" viewBox=\"0 0 576 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M549.655 124.083c-6.281-23.65-24.787-42.276-48.284-48.597C458.781 64 288 64 288 64S117.22 64 74.629 75.486c-23.497 6.322-42.003 24.947-48.284 48.597-11.412 42.867-11.412 132.305-11.412 132.305s0 89.438 11.412 132.305c6.281 23.65 24.787 41.5 48.284 47.821C117.22 448 288 448 288 448s170.78 0 213.371-11.486c23.497-6.321 42.003-24.171 48.284-47.821 11.412-42.867 11.412-132.305 11.412-132.305s0-89.438-11.412-132.305zm-317.51 213.508V175.185l142.739 81.205-142.739 81.201z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1b1b428e\" data-id=\"1b1b428e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6c6d7343 elementor-widget elementor-widget-text-editor\" data-id=\"6c6d7343\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div id=\"gmw-single-location-wrapper-537\" class=\"gmw-element-wrapper gmw-single-location-wrapper gmw-sl-wrapper gmw-sl-single-post-wrapper post \" object_type=\"post\" object_id=\"21781\"  style=\"width:100%\"><div class=\"gmw-sl-map-wrapper gmw-sl-element\"><div id=\"gmw-map-wrapper-537\" class=\"gmw-map-wrapper  sl single_location \" style=\"width:100%;height:300px;\"> <span id=\"gmw-resize-map-toggle-537\" class=\"gmw-resize-map-toggle gmw-icon-resize-full\" style=\"display:none;\" title=\"Resize map\"><\/span> <div id=\"gmw-map-loader-537\" class=\"gmw-map-loader\"><\/div> <div id=\"gmw-map-537\" class=\"gmw-map sl single_location\" style=\"width:100%; height:100%\" data-map_id=\"537\" data-prefix=\"sl\" data-map_type=\"single_location\" data-icons_usage=\"global\"><\/div> <\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-30c3c78c elementor-widget elementor-widget-text-editor\" data-id=\"30c3c78c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><div id=\"gmw-single-object-locations-wrapper-188\" class=\"gmw-element-wrapper gmw-single-location-wrapper gmw-sl-wrapper gmw-sl-single-post-wrapper post gmw-sl-multiple-locations\" object_type=\"post\" object_id=\"\"  style=\"width:100%\"><div class=\"gmw-sl-map-wrapper\"><div id=\"gmw-map-wrapper-188\" class=\"gmw-map-wrapper  sl single_location \" style=\"width:100%;height:350px;\"> <span id=\"gmw-resize-map-toggle-188\" class=\"gmw-resize-map-toggle gmw-icon-resize-full\" style=\"display:none;\" title=\"Resize map\"><\/span> <div id=\"gmw-map-loader-188\" class=\"gmw-map-loader\"><\/div> <div id=\"gmw-map-188\" class=\"gmw-map sl single_location\" style=\"width:100%; height:100%\" data-map_id=\"188\" data-prefix=\"sl\" data-map_type=\"single_location\" data-icons_usage=\"global\"><\/div> <\/div><\/div><\/div><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-dab03cb elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile e-flex e-con-boxed e-con e-parent\" data-id=\"dab03cb\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8c7c6c0 elementor-widget elementor-widget-text-editor\" data-id=\"8c7c6c0\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>LifeTrend Group nasce dall\u2019esperienza di un team di consulenti specializzati nel ramo vita. Il fondatore, Massimo Meldoli, dopo oltre vent\u2019anni nel settore assicurativo, ha scelto di dedicarsi alla consulenza e alla gestione del risparmio per clienti Retail e Corporate.<br \/>Ascolto, dialogo e relazione sono al centro di ogni percorso, con l\u2019obiettivo di costruire fiducia, proteggere ci\u00f2 che conta davvero e accompagnare i clienti nel raggiungimento dei loro progetti, coniugando redditivit\u00e0 e sicurezza del capitale.<br \/>Grazie alla collaborazione con Allianz Milano Moscova, Aladiah Broker ed Energon, LifeTrend Group offre soluzioni di elevata qualit\u00e0, chiare, efficaci e personalizzate, affermandosi come punto di riferimento per i propri clienti.<br \/>LT Financial Club \u00e8 l\u2019headquarter del Gruppo e il cuore della community: uno spazio esclusivo dedicato a eventi, talk e incontri con Opinion Leader, dove prendono forma esperienze che uniscono benessere, performance e visione, spaziando da Sport &amp;<br \/>Wellness a Business, Food, Fashion e Art.<br \/>Professionalit\u00e0, Affidabilit\u00e0 e Trasparenza guidano da sempre il nostro operato.<\/p><p>consulenti specializzati, consulenza, gestione del risparmio, soluzioni di qualit\u00e0, Risparmio, Investimento, soluzioni sicure, soluzioni per atleti, libert\u00e0 finanziaria, consulenza assicurativa, consulenza finanziaria, assistenza assicurativa, assistenza finanziaria, consulenti finanziari, consulenti assicurativi,consulenti specializzati a Milano , consulenza a Milano , gestione del risparmio a Milano , soluzioni di qualit\u00e0 a Milano , Risparmio a Milano , Investimento a Milano , soluzioni sicure a Milano , soluzioni per atleti a Milano , libert\u00e0 finanziaria a Milano , consulenza assicurativa a Milano , consulenza finanziaria a Milano , assistenza assicurativa a Milano , assistenza finanziaria a Milano , consulenti finanziari a Milano , consulenti assicurativi a Milano ,<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<div style=\"display: none;\">\n<p>LifeTrend Group nasce dall\u2019esperienza di un team di consulenti specializzati nel ramo vita. Il fondatore, Massimo Meldoli, dopo oltre vent\u2019anni nel settore assicurativo, ha scelto di dedicarsi alla consulenza e alla gestione del risparmio per clienti Retail e Corporate.<br \/>\nAscolto, dialogo e relazione sono al centro di ogni percorso, con l\u2019obiettivo di costruire fiducia, proteggere ci\u00f2 che conta davvero e accompagnare i clienti nel raggiungimento dei loro progetti, coniugando redditivit\u00e0 e sicurezza del capitale.<br \/>\nGrazie alla collaborazione con Allianz Milano Moscova, Aladiah Broker ed Energon, LifeTrend Group offre soluzioni di elevata qualit\u00e0, chiare, efficaci e personalizzate, affermandosi come punto di riferimento per i propri clienti.<br \/>\nLT Financial Club \u00e8 l\u2019headquarter del Gruppo e il cuore della community: uno spazio esclusivo dedicato a eventi, talk e incontri con Opinion Leader, dove prendono forma esperienze che uniscono benessere, performance e visione, spaziando da Sport &amp;<br \/>\nWellness a Business, Food, Fashion e Art.<br \/>\nProfessionalit\u00e0, Affidabilit\u00e0 e Trasparenza guidano da sempre il nostro operato.<\/p>\n<p>consulenti specializzati, consulenza, gestione del risparmio, soluzioni di qualit\u00e0, Risparmio, Investimento, soluzioni sicure, soluzioni per atleti, libert\u00e0 finanziaria, consulenza assicurativa, consulenza finanziaria, assistenza assicurativa, assistenza finanziaria, consulenti finanziari, consulenti assicurativi,<\/p>\n<p>consulenti specializzati a Milano , consulenza a Milano , gestione del risparmio a Milano , soluzioni di qualit\u00e0 a Milano , Risparmio a Milano , Investimento a Milano , soluzioni sicure a Milano , soluzioni per atleti a Milano , libert\u00e0 finanziaria a Milano , consulenza assicurativa a Milano , consulenza finanziaria a Milano , assistenza assicurativa a Milano , assistenza finanziaria a Milano , consulenti finanziari a Milano , consulenti assicurativi a Milano ,<\/p>\n<\/div>\n","protected":false},"featured_media":25696,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":""},"product_brand":[],"product_cat":[921,25],"product_tag":[5678,5679,3339,432,5672,434,1115,1114,5673,1069,5677,794,5674,5676,5675],"class_list":{"0":"post-21781","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-consulenza","7":"product_cat-professionisti-studio-consulenze","8":"product_tag-assistenza-assicurativa","9":"product_tag-assistenza-finanziaria","10":"product_tag-consulenti-assicurativi","11":"product_tag-consulenti-finanziari","12":"product_tag-consulenti-specializzati","13":"product_tag-consulenza","14":"product_tag-consulenza-assicurativa","15":"product_tag-consulenza-finanziaria","16":"product_tag-gestione-del-risparmio","17":"product_tag-investimento","18":"product_tag-liberta-finanziaria","19":"product_tag-risparmio","20":"product_tag-soluzioni-di-qualita","21":"product_tag-soluzioni-per-atleti","22":"product_tag-soluzioni-sicure","24":"first","25":"instock","26":"shipping-taxable","27":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>LifeTrend Group - Cral Policlinico di Milano<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/lifetrend-group\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"LifeTrend Group - Cral Policlinico di Milano\" \/>\n<meta property=\"og:description\" content=\"LifeTrend Group nasce dall\u2019esperienza di un team di consulenti specializzati nel ramo vita. Il fondatore, Massimo Meldoli, dopo oltre vent\u2019anni nel settore assicurativo, ha scelto di dedicarsi alla consulenza e alla gestione del risparmio per clienti Retail e Corporate. Ascolto, dialogo e relazione sono al centro di ogni percorso, con l\u2019obiettivo di costruire fiducia, proteggere ci\u00f2 che conta davvero e accompagnare i clienti nel raggiungimento dei loro progetti, coniugando redditivit\u00e0 e sicurezza del capitale. Grazie alla collaborazione con Allianz Milano Moscova, Aladiah Broker ed Energon, LifeTrend Group offre soluzioni di elevata qualit\u00e0, chiare, efficaci e personalizzate, affermandosi come punto di riferimento per i propri clienti. LT Financial Club \u00e8 l\u2019headquarter del Gruppo e il cuore della community: uno spazio esclusivo dedicato a eventi, talk e incontri con Opinion Leader, dove prendono forma esperienze che uniscono benessere, performance e visione, spaziando da Sport &amp; Wellness a Business, Food, Fashion e Art. Professionalit\u00e0, Affidabilit\u00e0 e Trasparenza guidano da sempre il nostro operato.  consulenti specializzati, consulenza, gestione del risparmio, soluzioni di qualit\u00e0, Risparmio, Investimento, soluzioni sicure, soluzioni per atleti, libert\u00e0 finanziaria, consulenza assicurativa, consulenza finanziaria, assistenza assicurativa, assistenza finanziaria, consulenti finanziari, consulenti assicurativi,  consulenti specializzati a Milano , consulenza a Milano , gestione del risparmio a Milano , soluzioni di qualit\u00e0 a Milano , Risparmio a Milano , Investimento a Milano , soluzioni sicure a Milano , soluzioni per atleti a Milano , libert\u00e0 finanziaria a Milano , consulenza assicurativa a Milano , consulenza finanziaria a Milano , assistenza assicurativa a Milano , assistenza finanziaria a Milano , consulenti finanziari a Milano , consulenti assicurativi a Milano ,\" \/>\n<meta property=\"og:url\" content=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/lifetrend-group\/\" \/>\n<meta property=\"og:site_name\" content=\"Cral Policlinico di Milano\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-20T15:23:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/07\/logo_LifeTrend-Group.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/lifetrend-group\/\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/lifetrend-group\/\",\"name\":\"LifeTrend Group - Cral Policlinico di Milano\",\"isPartOf\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/lifetrend-group\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/lifetrend-group\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/07\/logo_LifeTrend-Group.jpg\",\"datePublished\":\"2025-07-21T10:27:13+00:00\",\"dateModified\":\"2026-03-20T15:23:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/lifetrend-group\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/lifetrend-group\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/lifetrend-group\/#primaryimage\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/07\/logo_LifeTrend-Group.jpg\",\"contentUrl\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/07\/logo_LifeTrend-Group.jpg\",\"width\":300,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/lifetrend-group\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/negozio\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"LifeTrend Group\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/#website\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/\",\"name\":\"Cral Policlinico di Milano\",\"description\":\"Area Convenzioni\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"LifeTrend Group - Cral Policlinico di Milano","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/lifetrend-group\/","og_locale":"it_IT","og_type":"article","og_title":"LifeTrend Group - Cral Policlinico di Milano","og_description":"LifeTrend Group nasce dall\u2019esperienza di un team di consulenti specializzati nel ramo vita. Il fondatore, Massimo Meldoli, dopo oltre vent\u2019anni nel settore assicurativo, ha scelto di dedicarsi alla consulenza e alla gestione del risparmio per clienti Retail e Corporate. Ascolto, dialogo e relazione sono al centro di ogni percorso, con l\u2019obiettivo di costruire fiducia, proteggere ci\u00f2 che conta davvero e accompagnare i clienti nel raggiungimento dei loro progetti, coniugando redditivit\u00e0 e sicurezza del capitale. Grazie alla collaborazione con Allianz Milano Moscova, Aladiah Broker ed Energon, LifeTrend Group offre soluzioni di elevata qualit\u00e0, chiare, efficaci e personalizzate, affermandosi come punto di riferimento per i propri clienti. LT Financial Club \u00e8 l\u2019headquarter del Gruppo e il cuore della community: uno spazio esclusivo dedicato a eventi, talk e incontri con Opinion Leader, dove prendono forma esperienze che uniscono benessere, performance e visione, spaziando da Sport &amp; Wellness a Business, Food, Fashion e Art. Professionalit\u00e0, Affidabilit\u00e0 e Trasparenza guidano da sempre il nostro operato.  consulenti specializzati, consulenza, gestione del risparmio, soluzioni di qualit\u00e0, Risparmio, Investimento, soluzioni sicure, soluzioni per atleti, libert\u00e0 finanziaria, consulenza assicurativa, consulenza finanziaria, assistenza assicurativa, assistenza finanziaria, consulenti finanziari, consulenti assicurativi,  consulenti specializzati a Milano , consulenza a Milano , gestione del risparmio a Milano , soluzioni di qualit\u00e0 a Milano , Risparmio a Milano , Investimento a Milano , soluzioni sicure a Milano , soluzioni per atleti a Milano , libert\u00e0 finanziaria a Milano , consulenza assicurativa a Milano , consulenza finanziaria a Milano , assistenza assicurativa a Milano , assistenza finanziaria a Milano , consulenti finanziari a Milano , consulenti assicurativi a Milano ,","og_url":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/lifetrend-group\/","og_site_name":"Cral Policlinico di Milano","article_modified_time":"2026-03-20T15:23:34+00:00","og_image":[{"width":300,"height":300,"url":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/07\/logo_LifeTrend-Group.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/lifetrend-group\/","url":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/lifetrend-group\/","name":"LifeTrend Group - Cral Policlinico di Milano","isPartOf":{"@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/#website"},"primaryImageOfPage":{"@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/lifetrend-group\/#primaryimage"},"image":{"@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/lifetrend-group\/#primaryimage"},"thumbnailUrl":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/07\/logo_LifeTrend-Group.jpg","datePublished":"2025-07-21T10:27:13+00:00","dateModified":"2026-03-20T15:23:34+00:00","breadcrumb":{"@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/lifetrend-group\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/lifetrend-group\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/lifetrend-group\/#primaryimage","url":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/07\/logo_LifeTrend-Group.jpg","contentUrl":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/07\/logo_LifeTrend-Group.jpg","width":300,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/lifetrend-group\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/negozio\/"},{"@type":"ListItem","position":3,"name":"LifeTrend Group"}]},{"@type":"WebSite","@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/#website","url":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/","name":"Cral Policlinico di Milano","description":"Area Convenzioni","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/product\/21781","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/comments?post=21781"}],"version-history":[{"count":24,"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/product\/21781\/revisions"}],"predecessor-version":[{"id":30093,"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/product\/21781\/revisions\/30093"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/media\/25696"}],"wp:attachment":[{"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/media?parent=21781"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/product_brand?post=21781"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/product_cat?post=21781"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/product_tag?post=21781"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}