{"id":21466,"date":"2025-07-16T16:01:09","date_gmt":"2025-07-16T14:01:09","guid":{"rendered":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/?post_type=product&#038;p=21466"},"modified":"2026-02-25T10:27:58","modified_gmt":"2026-02-25T09:27:58","slug":"abbraccio-23","status":"publish","type":"product","link":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/abbraccio-23\/","title":{"rendered":"Abbraccio 23"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"21466\" class=\"elementor elementor-21466\">\n\t\t\t\t<div class=\"elementor-element elementor-element-12c8bfd e-con-full e-flex e-con e-parent\" data-id=\"12c8bfd\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-9bb3416 e-con-full e-flex e-con e-child\" data-id=\"9bb3416\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a322eb7 elementor-widget elementor-widget-image\" data-id=\"a322eb7\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"600\" height=\"70\" src=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/07\/Abbraccio23_logo-testo-bianco-600x70-1.png\" class=\"attachment-full size-full wp-image-21504\" alt=\"\" srcset=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/07\/Abbraccio23_logo-testo-bianco-600x70-1.png 600w, https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/07\/Abbraccio23_logo-testo-bianco-600x70-1-480x56.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 600px, 100vw\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ed9dfd2 elementor-widget elementor-widget-text-editor\" data-id=\"ed9dfd2\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>UNO STUDIO PROFESSIONALE ACCOGLIENTE CHE ABBRACCIA TUTTE LE ET\u00c0 E ACCOMPAGNA OGNI PERSONA NEL PROPRIO PERCORSO CON LA PROFESSIONALIT\u00c0 DEL SUO STAFF<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d29b108 e-con-full e-flex e-con e-child\" data-id=\"d29b108\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-33b9739 elementor-widget elementor-widget-image\" data-id=\"33b9739\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" fetchpriority=\"high\" decoding=\"async\" width=\"1000\" height=\"666\" src=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/07\/abbraccio23_0.jpg\" class=\"attachment-full size-full wp-image-21500\" alt=\"\" srcset=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/07\/abbraccio23_0.jpg 1000w, https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/07\/abbraccio23_0-980x653.jpg 980w, https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/07\/abbraccio23_0-480x320.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1000px, 100vw\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-df44736 e-flex e-con-boxed e-con e-parent\" data-id=\"df44736\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-668fb55 elementor-widget elementor-widget-text-editor\" data-id=\"668fb55\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>in Abbraccio 23 trovi\u2026<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5ad2335 elementor-widget elementor-widget-text-editor\" data-id=\"5ad2335\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u2022 NEUROPSICOMOTRICISTA<\/p><p>\u2022 PSICOMOTRICISTA<\/p><p>\u2022 CHINESIOLOGA<\/p><p>\u2022 MASSOTERAPISTA<\/p><p>\u2022 OSTEOPATA ADULTI<\/p><p>\u2022 OSTEOPATA GRAVIDANZA E NEONATI<\/p><p>\u2022 OSTETRICA PER RIEDUCAZIONE PERINEALE<\/p><p>\u2022 DIETISTA<\/p><p>\u2022 PSICOLOGA<\/p><p>\u2022 NATUROPATA<\/p><p>\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-99361ee e-flex e-con-boxed e-con e-parent\" data-id=\"99361ee\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-d3ab183 e-con-full e-flex e-con e-child\" data-id=\"d3ab183\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8cb702e elementor-widget elementor-widget-text-editor\" data-id=\"8cb702e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Chi siamo<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8f43cb8 e-con-full e-flex e-con e-child\" data-id=\"8f43cb8\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f6eb345 elementor-widget elementor-widget-text-editor\" data-id=\"f6eb345\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tELENA BACCHIEGA\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9e4b882 elementor-widget elementor-widget-text-editor\" data-id=\"9e4b882\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Dopo il percorso di formazione in scienze infermieristiche conseguo la specializzazione in ostetricia presso gli Istituti Clinici di Perfezionamento Mangiagalli di Milano.<\/p><p>Per 13 anni ho svolto la mia attivit\u00e0 presso la sala parto dell\u2019ospedale di Gallarate, nell\u2019assistenza diretta al travaglio e al parto.<\/p><p>Da oltre 15 anni sono libera professionista e conduco il \u201cpercorso nascita\u201d, accompagnando le future mamme e pap\u00e0 nei corsi di preparazione alla nascita, offrendo inoltre sostegno e consulenza specialistica personalizzata dopo il parto.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-568f6de elementor-widget elementor-widget-text-editor\" data-id=\"568f6de\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>I servizi di Elena \u2013 ostetrica<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c8b020b elementor-widget elementor-widget-text-editor\" data-id=\"c8b020b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u2022 Corsi di accompagnamento alla nascita per mamme e pap\u00e0<br \/>\u2022 Consulenza allattamento<br \/>\u2022 Gruppi post nascita a sostegno della genitorialit\u00e0<br \/>\u2022 Corsi di massaggio neonatale<br \/>\u2022 Corsi di acquaticit\u00e0 in gravidanza<br \/>\u2022 Corsi di Elena<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7e08c5d e-con-full e-flex e-con e-child\" data-id=\"7e08c5d\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-71e77f8 elementor-widget elementor-widget-text-editor\" data-id=\"71e77f8\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>SARA EVANGELISTA<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0b140a0 elementor-widget elementor-widget-text-editor\" data-id=\"0b140a0\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Laureata in Scienze dell\u2019Educazione, lavoro da anni sulle problematiche educative della famiglia, della scuola, del lavoro e della comunit\u00e0.<\/p><p>Accompagno i genitori nell\u2019educazione dei figli, valorizzando i ruoli educativi della mamma e del pap\u00e0 e aiutando i bambini nel riconoscere, comprendere e rielaborare le emozioni.<\/p><p>Intervengo sulle pratiche educative e aiuto a riflettere su cosa fare, a rileggere le situazioni ed individuare i percorsi operativi.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7a00820 elementor-widget elementor-widget-text-editor\" data-id=\"7a00820\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>I servizi di Sara \u2013 pedagogista<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-201cbaa elementor-widget elementor-widget-text-editor\" data-id=\"201cbaa\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u2022 Consulenza pedagogica<br \/>\u2022 Percorsi di sostegno emotivo per bambini<br \/>\u2022 Consulenza per mediazione familiare e di coppia<br \/>\u2022 Corsi mamma bis<br \/>\u2022 Serate tematiche a sostegno della genitorialit\u00e0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-90e6454 elementor-hidden-tablet elementor-hidden-mobile e-flex e-con-boxed e-con e-parent\" data-id=\"90e6454\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c77d773 elementor-widget elementor-widget-text-editor\" data-id=\"c77d773\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Lo staff<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-cb9e3b4 e-con-full e-flex e-con e-child\" data-id=\"cb9e3b4\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-48e5374 elementor-position-left elementor-vertical-align-middle elementor-widget elementor-widget-image-box\" data-id=\"48e5374\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"1000\" height=\"666\" src=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/07\/abbraccio23_1.jpg\" class=\"attachment-full size-full wp-image-21560\" alt=\"\" srcset=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/07\/abbraccio23_1.jpg 1000w, https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/07\/abbraccio23_1-980x653.jpg 980w, https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/07\/abbraccio23_1-480x320.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1000px, 100vw\" \/><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\"><span style=\"font-size:18px;font-weight: 700;color: #698044\">ALESSANDRO ARIOLI<\/span><br>\n<span style=\"font-weight: 500;font-style: oblique\">Osteopata<\/span><br>\nOsteopata con approccio manuale e centrato sulla persona. Mi occupo di dolore muscolo-scheletrico e viscerale, valutazione posturale, prevenzione e recupero da infortuni, riabilitazione funzionale e supporto in ambiti come la gravidanza, l\u2019et\u00e0 pediatrica e lo sport.<br>\n<br>\n\n<span style=\"font-size:18px;font-weight: 700;color: #698044\">ELISA SACCO<\/span><br>\n<span style=\"font-weight: 500;font-style: oblique\">Tutor dsa e bes, educatrice<\/span><br>\n\u2060Strategie di studio personalizzate \u2013 mediazione tra scuola e famiglia \u2013 \u2060\u2060tecniche di apprendimento \u2013 \u2060\u2060supporto emotivo \u2013 \u2060\u2060gestione dei compito con supporto di strumenti compensativi \u2013 \u2060\u2060visione del pdp<br>\n<br>\n\n<span style=\"font-size:18px;font-weight: 700;color: #698044\">JOHANA RENTERIA MAMANI<\/span><br>\n<span style=\"font-weight: 500;font-style: oblique\">Operatrice Olistica specializzata in tecniche di massaggio<\/span><br>\nMassaggio Olistico Rilassante, Back Massage, Massaggio Plantare, Massaggio Drenante, Massaggio Indiano, Flower Massage (Massaggio con i Fiori di Bach), Massaggio Aromaterapico (Massaggio con Oli Essenziali), Coppettazione<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e74565d elementor-position-right elementor-vertical-align-middle elementor-widget elementor-widget-image-box\" data-id=\"e74565d\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"666\" src=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/07\/abbraccio23_2.jpg\" class=\"attachment-full size-full wp-image-21561\" alt=\"\" srcset=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/07\/abbraccio23_2.jpg 1000w, https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/07\/abbraccio23_2-980x653.jpg 980w, https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/07\/abbraccio23_2-480x320.jpg 480w\" sizes=\"auto, (min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1000px, 100vw\" \/><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\"><font color=\"#698044\"><span style=\"font-size: 18px\"><b>LAURA CASATI<\/b><\/span><\/font><br>\n<i><b>Insegnante di yoga certificato<\/b><\/i><br>\nAppassionata di benessere psicofisico, offro lezioni di yoga private e di gruppo per condividere i benefici di questa antica pratica.<br>\n<br>\n\n<font color=\"#698044\"><span style=\"font-size: 18px\"><b>LUCA CASTELNUOVO<\/b><\/span><\/font><br>\n<i><b>Fisioterapista e Osteopata<\/b><\/i><br>\n\u2060Osteopata e fisioterapista esperto in terapia manuale e osteopatia<br>\nTerapia manuale con visione osteopatica, Esercizio terapeutico, Riabilitazione ortopedica, neurologica e respiratoria post covid,\nTecarterapia, kinesiotape<br>\n<br>\n\n<font color=\"#698044\"><span style=\"font-size: 18px\"><b>SARA MACULAN<\/b><\/span><\/font><br>Riflessologia plantare\nConsulenza Riflessologia Plantare metodo R.M.D.S, Consulenza Olistica(lettura iride e riflessologia plantare), Auricoloterapia, Consulenza Floriterapica (Fiori Bach e Bush Flower), Consulenza iridologica, Consulenza tecnica metamorfica, Trattamento Reiki metodo Usui, Lettura Tema Natale numerologico<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-93a74cc elementor-position-left elementor-vertical-align-middle elementor-widget elementor-widget-image-box\" data-id=\"93a74cc\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"666\" src=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/07\/abbraccio23_3.jpg\" class=\"attachment-full size-full wp-image-21562\" alt=\"\" srcset=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/07\/abbraccio23_3.jpg 1000w, https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/07\/abbraccio23_3-980x653.jpg 980w, https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/07\/abbraccio23_3-480x320.jpg 480w\" sizes=\"auto, (min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1000px, 100vw\" \/><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\"><font color=\"#698044\"><span style=\"font-size: 18px\"><b>STEFANIE FRANCESCA RUSSO<\/b><\/span><\/font><br>\n<i><b>Psicologa psicoterapeuta ad indirizzo integrato<\/b><\/i><br>\nSupporto psicologico \u2013 psicoterapia per preadolescenti \u2013 adolescenti \u2013 adulti \u2013 coppia.<br>\n<br>\n<font color=\"#698044\"><span style=\"font-size: 18px\"><b>VALENTINA CONTINI<\/b><\/span><\/font><br>\n<i><b>Massoterapista<\/b><\/i><br>\n\u2060Trattamenti terapeutici anche con la \u201ctecarterapia\u201d<br>\nTrattamenti: Massoterapia, Massaggio decontratturante, Massaggio drenante, Massaggio linfodrenante, Tecarterapia, Kinesiotaping, Bendaggi funzionali, Massaggio sportivo, Pancafit, Ginnastica posturale<br>\n<br>\n<font color=\"#698044\"><span style=\"font-size: 18px\"><b>DANIELA SQUIZZATO<\/b><\/span><\/font><br>\n<span style=\"font-weight: 500;font-style: oblique\">Ostetrica Per rieducazione Perineale<\/span><br>\nspecializzata nel trattamento delle disfunzioni pelviche come: dolore sessuale e perineale, vulvodinia, incontinenza, prolasso<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-42026f7 elementor-position-right elementor-vertical-align-middle elementor-widget elementor-widget-image-box\" data-id=\"42026f7\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"666\" src=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/07\/abbraccio23_4.jpg\" class=\"attachment-full size-full wp-image-21563\" alt=\"\" srcset=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/07\/abbraccio23_4.jpg 1000w, https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/07\/abbraccio23_4-980x653.jpg 980w, https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/07\/abbraccio23_4-480x320.jpg 480w\" sizes=\"auto, (min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1000px, 100vw\" \/><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\"><font color=\"#698044\"><span style=\"font-size: 18px\"><b>STEFANIA SPAN\u00d2<\/b><\/span><\/font><br>\n<i><b>Neuropsicomotricista<\/b><\/i><br>\nTerapista della Neuro e Psicomotricit\u00e0 dell\u2019Et\u00e0 Evolutiva.<br>\n<br>\n\n<font color=\"#698044\"><span style=\"font-size: 18px\"><b>JENNIFER CETRANGOLO<\/b><\/span><\/font><br>\nChinesiologia, Personal Trainer, Ginnastica in gravidanza, Ginnastica Posturale, Dimagrimento<br>\n<br>\n\n<font color=\"#698044\"><span style=\"font-size: 18px\"><b>MARZIA MARCON<\/b><\/span><\/font><br>\n<i><b>Psicomotricista<\/b><\/i><br>\nIdeazione, progettazione e conduzione di percorsi di psicomotricit\u00e0 in ambito educativo, preventivo e di aiuto, in piccoli gruppi e individuali.\nIdeazione e conduzione percorsi genitori-bambino<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-54a073b elementor-position-left elementor-vertical-align-middle elementor-widget elementor-widget-image-box\" data-id=\"54a073b\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"666\" src=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/07\/abbraccio23_5.jpg\" class=\"attachment-full size-full wp-image-21564\" alt=\"\" srcset=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/07\/abbraccio23_5.jpg 1000w, https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/07\/abbraccio23_5-980x653.jpg 980w, https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/07\/abbraccio23_5-480x320.jpg 480w\" sizes=\"auto, (min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1000px, 100vw\" \/><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\"><font color=\"#698044\"><span style=\"font-size: 18px\"><b>ASTRA MICHETTI<\/b><\/span><\/font><br>\n<i><b>Psicomotricista<\/b><\/i><br>\nPsicomotricit\u00e0 in ambito preventivo, educativo, d\u2019aiuto: percorsi individuali e di gruppo. Percorsi mamma-bambino<br>\n<br>\n\n<font color=\"#698044\"><span style=\"font-size: 18px\"><b>ANDRE\u00c8 MARTINA ZANIRATO<\/b><\/span><\/font><br>\n<i><b>Biologa nutrizionista<\/b><\/i><br>\n<br>\n\n<font color=\"#698044\"><span style=\"font-size: 18px\"><b>FRANCESCA LAURIELLO<\/b><\/span><\/font><br>\n<i><b>Psicologa a indirizzo sistemico relazionale<\/b><\/i><br>\nOffro percorsi di sostegno psicologico ad adolescenti, adulti, coppie, genitori e famiglia.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6fcae15 elementor-hidden-desktop e-flex e-con-boxed e-con e-parent\" data-id=\"6fcae15\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3b81d34 elementor-widget elementor-widget-text-editor\" data-id=\"3b81d34\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Lo staff<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-76272c4 e-con-full e-flex e-con e-child\" data-id=\"76272c4\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1b752ea elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"1b752ea\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"1000\" height=\"666\" src=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/07\/abbraccio23_1.jpg\" class=\"attachment-full size-full wp-image-21560\" alt=\"\" srcset=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/07\/abbraccio23_1.jpg 1000w, https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/07\/abbraccio23_1-980x653.jpg 980w, https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/07\/abbraccio23_1-480x320.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1000px, 100vw\" \/><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\"><span style=\"font-size:18px;font-weight: 700;color: #698044\">ALESSANDRO ARIOLI<\/span><br>\n<span style=\"font-weight: 500;font-style: oblique\">Osteopata<\/span><br>\nOsteopata con approccio manuale e centrato sulla persona. Mi occupo di dolore muscolo-scheletrico e viscerale, valutazione posturale, prevenzione e recupero da infortuni, riabilitazione funzionale e supporto in ambiti come la gravidanza, l\u2019et\u00e0 pediatrica e lo sport.<br>\n<br>\n\n<span style=\"font-size:18px;font-weight: 700;color: #698044\">ELISA SACCO<\/span><br>\n<span style=\"font-weight: 500;font-style: oblique\">Tutor dsa e bes, educatrice<\/span><br>\n\u2060Strategie di studio personalizzate \u2013 mediazione tra scuola e famiglia \u2013 \u2060\u2060tecniche di apprendimento \u2013 \u2060\u2060supporto emotivo \u2013 \u2060\u2060gestione dei compito con supporto di strumenti compensativi \u2013 \u2060\u2060visione del pdp<br>\n<br>\n\n<span style=\"font-size:18px;font-weight: 700;color: #698044\">JOHANA RENTERIA MAMANI<\/span><br>\n<span style=\"font-weight: 500;font-style: oblique\">Operatrice Olistica specializzata in tecniche di massaggio<\/span><br>\nMassaggio Olistico Rilassante, Back Massage, Massaggio Plantare, Massaggio Drenante, Massaggio Indiano, Flower Massage (Massaggio con i Fiori di Bach), Massaggio Aromaterapico (Massaggio con Oli Essenziali), Coppettazione<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f8efc32 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"f8efc32\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"666\" src=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/07\/abbraccio23_2.jpg\" class=\"attachment-full size-full wp-image-21561\" alt=\"\" srcset=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/07\/abbraccio23_2.jpg 1000w, https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/07\/abbraccio23_2-980x653.jpg 980w, https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/07\/abbraccio23_2-480x320.jpg 480w\" sizes=\"auto, (min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1000px, 100vw\" \/><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\"><font color=\"#698044\"><span style=\"font-size: 18px\"><b>LAURA CASATI<\/b><\/span><\/font><br>\n<i><b>Insegnante di yoga certificato<\/b><\/i><br>\nAppassionata di benessere psicofisico, offro lezioni di yoga private e di gruppo per condividere i benefici di questa antica pratica.<br>\n<br>\n\n<font color=\"#698044\"><span style=\"font-size: 18px\"><b>LUCA CASTELNUOVO<\/b><\/span><\/font><br>\n<i><b>Fisioterapista e Osteopata<\/b><\/i><br>\n\u2060Osteopata e fisioterapista esperto in terapia manuale e osteopatia<br>\nTerapia manuale con visione osteopatica, Esercizio terapeutico, Riabilitazione ortopedica, neurologica e respiratoria post covid,\nTecarterapia, kinesiotape<br>\n<br>\n\n<font color=\"#698044\"><span style=\"font-size: 18px\"><b>SARA MACULAN<\/b><\/span><\/font><br>Riflessologia plantare\nConsulenza Riflessologia Plantare metodo R.M.D.S, Consulenza Olistica(lettura iride e riflessologia plantare), Auricoloterapia, Consulenza Floriterapica (Fiori Bach e Bush Flower), Consulenza iridologica, Consulenza tecnica metamorfica, Trattamento Reiki metodo Usui, Lettura Tema Natale numerologico<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5ceb397 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"5ceb397\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"666\" src=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/07\/abbraccio23_3.jpg\" class=\"attachment-full size-full wp-image-21562\" alt=\"\" srcset=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/07\/abbraccio23_3.jpg 1000w, https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/07\/abbraccio23_3-980x653.jpg 980w, https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/07\/abbraccio23_3-480x320.jpg 480w\" sizes=\"auto, (min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1000px, 100vw\" \/><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\"><font color=\"#698044\"><span style=\"font-size: 18px\"><b>STEFANIE FRANCESCA RUSSO<\/b><\/span><\/font><br>\n<i><b>Psicologa psicoterapeuta ad indirizzo integrato<\/b><\/i><br>\nSupporto psicologico \u2013 psicoterapia per preadolescenti \u2013 adolescenti \u2013 adulti \u2013 coppia.<br>\n<br>\n<font color=\"#698044\"><span style=\"font-size: 18px\"><b>VALENTINA CONTINI<\/b><\/span><\/font><br>\n<i><b>Massoterapista<\/b><\/i><br>\n\u2060Trattamenti terapeutici anche con la \u201ctecarterapia\u201d<br>\nTrattamenti: Massoterapia, Massaggio decontratturante, Massaggio drenante, Massaggio linfodrenante, Tecarterapia, Kinesiotaping, Bendaggi funzionali, Massaggio sportivo, Pancafit, Ginnastica posturale<br>\n<br>\n<font color=\"#698044\"><span style=\"font-size: 18px\"><b>DANIELA SQUIZZATO<\/b><\/span><\/font><br>\n<span style=\"font-weight: 500;font-style: oblique\">Ostetrica Per rieducazione Perineale<\/span><br>\nspecializzata nel trattamento delle disfunzioni pelviche come: dolore sessuale e perineale, vulvodinia, incontinenza, prolasso<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3e1c0d3 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"3e1c0d3\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"666\" src=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/07\/abbraccio23_4.jpg\" class=\"attachment-full size-full wp-image-21563\" alt=\"\" srcset=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/07\/abbraccio23_4.jpg 1000w, https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/07\/abbraccio23_4-980x653.jpg 980w, https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/07\/abbraccio23_4-480x320.jpg 480w\" sizes=\"auto, (min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1000px, 100vw\" \/><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\"><font color=\"#698044\"><span style=\"font-size: 18px\"><b>STEFANIA SPAN\u00d2<\/b><\/span><\/font><br>\n<i><b>Neuropsicomotricista<\/b><\/i><br>\nTerapista della Neuro e Psicomotricit\u00e0 dell\u2019Et\u00e0 Evolutiva.<br>\n<br>\n\n<font color=\"#698044\"><span style=\"font-size: 18px\"><b>JENNIFER CETRANGOLO<\/b><\/span><\/font><br>\nChinesiologia, Personal Trainer, Ginnastica in gravidanza, Ginnastica Posturale, Dimagrimento<br>\n<br>\n\n<font color=\"#698044\"><span style=\"font-size: 18px\"><b>MARZIA MARCON<\/b><\/span><\/font><br>\n<i><b>Psicomotricista<\/b><\/i><br>\nIdeazione, progettazione e conduzione di percorsi di psicomotricit\u00e0 in ambito educativo, preventivo e di aiuto, in piccoli gruppi e individuali.\nIdeazione e conduzione percorsi genitori-bambino<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cbea8b5 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"cbea8b5\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"666\" src=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/07\/abbraccio23_5.jpg\" class=\"attachment-full size-full wp-image-21564\" alt=\"\" srcset=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/07\/abbraccio23_5.jpg 1000w, https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/07\/abbraccio23_5-980x653.jpg 980w, https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/07\/abbraccio23_5-480x320.jpg 480w\" sizes=\"auto, (min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1000px, 100vw\" \/><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\"><font color=\"#698044\"><span style=\"font-size: 18px\"><b>ASTRA MICHETTI<\/b><\/span><\/font><br>\n<i><b>Psicomotricista<\/b><\/i><br>\nPsicomotricit\u00e0 in ambito preventivo, educativo, d\u2019aiuto: percorsi individuali e di gruppo. Percorsi mamma-bambino<br>\n<br>\n\n<font color=\"#698044\"><span style=\"font-size: 18px\"><b>ANDRE\u00c8 MARTINA ZANIRATO<\/b><\/span><\/font><br>\n<i><b>Biologa nutrizionista<\/b><\/i><br>\n<br>\n\n<font color=\"#698044\"><span style=\"font-size: 18px\"><b>FRANCESCA LAURIELLO<\/b><\/span><\/font><br>\n<i><b>Psicologa a indirizzo sistemico relazionale<\/b><\/i><br>\nOffro percorsi di sostegno psicologico ad adolescenti, adulti, coppie, genitori e famiglia.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ac4bc6b e-flex e-con-boxed e-con e-parent\" data-id=\"ac4bc6b\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a764d1f elementor-widget elementor-widget-text-editor\" data-id=\"a764d1f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Agevolazioni riservate agli associati<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a48923e e-flex e-con-boxed e-con e-parent\" data-id=\"a48923e\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-121834c e-flex e-con-boxed e-con e-child\" data-id=\"121834c\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-be60601 elementor-widget elementor-widget-text-editor\" data-id=\"be60601\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Contatti<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8bcfa64 elementor-widget elementor-widget-text-editor\" data-id=\"8bcfa64\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Via Amatore Sciesa, 23c &#8211; 21013 Gallarate (VA)<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-aba5fc8 elementor-widget elementor-widget-text-editor\" data-id=\"aba5fc8\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Elena:<\/strong> +39 349 548 4238<br \/><strong>Sara:<\/strong> +39 320 212 7175<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3252d3a elementor-widget elementor-widget-text-editor\" data-id=\"3252d3a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Mail:<\/strong> <span style=\"color: #698044;\"><a style=\"color: #698044;\" href=\"mailto:info@abbraccio23.it\">info@abbraccio23.it<\/a><\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-73363d6 elementor-widget elementor-widget-text-editor\" data-id=\"73363d6\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong><span style=\"color: #698044;\"><a style=\"color: #698044;\" href=\"https:\/\/www.abbraccio23.it\/\">www.abbraccio23.it<\/a><\/span><\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-88e3801 e-con-full e-flex e-con e-child\" data-id=\"88e3801\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-27f9396 elementor-widget elementor-widget-text-editor\" data-id=\"27f9396\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><div id=\"gmw-single-object-locations-wrapper-129\" class=\"gmw-element-wrapper gmw-single-location-wrapper gmw-sl-wrapper gmw-sl-single-post-wrapper post gmw-sl-multiple-locations\" object_type=\"post\" object_id=\"\"  style=\"width:100%\"><div class=\"gmw-sl-map-wrapper\"><div id=\"gmw-map-wrapper-129\" class=\"gmw-map-wrapper  sl single_location \" style=\"width:100%;height:350px;\"> <span id=\"gmw-resize-map-toggle-129\" class=\"gmw-resize-map-toggle gmw-icon-resize-full\" style=\"display:none;\" title=\"Resize map\"><\/span> <div id=\"gmw-map-loader-129\" class=\"gmw-map-loader\"><\/div> <div id=\"gmw-map-129\" class=\"gmw-map sl single_location\" style=\"width:100%; height:100%\" data-map_id=\"129\" data-prefix=\"sl\" data-map_type=\"single_location\" data-icons_usage=\"global\"><\/div> <\/div><\/div><\/div><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>UNO STUDIO PROFESSIONALE ACCOGLIENTE CHE ABBRACCIA TUTTE LE ET\u00c0 E ACCOMPAGNA OGNI PERSONA NEL PROPRIO PERCORSO CON LA PROFESSIONALIT\u00c0 DEL SUO STAFF<\/p>\n<p>in Abbraccio 23 trovi\u2026<\/p>\n<p>NEUROPSICOMOTRICISTA<br \/>\nPSICOMOTRICISTA<br \/>\nCHINESIOLOGA<br \/>\nMASSOTERAPISTA<br \/>\nOSTEOPATA ADULTI<br \/>\nOSTEOPATA GRAVIDANZA E NEONATI<br \/>\nOSTETRICA PER RIEDUCAZIONE PERINEALE<br \/>\nDIETISTA<br \/>\nPSICOLOGA<br \/>\nNATUROPATA<\/p>\n<p>CHI SIAMO<\/p>\n<p>ELENA BACCHIEGA<\/p>\n<p>Dopo il percorso di formazione in scienze infermieristiche conseguo la specializzazione in ostetricia presso gli Istituti Clinici di Perfezionamento Mangiagalli di Milano.<\/p>\n<p>Per 13 anni ho svolto la mia attivit\u00e0 presso la sala parto dell\u2019ospedale di Gallarate, nell\u2019assistenza diretta al travaglio e al parto.<\/p>\n<p>Da oltre 15 anni sono libera professionista e conduco il \u201cpercorso nascita\u201d, accompagnando le future mamme e pap\u00e0 nei corsi di preparazione alla nascita, offrendo inoltre sostegno e consulenza specialistica personalizzata dopo il parto.<\/p>\n<p>I servizi di Elena \u2013 ostetrica<\/p>\n<p>Corsi di accompagnamento alla nascita per mamme e pap\u00e0<br \/>\nConsulenza allattamento<br \/>\nGruppi post nascita a sostegno della genitorialit\u00e0<br \/>\nCorsi di massaggio neonatale<br \/>\nCorsi di acquaticit\u00e0 in gravidanza<br \/>\nCorsi di Elena<\/p>\n<p>SARA EVANGELISTA<\/p>\n<p>Laureata in Scienze dell\u2019Educazione, lavoro da anni sulle problematiche educative della famiglia, della scuola, del lavoro e della comunit\u00e0.<\/p>\n<p>Accompagno i genitori nell\u2019educazione dei figli, valorizzando i ruoli educativi della mamma e del pap\u00e0 e aiutando i bambini nel riconoscere, comprendere e rielaborare le emozioni.<\/p>\n<p>Intervengo sulle pratiche educative e aiuto a riflettere su cosa fare, a rileggere le situazioni ed individuare i percorsi operativi.<\/p>\n<p>I servizi di Sara \u2013 pedagogista<\/p>\n<p>Consulenza pedagogica<br \/>\nPercorsi di sostegno emotivo per bambini<br \/>\nConsulenza per mediazione familiare e di coppia<br \/>\nCorsi mamma bis<br \/>\nSerate tematiche a sostegno della genitorialit\u00e0<\/p>\n<p>LO STAFF<\/p>\n<p>ALESSANDRO ARIOLI<br \/>\nOsteopata<br \/>\nOsteopata con approccio manuale e centrato sulla persona. Mi occupo di dolore muscolo-scheletrico e viscerale, valutazione posturale, prevenzione e recupero da infortuni, riabilitazione funzionale e supporto in ambiti come la gravidanza, l\u2019et\u00e0 pediatrica e lo sport.<\/p>\n<p>LAURA CASATI<br \/>\nInsegnante di yoga certificato<br \/>\nAppassionata di benessere psicofisico, offro lezioni di yoga private e di gruppo per condividere i benefici di questa antica pratica.<\/p>\n<p>LUCA CASTELNUOVO<br \/>\nFisioterapista e Osteopata<br \/>\nOsteopata e fisioterapista esperto in terapia manuale e osteopatia<br \/>\nTerapia manuale con visione osteopatica, Esercizio terapeutico, Riabilitazione ortopedica, neurologica e respiratoria post covid,<br \/>\nTecarterapia, kinesiotape<\/p>\n<p>JENNIFER CETRANGOLO<br \/>\nChinesiologia<br \/>\nPersonal Trainer<br \/>\nGinnastica in gravidanza<br \/>\nGinnastica Posturale<br \/>\nDimagrimento<\/p>\n<p>VALENTINA CONTINI<br \/>\nMassoterapista<br \/>\nTrattamenti terapeutici anche con la \u201ctecarterapia\u201d<br \/>\nTrattamenti:<br \/>\nMassoterapia, Massaggio decontratturante, Massaggio drenante, Massaggio linfodrenante, Tecarterapia, Kinesiotaping, Bendaggi funzionali, Massaggio sportivo, Pancafit, Ginnastica posturale<\/p>\n<p>FRANCESCA LAURIELLO<br \/>\nPsicologa a indirizzo sistemico relazionale<br \/>\noffro percorsi di sostegno psicologico ad adolescenti, adulti, coppie, genitori e famiglia.<\/p>\n<p>SARA MACULAN<br \/>\nRiflessologia plantare<br \/>\nConsulenza Riflessologia Plantare metodo R.M.D.S<br \/>\nConsulenza Olistica(lettura iride e riflessologia plantare)<br \/>\nAuricoloterapia<br \/>\nConsulenza Floriterapica (Fiori Bach e Bush Flower)<br \/>\nConsulenza iridologica<br \/>\nConsulenza tecnica metamorfica<br \/>\nTrattamento Reiki metodo Usui<br \/>\nLettura Tema Natale numerologico<\/p>\n<p>JOHANA RENTERIA MAMANI<br \/>\nOperatrice Olistica specializzata in tecniche di massaggio<br \/>\nMassaggio Olistico Rilassante, Back Massage, Massaggio Plantare, Massaggio Drenante, Massaggio Indiano, Flower Massage (Massaggio con i Fiori di Bach), Massaggio Aromaterapico (Massaggio con Oli Essenziali), Coppettazione<\/p>\n<p>MARZIA MARCON<br \/>\nPsicomotricista<br \/>\nideazione, progettazione e conduzione di percorsi di psicomotricit\u00e0 in ambito educativo, preventivo e di aiuto, in piccoli gruppi e individuali.<br \/>\nIdeazione e conduzione percorsi genitori-bambino<\/p>\n<p>ASTRA MICHETTI<br \/>\nPsicomotricista<br \/>\npsicomotricit\u00e0 in ambito preventivo, educativo, d\u2019aiuto: percorsi individuali e di gruppo. Percorsi mamma-bambino<\/p>\n<p>STEFANIE FRANCESCA RUSSO<br \/>\nPsicologa psicoterapeuta ad indirizzo integrato<br \/>\nSupporto psicologico \u2013 psicoterapia per preadolescenti \u2013 adolescenti \u2013 adulti \u2013 coppia<\/p>\n<p>ELISA SACCO<br \/>\nTutor dsa e bes, educatrice<br \/>\n\u2060Strategie di studio personalizzate \u2013 mediazione tra scuola e famiglia \u2013 \u2060\u2060tecniche di apprendimento \u2013 \u2060\u2060supporto emotivo \u2013 \u2060\u2060gestione dei compito con supporto di strumenti compensativi \u2013 \u2060\u2060visione del pdp<\/p>\n<p>DANIELA SQUIZZATO<br \/>\nOstetrica Per rieducazione Perineale<br \/>\nspecializzata nel trattamento delle disfunzioni pelviche come: dolore sessuale e perineale, vulvodinia, incontinenza, prolasso<\/p>\n<p>STEFANIA SPAN\u00d2<br \/>\nNeuropsicomotricista<br \/>\nTerapista della Neuro e Psicomotricit\u00e0 dell\u2019Et\u00e0 Evolutiva<\/p>\n<p>ANDRE\u00c8 MARTINA ZANIRATO<br \/>\nBiologa nutrizionista<\/p>\n<p>neuropsicomotricista, neuropsicomotricit\u00e0, psicomotricista, psicomotricit\u00e0, chinesiologa, chinesiologo, chinesiologi, massoterapista, massoterapia, massoterapisti, osteopata adulti, osteopata gravidanza, osteopata neonati, osteopata, osteopati, osteopatia, ostetrica per rieducazione perineale, dietista, dietisti, nutrizione, nutrizionisti, psicologa, psicologia, psicologi, naturopata, naturopati, naturopatia, Biologa nutrizionista, Biologi nutrizionisti,<\/p>\n","protected":false},"featured_media":21482,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":""},"product_brand":[],"product_cat":[26,4417],"product_tag":[1013,2362,4420,2429,2426,4425,4426,512,1955,1956,999,4427,992,4418,4419,2470,695,622,4421,4422,4423,623,511,4424,1883,1854,1857,4181,2370],"class_list":{"0":"post-21466","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-salute","7":"product_cat-studi-medici","8":"product_tag-biologa-nutrizionista","9":"product_tag-biologi-nutrizionisti","10":"product_tag-chinesiologa","11":"product_tag-chinesiologi","12":"product_tag-chinesiologo","13":"product_tag-dietista","14":"product_tag-dietisti","15":"product_tag-massoterapia","16":"product_tag-massoterapista","17":"product_tag-massoterapisti","18":"product_tag-naturopata","19":"product_tag-naturopati","20":"product_tag-naturopatia","21":"product_tag-neuropsicomotricista","22":"product_tag-neuropsicomotricita","23":"product_tag-nutrizione","24":"product_tag-nutrizionisti","25":"product_tag-osteopata","26":"product_tag-osteopata-adulti","27":"product_tag-osteopata-gravidanza","28":"product_tag-osteopata-neonati","29":"product_tag-osteopati","30":"product_tag-osteopatia","31":"product_tag-ostetrica-per-rieducazione-perineale","32":"product_tag-psicologa","33":"product_tag-psicologi","34":"product_tag-psicologia","35":"product_tag-psicomotricista","36":"product_tag-psicomotricita","38":"first","39":"instock","40":"shipping-taxable","41":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Abbraccio 23 - Cral Policlinico di Milano<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/abbraccio-23\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Abbraccio 23 - Cral Policlinico di Milano\" \/>\n<meta property=\"og:description\" content=\"UNO STUDIO PROFESSIONALE ACCOGLIENTE CHE ABBRACCIA TUTTE LE ET\u00c0 E ACCOMPAGNA OGNI PERSONA NEL PROPRIO PERCORSO CON LA PROFESSIONALIT\u00c0 DEL SUO STAFF  in Abbraccio 23 trovi\u2026  NEUROPSICOMOTRICISTA PSICOMOTRICISTA CHINESIOLOGA MASSOTERAPISTA OSTEOPATA ADULTI OSTEOPATA GRAVIDANZA E NEONATI OSTETRICA PER RIEDUCAZIONE PERINEALE DIETISTA PSICOLOGA NATUROPATA  CHI SIAMO  ELENA BACCHIEGA  Dopo il percorso di formazione in scienze infermieristiche conseguo la specializzazione in ostetricia presso gli Istituti Clinici di Perfezionamento Mangiagalli di Milano.  Per 13 anni ho svolto la mia attivit\u00e0 presso la sala parto dell\u2019ospedale di Gallarate, nell\u2019assistenza diretta al travaglio e al parto.  Da oltre 15 anni sono libera professionista e conduco il \u201cpercorso nascita\u201d, accompagnando le future mamme e pap\u00e0 nei corsi di preparazione alla nascita, offrendo inoltre sostegno e consulenza specialistica personalizzata dopo il parto.  I servizi di Elena \u2013 ostetrica  Corsi di accompagnamento alla nascita per mamme e pap\u00e0 Consulenza allattamento Gruppi post nascita a sostegno della genitorialit\u00e0 Corsi di massaggio neonatale Corsi di acquaticit\u00e0 in gravidanza Corsi di Elena  SARA EVANGELISTA  Laureata in Scienze dell\u2019Educazione, lavoro da anni sulle problematiche educative della famiglia, della scuola, del lavoro e della comunit\u00e0.  Accompagno i genitori nell\u2019educazione dei figli, valorizzando i ruoli educativi della mamma e del pap\u00e0 e aiutando i bambini nel riconoscere, comprendere e rielaborare le emozioni.  Intervengo sulle pratiche educative e aiuto a riflettere su cosa fare, a rileggere le situazioni ed individuare i percorsi operativi.  I servizi di Sara \u2013 pedagogista  Consulenza pedagogica Percorsi di sostegno emotivo per bambini Consulenza per mediazione familiare e di coppia Corsi mamma bis Serate tematiche a sostegno della genitorialit\u00e0  LO STAFF  ALESSANDRO ARIOLI Osteopata Osteopata con approccio manuale e centrato sulla persona. Mi occupo di dolore muscolo-scheletrico e viscerale, valutazione posturale, prevenzione e recupero da infortuni, riabilitazione funzionale e supporto in ambiti come la gravidanza, l\u2019et\u00e0 pediatrica e lo sport.  LAURA CASATI Insegnante di yoga certificato Appassionata di benessere psicofisico, offro lezioni di yoga private e di gruppo per condividere i benefici di questa antica pratica.  LUCA CASTELNUOVO Fisioterapista e Osteopata Osteopata e fisioterapista esperto in terapia manuale e osteopatia Terapia manuale con visione osteopatica, Esercizio terapeutico, Riabilitazione ortopedica, neurologica e respiratoria post covid, Tecarterapia, kinesiotape  JENNIFER CETRANGOLO Chinesiologia Personal Trainer Ginnastica in gravidanza Ginnastica Posturale Dimagrimento  VALENTINA CONTINI Massoterapista Trattamenti terapeutici anche con la \u201ctecarterapia\u201d Trattamenti: Massoterapia, Massaggio decontratturante, Massaggio drenante, Massaggio linfodrenante, Tecarterapia, Kinesiotaping, Bendaggi funzionali, Massaggio sportivo, Pancafit, Ginnastica posturale  FRANCESCA LAURIELLO Psicologa a indirizzo sistemico relazionale offro percorsi di sostegno psicologico ad adolescenti, adulti, coppie, genitori e famiglia.  SARA MACULAN Riflessologia plantare Consulenza Riflessologia Plantare metodo R.M.D.S Consulenza Olistica(lettura iride e riflessologia plantare) Auricoloterapia Consulenza Floriterapica (Fiori Bach e Bush Flower) Consulenza iridologica Consulenza tecnica metamorfica Trattamento Reiki metodo Usui Lettura Tema Natale numerologico  JOHANA RENTERIA MAMANI Operatrice Olistica specializzata in tecniche di massaggio Massaggio Olistico Rilassante, Back Massage, Massaggio Plantare, Massaggio Drenante, Massaggio Indiano, Flower Massage (Massaggio con i Fiori di Bach), Massaggio Aromaterapico (Massaggio con Oli Essenziali), Coppettazione  MARZIA MARCON Psicomotricista ideazione, progettazione e conduzione di percorsi di psicomotricit\u00e0 in ambito educativo, preventivo e di aiuto, in piccoli gruppi e individuali. Ideazione e conduzione percorsi genitori-bambino  ASTRA MICHETTI Psicomotricista psicomotricit\u00e0 in ambito preventivo, educativo, d\u2019aiuto: percorsi individuali e di gruppo. Percorsi mamma-bambino  STEFANIE FRANCESCA RUSSO Psicologa psicoterapeuta ad indirizzo integrato Supporto psicologico \u2013 psicoterapia per preadolescenti \u2013 adolescenti \u2013 adulti \u2013 coppia  ELISA SACCO Tutor dsa e bes, educatrice \u2060Strategie di studio personalizzate \u2013 mediazione tra scuola e famiglia \u2013 \u2060\u2060tecniche di apprendimento \u2013 \u2060\u2060supporto emotivo \u2013 \u2060\u2060gestione dei compito con supporto di strumenti compensativi \u2013 \u2060\u2060visione del pdp  DANIELA SQUIZZATO Ostetrica Per rieducazione Perineale specializzata nel trattamento delle disfunzioni pelviche come: dolore sessuale e perineale, vulvodinia, incontinenza, prolasso  STEFANIA SPAN\u00d2 Neuropsicomotricista Terapista della Neuro e Psicomotricit\u00e0 dell\u2019Et\u00e0 Evolutiva  ANDRE\u00c8 MARTINA ZANIRATO Biologa nutrizionista    neuropsicomotricista, neuropsicomotricit\u00e0, psicomotricista, psicomotricit\u00e0, chinesiologa, chinesiologo, chinesiologi, massoterapista, massoterapia, massoterapisti, osteopata adulti, osteopata gravidanza, osteopata neonati, osteopata, osteopati, osteopatia, ostetrica per rieducazione perineale, dietista, dietisti, nutrizione, nutrizionisti, psicologa, psicologia, psicologi, naturopata, naturopati, naturopatia, Biologa nutrizionista, Biologi nutrizionisti,\" \/>\n<meta property=\"og:url\" content=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/abbraccio-23\/\" \/>\n<meta property=\"og:site_name\" content=\"Cral Policlinico di Milano\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-25T09:27:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/07\/Logo-Drssa-Sara-EvangelistaAbbraccio-23.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/abbraccio-23\/\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/abbraccio-23\/\",\"name\":\"Abbraccio 23 - Cral Policlinico di Milano\",\"isPartOf\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/abbraccio-23\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/abbraccio-23\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/07\/Logo-Drssa-Sara-EvangelistaAbbraccio-23.jpg\",\"datePublished\":\"2025-07-16T14:01:09+00:00\",\"dateModified\":\"2026-02-25T09:27:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/abbraccio-23\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/abbraccio-23\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/abbraccio-23\/#primaryimage\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/07\/Logo-Drssa-Sara-EvangelistaAbbraccio-23.jpg\",\"contentUrl\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/07\/Logo-Drssa-Sara-EvangelistaAbbraccio-23.jpg\",\"width\":300,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/abbraccio-23\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/negozio\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Abbraccio 23\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/#website\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/\",\"name\":\"Cral Policlinico di Milano\",\"description\":\"Area Convenzioni\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Abbraccio 23 - Cral Policlinico di Milano","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/abbraccio-23\/","og_locale":"it_IT","og_type":"article","og_title":"Abbraccio 23 - Cral Policlinico di Milano","og_description":"UNO STUDIO PROFESSIONALE ACCOGLIENTE CHE ABBRACCIA TUTTE LE ET\u00c0 E ACCOMPAGNA OGNI PERSONA NEL PROPRIO PERCORSO CON LA PROFESSIONALIT\u00c0 DEL SUO STAFF  in Abbraccio 23 trovi\u2026  NEUROPSICOMOTRICISTA PSICOMOTRICISTA CHINESIOLOGA MASSOTERAPISTA OSTEOPATA ADULTI OSTEOPATA GRAVIDANZA E NEONATI OSTETRICA PER RIEDUCAZIONE PERINEALE DIETISTA PSICOLOGA NATUROPATA  CHI SIAMO  ELENA BACCHIEGA  Dopo il percorso di formazione in scienze infermieristiche conseguo la specializzazione in ostetricia presso gli Istituti Clinici di Perfezionamento Mangiagalli di Milano.  Per 13 anni ho svolto la mia attivit\u00e0 presso la sala parto dell\u2019ospedale di Gallarate, nell\u2019assistenza diretta al travaglio e al parto.  Da oltre 15 anni sono libera professionista e conduco il \u201cpercorso nascita\u201d, accompagnando le future mamme e pap\u00e0 nei corsi di preparazione alla nascita, offrendo inoltre sostegno e consulenza specialistica personalizzata dopo il parto.  I servizi di Elena \u2013 ostetrica  Corsi di accompagnamento alla nascita per mamme e pap\u00e0 Consulenza allattamento Gruppi post nascita a sostegno della genitorialit\u00e0 Corsi di massaggio neonatale Corsi di acquaticit\u00e0 in gravidanza Corsi di Elena  SARA EVANGELISTA  Laureata in Scienze dell\u2019Educazione, lavoro da anni sulle problematiche educative della famiglia, della scuola, del lavoro e della comunit\u00e0.  Accompagno i genitori nell\u2019educazione dei figli, valorizzando i ruoli educativi della mamma e del pap\u00e0 e aiutando i bambini nel riconoscere, comprendere e rielaborare le emozioni.  Intervengo sulle pratiche educative e aiuto a riflettere su cosa fare, a rileggere le situazioni ed individuare i percorsi operativi.  I servizi di Sara \u2013 pedagogista  Consulenza pedagogica Percorsi di sostegno emotivo per bambini Consulenza per mediazione familiare e di coppia Corsi mamma bis Serate tematiche a sostegno della genitorialit\u00e0  LO STAFF  ALESSANDRO ARIOLI Osteopata Osteopata con approccio manuale e centrato sulla persona. Mi occupo di dolore muscolo-scheletrico e viscerale, valutazione posturale, prevenzione e recupero da infortuni, riabilitazione funzionale e supporto in ambiti come la gravidanza, l\u2019et\u00e0 pediatrica e lo sport.  LAURA CASATI Insegnante di yoga certificato Appassionata di benessere psicofisico, offro lezioni di yoga private e di gruppo per condividere i benefici di questa antica pratica.  LUCA CASTELNUOVO Fisioterapista e Osteopata Osteopata e fisioterapista esperto in terapia manuale e osteopatia Terapia manuale con visione osteopatica, Esercizio terapeutico, Riabilitazione ortopedica, neurologica e respiratoria post covid, Tecarterapia, kinesiotape  JENNIFER CETRANGOLO Chinesiologia Personal Trainer Ginnastica in gravidanza Ginnastica Posturale Dimagrimento  VALENTINA CONTINI Massoterapista Trattamenti terapeutici anche con la \u201ctecarterapia\u201d Trattamenti: Massoterapia, Massaggio decontratturante, Massaggio drenante, Massaggio linfodrenante, Tecarterapia, Kinesiotaping, Bendaggi funzionali, Massaggio sportivo, Pancafit, Ginnastica posturale  FRANCESCA LAURIELLO Psicologa a indirizzo sistemico relazionale offro percorsi di sostegno psicologico ad adolescenti, adulti, coppie, genitori e famiglia.  SARA MACULAN Riflessologia plantare Consulenza Riflessologia Plantare metodo R.M.D.S Consulenza Olistica(lettura iride e riflessologia plantare) Auricoloterapia Consulenza Floriterapica (Fiori Bach e Bush Flower) Consulenza iridologica Consulenza tecnica metamorfica Trattamento Reiki metodo Usui Lettura Tema Natale numerologico  JOHANA RENTERIA MAMANI Operatrice Olistica specializzata in tecniche di massaggio Massaggio Olistico Rilassante, Back Massage, Massaggio Plantare, Massaggio Drenante, Massaggio Indiano, Flower Massage (Massaggio con i Fiori di Bach), Massaggio Aromaterapico (Massaggio con Oli Essenziali), Coppettazione  MARZIA MARCON Psicomotricista ideazione, progettazione e conduzione di percorsi di psicomotricit\u00e0 in ambito educativo, preventivo e di aiuto, in piccoli gruppi e individuali. Ideazione e conduzione percorsi genitori-bambino  ASTRA MICHETTI Psicomotricista psicomotricit\u00e0 in ambito preventivo, educativo, d\u2019aiuto: percorsi individuali e di gruppo. Percorsi mamma-bambino  STEFANIE FRANCESCA RUSSO Psicologa psicoterapeuta ad indirizzo integrato Supporto psicologico \u2013 psicoterapia per preadolescenti \u2013 adolescenti \u2013 adulti \u2013 coppia  ELISA SACCO Tutor dsa e bes, educatrice \u2060Strategie di studio personalizzate \u2013 mediazione tra scuola e famiglia \u2013 \u2060\u2060tecniche di apprendimento \u2013 \u2060\u2060supporto emotivo \u2013 \u2060\u2060gestione dei compito con supporto di strumenti compensativi \u2013 \u2060\u2060visione del pdp  DANIELA SQUIZZATO Ostetrica Per rieducazione Perineale specializzata nel trattamento delle disfunzioni pelviche come: dolore sessuale e perineale, vulvodinia, incontinenza, prolasso  STEFANIA SPAN\u00d2 Neuropsicomotricista Terapista della Neuro e Psicomotricit\u00e0 dell\u2019Et\u00e0 Evolutiva  ANDRE\u00c8 MARTINA ZANIRATO Biologa nutrizionista    neuropsicomotricista, neuropsicomotricit\u00e0, psicomotricista, psicomotricit\u00e0, chinesiologa, chinesiologo, chinesiologi, massoterapista, massoterapia, massoterapisti, osteopata adulti, osteopata gravidanza, osteopata neonati, osteopata, osteopati, osteopatia, ostetrica per rieducazione perineale, dietista, dietisti, nutrizione, nutrizionisti, psicologa, psicologia, psicologi, naturopata, naturopati, naturopatia, Biologa nutrizionista, Biologi nutrizionisti,","og_url":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/abbraccio-23\/","og_site_name":"Cral Policlinico di Milano","article_modified_time":"2026-02-25T09:27:58+00:00","og_image":[{"width":300,"height":300,"url":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/07\/Logo-Drssa-Sara-EvangelistaAbbraccio-23.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"8 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/abbraccio-23\/","url":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/abbraccio-23\/","name":"Abbraccio 23 - Cral Policlinico di Milano","isPartOf":{"@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/#website"},"primaryImageOfPage":{"@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/abbraccio-23\/#primaryimage"},"image":{"@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/abbraccio-23\/#primaryimage"},"thumbnailUrl":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/07\/Logo-Drssa-Sara-EvangelistaAbbraccio-23.jpg","datePublished":"2025-07-16T14:01:09+00:00","dateModified":"2026-02-25T09:27:58+00:00","breadcrumb":{"@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/abbraccio-23\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/abbraccio-23\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/abbraccio-23\/#primaryimage","url":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/07\/Logo-Drssa-Sara-EvangelistaAbbraccio-23.jpg","contentUrl":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/07\/Logo-Drssa-Sara-EvangelistaAbbraccio-23.jpg","width":300,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/abbraccio-23\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/negozio\/"},{"@type":"ListItem","position":3,"name":"Abbraccio 23"}]},{"@type":"WebSite","@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/#website","url":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/","name":"Cral Policlinico di Milano","description":"Area Convenzioni","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/product\/21466","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/comments?post=21466"}],"version-history":[{"count":112,"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/product\/21466\/revisions"}],"predecessor-version":[{"id":28730,"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/product\/21466\/revisions\/28730"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/media\/21482"}],"wp:attachment":[{"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/media?parent=21466"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/product_brand?post=21466"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/product_cat?post=21466"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/product_tag?post=21466"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}