{"id":2040,"date":"2022-04-13T16:38:46","date_gmt":"2022-04-13T14:38:46","guid":{"rendered":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/?post_type=product&#038;p=2040"},"modified":"2022-04-13T16:49:08","modified_gmt":"2022-04-13T14:49:08","slug":"the-longevity-suite-milano-brera","status":"publish","type":"product","link":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/the-longevity-suite-milano-brera\/","title":{"rendered":"The Longevity Suite &#8211; Milano Brera"},"content":{"rendered":"","protected":true},"excerpt":{"rendered":"","protected":true},"featured_media":2004,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":""},"product_brand":[],"product_cat":[20,509],"product_tag":[360,303,513,514,371,515],"class_list":{"0":"post-2040","1":"product","2":"type-product","3":"status-publish","4":"post-password-required","6":"product_cat-benessere-e-bellezza","7":"product_cat-crioterapia","8":"product_tag-bellezza","9":"product_tag-benessere","10":"product_tag-crioterapia","11":"product_tag-equilibrio","12":"product_tag-salute","13":"product_tag-suite","15":"first","16":"instock","17":"shipping-taxable","18":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>The Longevity Suite - Milano Brera - Cral Policlinico di Milano<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/the-longevity-suite-milano-brera\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"The Longevity Suite - Milano Brera - Cral Policlinico di Milano\" \/>\n<meta property=\"og:description\" content=\"Non \u00e8 disponibile alcun riassunto in quanto si tratta di un articolo protetto.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/the-longevity-suite-milano-brera\/\" \/>\n<meta property=\"og:site_name\" content=\"Cral Policlinico di Milano\" \/>\n<meta property=\"article:modified_time\" content=\"2022-04-13T14:49:08+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/the-longevity-suite-milano-brera\/\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/the-longevity-suite-milano-brera\/\",\"name\":\"The Longevity Suite - Milano Brera - Cral Policlinico di Milano\",\"isPartOf\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/#website\"},\"datePublished\":\"2022-04-13T14:38:46+00:00\",\"dateModified\":\"2022-04-13T14:49:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/the-longevity-suite-milano-brera\/#breadcrumb\"},\"inLanguage\":\"it-IT\"},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/#website\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/\",\"name\":\"Cral Policlinico di Milano\",\"description\":\"Area Convenzioni\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"The Longevity Suite - Milano Brera - Cral Policlinico di Milano","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/the-longevity-suite-milano-brera\/","og_locale":"it_IT","og_type":"article","og_title":"The Longevity Suite - Milano Brera - Cral Policlinico di Milano","og_description":"Non \u00e8 disponibile alcun riassunto in quanto si tratta di un articolo protetto.","og_url":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/the-longevity-suite-milano-brera\/","og_site_name":"Cral Policlinico di Milano","article_modified_time":"2022-04-13T14:49:08+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"8 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/the-longevity-suite-milano-brera\/","url":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/the-longevity-suite-milano-brera\/","name":"The Longevity Suite - Milano Brera - Cral Policlinico di Milano","isPartOf":{"@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/#website"},"datePublished":"2022-04-13T14:38:46+00:00","dateModified":"2022-04-13T14:49:08+00:00","breadcrumb":{"@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/the-longevity-suite-milano-brera\/#breadcrumb"},"inLanguage":"it-IT"},{"@type":"WebSite","@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/#website","url":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/","name":"Cral Policlinico di Milano","description":"Area Convenzioni","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/product\/2040","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/comments?post=2040"}],"version-history":[{"count":0,"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/product\/2040\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/media\/2004"}],"wp:attachment":[{"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/media?parent=2040"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/product_brand?post=2040"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/product_cat?post=2040"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/product_tag?post=2040"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}