{"id":19861,"date":"2025-05-20T11:17:07","date_gmt":"2025-05-20T09:17:07","guid":{"rendered":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/?post_type=product&#038;p=19861"},"modified":"2025-05-30T11:13:06","modified_gmt":"2025-05-30T09:13:06","slug":"consulenti-finanziari-finecobank-federico-lo-bianco-e-primo-ghisi","status":"publish","type":"product","link":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/consulenti-finanziari-finecobank-federico-lo-bianco-e-primo-ghisi\/","title":{"rendered":"Consulenti finanziari Finecobank &#8211; Federico Lo Bianco e Primo Ghisi"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"19861\" class=\"elementor elementor-19861\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d785758 e-con-full e-flex e-con e-parent\" data-id=\"d785758\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-776df8c e-con-full e-flex e-con e-child\" data-id=\"776df8c\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1994e5b elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"1994e5b\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" fetchpriority=\"high\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/05\/LOGO.png\" class=\"attachment-full size-full wp-image-19869\" alt=\"\" srcset=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/05\/LOGO.png 500w, https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/05\/LOGO-480x480.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 500px, 100vw\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-65e85f8 e-con-full e-flex e-con e-child\" data-id=\"65e85f8\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0aa4d20 elementor-widget elementor-widget-spacer\" data-id=\"0aa4d20\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-63a38f0 elementor-hidden-desktop e-flex e-con-boxed e-con e-parent\" data-id=\"63a38f0\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-cee7478 e-flex e-con-boxed e-con e-child\" data-id=\"cee7478\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-70b4c59 elementor-widget elementor-widget-text-editor\" data-id=\"70b4c59\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Chi siamo<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5ac0951 elementor-widget elementor-widget-text-editor\" data-id=\"5ac0951\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Siamo Federico Lo Bianco e Primo Ghisi, consulenti finanziari Finecobank.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-85f1c8b elementor-widget elementor-widget-text-editor\" data-id=\"85f1c8b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Il nostro ruolo \u00e8 quello di affiancare i clienti nell&#8217;importante scelta relativa alla gestione del patrimonio personale e familiare, considerando prioritari aspetti quali il controllo del rischio, il rendimento, la fiscalit\u00e0, l&#8217;orizzonte temporale, la qualit\u00e0 dei prodotti e il controllo dei costi.<\/p><p>Offriamo una consulenza a 360 gradi che tocca anche tematiche quali protezione, trasferimento del patrimonio di famiglia nonch\u00e9 il passaggio generazionale e la personalizzazione degli investimenti.<\/p><p>L&#8217;obiettivo principale \u00e8 aiutare i clienti a prendere decisioni informate per ottimizzare la crescita e la protezione del proprio patrimonio finanziario.<br \/>Per noi, la fiducia e la comunicazione sono fondamentali per stabilire una relazione efficace e di lungo termine.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0299da8 elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"0299da8\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carosello d&#039;immagini\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper swiper-image-stretch\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 di 2\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/05\/Lo-Bianco.png\" alt=\"Federico Lo Bianco\" \/><figcaption class=\"elementor-image-carousel-caption\">Federico Lo Bianco<\/figcaption><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 di 2\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/05\/Ghisi.png\" alt=\"Primo Ghisi\" \/><figcaption class=\"elementor-image-carousel-caption\">Primo Ghisi<\/figcaption><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-783f2bb e-con-full e-flex e-con e-child\" data-id=\"783f2bb\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a86bde2 elementor-widget elementor-widget-text-editor\" data-id=\"a86bde2\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Servizi offerti<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4180465 elementor-widget elementor-widget-text-editor\" data-id=\"4180465\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u2022 Investimenti finanziari a 360 gradi (fondi, ETF, obbligazioni, certificati ecc.)<br \/>\u2022 Investimenti assicurativi<br \/>\u2022 Fondi Pensione<br \/>\u2022 Diagnosi di portafogli presso altri istituti<br \/>\u2022 Supporto nel passaggio generazionale<br \/>\u2022 Conti correnti e mutui<br \/>\u2022 Gestione liquidit\u00e0<br \/>\u2022 Possibilit\u00e0 di appuntamenti fuori sede<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-fe467b3 elementor-hidden-tablet elementor-hidden-mobile e-flex e-con-boxed e-con e-parent\" data-id=\"fe467b3\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-03ff3fa e-con-full e-flex e-con e-child\" data-id=\"03ff3fa\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7db54d0 elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"7db54d0\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carosello d&#039;immagini\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper swiper-image-stretch\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 di 2\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/05\/Lo-Bianco.png\" alt=\"Federico Lo Bianco\" \/><figcaption class=\"elementor-image-carousel-caption\">Federico Lo Bianco<\/figcaption><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 di 2\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/05\/Ghisi.png\" alt=\"Primo Ghisi\" \/><figcaption class=\"elementor-image-carousel-caption\">Primo Ghisi<\/figcaption><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1dd972c e-con-full e-flex e-con e-child\" data-id=\"1dd972c\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-77d9142 elementor-widget elementor-widget-text-editor\" data-id=\"77d9142\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Chi siamo<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-262ba89 elementor-widget elementor-widget-text-editor\" data-id=\"262ba89\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Siamo Federico Lo Bianco e Primo Ghisi, consulenti finanziari Finecobank.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5e58d01 elementor-widget elementor-widget-text-editor\" data-id=\"5e58d01\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Il nostro ruolo \u00e8 quello di affiancare i clienti nell&#8217;importante scelta relativa alla gestione del patrimonio personale e familiare, considerando prioritari aspetti quali il controllo del rischio, il rendimento, la fiscalit\u00e0, l&#8217;orizzonte temporale, la qualit\u00e0 dei prodotti e il controllo dei costi.<\/p><p>Offriamo una consulenza a 360 gradi che tocca anche tematiche quali protezione, trasferimento del patrimonio di famiglia nonch\u00e9 il passaggio generazionale e la personalizzazione degli investimenti.<\/p><p>L&#8217;obiettivo principale \u00e8 aiutare i clienti a prendere decisioni informate per ottimizzare la crescita e la protezione del proprio patrimonio finanziario.<br \/>Per noi, la fiducia e la comunicazione sono fondamentali per stabilire una relazione efficace e di lungo termine.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-91488bd e-con-full e-flex e-con e-child\" data-id=\"91488bd\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fe94fe6 elementor-widget elementor-widget-text-editor\" data-id=\"fe94fe6\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Servizi offerti<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1a4048e elementor-widget elementor-widget-text-editor\" data-id=\"1a4048e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u2022 Investimenti finanziari a 360 gradi (fondi, ETF, obbligazioni, certificati ecc.)<br \/>\u2022 Investimenti assicurativi<br \/>\u2022 Fondi Pensione<br \/>\u2022 Diagnosi di portafogli presso altri istituti<br \/>\u2022 Supporto nel passaggio generazionale<br \/>\u2022 Conti correnti e mutui<br \/>\u2022 Gestione liquidit\u00e0<br \/>\u2022 Possibilit\u00e0 di appuntamenti fuori sede<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1f15f4c5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1f15f4c5\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6da671c9\" data-id=\"6da671c9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-13b734d7 elementor-widget elementor-widget-text-editor\" data-id=\"13b734d7\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Agevolazioni riservate agli associati<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-912cb21 elementor-hidden-desktop e-flex e-con-boxed e-con e-parent\" data-id=\"912cb21\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-f72f990 e-flex e-con-boxed e-con e-child\" data-id=\"f72f990\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-86ef75d elementor-widget elementor-widget-text-editor\" data-id=\"86ef75d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>contatti<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4525d75 elementor-widget elementor-widget-text-editor\" data-id=\"4525d75\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong><span style=\"color: #333333;\">C.so Garibaldi, 86 &#8211; 20121 Milano<\/span><\/strong><\/p><p><span style=\"color: #0033a7;\"><strong>Federico Lo Bianco<\/strong><\/span><br \/><span style=\"color: #333333;\"><strong>Cell: <\/strong><a style=\"color: #333333;\" href=\"tel:+393315358893\">331 5358893<\/a><\/span><br \/><span style=\"color: #333333;\"><strong>Mail: <\/strong><a style=\"color: #333333;\" href=\"mailto:federico.lobianco@pfafineco.it\">federico.lobianco@pfafineco.it<\/a><\/span><br \/><span style=\"color: #333333;\"><strong>Sito web: <\/strong><a style=\"color: #333333;\" href=\"https:\/\/federicolobianco.consulentefinecobank.com\/\">federicolobianco.consulentefinecobank.com<\/a><\/span><\/p><p><span style=\"color: #0033a7;\"><strong>Primo Ghisi<\/strong><\/span><br \/><span style=\"color: #333333;\"><strong>Cell: <\/strong><a style=\"color: #333333;\" href=\"tel:+393384390614\">338 4390614<\/a><\/span><br \/><span style=\"color: #333333;\"><strong>Mail: <\/strong><a style=\"color: #333333;\" href=\"mailto:primo.ghisi@pfafineco.it\">primo.ghisi@pfafineco.it<\/a><\/span><br \/><span style=\"color: #333333;\"><strong>Sito web: <\/strong><a style=\"color: #333333;\" href=\"https:\/\/primoghisi.consulentefinecobank.com\/\">primoghisi.consulentefinecobank.com<\/a><\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e6ab767 elementor-shape-circle e-grid-align-left elementor-grid-0 elementor-widget elementor-widget-social-icons\" data-id=\"e6ab767\" data-element_type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-instagram elementor-repeater-item-1539373\" href=\"https:\/\/www.instagram.com\/federico.lobianco_pfa\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Instagram<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-instagram\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.1 141c-63.6 0-114.9 51.3-114.9 114.9s51.3 114.9 114.9 114.9S339 319.5 339 255.9 287.7 141 224.1 141zm0 189.6c-41.1 0-74.7-33.5-74.7-74.7s33.5-74.7 74.7-74.7 74.7 33.5 74.7 74.7-33.6 74.7-74.7 74.7zm146.4-194.3c0 14.9-12 26.8-26.8 26.8-14.9 0-26.8-12-26.8-26.8s12-26.8 26.8-26.8 26.8 12 26.8 26.8zm76.1 27.2c-1.7-35.9-9.9-67.7-36.2-93.9-26.2-26.2-58-34.4-93.9-36.2-37-2.1-147.9-2.1-184.9 0-35.8 1.7-67.6 9.9-93.9 36.1s-34.4 58-36.2 93.9c-2.1 37-2.1 147.9 0 184.9 1.7 35.9 9.9 67.7 36.2 93.9s58 34.4 93.9 36.2c37 2.1 147.9 2.1 184.9 0 35.9-1.7 67.7-9.9 93.9-36.2 26.2-26.2 34.4-58 36.2-93.9 2.1-37 2.1-147.8 0-184.8zM398.8 388c-7.8 19.6-22.9 34.7-42.6 42.6-29.5 11.7-99.5 9-132.1 9s-102.7 2.6-132.1-9c-19.6-7.8-34.7-22.9-42.6-42.6-11.7-29.5-9-99.5-9-132.1s-2.6-102.7 9-132.1c7.8-19.6 22.9-34.7 42.6-42.6 29.5-11.7 99.5-9 132.1-9s102.7-2.6 132.1 9c19.6 7.8 34.7 22.9 42.6 42.6 11.7 29.5 9 99.5 9 132.1s2.7 102.7-9 132.1z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-linkedin elementor-repeater-item-8e0ca5f\" href=\"http:\/\/www.linkedin.com\/in\/federicolobianco\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Linkedin<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-linkedin\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 32H31.9C14.3 32 0 46.5 0 64.3v383.4C0 465.5 14.3 480 31.9 480H416c17.6 0 32-14.5 32-32.3V64.3c0-17.8-14.4-32.3-32-32.3zM135.4 416H69V202.2h66.5V416zm-33.2-243c-21.3 0-38.5-17.3-38.5-38.5S80.9 96 102.2 96c21.2 0 38.5 17.3 38.5 38.5 0 21.3-17.2 38.5-38.5 38.5zm282.1 243h-66.4V312c0-24.8-.5-56.7-34.5-56.7-34.6 0-39.9 27-39.9 54.9V416h-66.4V202.2h63.7v29.2h.9c8.9-16.8 30.6-34.5 62.9-34.5 67.2 0 79.7 44.3 79.7 101.9V416z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bb6a9ec elementor-widget elementor-widget-text-editor\" data-id=\"bb6a9ec\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><div id=\"gmw-single-location-wrapper-394\" class=\"gmw-element-wrapper gmw-single-location-wrapper gmw-sl-wrapper gmw-sl-single-post-wrapper post \" object_type=\"post\" object_id=\"19861\"  style=\"width:100%\"><div class=\"gmw-sl-map-wrapper gmw-sl-element\"><div id=\"gmw-map-wrapper-394\" class=\"gmw-map-wrapper  sl single_location \" style=\"width:100%;height:300px;\"> <span id=\"gmw-resize-map-toggle-394\" class=\"gmw-resize-map-toggle gmw-icon-resize-full\" style=\"display:none;\" title=\"Resize map\"><\/span> <div id=\"gmw-map-loader-394\" class=\"gmw-map-loader\"><\/div> <div id=\"gmw-map-394\" class=\"gmw-map sl single_location\" style=\"width:100%; height:100%\" data-map_id=\"394\" data-prefix=\"sl\" data-map_type=\"single_location\" data-icons_usage=\"global\"><\/div> <\/div><\/div><\/div><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6e9d425 elementor-hidden-tablet elementor-hidden-mobile e-flex e-con-boxed e-con e-parent\" data-id=\"6e9d425\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-4229adc e-con-full e-flex e-con e-child\" data-id=\"4229adc\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-62eda89 elementor-widget elementor-widget-text-editor\" data-id=\"62eda89\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>contatti<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-487d56d elementor-widget elementor-widget-text-editor\" data-id=\"487d56d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong><span style=\"color: #333333;\">C.so Garibaldi, 86 &#8211; 20121 Milano<\/span><\/strong><\/p><p><span style=\"color: #0033a7;\"><strong>Federico Lo Bianco<\/strong><\/span><br \/><span style=\"color: #333333;\"><strong>Cell: <\/strong><a style=\"color: #333333;\" href=\"tel:+393315358893\">331 5358893<\/a><\/span><br \/><span style=\"color: #333333;\"><strong>Mail: <\/strong><a style=\"color: #333333;\" href=\"mailto:federico.lobianco@pfafineco.it\">federico.lobianco@pfafineco.it<\/a><\/span><br \/><span style=\"color: #333333;\"><strong>Sito web: <\/strong><a style=\"color: #333333;\" href=\"https:\/\/federicolobianco.consulentefinecobank.com\/\">federicolobianco.consulentefinecobank.com<\/a><\/span><\/p><p><span style=\"color: #0033a7;\"><strong>Primo Ghisi<\/strong><\/span><br \/><span style=\"color: #333333;\"><strong>Cell: <\/strong><a style=\"color: #333333;\" href=\"tel:+393384390614\">338 4390614<\/a><\/span><br \/><span style=\"color: #333333;\"><strong>Mail: <\/strong><a style=\"color: #333333;\" href=\"mailto:primo.ghisi@pfafineco.it\">primo.ghisi@pfafineco.it<\/a><\/span><br \/><span style=\"color: #333333;\"><strong>Sito web: <\/strong><a style=\"color: #333333;\" href=\"https:\/\/primoghisi.consulentefinecobank.com\/\">primoghisi.consulentefinecobank.com<\/a><\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6223569 elementor-shape-circle e-grid-align-left elementor-grid-0 elementor-widget elementor-widget-social-icons\" data-id=\"6223569\" data-element_type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-instagram elementor-repeater-item-1539373\" href=\"https:\/\/www.instagram.com\/federico.lobianco_pfa\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Instagram<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-instagram\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.1 141c-63.6 0-114.9 51.3-114.9 114.9s51.3 114.9 114.9 114.9S339 319.5 339 255.9 287.7 141 224.1 141zm0 189.6c-41.1 0-74.7-33.5-74.7-74.7s33.5-74.7 74.7-74.7 74.7 33.5 74.7 74.7-33.6 74.7-74.7 74.7zm146.4-194.3c0 14.9-12 26.8-26.8 26.8-14.9 0-26.8-12-26.8-26.8s12-26.8 26.8-26.8 26.8 12 26.8 26.8zm76.1 27.2c-1.7-35.9-9.9-67.7-36.2-93.9-26.2-26.2-58-34.4-93.9-36.2-37-2.1-147.9-2.1-184.9 0-35.8 1.7-67.6 9.9-93.9 36.1s-34.4 58-36.2 93.9c-2.1 37-2.1 147.9 0 184.9 1.7 35.9 9.9 67.7 36.2 93.9s58 34.4 93.9 36.2c37 2.1 147.9 2.1 184.9 0 35.9-1.7 67.7-9.9 93.9-36.2 26.2-26.2 34.4-58 36.2-93.9 2.1-37 2.1-147.8 0-184.8zM398.8 388c-7.8 19.6-22.9 34.7-42.6 42.6-29.5 11.7-99.5 9-132.1 9s-102.7 2.6-132.1-9c-19.6-7.8-34.7-22.9-42.6-42.6-11.7-29.5-9-99.5-9-132.1s-2.6-102.7 9-132.1c7.8-19.6 22.9-34.7 42.6-42.6 29.5-11.7 99.5-9 132.1-9s102.7-2.6 132.1 9c19.6 7.8 34.7 22.9 42.6 42.6 11.7 29.5 9 99.5 9 132.1s2.7 102.7-9 132.1z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-linkedin elementor-repeater-item-8e0ca5f\" href=\"http:\/\/www.linkedin.com\/in\/federicolobianco\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Linkedin<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-linkedin\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 32H31.9C14.3 32 0 46.5 0 64.3v383.4C0 465.5 14.3 480 31.9 480H416c17.6 0 32-14.5 32-32.3V64.3c0-17.8-14.4-32.3-32-32.3zM135.4 416H69V202.2h66.5V416zm-33.2-243c-21.3 0-38.5-17.3-38.5-38.5S80.9 96 102.2 96c21.2 0 38.5 17.3 38.5 38.5 0 21.3-17.2 38.5-38.5 38.5zm282.1 243h-66.4V312c0-24.8-.5-56.7-34.5-56.7-34.6 0-39.9 27-39.9 54.9V416h-66.4V202.2h63.7v29.2h.9c8.9-16.8 30.6-34.5 62.9-34.5 67.2 0 79.7 44.3 79.7 101.9V416z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-32605c3 e-con-full e-flex e-con e-child\" data-id=\"32605c3\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3789fec elementor-widget elementor-widget-text-editor\" data-id=\"3789fec\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><div id=\"gmw-single-location-wrapper-342\" class=\"gmw-element-wrapper gmw-single-location-wrapper gmw-sl-wrapper gmw-sl-single-post-wrapper post \" object_type=\"post\" object_id=\"19861\"  style=\"width:100%\"><div class=\"gmw-sl-map-wrapper gmw-sl-element\"><div id=\"gmw-map-wrapper-342\" class=\"gmw-map-wrapper  sl single_location \" style=\"width:100%;height:300px;\"> <span id=\"gmw-resize-map-toggle-342\" class=\"gmw-resize-map-toggle gmw-icon-resize-full\" style=\"display:none;\" title=\"Resize map\"><\/span> <div id=\"gmw-map-loader-342\" class=\"gmw-map-loader\"><\/div> <div id=\"gmw-map-342\" class=\"gmw-map sl single_location\" style=\"width:100%; height:100%\" data-map_id=\"342\" data-prefix=\"sl\" data-map_type=\"single_location\" data-icons_usage=\"global\"><\/div> <\/div><\/div><\/div><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-46dc042 elementor-section-content-middle elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"46dc042\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-4a6b5be7\" data-id=\"4a6b5be7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3b84fbe6 elementor-widget elementor-widget-text-editor\" data-id=\"3b84fbe6\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tContatti\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-12c8c40f elementor-shape-circle e-grid-align-left elementor-grid-0 elementor-widget elementor-widget-social-icons\" data-id=\"12c8c40f\" data-element_type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-facebook elementor-repeater-item-1539373\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Facebook<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-facebook\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M504 256C504 119 393 8 256 8S8 119 8 256c0 123.78 90.69 226.38 209.25 245V327.69h-63V256h63v-54.64c0-62.15 37-96.48 93.67-96.48 27.14 0 55.52 4.84 55.52 4.84v61h-31.28c-30.8 0-40.41 19.12-40.41 38.73V256h68.78l-11 71.69h-57.78V501C413.31 482.38 504 379.78 504 256z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-twitter elementor-repeater-item-8913cb9\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Twitter<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-twitter\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M459.37 151.716c.325 4.548.325 9.097.325 13.645 0 138.72-105.583 298.558-298.558 298.558-59.452 0-114.68-17.219-161.137-47.106 8.447.974 16.568 1.299 25.34 1.299 49.055 0 94.213-16.568 130.274-44.832-46.132-.975-84.792-31.188-98.112-72.772 6.498.974 12.995 1.624 19.818 1.624 9.421 0 18.843-1.3 27.614-3.573-48.081-9.747-84.143-51.98-84.143-102.985v-1.299c13.969 7.797 30.214 12.67 47.431 13.319-28.264-18.843-46.781-51.005-46.781-87.391 0-19.492 5.197-37.36 14.294-52.954 51.655 63.675 129.3 105.258 216.365 109.807-1.624-7.797-2.599-15.918-2.599-24.04 0-57.828 46.782-104.934 104.934-104.934 30.213 0 57.502 12.67 76.67 33.137 23.715-4.548 46.456-13.32 66.599-25.34-7.798 24.366-24.366 44.833-46.132 57.827 21.117-2.273 41.584-8.122 60.426-16.243-14.292 20.791-32.161 39.308-52.628 54.253z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-youtube elementor-repeater-item-3255c55\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Youtube<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-youtube\" viewBox=\"0 0 576 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M549.655 124.083c-6.281-23.65-24.787-42.276-48.284-48.597C458.781 64 288 64 288 64S117.22 64 74.629 75.486c-23.497 6.322-42.003 24.947-48.284 48.597-11.412 42.867-11.412 132.305-11.412 132.305s0 89.438 11.412 132.305c6.281 23.65 24.787 41.5 48.284 47.821C117.22 448 288 448 288 448s170.78 0 213.371-11.486c23.497-6.321 42.003-24.171 48.284-47.821 11.412-42.867 11.412-132.305 11.412-132.305s0-89.438-11.412-132.305zm-317.51 213.508V175.185l142.739 81.205-142.739 81.201z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1e792bce\" data-id=\"1e792bce\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-779134a elementor-widget elementor-widget-text-editor\" data-id=\"779134a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div id=\"gmw-single-location-wrapper-252\" class=\"gmw-element-wrapper gmw-single-location-wrapper gmw-sl-wrapper gmw-sl-single-post-wrapper post \" object_type=\"post\" object_id=\"19861\"  style=\"width:100%\"><div class=\"gmw-sl-map-wrapper gmw-sl-element\"><div id=\"gmw-map-wrapper-252\" class=\"gmw-map-wrapper  sl single_location \" style=\"width:100%;height:300px;\"> <span id=\"gmw-resize-map-toggle-252\" class=\"gmw-resize-map-toggle gmw-icon-resize-full\" style=\"display:none;\" title=\"Resize map\"><\/span> <div id=\"gmw-map-loader-252\" class=\"gmw-map-loader\"><\/div> <div id=\"gmw-map-252\" class=\"gmw-map sl single_location\" style=\"width:100%; height:100%\" data-map_id=\"252\" data-prefix=\"sl\" data-map_type=\"single_location\" data-icons_usage=\"global\"><\/div> <\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-522b0d36 elementor-widget elementor-widget-text-editor\" data-id=\"522b0d36\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><div id=\"gmw-single-object-locations-wrapper-158\" class=\"gmw-element-wrapper gmw-single-location-wrapper gmw-sl-wrapper gmw-sl-single-post-wrapper post gmw-sl-multiple-locations\" object_type=\"post\" object_id=\"\"  style=\"width:100%\"><div class=\"gmw-sl-map-wrapper\"><div id=\"gmw-map-wrapper-158\" class=\"gmw-map-wrapper  sl single_location \" style=\"width:100%;height:350px;\"> <span id=\"gmw-resize-map-toggle-158\" class=\"gmw-resize-map-toggle gmw-icon-resize-full\" style=\"display:none;\" title=\"Resize map\"><\/span> <div id=\"gmw-map-loader-158\" class=\"gmw-map-loader\"><\/div> <div id=\"gmw-map-158\" class=\"gmw-map sl single_location\" style=\"width:100%; height:100%\" data-map_id=\"158\" data-prefix=\"sl\" data-map_type=\"single_location\" data-icons_usage=\"global\"><\/div> <\/div><\/div><\/div><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<div style= \"display: none\">\n<p>Siamo Federico Lo Bianco e Primo Ghisi, consulenti finanziari Finecobank. Il nostro ruolo \u00e8 quello di affiancare i clienti nell&#8217;importante scelta relativa alla gestione del patrimonio personale e familiare, considerando prioritari aspetti quali il controllo del rischio, il rendimento, la fiscalit\u00e0, l&#8217;orizzonte temporale, la qualit\u00e0 dei prodotti e il controllo dei costi.<br \/>\nOffriamo una consulenza a 360 gradi che tocca anche tematiche quali protezione, trasferimento del patrimonio di famiglia nonch\u00e9 il passaggio generazionale e la personalizzazione degli investimenti. L&#8217;obiettivo principale \u00e8 aiutare i clienti a prendere decisioni informate per ottimizzare la crescita e la protezione del proprio patrimonio finanziario.<br \/>\nPer noi, la fiducia e la comunicazione sono fondamentali per stabilire una relazione efficace e di lungo termine.<br \/>\n\u2022 Servizi offerti:<br \/>\nInvestimenti finanziari a 360 gradi (fondi, ETF, obbligazioni, certificati ecc.)<br \/>\nInvestimenti assicurativi<br \/>\nFondi Pensione<br \/>\nDiagnosi di portafogli presso altri istituti<br \/>\nSupporto nel passaggio generazionale<br \/>\nConti correnti e mutui<br \/>\nGestione liquidit\u00e0<br \/>\nPossibilit\u00e0 di appuntamenti fuori sede<\/p>\n<p>consulenti finanziari, consulente finanziario, consulenza finanziaria, investimenti, investimento, patrimonio finanziario, protezione del patrimonio, Investimenti finanziari, Investimenti assicurativi, Fondi Pensione, Diagnosi di portafogli, Supporto nel passaggio generazionale, Conti correnti, mutui, Gestione liquidit\u00e0, investire<\/p>\n<p>consulenti finanziari a Milano, consulente finanziario a Milano, consulenza finanziaria a Milano, investimenti a Milano, investimento a Milano, patrimonio finanziario a Milano, protezione del patrimonio a Milano, Investimenti finanziari a Milano, Investimenti assicurativi a Milano, Fondi Pensione a Milano, Diagnosi di portafogli a Milano, Supporto nel passaggio generazionale a Milano, Conti correnti a Milano, mutui a Milano, Gestione liquidit\u00e0 a Milano, investire a Milano<\/p>\n<\/div>\n","protected":false},"featured_media":19862,"comment_status":"open","ping_status":"closed","template":"elementor_header_footer","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":""},"product_brand":[],"product_cat":[88,22],"product_tag":[430,432,1114,1177,4039,3337,4041,1068,4038,4037,1069,4042,747,4035,4036,4040],"class_list":{"0":"post-19861","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-consulenti-finanziari-e-patrimoniali","7":"product_cat-finanza-assicurazioni","8":"product_tag-consulente-finanziario","9":"product_tag-consulenti-finanziari","10":"product_tag-consulenza-finanziaria","11":"product_tag-conti-correnti","12":"product_tag-diagnosi-di-portafogli","13":"product_tag-fondi-pensione","14":"product_tag-gestione-liquidita","15":"product_tag-investimenti","16":"product_tag-investimenti-assicurativi","17":"product_tag-investimenti-finanziari","18":"product_tag-investimento","19":"product_tag-investire","20":"product_tag-mutui","21":"product_tag-patrimonio-finanziario","22":"product_tag-protezione-del-patrimonio","23":"product_tag-supporto-nel-passaggio-generazionale","25":"first","26":"instock","27":"shipping-taxable","28":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Consulenti finanziari Finecobank - Federico Lo Bianco e Primo Ghisi - Cral Policlinico di Milano<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/consulenti-finanziari-finecobank-federico-lo-bianco-e-primo-ghisi\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Consulenti finanziari Finecobank - Federico Lo Bianco e Primo Ghisi - Cral Policlinico di Milano\" \/>\n<meta property=\"og:description\" content=\"Siamo Federico Lo Bianco e Primo Ghisi, consulenti finanziari Finecobank. Il nostro ruolo \u00e8 quello di affiancare i clienti nell&#039;importante scelta relativa alla gestione del patrimonio personale e familiare, considerando prioritari aspetti quali il controllo del rischio, il rendimento, la fiscalit\u00e0, l&#039;orizzonte temporale, la qualit\u00e0 dei prodotti e il controllo dei costi. Offriamo una consulenza a 360 gradi che tocca anche tematiche quali protezione, trasferimento del patrimonio di famiglia nonch\u00e9 il passaggio generazionale e la personalizzazione degli investimenti. L&#039;obiettivo principale \u00e8 aiutare i clienti a prendere decisioni informate per ottimizzare la crescita e la protezione del proprio patrimonio finanziario. Per noi, la fiducia e la comunicazione sono fondamentali per stabilire una relazione efficace e di lungo termine. \u2022 Servizi offerti: Investimenti finanziari a 360 gradi (fondi, ETF, obbligazioni, certificati ecc.) Investimenti assicurativi Fondi Pensione Diagnosi di portafogli presso altri istituti Supporto nel passaggio generazionale Conti correnti e mutui Gestione liquidit\u00e0 Possibilit\u00e0 di appuntamenti fuori sede    consulenti finanziari, consulente finanziario, consulenza finanziaria, investimenti, investimento, patrimonio finanziario, protezione del patrimonio, Investimenti finanziari, Investimenti assicurativi, Fondi Pensione, Diagnosi di portafogli, Supporto nel passaggio generazionale, Conti correnti, mutui, Gestione liquidit\u00e0, investire    consulenti finanziari a Milano, consulente finanziario a Milano, consulenza finanziaria a Milano, investimenti a Milano, investimento a Milano, patrimonio finanziario a Milano, protezione del patrimonio a Milano, Investimenti finanziari a Milano, Investimenti assicurativi a Milano, Fondi Pensione a Milano, Diagnosi di portafogli a Milano, Supporto nel passaggio generazionale a Milano, Conti correnti a Milano, mutui a Milano, Gestione liquidit\u00e0 a Milano, investire a Milano\" \/>\n<meta property=\"og:url\" content=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/consulenti-finanziari-finecobank-federico-lo-bianco-e-primo-ghisi\/\" \/>\n<meta property=\"og:site_name\" content=\"Cral Policlinico di Milano\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-30T09:13:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/05\/logo_Federico-Lo-Bianco-e-Primo-Ghisi.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/consulenti-finanziari-finecobank-federico-lo-bianco-e-primo-ghisi\/\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/consulenti-finanziari-finecobank-federico-lo-bianco-e-primo-ghisi\/\",\"name\":\"Consulenti finanziari Finecobank - Federico Lo Bianco e Primo Ghisi - Cral Policlinico di Milano\",\"isPartOf\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/consulenti-finanziari-finecobank-federico-lo-bianco-e-primo-ghisi\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/consulenti-finanziari-finecobank-federico-lo-bianco-e-primo-ghisi\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/05\/logo_Federico-Lo-Bianco-e-Primo-Ghisi.jpg\",\"datePublished\":\"2025-05-20T09:17:07+00:00\",\"dateModified\":\"2025-05-30T09:13:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/consulenti-finanziari-finecobank-federico-lo-bianco-e-primo-ghisi\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/consulenti-finanziari-finecobank-federico-lo-bianco-e-primo-ghisi\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/consulenti-finanziari-finecobank-federico-lo-bianco-e-primo-ghisi\/#primaryimage\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/05\/logo_Federico-Lo-Bianco-e-Primo-Ghisi.jpg\",\"contentUrl\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/05\/logo_Federico-Lo-Bianco-e-Primo-Ghisi.jpg\",\"width\":300,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/consulenti-finanziari-finecobank-federico-lo-bianco-e-primo-ghisi\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/negozio\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Consulenti finanziari Finecobank &#8211; Federico Lo Bianco e Primo Ghisi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/#website\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/\",\"name\":\"Cral Policlinico di Milano\",\"description\":\"Area Convenzioni\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Consulenti finanziari Finecobank - Federico Lo Bianco e Primo Ghisi - Cral Policlinico di Milano","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/consulenti-finanziari-finecobank-federico-lo-bianco-e-primo-ghisi\/","og_locale":"it_IT","og_type":"article","og_title":"Consulenti finanziari Finecobank - Federico Lo Bianco e Primo Ghisi - Cral Policlinico di Milano","og_description":"Siamo Federico Lo Bianco e Primo Ghisi, consulenti finanziari Finecobank. Il nostro ruolo \u00e8 quello di affiancare i clienti nell'importante scelta relativa alla gestione del patrimonio personale e familiare, considerando prioritari aspetti quali il controllo del rischio, il rendimento, la fiscalit\u00e0, l'orizzonte temporale, la qualit\u00e0 dei prodotti e il controllo dei costi. Offriamo una consulenza a 360 gradi che tocca anche tematiche quali protezione, trasferimento del patrimonio di famiglia nonch\u00e9 il passaggio generazionale e la personalizzazione degli investimenti. L'obiettivo principale \u00e8 aiutare i clienti a prendere decisioni informate per ottimizzare la crescita e la protezione del proprio patrimonio finanziario. Per noi, la fiducia e la comunicazione sono fondamentali per stabilire una relazione efficace e di lungo termine. \u2022 Servizi offerti: Investimenti finanziari a 360 gradi (fondi, ETF, obbligazioni, certificati ecc.) Investimenti assicurativi Fondi Pensione Diagnosi di portafogli presso altri istituti Supporto nel passaggio generazionale Conti correnti e mutui Gestione liquidit\u00e0 Possibilit\u00e0 di appuntamenti fuori sede    consulenti finanziari, consulente finanziario, consulenza finanziaria, investimenti, investimento, patrimonio finanziario, protezione del patrimonio, Investimenti finanziari, Investimenti assicurativi, Fondi Pensione, Diagnosi di portafogli, Supporto nel passaggio generazionale, Conti correnti, mutui, Gestione liquidit\u00e0, investire    consulenti finanziari a Milano, consulente finanziario a Milano, consulenza finanziaria a Milano, investimenti a Milano, investimento a Milano, patrimonio finanziario a Milano, protezione del patrimonio a Milano, Investimenti finanziari a Milano, Investimenti assicurativi a Milano, Fondi Pensione a Milano, Diagnosi di portafogli a Milano, Supporto nel passaggio generazionale a Milano, Conti correnti a Milano, mutui a Milano, Gestione liquidit\u00e0 a Milano, investire a Milano","og_url":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/consulenti-finanziari-finecobank-federico-lo-bianco-e-primo-ghisi\/","og_site_name":"Cral Policlinico di Milano","article_modified_time":"2025-05-30T09:13:06+00:00","og_image":[{"width":300,"height":300,"url":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/05\/logo_Federico-Lo-Bianco-e-Primo-Ghisi.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/consulenti-finanziari-finecobank-federico-lo-bianco-e-primo-ghisi\/","url":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/consulenti-finanziari-finecobank-federico-lo-bianco-e-primo-ghisi\/","name":"Consulenti finanziari Finecobank - Federico Lo Bianco e Primo Ghisi - Cral Policlinico di Milano","isPartOf":{"@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/#website"},"primaryImageOfPage":{"@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/consulenti-finanziari-finecobank-federico-lo-bianco-e-primo-ghisi\/#primaryimage"},"image":{"@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/consulenti-finanziari-finecobank-federico-lo-bianco-e-primo-ghisi\/#primaryimage"},"thumbnailUrl":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/05\/logo_Federico-Lo-Bianco-e-Primo-Ghisi.jpg","datePublished":"2025-05-20T09:17:07+00:00","dateModified":"2025-05-30T09:13:06+00:00","breadcrumb":{"@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/consulenti-finanziari-finecobank-federico-lo-bianco-e-primo-ghisi\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/consulenti-finanziari-finecobank-federico-lo-bianco-e-primo-ghisi\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/consulenti-finanziari-finecobank-federico-lo-bianco-e-primo-ghisi\/#primaryimage","url":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/05\/logo_Federico-Lo-Bianco-e-Primo-Ghisi.jpg","contentUrl":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/05\/logo_Federico-Lo-Bianco-e-Primo-Ghisi.jpg","width":300,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/consulenti-finanziari-finecobank-federico-lo-bianco-e-primo-ghisi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/negozio\/"},{"@type":"ListItem","position":3,"name":"Consulenti finanziari Finecobank &#8211; Federico Lo Bianco e Primo Ghisi"}]},{"@type":"WebSite","@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/#website","url":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/","name":"Cral Policlinico di Milano","description":"Area Convenzioni","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/product\/19861","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/comments?post=19861"}],"version-history":[{"count":10,"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/product\/19861\/revisions"}],"predecessor-version":[{"id":19878,"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/product\/19861\/revisions\/19878"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/media\/19862"}],"wp:attachment":[{"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/media?parent=19861"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/product_brand?post=19861"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/product_cat?post=19861"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/product_tag?post=19861"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}