{"id":19814,"date":"2025-05-19T15:10:39","date_gmt":"2025-05-19T13:10:39","guid":{"rendered":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/?post_type=product&#038;p=19814"},"modified":"2025-05-20T10:15:59","modified_gmt":"2025-05-20T08:15:59","slug":"sofia-carta-interior-designer","status":"publish","type":"product","link":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/sofia-carta-interior-designer\/","title":{"rendered":"Sofia Carta &#8211; Interior Designer"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"19814\" class=\"elementor elementor-19814\">\n\t\t\t\t<div class=\"elementor-element elementor-element-effaa08 e-flex e-con-boxed e-con e-parent\" data-id=\"effaa08\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-5479228 e-con-full e-flex e-con e-child\" data-id=\"5479228\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-aa9c97f elementor-widget__width-inherit elementor-widget elementor-widget-image\" data-id=\"aa9c97f\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" fetchpriority=\"high\" decoding=\"async\" width=\"825\" height=\"1024\" src=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/05\/Foto-profilo-02.jpeg\" class=\"attachment-full size-full wp-image-19837\" alt=\"\" srcset=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/05\/Foto-profilo-02.jpeg 825w, https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/05\/Foto-profilo-02-480x596.jpeg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 825px, 100vw\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-02b50f6 e-con-full e-flex e-con e-child\" data-id=\"02b50f6\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4234bcd elementor-widget elementor-widget-spacer\" data-id=\"4234bcd\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b2fba88 elementor-hidden-desktop e-flex e-con-boxed e-con e-parent\" data-id=\"b2fba88\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-3210851 e-flex e-con-boxed e-con e-child\" data-id=\"3210851\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-eecdc2c elementor-widget elementor-widget-text-editor\" data-id=\"eecdc2c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Chi sono<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-00b6082 elementor-widget elementor-widget-text-editor\" data-id=\"00b6082\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Sono Sofia Carta, interior designer e fondatrice di Sofia Carta Studio.<\/p><p>Dopo un percorso formativo nel mondo dell&#8217;oreficeria ho conseguito la laurea in Interior Design, ho avuto il privilegio di collaborare con importanti studi milanesi specializzati nel lusso e nel colore.<\/p><p>Nel 2021 ho dato vita al mio studio. Nel 2023 ho ricevuto il premio Best Service di Houzz e nel 2025 sono stata nominata tra i 15 migliori studi di interior design di Milano.<\/p><p>Credo che ogni casa debba essere un&#8217;estensione autentica di chi la vive.<\/p><p>Non progetto ambienti standardizzati: creo spazi che accolgono e raccontano. Guidarti con sensibilit\u00e0 e competenza \u00e8 la mia promessa, perch\u00e9 la tua casa non sia solo bella, ma profondamente tua.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e5ec98c e-flex e-con-boxed e-con e-child\" data-id=\"e5ec98c\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7c0d5f8 elementor-widget__width-inherit elementor-widget elementor-widget-image\" data-id=\"7c0d5f8\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1707\" height=\"2560\" src=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/05\/Foto-profilo-scaled.jpg\" class=\"attachment-full size-full wp-image-19838\" alt=\"\" srcset=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/05\/Foto-profilo-scaled.jpg 1707w, https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/05\/Foto-profilo-1280x1920.jpg 1280w, https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/05\/Foto-profilo-980x1470.jpg 980w, https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/05\/Foto-profilo-480x720.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) and (max-width: 1280px) 1280px, (min-width: 1281px) 1707px, 100vw\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-aba61af e-flex e-con-boxed e-con e-child\" data-id=\"aba61af\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2cf6091 elementor-widget elementor-widget-text-editor\" data-id=\"2cf6091\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Ogni progetto \u00e8 pensato per rispondere in modo specifico alle esigenze e ai desideri di chi si affida a me, attraverso tre proposte principali:<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-14ce2b7 elementor-widget elementor-widget-text-editor\" data-id=\"14ce2b7\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>1. Concept &amp; Mood<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c7a81cb elementor-widget elementor-widget-text-editor\" data-id=\"c7a81cb\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Una consulenza dedicata a chi desidera arredare o rinnovare una stanza. <br \/>Attraverso una moodboard ispirazionale e una planimetria con disposizione degli arredi.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-94ffc49 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"94ffc49\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ef2eed2 elementor-widget elementor-widget-text-editor\" data-id=\"ef2eed2\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>2. Re-Style<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-933e5c2 elementor-widget elementor-widget-text-editor\" data-id=\"933e5c2\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Un servizio ideale per chi vuole dare nuova vita alla propria casa senza interventi strutturali. Attraverso la scelta di colori, tessuti, arredi e illuminazione, ottimizziamo gli spazi esistenti creando una nuova armonia.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e5c900b elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"e5c900b\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-91b11d2 elementor-widget elementor-widget-text-editor\" data-id=\"91b11d2\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>3. Signature Atelier<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b862ebc elementor-widget elementor-widget-text-editor\" data-id=\"b862ebc\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Il mio servizio pi\u00f9 completo: un progetto chiavi in mano per chi desidera una ristrutturazione completa senza stress. Mi occupo di tutto, dal concept iniziale alla scelta dei materiali, fino al coordinamento dei fornitori e degli artigiani.<br \/>Se desideri vivere in una casa che ti rappresenti davvero, sar\u00f2 felice di accompagnarti in questo viaggio unico.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5af0616 e-flex e-con-boxed e-con e-child\" data-id=\"5af0616\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-af66f65 elementor-pagination-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"af66f65\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;dots&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carosello d&#039;immagini\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper swiper-image-stretch\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 di 11\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/05\/K7A1262-scaled.jpg\" alt=\"_K7A1262\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 di 11\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/05\/K7A1432-scaled.jpg\" alt=\"_K7A1432\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 di 11\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/05\/K7A9975-scaled.jpg\" alt=\"_K7A9975\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 di 11\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/05\/K7A9965-scaled.jpg\" alt=\"_K7A9965\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 di 11\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/05\/K7A9943-scaled.jpg\" alt=\"_K7A9943\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 di 11\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/05\/K7A9922-scaled.jpg\" alt=\"_K7A9922\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 di 11\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/05\/K7A9803-scaled.jpg\" alt=\"_K7A9803\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 di 11\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/05\/K7A9841-scaled.jpg\" alt=\"_K7A9841\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"9 di 11\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/05\/K7A1382-scaled.jpg\" alt=\"_K7A1382\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"10 di 11\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/05\/K7A1342-scaled.jpg\" alt=\"_K7A1342\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"11 di 11\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/05\/K7A1375-scaled.jpg\" alt=\"_K7A1375\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-903f279 elementor-hidden-tablet elementor-hidden-mobile e-flex e-con-boxed e-con e-parent\" data-id=\"903f279\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-a5f1a36 e-con-full e-flex e-con e-child\" data-id=\"a5f1a36\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7a3ef89 elementor-widget elementor-widget-text-editor\" data-id=\"7a3ef89\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Chi sono<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ad0cdce elementor-widget elementor-widget-text-editor\" data-id=\"ad0cdce\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Sono Sofia Carta, interior designer e fondatrice di Sofia Carta Studio.<\/p><p>Dopo un percorso formativo nel mondo dell&#8217;oreficeria ho conseguito la laurea in Interior Design, ho avuto il privilegio di collaborare con importanti studi milanesi specializzati nel lusso e nel colore.<\/p><p>Nel 2021 ho dato vita al mio studio. Nel 2023 ho ricevuto il premio Best Service di Houzz e nel 2025 sono stata nominata tra i 15 migliori studi di interior design di Milano.<\/p><p>Credo che ogni casa debba essere un&#8217;estensione autentica di chi la vive.<\/p><p>Non progetto ambienti standardizzati: creo spazi che accolgono e raccontano. Guidarti con sensibilit\u00e0 e competenza \u00e8 la mia promessa, perch\u00e9 la tua casa non sia solo bella, ma profondamente tua.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-dd46e81 e-con-full e-flex e-con e-child\" data-id=\"dd46e81\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7903261 elementor-widget__width-inherit elementor-widget elementor-widget-image\" data-id=\"7903261\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1707\" height=\"2560\" src=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/05\/Foto-profilo-scaled.jpg\" class=\"attachment-full size-full wp-image-19838\" alt=\"\" srcset=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/05\/Foto-profilo-scaled.jpg 1707w, https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/05\/Foto-profilo-1280x1920.jpg 1280w, https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/05\/Foto-profilo-980x1470.jpg 980w, https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/05\/Foto-profilo-480x720.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) and (max-width: 1280px) 1280px, (min-width: 1281px) 1707px, 100vw\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-100f7b6 e-con-full e-flex e-con e-child\" data-id=\"100f7b6\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f46ff53 elementor-pagination-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"f46ff53\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;dots&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carosello d&#039;immagini\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper swiper-image-stretch\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 di 11\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/05\/K7A1262-scaled.jpg\" alt=\"_K7A1262\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 di 11\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/05\/K7A1432-scaled.jpg\" alt=\"_K7A1432\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 di 11\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/05\/K7A9975-scaled.jpg\" alt=\"_K7A9975\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 di 11\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/05\/K7A9965-scaled.jpg\" alt=\"_K7A9965\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 di 11\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/05\/K7A9943-scaled.jpg\" alt=\"_K7A9943\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 di 11\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/05\/K7A9922-scaled.jpg\" alt=\"_K7A9922\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 di 11\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/05\/K7A9803-scaled.jpg\" alt=\"_K7A9803\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 di 11\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/05\/K7A9841-scaled.jpg\" alt=\"_K7A9841\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"9 di 11\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/05\/K7A1382-scaled.jpg\" alt=\"_K7A1382\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"10 di 11\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/05\/K7A1342-scaled.jpg\" alt=\"_K7A1342\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"11 di 11\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/05\/K7A1375-scaled.jpg\" alt=\"_K7A1375\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b6f86ea e-con-full e-flex e-con e-child\" data-id=\"b6f86ea\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fad9877 elementor-widget elementor-widget-text-editor\" data-id=\"fad9877\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Ogni progetto \u00e8 pensato per rispondere in modo specifico alle esigenze e ai desideri di chi si affida a me, attraverso tre proposte principali:<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-00c9ae9 elementor-widget elementor-widget-text-editor\" data-id=\"00c9ae9\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>1. Concept &amp; Mood<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3c21c58 elementor-widget elementor-widget-text-editor\" data-id=\"3c21c58\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Una consulenza dedicata a chi desidera arredare o rinnovare una stanza. <br \/>Attraverso una moodboard ispirazionale e una planimetria con disposizione degli arredi.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-04c7e67 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"04c7e67\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-635962b elementor-widget elementor-widget-text-editor\" data-id=\"635962b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>2. Re-Style<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c2ef914 elementor-widget elementor-widget-text-editor\" data-id=\"c2ef914\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Un servizio ideale per chi vuole dare nuova vita alla propria casa senza interventi strutturali. Attraverso la scelta di colori, tessuti, arredi e illuminazione, ottimizziamo gli spazi esistenti creando una nuova armonia.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4161afc elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"4161afc\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1238372 elementor-widget elementor-widget-text-editor\" data-id=\"1238372\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>3. Signature Atelier<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-82eea1a elementor-widget elementor-widget-text-editor\" data-id=\"82eea1a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Il mio servizio pi\u00f9 completo: un progetto chiavi in mano per chi desidera una ristrutturazione completa senza stress. Mi occupo di tutto, dal concept iniziale alla scelta dei materiali, fino al coordinamento dei fornitori e degli artigiani.<br \/>Se desideri vivere in una casa che ti rappresenti davvero, sar\u00f2 felice di accompagnarti in questo viaggio unico.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-aa9cd5f e-con-full e-flex e-con e-parent\" data-id=\"aa9cd5f\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-a416019 e-con-full e-flex e-con e-child\" data-id=\"a416019\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f677d49 elementor-widget elementor-widget-spacer\" data-id=\"f677d49\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-670088d e-con-full e-flex e-con e-child\" data-id=\"670088d\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-44a89e8 elementor-widget elementor-widget-text-editor\" data-id=\"44a89e8\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Per gli associati <br \/><strong>sconto del 15% \/ 20%<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-12ec114 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"12ec114\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5f243d5 elementor-widget elementor-widget-text-editor\" data-id=\"5f243d5\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Sofia Carta Studio<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4e9f83e elementor-widget elementor-widget-text-editor\" data-id=\"4e9f83e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Contatti<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bb83974 elementor-widget elementor-widget-text-editor\" data-id=\"bb83974\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"aiAXrc\"><span style=\"color: #ffffff;\">Via Gastone da Foix, 7 &#8211; <span class=\"fMYBhe\">20141 Milano<br \/><strong>Cell:<\/strong> <a style=\"color: #ffffff;\" href=\"tel:+393201128540\">3201128540<\/a><\/span><\/span><br \/><span style=\"color: #ffffff;\"><strong>Mail: <\/strong><a style=\"color: #ffffff;\" href=\"mailto:interior@sofiacarta.com\">interior@sofiacarta.com<\/a><\/span><br \/><span style=\"color: #ffffff;\"><strong>Pec: <\/strong><a style=\"color: #ffffff;\" href=\"mailto:sofiacartastudio@pec.it\">sofiacartastudio@pec.it<\/a><\/span><br \/><span style=\"color: #ffffff;\"><strong>Sito web: <\/strong><a style=\"color: #ffffff;\" href=\"https:\/\/www.sofiacarta.com\/\">www.sofiacarta.com<\/a><\/span><br \/><span style=\"color: #ffffff;\"><b>Lun &#8211; Ven: <\/b>9.30 &#8211; 18.30<\/span><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-45a7ce1 e-con-full e-flex e-con e-parent\" data-id=\"45a7ce1\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cad45b0 elementor-widget elementor-widget-text-editor\" data-id=\"cad45b0\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><div id=\"gmw-single-location-wrapper-106\" class=\"gmw-element-wrapper gmw-single-location-wrapper gmw-sl-wrapper gmw-sl-single-post-wrapper post \" object_type=\"post\" object_id=\"19814\"  style=\"width:100%\"><div class=\"gmw-sl-map-wrapper gmw-sl-element\"><div id=\"gmw-map-wrapper-106\" class=\"gmw-map-wrapper  sl single_location \" style=\"width:100%;height:420px;\"> <span id=\"gmw-resize-map-toggle-106\" class=\"gmw-resize-map-toggle gmw-icon-resize-full\" style=\"display:none;\" title=\"Resize map\"><\/span> <div id=\"gmw-map-loader-106\" class=\"gmw-map-loader\"><\/div> <div id=\"gmw-map-106\" class=\"gmw-map sl single_location\" style=\"width:100%; height:100%\" data-map_id=\"106\" data-prefix=\"sl\" data-map_type=\"single_location\" data-icons_usage=\"global\"><\/div> <\/div><\/div><\/div><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-357fa087 elementor-section-content-middle elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"357fa087\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6f3a4a0e\" data-id=\"6f3a4a0e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-254efb93 elementor-widget elementor-widget-text-editor\" data-id=\"254efb93\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tContatti\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6cce0a4 elementor-shape-circle e-grid-align-left elementor-grid-0 elementor-widget elementor-widget-social-icons\" data-id=\"6cce0a4\" data-element_type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-facebook elementor-repeater-item-1539373\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Facebook<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-facebook\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M504 256C504 119 393 8 256 8S8 119 8 256c0 123.78 90.69 226.38 209.25 245V327.69h-63V256h63v-54.64c0-62.15 37-96.48 93.67-96.48 27.14 0 55.52 4.84 55.52 4.84v61h-31.28c-30.8 0-40.41 19.12-40.41 38.73V256h68.78l-11 71.69h-57.78V501C413.31 482.38 504 379.78 504 256z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-twitter elementor-repeater-item-8913cb9\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Twitter<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-twitter\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M459.37 151.716c.325 4.548.325 9.097.325 13.645 0 138.72-105.583 298.558-298.558 298.558-59.452 0-114.68-17.219-161.137-47.106 8.447.974 16.568 1.299 25.34 1.299 49.055 0 94.213-16.568 130.274-44.832-46.132-.975-84.792-31.188-98.112-72.772 6.498.974 12.995 1.624 19.818 1.624 9.421 0 18.843-1.3 27.614-3.573-48.081-9.747-84.143-51.98-84.143-102.985v-1.299c13.969 7.797 30.214 12.67 47.431 13.319-28.264-18.843-46.781-51.005-46.781-87.391 0-19.492 5.197-37.36 14.294-52.954 51.655 63.675 129.3 105.258 216.365 109.807-1.624-7.797-2.599-15.918-2.599-24.04 0-57.828 46.782-104.934 104.934-104.934 30.213 0 57.502 12.67 76.67 33.137 23.715-4.548 46.456-13.32 66.599-25.34-7.798 24.366-24.366 44.833-46.132 57.827 21.117-2.273 41.584-8.122 60.426-16.243-14.292 20.791-32.161 39.308-52.628 54.253z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-youtube elementor-repeater-item-3255c55\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Youtube<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-youtube\" viewBox=\"0 0 576 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M549.655 124.083c-6.281-23.65-24.787-42.276-48.284-48.597C458.781 64 288 64 288 64S117.22 64 74.629 75.486c-23.497 6.322-42.003 24.947-48.284 48.597-11.412 42.867-11.412 132.305-11.412 132.305s0 89.438 11.412 132.305c6.281 23.65 24.787 41.5 48.284 47.821C117.22 448 288 448 288 448s170.78 0 213.371-11.486c23.497-6.321 42.003-24.171 48.284-47.821 11.412-42.867 11.412-132.305 11.412-132.305s0-89.438-11.412-132.305zm-317.51 213.508V175.185l142.739 81.205-142.739 81.201z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-10ea309e\" data-id=\"10ea309e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-62c22f80 elementor-widget elementor-widget-text-editor\" data-id=\"62c22f80\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div id=\"gmw-single-location-wrapper-143\" class=\"gmw-element-wrapper gmw-single-location-wrapper gmw-sl-wrapper gmw-sl-single-post-wrapper post \" object_type=\"post\" object_id=\"19814\"  style=\"width:100%\"><div class=\"gmw-sl-map-wrapper gmw-sl-element\"><div id=\"gmw-map-wrapper-143\" class=\"gmw-map-wrapper  sl single_location \" style=\"width:100%;height:300px;\"> <span id=\"gmw-resize-map-toggle-143\" class=\"gmw-resize-map-toggle gmw-icon-resize-full\" style=\"display:none;\" title=\"Resize map\"><\/span> <div id=\"gmw-map-loader-143\" class=\"gmw-map-loader\"><\/div> <div id=\"gmw-map-143\" class=\"gmw-map sl single_location\" style=\"width:100%; height:100%\" data-map_id=\"143\" data-prefix=\"sl\" data-map_type=\"single_location\" data-icons_usage=\"global\"><\/div> <\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ab8ac78 elementor-widget elementor-widget-text-editor\" data-id=\"ab8ac78\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><div id=\"gmw-single-object-locations-wrapper-511\" class=\"gmw-element-wrapper gmw-single-location-wrapper gmw-sl-wrapper gmw-sl-single-post-wrapper post gmw-sl-multiple-locations\" object_type=\"post\" object_id=\"\"  style=\"width:100%\"><div class=\"gmw-sl-map-wrapper\"><div id=\"gmw-map-wrapper-511\" class=\"gmw-map-wrapper  sl single_location \" style=\"width:100%;height:350px;\"> <span id=\"gmw-resize-map-toggle-511\" class=\"gmw-resize-map-toggle gmw-icon-resize-full\" style=\"display:none;\" title=\"Resize map\"><\/span> <div id=\"gmw-map-loader-511\" class=\"gmw-map-loader\"><\/div> <div id=\"gmw-map-511\" class=\"gmw-map sl single_location\" style=\"width:100%; height:100%\" data-map_id=\"511\" data-prefix=\"sl\" data-map_type=\"single_location\" data-icons_usage=\"global\"><\/div> <\/div><\/div><\/div><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<div style= \"display: none\">\n<p>Sono Sofia Carta, interior designer e fondatrice di Sofia Carta Studio. Dopo un percorso formativo nel mondo dell&#8217;oreficeria ho conseguito la laurea in Interior Design, ho avuto il privilegio di collaborare con importanti studi milanesi specializzati nel lusso e nel colore. Nel 2021 ho dato vita al mio studio. Nel 2023 ho ricevuto il premio Best Service di Houzz e nel 2025 sono stata nominata tra i 15 migliori studi di interior design di Milano. Credo che ogni casa debba essere un&#8217;estensione autentica di chi la vive. Non progetto ambienti standardizzati: creo spazi che accolgono e raccontano. Guidarti con sensibilit\u00e0 e competenza \u00e8 la mia promessa, perch\u00e9 la tua casa non sia solo bella, ma profondamente tua.<br \/>\nOgni progetto \u00e8 pensato per rispondere in modo specifico alle esigenze e ai desideri di chi si affida a me, attraverso tre proposte principali: 1. Concept &#038; Mood<br \/>\nUna consulenza dedicata a chi desidera arredare o rinnovare una stanza. Attraverso una moodboard ispirazionale e una planimetria con disposizione degli arredi. 2. Re-Style<br \/>\n Un servizio ideale per chi vuole dare nuova vita alla propria casa senza interventi strutturali. Attraverso la scelta di colori, tessuti, arredi e illuminazione, ottimizziamo gli spazi esistenti creando una nuova armonia. 3. Signature Atelier Il mio servizio pi\u00f9 completo: un progetto chiavi in mano per chi desidera una ristrutturazione completa senza stress. Mi occupo di tutto, dal concept iniziale alla scelta dei materiali, fino al coordinamento dei fornitori e degli artigiani.<br \/>\nSe desideri vivere in una casa che ti rappresenti davvero, sar\u00f2 felice di accompagnarti in questo viaggio unico.<\/p>\n<p>interior designer, interior design, studi di interior design, studio di interior design, arredi, arredo, arredamento, arredamenti, arredo casa, arredo interno casa, arredare casa, arredo stanza, rinnovare stanza, rinnovare casa, rinnovo camere, ristrutturazione , Designer d&#8217;interni, Architetto Interior Designer, arredo moderno, arredo casa moderno, <\/p>\n<p>interior designer a Milano, interior design a Milano, studi di interior design a Milano, studio di interior design a Milano, arredi a Milano, arredo a Milano, arredamento a Milano, arredamenti a Milano, arredo casa a Milano, arredo interno casa a Milano, arredare casa a Milano, arredo stanza a Milano, rinnovare stanza a Milano, rinnovare casa a Milano, rinnovo camere a Milano, ristrutturazione a Milano, Designer d&#8217;interni a Milano, Architetto Interior Designer a Milano, arredo moderno a Milano, arredo casa moderno a Milano, <\/p>\n<\/div>\n","protected":false},"featured_media":19815,"comment_status":"open","ping_status":"closed","template":"elementor_header_footer","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":""},"product_brand":[],"product_cat":[68,21,1392],"product_tag":[4032,289,328,893,894,331,1321,4034,4026,4033,4027,4031,534,2665,4029,4028,4030,932,4024,4025],"class_list":{"0":"post-19814","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-arredamenti","7":"product_cat-casa","8":"product_cat-interior-design","9":"product_tag-architetto-interior-designer","10":"product_tag-arredamenti","11":"product_tag-arredamento","12":"product_tag-arredare-casa","13":"product_tag-arredi","14":"product_tag-arredo","15":"product_tag-arredo-casa","16":"product_tag-arredo-casa-moderno","17":"product_tag-arredo-interno-casa","18":"product_tag-arredo-moderno","19":"product_tag-arredo-stanza","20":"product_tag-designer-dinterni","21":"product_tag-interior-design","22":"product_tag-interior-designer","23":"product_tag-rinnovare-casa","24":"product_tag-rinnovare-stanza","25":"product_tag-rinnovo-camere","26":"product_tag-ristrutturazione","27":"product_tag-studi-di-interior-design","28":"product_tag-studio-di-interior-design","30":"first","31":"instock","32":"shipping-taxable","33":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Sofia Carta - Interior Designer - Cral Policlinico di Milano<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/sofia-carta-interior-designer\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sofia Carta - Interior Designer - Cral Policlinico di Milano\" \/>\n<meta property=\"og:description\" content=\"Sono Sofia Carta, interior designer e fondatrice di Sofia Carta Studio. Dopo un percorso formativo nel mondo dell&#039;oreficeria ho conseguito la laurea in Interior Design, ho avuto il privilegio di collaborare con importanti studi milanesi specializzati nel lusso e nel colore. Nel 2021 ho dato vita al mio studio. Nel 2023 ho ricevuto il premio Best Service di Houzz e nel 2025 sono stata nominata tra i 15 migliori studi di interior design di Milano. Credo che ogni casa debba essere un&#039;estensione autentica di chi la vive. Non progetto ambienti standardizzati: creo spazi che accolgono e raccontano. Guidarti con sensibilit\u00e0 e competenza \u00e8 la mia promessa, perch\u00e9 la tua casa non sia solo bella, ma profondamente tua. Ogni progetto \u00e8 pensato per rispondere in modo specifico alle esigenze e ai desideri di chi si affida a me, attraverso tre proposte principali: 1. Concept &amp; Mood Una consulenza dedicata a chi desidera arredare o rinnovare una stanza. Attraverso una moodboard ispirazionale e una planimetria con disposizione degli arredi. 2. Re-Style  Un servizio ideale per chi vuole dare nuova vita alla propria casa senza interventi strutturali. Attraverso la scelta di colori, tessuti, arredi e illuminazione, ottimizziamo gli spazi esistenti creando una nuova armonia. 3. Signature Atelier Il mio servizio pi\u00f9 completo: un progetto chiavi in mano per chi desidera una ristrutturazione completa senza stress. Mi occupo di tutto, dal concept iniziale alla scelta dei materiali, fino al coordinamento dei fornitori e degli artigiani. Se desideri vivere in una casa che ti rappresenti davvero, sar\u00f2 felice di accompagnarti in questo viaggio unico.    interior designer, interior design, studi di interior design, studio di interior design, arredi, arredo, arredamento, arredamenti, arredo casa, arredo interno casa, arredare casa, arredo stanza, rinnovare stanza, rinnovare casa, rinnovo camere, ristrutturazione , Designer d&#039;interni, Architetto Interior Designer, arredo moderno, arredo casa moderno,     interior designer a Milano, interior design a Milano, studi di interior design a Milano, studio di interior design a Milano, arredi a Milano, arredo a Milano, arredamento a Milano, arredamenti a Milano, arredo casa a Milano, arredo interno casa a Milano, arredare casa a Milano, arredo stanza a Milano, rinnovare stanza a Milano, rinnovare casa a Milano, rinnovo camere a Milano, ristrutturazione a Milano, Designer d&#039;interni a Milano, Architetto Interior Designer a Milano, arredo moderno a Milano, arredo casa moderno a Milano,\" \/>\n<meta property=\"og:url\" content=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/sofia-carta-interior-designer\/\" \/>\n<meta property=\"og:site_name\" content=\"Cral Policlinico di Milano\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-20T08:15:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/05\/logo_Sofia-Carta.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"9 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/sofia-carta-interior-designer\/\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/sofia-carta-interior-designer\/\",\"name\":\"Sofia Carta - Interior Designer - Cral Policlinico di Milano\",\"isPartOf\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/sofia-carta-interior-designer\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/sofia-carta-interior-designer\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/05\/logo_Sofia-Carta.jpg\",\"datePublished\":\"2025-05-19T13:10:39+00:00\",\"dateModified\":\"2025-05-20T08:15:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/sofia-carta-interior-designer\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/sofia-carta-interior-designer\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/sofia-carta-interior-designer\/#primaryimage\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/05\/logo_Sofia-Carta.jpg\",\"contentUrl\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/05\/logo_Sofia-Carta.jpg\",\"width\":300,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/sofia-carta-interior-designer\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/negozio\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Sofia Carta &#8211; Interior Designer\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/#website\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/\",\"name\":\"Cral Policlinico di Milano\",\"description\":\"Area Convenzioni\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sofia Carta - Interior Designer - Cral Policlinico di Milano","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/sofia-carta-interior-designer\/","og_locale":"it_IT","og_type":"article","og_title":"Sofia Carta - Interior Designer - Cral Policlinico di Milano","og_description":"Sono Sofia Carta, interior designer e fondatrice di Sofia Carta Studio. Dopo un percorso formativo nel mondo dell'oreficeria ho conseguito la laurea in Interior Design, ho avuto il privilegio di collaborare con importanti studi milanesi specializzati nel lusso e nel colore. Nel 2021 ho dato vita al mio studio. Nel 2023 ho ricevuto il premio Best Service di Houzz e nel 2025 sono stata nominata tra i 15 migliori studi di interior design di Milano. Credo che ogni casa debba essere un'estensione autentica di chi la vive. Non progetto ambienti standardizzati: creo spazi che accolgono e raccontano. Guidarti con sensibilit\u00e0 e competenza \u00e8 la mia promessa, perch\u00e9 la tua casa non sia solo bella, ma profondamente tua. Ogni progetto \u00e8 pensato per rispondere in modo specifico alle esigenze e ai desideri di chi si affida a me, attraverso tre proposte principali: 1. Concept & Mood Una consulenza dedicata a chi desidera arredare o rinnovare una stanza. Attraverso una moodboard ispirazionale e una planimetria con disposizione degli arredi. 2. Re-Style  Un servizio ideale per chi vuole dare nuova vita alla propria casa senza interventi strutturali. Attraverso la scelta di colori, tessuti, arredi e illuminazione, ottimizziamo gli spazi esistenti creando una nuova armonia. 3. Signature Atelier Il mio servizio pi\u00f9 completo: un progetto chiavi in mano per chi desidera una ristrutturazione completa senza stress. Mi occupo di tutto, dal concept iniziale alla scelta dei materiali, fino al coordinamento dei fornitori e degli artigiani. Se desideri vivere in una casa che ti rappresenti davvero, sar\u00f2 felice di accompagnarti in questo viaggio unico.    interior designer, interior design, studi di interior design, studio di interior design, arredi, arredo, arredamento, arredamenti, arredo casa, arredo interno casa, arredare casa, arredo stanza, rinnovare stanza, rinnovare casa, rinnovo camere, ristrutturazione , Designer d'interni, Architetto Interior Designer, arredo moderno, arredo casa moderno,     interior designer a Milano, interior design a Milano, studi di interior design a Milano, studio di interior design a Milano, arredi a Milano, arredo a Milano, arredamento a Milano, arredamenti a Milano, arredo casa a Milano, arredo interno casa a Milano, arredare casa a Milano, arredo stanza a Milano, rinnovare stanza a Milano, rinnovare casa a Milano, rinnovo camere a Milano, ristrutturazione a Milano, Designer d'interni a Milano, Architetto Interior Designer a Milano, arredo moderno a Milano, arredo casa moderno a Milano,","og_url":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/sofia-carta-interior-designer\/","og_site_name":"Cral Policlinico di Milano","article_modified_time":"2025-05-20T08:15:59+00:00","og_image":[{"width":300,"height":300,"url":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/05\/logo_Sofia-Carta.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"9 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/sofia-carta-interior-designer\/","url":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/sofia-carta-interior-designer\/","name":"Sofia Carta - Interior Designer - Cral Policlinico di Milano","isPartOf":{"@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/#website"},"primaryImageOfPage":{"@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/sofia-carta-interior-designer\/#primaryimage"},"image":{"@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/sofia-carta-interior-designer\/#primaryimage"},"thumbnailUrl":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/05\/logo_Sofia-Carta.jpg","datePublished":"2025-05-19T13:10:39+00:00","dateModified":"2025-05-20T08:15:59+00:00","breadcrumb":{"@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/sofia-carta-interior-designer\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/sofia-carta-interior-designer\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/sofia-carta-interior-designer\/#primaryimage","url":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/05\/logo_Sofia-Carta.jpg","contentUrl":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/05\/logo_Sofia-Carta.jpg","width":300,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/sofia-carta-interior-designer\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/negozio\/"},{"@type":"ListItem","position":3,"name":"Sofia Carta &#8211; Interior Designer"}]},{"@type":"WebSite","@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/#website","url":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/","name":"Cral Policlinico di Milano","description":"Area Convenzioni","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/product\/19814","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/comments?post=19814"}],"version-history":[{"count":22,"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/product\/19814\/revisions"}],"predecessor-version":[{"id":19857,"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/product\/19814\/revisions\/19857"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/media\/19815"}],"wp:attachment":[{"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/media?parent=19814"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/product_brand?post=19814"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/product_cat?post=19814"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/product_tag?post=19814"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}