{"id":19333,"date":"2025-05-05T11:27:20","date_gmt":"2025-05-05T09:27:20","guid":{"rendered":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/?post_type=product&#038;p=19333"},"modified":"2025-05-12T10:22:06","modified_gmt":"2025-05-12T08:22:06","slug":"dott-ssa-moira-minurri-pedagogista-e-coach-umanista","status":"publish","type":"product","link":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/dott-ssa-moira-minurri-pedagogista-e-coach-umanista\/","title":{"rendered":"Dott.ssa Moira Minurri &#8211; Pedagogista e Coach Umanista"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"19333\" class=\"elementor elementor-19333\">\n\t\t\t\t<div class=\"elementor-element elementor-element-272c8c4 e-flex e-con-boxed e-con e-parent\" data-id=\"272c8c4\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3d6a864 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"3d6a864\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" fetchpriority=\"high\" decoding=\"async\" width=\"2560\" height=\"1810\" src=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/05\/logo_viola_claim_mm-scaled.png\" class=\"attachment-full size-full wp-image-19344\" alt=\"\" srcset=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/05\/logo_viola_claim_mm-scaled.png 2560w, https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/05\/logo_viola_claim_mm-1280x905.png 1280w, https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/05\/logo_viola_claim_mm-980x693.png 980w, https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/05\/logo_viola_claim_mm-480x339.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) and (max-width: 1280px) 1280px, (min-width: 1281px) 2560px, 100vw\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f86f67a elementor-hidden-tablet elementor-hidden-mobile e-flex e-con-boxed e-con e-parent\" data-id=\"f86f67a\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-105661f e-con-full e-flex e-con e-child\" data-id=\"105661f\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6bd7150 elementor-widget elementor-widget-text-editor\" data-id=\"6bd7150\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Chi sono<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-37a0709 elementor-widget elementor-widget-text-editor\" data-id=\"37a0709\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Sono Moira, amo accompagnare le persone e le organizzazioni ad esprimere al meglio le proprie potenzialit\u00e0 per ricercare soluzioni creative ed efficaci all\u2019interno di un progetto personalizzato.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c271313 elementor-widget elementor-widget-text-editor\" data-id=\"c271313\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Il mio scopo?<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-44f0816 elementor-widget elementor-widget-text-editor\" data-id=\"44f0816\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Essere una professionista di supporto nei processi di crescita ed evoluzione e far stare bene le persone.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a3cde04 e-con-full e-flex e-con e-child\" data-id=\"a3cde04\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d567a06 elementor-widget__width-inherit elementor-widget elementor-widget-image\" data-id=\"d567a06\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"530\" height=\"530\" src=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/05\/moira_minurri.png\" class=\"attachment-full size-full wp-image-19346\" alt=\"\" srcset=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/05\/moira_minurri.png 530w, https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/05\/moira_minurri-480x480.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 530px, 100vw\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c1673d6 e-con-full e-flex e-con e-child\" data-id=\"c1673d6\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-55334a8 elementor-widget elementor-widget-text-editor\" data-id=\"55334a8\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Specializzazioni:<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4c80bbb elementor-widget elementor-widget-text-editor\" data-id=\"4c80bbb\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u2022 Pedagogista<br \/>\u2022 Coach Umanista<br \/>\u2022 Arte terapista e musicoterapista<br \/>\u2022 Formatrice<br \/>\u2022 Progettista educativa e sociale<br \/>\u2022 Operatrice Mindfulness<\/p><p>Vuoi richiedere una consulenza? <br \/>Vuoi prenotare le tue sessioni di Coaching? <br \/>Vuoi realizzare un progetto educativo in linea con l\u2019approccio professionale che propongo? <br \/>Vuoi migliorare il tuo Benessere e quello dei tuoi dipendenti?<br \/><span style=\"color: #833b9a;\"><strong>SONO A TUA DISPOSIZIONE!<\/strong><\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9cfaa02 elementor-hidden-desktop e-flex e-con-boxed e-con e-parent\" data-id=\"9cfaa02\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-fe68751 e-con-full e-flex e-con e-child\" data-id=\"fe68751\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-db08ad7 elementor-widget elementor-widget-text-editor\" data-id=\"db08ad7\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Chi sono<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fcc871b elementor-widget elementor-widget-text-editor\" data-id=\"fcc871b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Sono Moira, amo accompagnare le persone e le organizzazioni ad esprimere al meglio le proprie potenzialit\u00e0 per ricercare soluzioni creative ed efficaci all\u2019interno di un progetto personalizzato.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-628af48 elementor-widget elementor-widget-text-editor\" data-id=\"628af48\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Il mio scopo?<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b586145 elementor-widget elementor-widget-text-editor\" data-id=\"b586145\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Essere una professionista di supporto nei processi di crescita ed evoluzione e far stare bene le persone.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0f41f1b e-flex e-con-boxed e-con e-child\" data-id=\"0f41f1b\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-493b43e elementor-widget__width-inherit elementor-widget elementor-widget-image\" data-id=\"493b43e\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"530\" height=\"530\" src=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/05\/moira_minurri.png\" class=\"attachment-full size-full wp-image-19346\" alt=\"\" srcset=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/05\/moira_minurri.png 530w, https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/05\/moira_minurri-480x480.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 530px, 100vw\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1bb8a6b e-flex e-con-boxed e-con e-child\" data-id=\"1bb8a6b\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0bb512b elementor-widget elementor-widget-text-editor\" data-id=\"0bb512b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Specializzazioni:<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-33e8b44 elementor-widget elementor-widget-text-editor\" data-id=\"33e8b44\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u2022 Pedagogista<br \/>\u2022 Coach Umanista<br \/>\u2022 Arte terapista e musicoterapista<br \/>\u2022 Formatrice<br \/>\u2022 Progettista educativa e sociale<br \/>\u2022 Operatrice Mindfulness<\/p><p>Vuoi richiedere una consulenza? <br \/>Vuoi prenotare le tue sessioni di Coaching? <br \/>Vuoi realizzare un progetto educativo in linea con l\u2019approccio professionale che propongo? <br \/>Vuoi migliorare il tuo Benessere e quello dei tuoi dipendenti?<br \/><span style=\"color: #833b9a;\"><strong>SONO A TUA DISPOSIZIONE!<\/strong><\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a12d306 e-flex e-con-boxed e-con e-parent\" data-id=\"a12d306\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-45084a8 elementor-widget elementor-widget-text-editor\" data-id=\"45084a8\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Agevolazioni riservate agli associati<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-72e81db e-flex e-con-boxed e-con e-parent\" data-id=\"72e81db\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-e82a056 e-con-full e-flex e-con e-child\" data-id=\"e82a056\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-79e3c9c elementor-widget elementor-widget-text-editor\" data-id=\"79e3c9c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Iscrizione GRATUITA al gruppo whatsapp<br \/>CreIn &#8211; Crescere Insieme<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bad9925 elementor-widget__width-inherit elementor-widget-tablet__width-initial elementor-widget elementor-widget-image\" data-id=\"bad9925\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"1262\" src=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/05\/Contatdtami-1024.jpg\" class=\"attachment-full size-full wp-image-19376\" alt=\"\" srcset=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/05\/Contatdtami-1024.jpg 1024w, https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/05\/Contatdtami-1024-980x1208.jpg 980w, https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/05\/Contatdtami-1024-480x592.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a84fcad e-con-full e-flex e-con e-child\" data-id=\"a84fcad\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-085ab63 elementor-widget elementor-widget-text-editor\" data-id=\"085ab63\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Contattami<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-584e57f elementor-widget elementor-widget-text-editor\" data-id=\"584e57f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #333333;\">Chiamami al <a style=\"color: #333333;\" href=\"tel:+393355685620\"><strong>335 568 5620<\/strong><\/a> o scrivimi direttamente una mail <a style=\"color: #333333;\" href=\"mailto:sinergie@moiraminurri.it\"><strong>sinergie@moiraminurri.it<\/strong><\/a><\/span><\/p><p><span style=\"color: #333333;\">Visita il sito per approfondire le attivit\u00e0 che svolgo <a style=\"color: #333333;\" href=\"https:\/\/moiraminurri.it\/\"><strong>www.moiraminurri.it<\/strong><\/a><\/span><\/p><p><span style=\"color: #333333;\">Ricevo ON LINE su Zoom<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8f2d29b elementor-shape-circle elementor-grid-0 e-grid-align-center elementor-widget elementor-widget-social-icons\" data-id=\"8f2d29b\" data-element_type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-whatsapp elementor-repeater-item-1539373\" href=\"https:\/\/chat.whatsapp.com\/HB6ywFPrYiEECNyGZToOUH\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Whatsapp<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-whatsapp\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M380.9 97.1C339 55.1 283.2 32 223.9 32c-122.4 0-222 99.6-222 222 0 39.1 10.2 77.3 29.6 111L0 480l117.7-30.9c32.4 17.7 68.9 27 106.1 27h.1c122.3 0 224.1-99.6 224.1-222 0-59.3-25.2-115-67.1-157zm-157 341.6c-33.2 0-65.7-8.9-94-25.7l-6.7-4-69.8 18.3L72 359.2l-4.4-7c-18.5-29.4-28.2-63.3-28.2-98.2 0-101.7 82.8-184.5 184.6-184.5 49.3 0 95.6 19.2 130.4 54.1 34.8 34.9 56.2 81.2 56.1 130.5 0 101.8-84.9 184.6-186.6 184.6zm101.2-138.2c-5.5-2.8-32.8-16.2-37.9-18-5.1-1.9-8.8-2.8-12.5 2.8-3.7 5.6-14.3 18-17.6 21.8-3.2 3.7-6.5 4.2-12 1.4-32.6-16.3-54-29.1-75.5-66-5.7-9.8 5.7-9.1 16.3-30.3 1.8-3.7.9-6.9-.5-9.7-1.4-2.8-12.5-30.1-17.1-41.2-4.5-10.8-9.1-9.3-12.5-9.5-3.2-.2-6.9-.2-10.6-.2-3.7 0-9.7 1.4-14.8 6.9-5.1 5.6-19.4 19-19.4 46.3 0 27.3 19.9 53.7 22.6 57.4 2.8 3.7 39.1 59.7 94.8 83.8 35.2 15.2 49 16.5 66.6 13.9 10.7-1.6 32.8-13.4 37.4-26.4 4.6-13 4.6-24.1 3.2-26.4-1.3-2.5-5-3.9-10.5-6.6z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6f6710aa elementor-section-content-middle elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6f6710aa\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-23ffaee8\" data-id=\"23ffaee8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6b9e533d elementor-widget elementor-widget-text-editor\" data-id=\"6b9e533d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tContatti\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2e2f2775 elementor-shape-circle e-grid-align-left elementor-grid-0 elementor-widget elementor-widget-social-icons\" data-id=\"2e2f2775\" data-element_type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-facebook elementor-repeater-item-1539373\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Facebook<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-facebook\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M504 256C504 119 393 8 256 8S8 119 8 256c0 123.78 90.69 226.38 209.25 245V327.69h-63V256h63v-54.64c0-62.15 37-96.48 93.67-96.48 27.14 0 55.52 4.84 55.52 4.84v61h-31.28c-30.8 0-40.41 19.12-40.41 38.73V256h68.78l-11 71.69h-57.78V501C413.31 482.38 504 379.78 504 256z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-twitter elementor-repeater-item-8913cb9\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Twitter<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-twitter\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M459.37 151.716c.325 4.548.325 9.097.325 13.645 0 138.72-105.583 298.558-298.558 298.558-59.452 0-114.68-17.219-161.137-47.106 8.447.974 16.568 1.299 25.34 1.299 49.055 0 94.213-16.568 130.274-44.832-46.132-.975-84.792-31.188-98.112-72.772 6.498.974 12.995 1.624 19.818 1.624 9.421 0 18.843-1.3 27.614-3.573-48.081-9.747-84.143-51.98-84.143-102.985v-1.299c13.969 7.797 30.214 12.67 47.431 13.319-28.264-18.843-46.781-51.005-46.781-87.391 0-19.492 5.197-37.36 14.294-52.954 51.655 63.675 129.3 105.258 216.365 109.807-1.624-7.797-2.599-15.918-2.599-24.04 0-57.828 46.782-104.934 104.934-104.934 30.213 0 57.502 12.67 76.67 33.137 23.715-4.548 46.456-13.32 66.599-25.34-7.798 24.366-24.366 44.833-46.132 57.827 21.117-2.273 41.584-8.122 60.426-16.243-14.292 20.791-32.161 39.308-52.628 54.253z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-youtube elementor-repeater-item-3255c55\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Youtube<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-youtube\" viewBox=\"0 0 576 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M549.655 124.083c-6.281-23.65-24.787-42.276-48.284-48.597C458.781 64 288 64 288 64S117.22 64 74.629 75.486c-23.497 6.322-42.003 24.947-48.284 48.597-11.412 42.867-11.412 132.305-11.412 132.305s0 89.438 11.412 132.305c6.281 23.65 24.787 41.5 48.284 47.821C117.22 448 288 448 288 448s170.78 0 213.371-11.486c23.497-6.321 42.003-24.171 48.284-47.821 11.412-42.867 11.412-132.305 11.412-132.305s0-89.438-11.412-132.305zm-317.51 213.508V175.185l142.739 81.205-142.739 81.201z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5505f8ef\" data-id=\"5505f8ef\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-641541fc elementor-widget elementor-widget-text-editor\" data-id=\"641541fc\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div id=\"gmw-single-location-wrapper-239\" class=\"gmw-element-wrapper gmw-single-location-wrapper gmw-sl-wrapper gmw-sl-single-post-wrapper post \" object_type=\"post\" object_id=\"19333\"  style=\"width:100%\"><div class=\"gmw-sl-map-wrapper gmw-sl-element\"><div id=\"gmw-map-wrapper-239\" class=\"gmw-map-wrapper  sl single_location \" style=\"width:100%;height:300px;\"> <span id=\"gmw-resize-map-toggle-239\" class=\"gmw-resize-map-toggle gmw-icon-resize-full\" style=\"display:none;\" title=\"Resize map\"><\/span> <div id=\"gmw-map-loader-239\" class=\"gmw-map-loader\"><\/div> <div id=\"gmw-map-239\" class=\"gmw-map sl single_location\" style=\"width:100%; height:100%\" data-map_id=\"239\" data-prefix=\"sl\" data-map_type=\"single_location\" data-icons_usage=\"global\"><\/div> <\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-14f987b0 elementor-widget elementor-widget-text-editor\" data-id=\"14f987b0\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><div id=\"gmw-single-object-locations-wrapper-137\" class=\"gmw-element-wrapper gmw-single-location-wrapper gmw-sl-wrapper gmw-sl-single-post-wrapper post gmw-sl-multiple-locations\" object_type=\"post\" object_id=\"\"  style=\"width:100%\"><div class=\"gmw-sl-map-wrapper\"><div id=\"gmw-map-wrapper-137\" class=\"gmw-map-wrapper  sl single_location \" style=\"width:100%;height:350px;\"> <span id=\"gmw-resize-map-toggle-137\" class=\"gmw-resize-map-toggle gmw-icon-resize-full\" style=\"display:none;\" title=\"Resize map\"><\/span> <div id=\"gmw-map-loader-137\" class=\"gmw-map-loader\"><\/div> <div id=\"gmw-map-137\" class=\"gmw-map sl single_location\" style=\"width:100%; height:100%\" data-map_id=\"137\" data-prefix=\"sl\" data-map_type=\"single_location\" data-icons_usage=\"global\"><\/div> <\/div><\/div><\/div><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<div style=\"display: none;\">\n<p>Ciao sono Moira, amo accompagnare le persone e le organizzazioni ad esprimere al meglio le proprie potenzialit\u00e0 per ricercare soluzioni creative ed efficaci all\u2019interno di un progetto personalizzato.<br \/>\nIl mio scopo ? Essere una professionista di supporto nei processi di crescita ed evoluzione e far stare bene le persone.<br \/>\nSpecializzazioni:<br \/>\nPedagogista<br \/>\nCoach Umanista<br \/>\nArte terapista e musicoterapista<br \/>\nFormatrice<br \/>\nProgettista educativa e sociale<br \/>\nOperatrice Mindfulness<br \/>\nVuoi richiedere una consulenza? Vuoi prenotare le tue sessioni di<br \/>\nCoaching? Vuoi realizzare un progetto educativo in linea con l\u2019approccio<br \/>\nprofessionale che propongo? Vuoi migliorare il tuo Benessere e quello dei<br \/>\ntuoi dipendenti?<br \/>\nSONO A TUA DISPOSIZIONE!<\/p>\n<p>Pedagogista, Coach Umanista, Arte terapista, musicoterapista, Mindfulness, Consulenza pedagogica, Consulente pedagogico, pedagogia, sessioni di Coaching, servizi educativi, attivit\u00e0 educative,<\/p>\n<p>Pedagogista a Varese, Coach Umanista a Varese, Arte terapista a Varese, musicoterapista a Varese, Mindfulness a Varese, Consulenza pedagogica a Varese, Consulente pedagogico a Varese, pedagogia a Varese, sessioni di Coaching a Varese, servizi educativi a Varese, attivit\u00e0 educative a Varese,<\/p>\n<p>Pedagogista online, Coach Umanista online, Arte terapista online, musicoterapista online, Mindfulness online, Consulenza pedagogica online, Consulente pedagogico online, pedagogia online, sessioni di Coaching online, servizi educativi online, attivit\u00e0 educative online,<\/p>\n<\/div>\n","protected":false},"featured_media":19334,"comment_status":"open","ping_status":"closed","template":"elementor_header_footer","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":""},"product_brand":[],"product_cat":[3961,26],"product_tag":[3954,3960,3953,3957,3956,712,3955,3958,3952,2937,3959],"class_list":{"0":"post-19333","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-pedagogista","7":"product_cat-salute","8":"product_tag-arte-terapista","9":"product_tag-attivita-educative","10":"product_tag-coach-umanista","11":"product_tag-consulente-pedagogico","12":"product_tag-consulenza-pedagogica","13":"product_tag-mindfulness","14":"product_tag-musicoterapista","15":"product_tag-pedagogia","16":"product_tag-pedagogista","17":"product_tag-servizi-educativi","18":"product_tag-sessioni-di-coaching","20":"first","21":"instock","22":"shipping-taxable","23":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Dott.ssa Moira Minurri - Pedagogista e Coach Umanista - Cral Policlinico di Milano<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/dott-ssa-moira-minurri-pedagogista-e-coach-umanista\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dott.ssa Moira Minurri - Pedagogista e Coach Umanista - Cral Policlinico di Milano\" \/>\n<meta property=\"og:description\" content=\"Ciao sono Moira, amo accompagnare le persone e le organizzazioni ad esprimere al meglio le proprie potenzialit\u00e0 per ricercare soluzioni creative ed efficaci all\u2019interno di un progetto personalizzato. Il mio scopo ? Essere una professionista di supporto nei processi di crescita ed evoluzione e far stare bene le persone. Specializzazioni: Pedagogista Coach Umanista Arte terapista e musicoterapista Formatrice Progettista educativa e sociale Operatrice Mindfulness Vuoi richiedere una consulenza? Vuoi prenotare le tue sessioni di Coaching? Vuoi realizzare un progetto educativo in linea con l\u2019approccio professionale che propongo? Vuoi migliorare il tuo Benessere e quello dei tuoi dipendenti? SONO A TUA DISPOSIZIONE!  Pedagogista, Coach Umanista, Arte terapista, musicoterapista, Mindfulness, Consulenza pedagogica, Consulente pedagogico, pedagogia, sessioni di Coaching, servizi educativi, attivit\u00e0 educative,  Pedagogista a Varese, Coach Umanista a Varese, Arte terapista a Varese, musicoterapista a Varese, Mindfulness a Varese, Consulenza pedagogica a Varese, Consulente pedagogico a Varese, pedagogia a Varese, sessioni di Coaching a Varese, servizi educativi a Varese, attivit\u00e0 educative a Varese,  Pedagogista online, Coach Umanista online, Arte terapista online, musicoterapista online, Mindfulness online, Consulenza pedagogica online, Consulente pedagogico online, pedagogia online, sessioni di Coaching online, servizi educativi online, attivit\u00e0 educative online,\" \/>\n<meta property=\"og:url\" content=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/dott-ssa-moira-minurri-pedagogista-e-coach-umanista\/\" \/>\n<meta property=\"og:site_name\" content=\"Cral Policlinico di Milano\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-12T08:22:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/05\/logo_Moira-Minurri.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/dott-ssa-moira-minurri-pedagogista-e-coach-umanista\/\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/dott-ssa-moira-minurri-pedagogista-e-coach-umanista\/\",\"name\":\"Dott.ssa Moira Minurri - Pedagogista e Coach Umanista - Cral Policlinico di Milano\",\"isPartOf\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/dott-ssa-moira-minurri-pedagogista-e-coach-umanista\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/dott-ssa-moira-minurri-pedagogista-e-coach-umanista\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/05\/logo_Moira-Minurri.jpg\",\"datePublished\":\"2025-05-05T09:27:20+00:00\",\"dateModified\":\"2025-05-12T08:22:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/dott-ssa-moira-minurri-pedagogista-e-coach-umanista\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/dott-ssa-moira-minurri-pedagogista-e-coach-umanista\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/dott-ssa-moira-minurri-pedagogista-e-coach-umanista\/#primaryimage\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/05\/logo_Moira-Minurri.jpg\",\"contentUrl\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/05\/logo_Moira-Minurri.jpg\",\"width\":300,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/dott-ssa-moira-minurri-pedagogista-e-coach-umanista\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/negozio\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Dott.ssa Moira Minurri &#8211; Pedagogista e Coach Umanista\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/#website\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/\",\"name\":\"Cral Policlinico di Milano\",\"description\":\"Area Convenzioni\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dott.ssa Moira Minurri - Pedagogista e Coach Umanista - Cral Policlinico di Milano","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/dott-ssa-moira-minurri-pedagogista-e-coach-umanista\/","og_locale":"it_IT","og_type":"article","og_title":"Dott.ssa Moira Minurri - Pedagogista e Coach Umanista - Cral Policlinico di Milano","og_description":"Ciao sono Moira, amo accompagnare le persone e le organizzazioni ad esprimere al meglio le proprie potenzialit\u00e0 per ricercare soluzioni creative ed efficaci all\u2019interno di un progetto personalizzato. Il mio scopo ? Essere una professionista di supporto nei processi di crescita ed evoluzione e far stare bene le persone. Specializzazioni: Pedagogista Coach Umanista Arte terapista e musicoterapista Formatrice Progettista educativa e sociale Operatrice Mindfulness Vuoi richiedere una consulenza? Vuoi prenotare le tue sessioni di Coaching? Vuoi realizzare un progetto educativo in linea con l\u2019approccio professionale che propongo? Vuoi migliorare il tuo Benessere e quello dei tuoi dipendenti? SONO A TUA DISPOSIZIONE!  Pedagogista, Coach Umanista, Arte terapista, musicoterapista, Mindfulness, Consulenza pedagogica, Consulente pedagogico, pedagogia, sessioni di Coaching, servizi educativi, attivit\u00e0 educative,  Pedagogista a Varese, Coach Umanista a Varese, Arte terapista a Varese, musicoterapista a Varese, Mindfulness a Varese, Consulenza pedagogica a Varese, Consulente pedagogico a Varese, pedagogia a Varese, sessioni di Coaching a Varese, servizi educativi a Varese, attivit\u00e0 educative a Varese,  Pedagogista online, Coach Umanista online, Arte terapista online, musicoterapista online, Mindfulness online, Consulenza pedagogica online, Consulente pedagogico online, pedagogia online, sessioni di Coaching online, servizi educativi online, attivit\u00e0 educative online,","og_url":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/dott-ssa-moira-minurri-pedagogista-e-coach-umanista\/","og_site_name":"Cral Policlinico di Milano","article_modified_time":"2025-05-12T08:22:06+00:00","og_image":[{"width":300,"height":300,"url":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/05\/logo_Moira-Minurri.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/dott-ssa-moira-minurri-pedagogista-e-coach-umanista\/","url":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/dott-ssa-moira-minurri-pedagogista-e-coach-umanista\/","name":"Dott.ssa Moira Minurri - Pedagogista e Coach Umanista - Cral Policlinico di Milano","isPartOf":{"@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/#website"},"primaryImageOfPage":{"@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/dott-ssa-moira-minurri-pedagogista-e-coach-umanista\/#primaryimage"},"image":{"@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/dott-ssa-moira-minurri-pedagogista-e-coach-umanista\/#primaryimage"},"thumbnailUrl":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/05\/logo_Moira-Minurri.jpg","datePublished":"2025-05-05T09:27:20+00:00","dateModified":"2025-05-12T08:22:06+00:00","breadcrumb":{"@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/dott-ssa-moira-minurri-pedagogista-e-coach-umanista\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/dott-ssa-moira-minurri-pedagogista-e-coach-umanista\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/dott-ssa-moira-minurri-pedagogista-e-coach-umanista\/#primaryimage","url":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/05\/logo_Moira-Minurri.jpg","contentUrl":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/05\/logo_Moira-Minurri.jpg","width":300,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/dott-ssa-moira-minurri-pedagogista-e-coach-umanista\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/negozio\/"},{"@type":"ListItem","position":3,"name":"Dott.ssa Moira Minurri &#8211; Pedagogista e Coach Umanista"}]},{"@type":"WebSite","@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/#website","url":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/","name":"Cral Policlinico di Milano","description":"Area Convenzioni","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/product\/19333","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/comments?post=19333"}],"version-history":[{"count":39,"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/product\/19333\/revisions"}],"predecessor-version":[{"id":19607,"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/product\/19333\/revisions\/19607"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/media\/19334"}],"wp:attachment":[{"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/media?parent=19333"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/product_brand?post=19333"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/product_cat?post=19333"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/product_tag?post=19333"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}