{"id":17984,"date":"2025-03-24T15:51:09","date_gmt":"2025-03-24T14:51:09","guid":{"rendered":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/?post_type=product&#038;p=17984"},"modified":"2025-04-29T14:26:57","modified_gmt":"2025-04-29T12:26:57","slug":"sinervis-academy","status":"publish","type":"product","link":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/sinervis-academy\/","title":{"rendered":"SinerVis Academy"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"17984\" class=\"elementor elementor-17984\">\n\t\t\t\t<div class=\"elementor-element elementor-element-961c97d e-flex e-con-boxed e-con e-parent\" data-id=\"961c97d\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4541cd8 elementor-widget elementor-widget-text-editor\" data-id=\"4541cd8\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Ottieni il 15% di sconto sui corsi di <em><strong>formazione<\/strong> <\/em>di Sinervis Academy<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1567427 elementor-widget elementor-widget-text-editor\" data-id=\"1567427\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Migliora le tue competenze con la nostra formazione professionale. Approfitta subito di questa partnership e porta la tua carriera al livello successivo!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1b4ac5c e-flex e-con-boxed e-con e-child\" data-id=\"1b4ac5c\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3abab33 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"3abab33\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-star\" viewBox=\"0 0 576 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M259.3 17.8L194 150.2 47.9 171.5c-26.2 3.8-36.7 36.1-17.7 54.6l105.7 103-25 145.5c-4.5 26.3 23.2 46 46.4 33.7L288 439.6l130.7 68.7c23.2 12.2 50.9-7.4 46.4-33.7l-25-145.5 105.7-103c19-18.5 8.5-50.8-17.7-54.6L382 150.2 316.7 17.8c-11.7-23.6-45.6-23.9-57.4 0z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-647c57a elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"647c57a\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-star\" viewBox=\"0 0 576 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M259.3 17.8L194 150.2 47.9 171.5c-26.2 3.8-36.7 36.1-17.7 54.6l105.7 103-25 145.5c-4.5 26.3 23.2 46 46.4 33.7L288 439.6l130.7 68.7c23.2 12.2 50.9-7.4 46.4-33.7l-25-145.5 105.7-103c19-18.5 8.5-50.8-17.7-54.6L382 150.2 316.7 17.8c-11.7-23.6-45.6-23.9-57.4 0z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f79081c elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"f79081c\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-star\" viewBox=\"0 0 576 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M259.3 17.8L194 150.2 47.9 171.5c-26.2 3.8-36.7 36.1-17.7 54.6l105.7 103-25 145.5c-4.5 26.3 23.2 46 46.4 33.7L288 439.6l130.7 68.7c23.2 12.2 50.9-7.4 46.4-33.7l-25-145.5 105.7-103c19-18.5 8.5-50.8-17.7-54.6L382 150.2 316.7 17.8c-11.7-23.6-45.6-23.9-57.4 0z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bb07550 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"bb07550\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-star\" viewBox=\"0 0 576 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M259.3 17.8L194 150.2 47.9 171.5c-26.2 3.8-36.7 36.1-17.7 54.6l105.7 103-25 145.5c-4.5 26.3 23.2 46 46.4 33.7L288 439.6l130.7 68.7c23.2 12.2 50.9-7.4 46.4-33.7l-25-145.5 105.7-103c19-18.5 8.5-50.8-17.7-54.6L382 150.2 316.7 17.8c-11.7-23.6-45.6-23.9-57.4 0z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-eaaa384 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"eaaa384\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-star\" viewBox=\"0 0 576 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M259.3 17.8L194 150.2 47.9 171.5c-26.2 3.8-36.7 36.1-17.7 54.6l105.7 103-25 145.5c-4.5 26.3 23.2 46 46.4 33.7L288 439.6l130.7 68.7c23.2 12.2 50.9-7.4 46.4-33.7l-25-145.5 105.7-103c19-18.5 8.5-50.8-17.7-54.6L382 150.2 316.7 17.8c-11.7-23.6-45.6-23.9-57.4 0z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5d9ffa0 elementor-widget elementor-widget-text-editor\" data-id=\"5d9ffa0\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>5\/5<\/strong> (327 recensioni Google)<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5a60c5a e-flex e-con-boxed e-con e-parent\" data-id=\"5a60c5a\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-b6934d2 e-con-full e-flex e-con e-child\" data-id=\"b6934d2\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-114fee7 elementor-widget__width-inherit elementor-widget elementor-widget-image\" data-id=\"114fee7\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" fetchpriority=\"high\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/03\/dcffd54174894c51b1de271e748d77042-scaled.jpg\" class=\"attachment-full size-full wp-image-18903\" alt=\"\" srcset=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/03\/dcffd54174894c51b1de271e748d77042-scaled.jpg 2560w, https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/03\/dcffd54174894c51b1de271e748d77042-1280x854.jpg 1280w, https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/03\/dcffd54174894c51b1de271e748d77042-980x653.jpg 980w, https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/03\/dcffd54174894c51b1de271e748d77042-480x320.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) and (max-width: 1280px) 1280px, (min-width: 1281px) 2560px, 100vw\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a5fe969 elementor-widget elementor-widget-text-editor\" data-id=\"a5fe969\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Corsi per aziende<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f9bca2a elementor-widget elementor-widget-text-editor\" data-id=\"f9bca2a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Offriamo corsi personalizzati per piccole, medie e grande aziende, progettati su misura per soddisfare tutte le specifiche esigenze della tua organizzazione.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-bbd43e4 e-con-full e-flex e-con e-child\" data-id=\"bbd43e4\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6d96e63 elementor-widget__width-inherit elementor-widget elementor-widget-image\" data-id=\"6d96e63\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/03\/dcffd5417489c51b1de271e748d77042-scaled.jpg\" class=\"attachment-full size-full wp-image-18884\" alt=\"\" srcset=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/03\/dcffd5417489c51b1de271e748d77042-scaled.jpg 2560w, https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/03\/dcffd5417489c51b1de271e748d77042-1280x854.jpg 1280w, https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/03\/dcffd5417489c51b1de271e748d77042-980x653.jpg 980w, https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/03\/dcffd5417489c51b1de271e748d77042-480x320.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) and (max-width: 1280px) 1280px, (min-width: 1281px) 2560px, 100vw\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ff11685 elementor-widget elementor-widget-text-editor\" data-id=\"ff11685\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Corsi per privati<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fdc384d elementor-widget elementor-widget-text-editor\" data-id=\"fdc384d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Prendi il controllo della tua carriera con i nostri corsi personalizzati: un nuovo inizio per realizzare il tuo futuro professionale.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7190e15 e-con-full e-flex e-con e-child\" data-id=\"7190e15\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d3852ed elementor-widget__width-inherit elementor-widget elementor-widget-image\" data-id=\"d3852ed\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/03\/dcffd541748951b1de271e748d77042-scaled.jpg\" class=\"attachment-full size-full wp-image-18904\" alt=\"\" srcset=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/03\/dcffd541748951b1de271e748d77042-scaled.jpg 2560w, https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/03\/dcffd541748951b1de271e748d77042-1280x854.jpg 1280w, https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/03\/dcffd541748951b1de271e748d77042-980x653.jpg 980w, https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/03\/dcffd541748951b1de271e748d77042-480x320.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) and (max-width: 1280px) 1280px, (min-width: 1281px) 2560px, 100vw\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0590bd4 elementor-widget elementor-widget-text-editor\" data-id=\"0590bd4\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Academy<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9279908 elementor-widget elementor-widget-text-editor\" data-id=\"9279908\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Percorsi formativi full time su misura per sviluppare completamente le competenze della figura professionale target.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d031c39 elementor-hidden-desktop e-flex e-con-boxed e-con e-parent\" data-id=\"d031c39\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-b092630 e-flex e-con-boxed e-con e-child\" data-id=\"b092630\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-25cd1f8 elementor-widget elementor-widget-text-editor\" data-id=\"25cd1f8\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #f86b00;\">o<\/span> CHI \u00e8 SINERVIS ACADEMY<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2920889 elementor-widget elementor-widget-text-editor\" data-id=\"2920889\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Dal 2003 siamo la <strong>migliore <\/strong><strong>scuola di formazione <\/strong><strong>informatica.<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-db1f3c0 elementor-widget elementor-widget-button\" data-id=\"db1f3c0\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/corsi.sinervis.com\/?utm_source=cral&#038;utm_medium=landing&#038;utm_campaign=linkbuild\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Visita il nostro sito<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4a942b9 e-flex e-con-boxed e-con e-child\" data-id=\"4a942b9\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7c22053 elementor-widget elementor-widget-text-editor\" data-id=\"7c22053\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Progettiamo i tuoi percorsi di formazione in base agli obiettivi e le richieste attuali del mondo del lavoro, attivando la tua motivazione attraverso un clima favorevole alla partecipazione e all\u2019interazione per aiutarti a costruire una professionalit\u00e0 solida e vincente.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5510e0a e-con-full e-flex e-con e-child\" data-id=\"5510e0a\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cfe32a4 elementor-widget elementor-widget-text-editor\" data-id=\"cfe32a4\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t+100\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cf0b40a elementor-widget elementor-widget-text-editor\" data-id=\"cf0b40a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>CORSI A CATALOGO<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-57dac9f e-con-full e-flex e-con e-child\" data-id=\"57dac9f\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4ebe19d elementor-widget elementor-widget-text-editor\" data-id=\"4ebe19d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>+40k<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a71ba37 elementor-widget elementor-widget-text-editor\" data-id=\"a71ba37\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>ORE EROGATE DI CORSI<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-25dbccb e-con-full e-flex e-con e-child\" data-id=\"25dbccb\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a128b3c elementor-widget elementor-widget-text-editor\" data-id=\"a128b3c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>+600<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fc90d8f elementor-widget elementor-widget-text-editor\" data-id=\"fc90d8f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>DOCENTI QUALIFICATI<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c424871 e-con-full e-flex e-con e-child\" data-id=\"c424871\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-08aa571 elementor-widget elementor-widget-text-editor\" data-id=\"08aa571\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>+50k<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b63334f elementor-widget elementor-widget-text-editor\" data-id=\"b63334f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>CORSISTI FORMATI<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-fd4f2f6 e-con-full e-flex e-con e-child\" data-id=\"fd4f2f6\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-fd58dc0 e-flex e-con-boxed e-con e-child\" data-id=\"fd58dc0\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9016ea8 elementor-widget elementor-widget-text-editor\" data-id=\"9016ea8\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Promozione: sconto solo per i convenzionati pari al <strong>15<\/strong>% per tutti i corsi a catalogo<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ba0ba4c elementor-widget elementor-widget-text-editor\" data-id=\"ba0ba4c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Approfitta di questa convenzione che ti da diritto ad uno sconto esclusivo del 15% su tutti i corsi presenti nel nostro catalogo dei corsi di gruppo. Approfitta ora di questa offerta per aggiornare le tue competenze con i migliori percorsi formativi. Scopri i corsi disponibili e iscriviti oggi stesso!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-852afc2 elementor-hidden-tablet elementor-hidden-mobile e-flex e-con-boxed e-con e-parent\" data-id=\"852afc2\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-299a7a9 e-con-full e-flex e-con e-child\" data-id=\"299a7a9\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8c43e64 elementor-widget elementor-widget-text-editor\" data-id=\"8c43e64\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #f86b00;\">o<\/span> CHI \u00e8 SINERVIS ACADEMY<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f5ee44a elementor-widget elementor-widget-text-editor\" data-id=\"f5ee44a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Dal 2003 siamo la <strong>migliore <\/strong><strong>scuola di formazione <\/strong><strong>informatica.<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7b08280 elementor-widget elementor-widget-button\" data-id=\"7b08280\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/corsi.sinervis.com\/?utm_source=cral&#038;utm_medium=landing&#038;utm_campaign=linkbuild\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Visita il nostro sito<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-aa15604 e-con-full e-flex e-con e-child\" data-id=\"aa15604\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-71f40b4 elementor-widget elementor-widget-text-editor\" data-id=\"71f40b4\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Progettiamo i tuoi percorsi di formazione in base agli obiettivi e le richieste attuali del mondo del lavoro, attivando la tua motivazione attraverso un clima favorevole alla partecipazione e all\u2019interazione per aiutarti a costruire una professionalit\u00e0 solida e vincente.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-90f09e9 e-con-full e-flex e-con e-child\" data-id=\"90f09e9\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6a87991 elementor-widget elementor-widget-text-editor\" data-id=\"6a87991\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t+100\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-361c059 elementor-widget elementor-widget-text-editor\" data-id=\"361c059\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>CORSI A CATALOGO<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3c3682c e-con-full e-flex e-con e-child\" data-id=\"3c3682c\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e4c10dd elementor-widget elementor-widget-text-editor\" data-id=\"e4c10dd\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>+40k<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-abff2ae elementor-widget elementor-widget-text-editor\" data-id=\"abff2ae\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>ORE EROGATE DI CORSI<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7246807 e-con-full e-flex e-con e-child\" data-id=\"7246807\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c456c83 elementor-widget elementor-widget-text-editor\" data-id=\"c456c83\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>+600<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c6141ae elementor-widget elementor-widget-text-editor\" data-id=\"c6141ae\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>DOCENTI QUALIFICATI<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d13925a e-con-full e-flex e-con e-child\" data-id=\"d13925a\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-40d416a elementor-widget elementor-widget-text-editor\" data-id=\"40d416a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>+50k<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ee75d6f elementor-widget elementor-widget-text-editor\" data-id=\"ee75d6f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>CORSISTI FORMATI<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-83946c5 e-con-full e-flex e-con e-child\" data-id=\"83946c5\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-056b4ad e-con-full e-flex e-con e-child\" data-id=\"056b4ad\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-81264c0 elementor-widget elementor-widget-text-editor\" data-id=\"81264c0\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Promozione: sconto solo per i convenzionati pari al <strong>15<\/strong>% per tutti i corsi a catalogo<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8e30541 elementor-widget elementor-widget-text-editor\" data-id=\"8e30541\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Approfitta di questa convenzione che ti da diritto ad uno sconto esclusivo del 15% su tutti i corsi presenti nel nostro catalogo dei corsi di gruppo. Approfitta ora di questa offerta per aggiornare le tue competenze con i migliori percorsi formativi. Scopri i corsi disponibili e iscriviti oggi stesso!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-99a99e9 elementor-hidden-desktop e-flex e-con-boxed e-con e-parent\" data-id=\"99a99e9\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-73851ad e-flex e-con-boxed e-con e-child\" data-id=\"73851ad\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<a class=\"elementor-element elementor-element-3016add e-flex e-con-boxed e-con e-child\" data-id=\"3016add\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\" href=\"https:\/\/corsi.sinervis.com\/programmi-corsi\/corso-excel-base-intermedio\/?utm_source=cral&#038;utm_medium=landing&#038;utm_campaign=linkbuild\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-084ca20 elementor-widget elementor-widget-text-editor\" data-id=\"084ca20\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>EXCEL<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d53fc73 elementor-widget elementor-widget-text-editor\" data-id=\"d53fc73\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>ANALISI<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<div class=\"elementor-element elementor-element-2443b73 elementor-widget elementor-widget-text-editor\" data-id=\"2443b73\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>DIVENTA UN ESPERTO DI EXCEL<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-87d3058 elementor-widget elementor-widget-text-editor\" data-id=\"87d3058\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Excel Base<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-481cb75 e-flex e-con-boxed e-con e-child\" data-id=\"481cb75\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b07c13f elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"b07c13f\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-map-marker-alt\" viewBox=\"0 0 384 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M172.268 501.67C26.97 291.031 0 269.413 0 192 0 85.961 85.961 0 192 0s192 85.961 192 192c0 77.413-26.97 99.031-172.268 309.67-9.535 13.774-29.93 13.773-39.464 0zM192 272c44.183 0 80-35.817 80-80s-35.817-80-80-80-80 35.817-80 80 35.817 80 80 80z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7bbee01 elementor-widget elementor-widget-text-editor\" data-id=\"7bbee01\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>STREAMING O PRESENZA<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2aeaaed elementor-widget elementor-widget-text-editor\" data-id=\"2aeaaed\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Un corso pratico e operativo per sviluppare competenze in Microsoft Excel, dalla gestione di fogli di calcolo all\u2019uso di funzioni avanzate, perfetto per aumentare la produttivit\u00e0 personale e aziendale.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8f973f9 elementor-widget elementor-widget-button\" data-id=\"8f973f9\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/corsi.sinervis.com\/programmi-corsi\/corso-excel-base-intermedio\/?utm_source=cral&#038;utm_medium=landing&#038;utm_campaign=linkbuild\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Scopri<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-481f708 e-flex e-con-boxed e-con e-child\" data-id=\"481f708\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<a class=\"elementor-element elementor-element-15cef65 e-flex e-con-boxed e-con e-child\" data-id=\"15cef65\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\" href=\"https:\/\/corsi.sinervis.com\/programmi-corsi\/corso-excel-avanzato\/?utm_source=cral&#038;utm_medium=landing&#038;utm_campaign=linkbuild\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a079ebf elementor-widget elementor-widget-text-editor\" data-id=\"a079ebf\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>EXCEL<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-06b15f6 elementor-widget elementor-widget-text-editor\" data-id=\"06b15f6\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>AI<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<div class=\"elementor-element elementor-element-4583e9c elementor-widget elementor-widget-text-editor\" data-id=\"4583e9c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>DIVENTA UN ESPERTO DI EXCEL E INTELLIGENZA ARTIFICIALE<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5949f63 elementor-widget elementor-widget-text-editor\" data-id=\"5949f63\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Excel Avanzato con AI<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-097d602 e-flex e-con-boxed e-con e-child\" data-id=\"097d602\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f948835 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"f948835\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-map-marker-alt\" viewBox=\"0 0 384 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M172.268 501.67C26.97 291.031 0 269.413 0 192 0 85.961 85.961 0 192 0s192 85.961 192 192c0 77.413-26.97 99.031-172.268 309.67-9.535 13.774-29.93 13.773-39.464 0zM192 272c44.183 0 80-35.817 80-80s-35.817-80-80-80-80 35.817-80 80 35.817 80 80 80z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b526108 elementor-widget elementor-widget-text-editor\" data-id=\"b526108\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>STREAMING O PRESENZA<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bd0cf1e elementor-widget elementor-widget-text-editor\" data-id=\"bd0cf1e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Un corso pratico e operativo per padroneggiare le funzionalit\u00e0 avanzate di Excel, integrando strumenti di Intelligenza Artificiale per l\u2019analisi e l\u2019automazione dei dati!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1ebda02 elementor-widget elementor-widget-button\" data-id=\"1ebda02\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/corsi.sinervis.com\/programmi-corsi\/corso-excel-avanzato\/?utm_source=cral&#038;utm_medium=landing&#038;utm_campaign=linkbuild\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Scopri<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8395075 e-flex e-con-boxed e-con e-child\" data-id=\"8395075\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<a class=\"elementor-element elementor-element-06630e8 e-flex e-con-boxed e-con e-child\" data-id=\"06630e8\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\" href=\"https:\/\/corsi.sinervis.com\/programmi-corsi\/corso-microsoft-office-base\/?utm_source=cral&#038;utm_medium=landing&#038;utm_campaign=linkbuild\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fe0a112 elementor-widget elementor-widget-text-editor\" data-id=\"fe0a112\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>OFFICE<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f50af9c elementor-widget elementor-widget-text-editor\" data-id=\"f50af9c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>SOFTWARE<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<div class=\"elementor-element elementor-element-2498f05 elementor-widget elementor-widget-text-editor\" data-id=\"2498f05\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>DIVENTA UN ESPERTO DI SOFTWARE MICROSOFT OFFICE<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1bb04f9 elementor-widget elementor-widget-text-editor\" data-id=\"1bb04f9\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Office Base<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-30cf0c1 e-flex e-con-boxed e-con e-child\" data-id=\"30cf0c1\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b247bb3 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"b247bb3\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-map-marker-alt\" viewBox=\"0 0 384 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M172.268 501.67C26.97 291.031 0 269.413 0 192 0 85.961 85.961 0 192 0s192 85.961 192 192c0 77.413-26.97 99.031-172.268 309.67-9.535 13.774-29.93 13.773-39.464 0zM192 272c44.183 0 80-35.817 80-80s-35.817-80-80-80-80 35.817-80 80 35.817 80 80 80z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1fbe913 elementor-widget elementor-widget-text-editor\" data-id=\"1fbe913\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>STREAMING O PRESENZA<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-94cd987 elementor-widget elementor-widget-text-editor\" data-id=\"94cd987\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Un corso pratico e operativo per imparare a utilizzare gli strumenti essenziali di Microsoft Office, ottimizzando il lavoro con documenti, fogli di calcolo e presentazioni.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0b12490 elementor-widget elementor-widget-button\" data-id=\"0b12490\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/corsi.sinervis.com\/programmi-corsi\/corso-microsoft-office-base\/?utm_source=cral&#038;utm_medium=landing&#038;utm_campaign=linkbuild\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Scopri<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4803067 e-flex e-con-boxed e-con e-child\" data-id=\"4803067\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<a class=\"elementor-element elementor-element-7967f86 e-flex e-con-boxed e-con e-child\" data-id=\"7967f86\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\" href=\"https:\/\/corsi.sinervis.com\/programmi-corsi\/corso-strategie-ai-per-aumento-della-produttivita-aziendale\/?utm_source=cral&#038;utm_medium=landing&#038;utm_campaign=linkbuild\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-63243ca elementor-widget elementor-widget-text-editor\" data-id=\"63243ca\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>AI<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d2f54d9 elementor-widget elementor-widget-text-editor\" data-id=\"d2f54d9\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>STRATEGIA<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<div class=\"elementor-element elementor-element-997fa45 elementor-widget elementor-widget-text-editor\" data-id=\"997fa45\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>DIVENTA UN ESPERTO DI AI<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9500b9b elementor-widget elementor-widget-text-editor\" data-id=\"9500b9b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Corso Strategie AI per l\u2019Aumento della Produttivit\u00e0 Aziendale<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-af2a494 e-flex e-con-boxed e-con e-child\" data-id=\"af2a494\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7b9f728 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"7b9f728\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-map-marker-alt\" viewBox=\"0 0 384 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M172.268 501.67C26.97 291.031 0 269.413 0 192 0 85.961 85.961 0 192 0s192 85.961 192 192c0 77.413-26.97 99.031-172.268 309.67-9.535 13.774-29.93 13.773-39.464 0zM192 272c44.183 0 80-35.817 80-80s-35.817-80-80-80-80 35.817-80 80 35.817 80 80 80z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f6b7924 elementor-widget elementor-widget-text-editor\" data-id=\"f6b7924\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>STREAMING O PRESENZA<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0ddc930 elementor-widget elementor-widget-text-editor\" data-id=\"0ddc930\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Un corso pratico per approfondire l\u2019automazione intelligente e il suo ruolo nel migliorare l\u2019efficienza operativa del mondo del lavoro<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-830824f elementor-widget elementor-widget-button\" data-id=\"830824f\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/corsi.sinervis.com\/programmi-corsi\/corso-strategie-ai-per-aumento-della-produttivita-aziendale\/?utm_source=cral&#038;utm_medium=landing&#038;utm_campaign=linkbuild\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Scopri<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-00e7659 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"00e7659\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/corsi.sinervis.com\/corsi\/?utm_source=cral&#038;utm_medium=landing&#038;utm_campaign=linkbuild\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Scopri tutti i corsi SinerVis a catalogo<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-cfb6f11 elementor-hidden-tablet elementor-hidden-mobile e-flex e-con-boxed e-con e-parent\" data-id=\"cfb6f11\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-55e769f e-con-full e-flex e-con e-child\" data-id=\"55e769f\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<a class=\"elementor-element elementor-element-926a101 e-flex e-con-boxed e-con e-child\" data-id=\"926a101\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\" href=\"https:\/\/corsi.sinervis.com\/programmi-corsi\/corso-excel-base-intermedio\/?utm_source=cral&#038;utm_medium=landing&#038;utm_campaign=linkbuild\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8744688 elementor-widget elementor-widget-text-editor\" data-id=\"8744688\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>EXCEL<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ce3481b elementor-widget elementor-widget-text-editor\" data-id=\"ce3481b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>ANALISI<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<div class=\"elementor-element elementor-element-8e41738 elementor-widget elementor-widget-text-editor\" data-id=\"8e41738\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>DIVENTA UN ESPERTO DI EXCEL<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9c7579b elementor-widget elementor-widget-text-editor\" data-id=\"9c7579b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Excel Base<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b655fb4 e-flex e-con-boxed e-con e-child\" data-id=\"b655fb4\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-36ec883 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"36ec883\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-map-marker-alt\" viewBox=\"0 0 384 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M172.268 501.67C26.97 291.031 0 269.413 0 192 0 85.961 85.961 0 192 0s192 85.961 192 192c0 77.413-26.97 99.031-172.268 309.67-9.535 13.774-29.93 13.773-39.464 0zM192 272c44.183 0 80-35.817 80-80s-35.817-80-80-80-80 35.817-80 80 35.817 80 80 80z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-47af0d8 elementor-widget elementor-widget-text-editor\" data-id=\"47af0d8\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>STREAMING O PRESENZA<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-77293c0 elementor-widget elementor-widget-text-editor\" data-id=\"77293c0\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Un corso pratico e operativo per sviluppare competenze in Microsoft Excel, dalla gestione di fogli di calcolo all\u2019uso di funzioni avanzate, perfetto per aumentare la produttivit\u00e0 personale e aziendale.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4823c6f elementor-widget elementor-widget-button\" data-id=\"4823c6f\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/corsi.sinervis.com\/programmi-corsi\/corso-excel-base-intermedio\/?utm_source=cral&#038;utm_medium=landing&#038;utm_campaign=linkbuild\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Scopri<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-aae3292 e-con-full e-flex e-con e-child\" data-id=\"aae3292\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<a class=\"elementor-element elementor-element-839f7cc e-flex e-con-boxed e-con e-child\" data-id=\"839f7cc\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\" href=\"https:\/\/corsi.sinervis.com\/programmi-corsi\/corso-excel-avanzato\/?utm_source=cral&#038;utm_medium=landing&#038;utm_campaign=linkbuild\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a2169d1 elementor-widget elementor-widget-text-editor\" data-id=\"a2169d1\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>EXCEL<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-77d092a elementor-widget elementor-widget-text-editor\" data-id=\"77d092a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>AI<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<div class=\"elementor-element elementor-element-338f19c elementor-widget elementor-widget-text-editor\" data-id=\"338f19c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>DIVENTA UN ESPERTO DI EXCEL E INTELLIGENZA ARTIFICIALE<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-95bd45a elementor-widget elementor-widget-text-editor\" data-id=\"95bd45a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Excel Avanzato con AI<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-061a634 e-flex e-con-boxed e-con e-child\" data-id=\"061a634\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-722eafc elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"722eafc\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-map-marker-alt\" viewBox=\"0 0 384 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M172.268 501.67C26.97 291.031 0 269.413 0 192 0 85.961 85.961 0 192 0s192 85.961 192 192c0 77.413-26.97 99.031-172.268 309.67-9.535 13.774-29.93 13.773-39.464 0zM192 272c44.183 0 80-35.817 80-80s-35.817-80-80-80-80 35.817-80 80 35.817 80 80 80z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0c466ef elementor-widget elementor-widget-text-editor\" data-id=\"0c466ef\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>STREAMING O PRESENZA<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-43df2a7 elementor-widget elementor-widget-text-editor\" data-id=\"43df2a7\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Un corso pratico e operativo per padroneggiare le funzionalit\u00e0 avanzate di Excel, integrando strumenti di Intelligenza Artificiale per l\u2019analisi e l\u2019automazione dei dati!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bf065fe elementor-widget elementor-widget-button\" data-id=\"bf065fe\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/corsi.sinervis.com\/programmi-corsi\/corso-excel-avanzato\/?utm_source=cral&#038;utm_medium=landing&#038;utm_campaign=linkbuild\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Scopri<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a877dea e-con-full e-flex e-con e-child\" data-id=\"a877dea\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<a class=\"elementor-element elementor-element-248dae6 e-flex e-con-boxed e-con e-child\" data-id=\"248dae6\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\" href=\"https:\/\/corsi.sinervis.com\/programmi-corsi\/corso-microsoft-office-base\/?utm_source=cral&#038;utm_medium=landing&#038;utm_campaign=linkbuild\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-82f45c1 elementor-widget elementor-widget-text-editor\" data-id=\"82f45c1\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>OFFICE<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-28bafd1 elementor-widget elementor-widget-text-editor\" data-id=\"28bafd1\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>SOFTWARE<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<div class=\"elementor-element elementor-element-9a6e166 elementor-widget elementor-widget-text-editor\" data-id=\"9a6e166\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>DIVENTA UN ESPERTO DI SOFTWARE MICROSOFT OFFICE<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f7ae028 elementor-widget elementor-widget-text-editor\" data-id=\"f7ae028\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Office Base<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ccb07d4 e-flex e-con-boxed e-con e-child\" data-id=\"ccb07d4\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b3045f1 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"b3045f1\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-map-marker-alt\" viewBox=\"0 0 384 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M172.268 501.67C26.97 291.031 0 269.413 0 192 0 85.961 85.961 0 192 0s192 85.961 192 192c0 77.413-26.97 99.031-172.268 309.67-9.535 13.774-29.93 13.773-39.464 0zM192 272c44.183 0 80-35.817 80-80s-35.817-80-80-80-80 35.817-80 80 35.817 80 80 80z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d713dd5 elementor-widget elementor-widget-text-editor\" data-id=\"d713dd5\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>STREAMING O PRESENZA<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-aae2a99 elementor-widget elementor-widget-text-editor\" data-id=\"aae2a99\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Un corso pratico e operativo per imparare a utilizzare gli strumenti essenziali di Microsoft Office, ottimizzando il lavoro con documenti, fogli di calcolo e presentazioni.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b79dc19 elementor-widget elementor-widget-button\" data-id=\"b79dc19\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/corsi.sinervis.com\/programmi-corsi\/corso-microsoft-office-base\/?utm_source=cral&#038;utm_medium=landing&#038;utm_campaign=linkbuild\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Scopri<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-11146a1 e-con-full e-flex e-con e-child\" data-id=\"11146a1\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<a class=\"elementor-element elementor-element-7379c1a e-flex e-con-boxed e-con e-child\" data-id=\"7379c1a\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\" href=\"https:\/\/corsi.sinervis.com\/programmi-corsi\/corso-strategie-ai-per-aumento-della-produttivita-aziendale\/?utm_source=cral&#038;utm_medium=landing&#038;utm_campaign=linkbuild\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d27208b elementor-widget elementor-widget-text-editor\" data-id=\"d27208b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>AI<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-20d4278 elementor-widget elementor-widget-text-editor\" data-id=\"20d4278\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>STRATEGIA<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<div class=\"elementor-element elementor-element-ae3ea8b elementor-widget elementor-widget-text-editor\" data-id=\"ae3ea8b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>DIVENTA UN ESPERTO DI AI<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4c2d4f8 elementor-widget elementor-widget-text-editor\" data-id=\"4c2d4f8\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Corso Strategie AI per l\u2019Aumento della Produttivit\u00e0 Aziendale<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5b530f7 e-flex e-con-boxed e-con e-child\" data-id=\"5b530f7\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cb3aa3b elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"cb3aa3b\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-map-marker-alt\" viewBox=\"0 0 384 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M172.268 501.67C26.97 291.031 0 269.413 0 192 0 85.961 85.961 0 192 0s192 85.961 192 192c0 77.413-26.97 99.031-172.268 309.67-9.535 13.774-29.93 13.773-39.464 0zM192 272c44.183 0 80-35.817 80-80s-35.817-80-80-80-80 35.817-80 80 35.817 80 80 80z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-923a720 elementor-widget elementor-widget-text-editor\" data-id=\"923a720\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>STREAMING O PRESENZA<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f98a8b4 elementor-widget elementor-widget-text-editor\" data-id=\"f98a8b4\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Un corso pratico per approfondire l\u2019automazione intelligente e il suo ruolo nel migliorare l\u2019efficienza operativa del mondo del lavoro<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b030d5b elementor-widget elementor-widget-button\" data-id=\"b030d5b\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/corsi.sinervis.com\/programmi-corsi\/corso-strategie-ai-per-aumento-della-produttivita-aziendale\/?utm_source=cral&#038;utm_medium=landing&#038;utm_campaign=linkbuild\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Scopri<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-535b0e3 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"535b0e3\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/corsi.sinervis.com\/corsi\/?utm_source=cral&#038;utm_medium=landing&#038;utm_campaign=linkbuild\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Scopri tutti i corsi SinerVis a catalogo<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-af2f65f e-flex e-con-boxed e-con e-parent\" data-id=\"af2f65f\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-1f20fd1 e-con-full e-flex e-con e-child\" data-id=\"1f20fd1\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-51e2fc1 elementor-widget elementor-widget-text-editor\" data-id=\"51e2fc1\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Coupon sconto 15%<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fcafae0 elementor-widget elementor-widget-text-editor\" data-id=\"fcafae0\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Per accedere al tuo sconto del 15% comunica in fase di compilazione form sul sito SinerVis, insieme ai tuoi dati, il <strong>codice sconto &#8220;CRALMangiagalli&#8221;.<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7cb61c4 e-con-full e-flex e-con e-child\" data-id=\"7cb61c4\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-6686ea8 e-con-full e-flex e-con e-child\" data-id=\"6686ea8\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e95e34f elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"e95e34f\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-gift\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M32 448c0 17.7 14.3 32 32 32h160V320H32v128zm256 32h160c17.7 0 32-14.3 32-32V320H288v160zm192-320h-42.1c6.2-12.1 10.1-25.5 10.1-40 0-48.5-39.5-88-88-88-41.6 0-68.5 21.3-103 68.3-34.5-47-61.4-68.3-103-68.3-48.5 0-88 39.5-88 88 0 14.5 3.8 27.9 10.1 40H32c-17.7 0-32 14.3-32 32v80c0 8.8 7.2 16 16 16h480c8.8 0 16-7.2 16-16v-80c0-17.7-14.3-32-32-32zm-326.1 0c-22.1 0-40-17.9-40-40s17.9-40 40-40c19.9 0 34.6 3.3 86.1 80h-86.1zm206.1 0h-86.1c51.4-76.5 65.7-80 86.1-80 22.1 0 40 17.9 40 40s-17.9 40-40 40z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6f4b285 elementor-widget elementor-widget-text-editor\" data-id=\"6f4b285\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>SCONTO 15%<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a79808f elementor-widget elementor-widget-text-editor\" data-id=\"a79808f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>CODICE<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ce57131 elementor-widget elementor-widget-text-editor\" data-id=\"ce57131\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>CRALMangiagalli<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-67aafca elementor-hidden-desktop e-flex e-con-boxed e-con e-parent\" data-id=\"67aafca\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-31eaef8 e-flex e-con-boxed e-con e-child\" data-id=\"31eaef8\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-ab794ac e-flex e-con-boxed e-con e-child\" data-id=\"ab794ac\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e434457 elementor-widget elementor-widget-text-editor\" data-id=\"e434457\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #f86b00;\">O <\/span>CERTIFICAZIONE ISO<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9186287 elementor-widget elementor-widget-text-editor\" data-id=\"9186287\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Certificazione ISO 9001:2015<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-994a36f elementor-widget elementor-widget-text-editor\" data-id=\"994a36f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>In SinerVis ci impegniamo nel mettere a disposizione del cliente strumenti formativi di valore e garantiti, ed \u00e8 per questo motivo che abbiamo acquisito la <strong>Certificazione Internazionale ISO 9001:2015<\/strong> per la qualit\u00e0 nella progettazione e nell\u2019erogazione dei percorsi formativi di informatica. Progettiamo ogni percorso didattico sempre con grande cura, e aggiorniamo periodicamente, secondo gli standard ISO, tutti i contenuti formativi sviluppati dal nostro team di docenti.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-da89979 elementor-widget__width-initial elementor-hidden-mobile elementor-widget elementor-widget-image\" data-id=\"da89979\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"840\" height=\"1200\" src=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/03\/9d8445be1a1c12969dc5fecfaf42cd6a.png\" class=\"attachment-full size-full wp-image-18907\" alt=\"\" srcset=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/03\/9d8445be1a1c12969dc5fecfaf42cd6a.png 840w, https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/03\/9d8445be1a1c12969dc5fecfaf42cd6a-480x686.png 480w\" sizes=\"auto, (min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 840px, 100vw\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f714a01 elementor-widget elementor-widget-button\" data-id=\"f714a01\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/corsi.sinervis.com\/?utm_source=cral&#038;utm_medium=landing&#038;utm_campaign=linkbuild\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Visita il nostro sito<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f0a878b elementor-hidden-tablet elementor-hidden-mobile e-flex e-con-boxed e-con e-parent\" data-id=\"f0a878b\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-03e9e20 e-con-full e-flex e-con e-child\" data-id=\"03e9e20\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9402a8c elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"9402a8c\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"840\" height=\"1200\" src=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/03\/9d8445be1a1c12969dc5fecfaf42cd6a.png\" class=\"attachment-full size-full wp-image-18907\" alt=\"\" srcset=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/03\/9d8445be1a1c12969dc5fecfaf42cd6a.png 840w, https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/03\/9d8445be1a1c12969dc5fecfaf42cd6a-480x686.png 480w\" sizes=\"auto, (min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 840px, 100vw\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8905e63 e-con-full e-flex e-con e-child\" data-id=\"8905e63\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7aca44c elementor-widget elementor-widget-text-editor\" data-id=\"7aca44c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #f86b00;\">O <\/span>CERTIFICAZIONE ISO<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-850ef2e elementor-widget elementor-widget-text-editor\" data-id=\"850ef2e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Certificazione ISO 9001:2015<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bbbcc28 elementor-widget elementor-widget-text-editor\" data-id=\"bbbcc28\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>In SinerVis ci impegniamo nel mettere a disposizione del cliente strumenti formativi di valore e garantiti, ed \u00e8 per questo motivo che abbiamo acquisito la <strong>Certificazione Internazionale ISO 9001:2015<\/strong> per la qualit\u00e0 nella progettazione e nell\u2019erogazione dei percorsi formativi di informatica. Progettiamo ogni percorso didattico sempre con grande cura, e aggiorniamo periodicamente, secondo gli standard ISO, tutti i contenuti formativi sviluppati dal nostro team di docenti.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-898d116 elementor-widget elementor-widget-button\" data-id=\"898d116\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/corsi.sinervis.com\/?utm_source=cral&#038;utm_medium=landing&#038;utm_campaign=linkbuild\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Visita il nostro sito<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ae65cf3 e-con-full elementor-hidden-desktop e-flex e-con e-parent\" data-id=\"ae65cf3\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-fd7e050 e-flex e-con-boxed e-con e-child\" data-id=\"fd7e050\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fd5bafa elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"fd5bafa\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"703\" src=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/03\/31b2d9a69763707d922be61ed4a4187d.png\" class=\"attachment-full size-full wp-image-18915\" alt=\"\" srcset=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/03\/31b2d9a69763707d922be61ed4a4187d.png 1024w, https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/03\/31b2d9a69763707d922be61ed4a4187d-980x673.png 980w, https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/03\/31b2d9a69763707d922be61ed4a4187d-480x330.png 480w\" sizes=\"auto, (min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ef17467 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"ef17467\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"291\" height=\"148\" src=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/03\/be350a91b77c8446db7ca3e55725f4fa.png\" class=\"attachment-full size-full wp-image-18914\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6d8e218 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"6d8e218\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"1437\" height=\"247\" src=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/03\/tesi.png\" class=\"attachment-full size-full wp-image-18918\" alt=\"\" srcset=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/03\/tesi.png 1437w, https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/03\/tesi-1280x220.png 1280w, https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/03\/tesi-980x168.png 980w, https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/03\/tesi-480x83.png 480w\" sizes=\"auto, (min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) and (max-width: 1280px) 1280px, (min-width: 1281px) 1437px, 100vw\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e726a37 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"e726a37\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"723\" height=\"209\" src=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/03\/mic.png\" class=\"attachment-full size-full wp-image-18917\" alt=\"\" srcset=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/03\/mic.png 723w, https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/03\/mic-480x139.png 480w\" sizes=\"auto, (min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 723px, 100vw\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-005c04a e-flex e-con-boxed e-con e-child\" data-id=\"005c04a\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e50d1e8 elementor-widget elementor-widget-text-editor\" data-id=\"e50d1e8\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>I nostri accreditamenti<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e6c12d5 elementor-widget elementor-widget-text-editor\" data-id=\"e6c12d5\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Siamo orgogliosi di aver conseguito negli anni tutti i pi\u00f9 importanti accreditamenti presenti sul mercato. SinerVis Academy \u00e8 accreditata:<br \/><strong>\u2013\u00a0Test Center ufficiale Pearson Vue\u2028<\/strong><br \/><strong>\u2013\u00a0Microsoft Training Center\u2028<\/strong><br \/><strong>\u2013\u00a0Tesi Automazione\u2028<\/strong><br \/><strong>\u2013\u00a0Test Center ICDL\u2028<\/strong><br \/><strong>\u2013\u00a0Accreditamento Formatem<\/strong>p<\/p><p>Questi prestigiosi riconoscimenti ci consentono di\u00a0offrire formazione certificata a livello internazionale in tutti gli ambiti del mondo IT, potendo erogare direttamente, per nostri clienti, le certificazioni internazionali di tutti i pi\u00f9 importanti player Globali, oltre a permetterci di erogare qualsiasi tipo di formazione finanziata.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-76d338a e-con-full elementor-hidden-tablet elementor-hidden-mobile e-flex e-con e-parent\" data-id=\"76d338a\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-6ba50e9 e-con-full e-flex e-con e-child\" data-id=\"6ba50e9\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b445bf5 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"b445bf5\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"703\" src=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/03\/31b2d9a69763707d922be61ed4a4187d.png\" class=\"attachment-full size-full wp-image-18915\" alt=\"\" srcset=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/03\/31b2d9a69763707d922be61ed4a4187d.png 1024w, https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/03\/31b2d9a69763707d922be61ed4a4187d-980x673.png 980w, https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/03\/31b2d9a69763707d922be61ed4a4187d-480x330.png 480w\" sizes=\"auto, (min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-84dfd8b elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"84dfd8b\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"291\" height=\"148\" src=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/03\/be350a91b77c8446db7ca3e55725f4fa.png\" class=\"attachment-full size-full wp-image-18914\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c80ca7f elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"c80ca7f\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"1437\" height=\"247\" src=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/03\/tesi.png\" class=\"attachment-full size-full wp-image-18918\" alt=\"\" srcset=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/03\/tesi.png 1437w, https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/03\/tesi-1280x220.png 1280w, https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/03\/tesi-980x168.png 980w, https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/03\/tesi-480x83.png 480w\" sizes=\"auto, (min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) and (max-width: 1280px) 1280px, (min-width: 1281px) 1437px, 100vw\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4958540 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"4958540\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"723\" height=\"209\" src=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/03\/mic.png\" class=\"attachment-full size-full wp-image-18917\" alt=\"\" srcset=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/03\/mic.png 723w, https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/03\/mic-480x139.png 480w\" sizes=\"auto, (min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 723px, 100vw\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-91177c2 e-con-full e-flex e-con e-child\" data-id=\"91177c2\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3a1923c elementor-widget elementor-widget-text-editor\" data-id=\"3a1923c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>I nostri accreditamenti<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-53a19df elementor-widget elementor-widget-text-editor\" data-id=\"53a19df\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Siamo orgogliosi di aver conseguito negli anni tutti i pi\u00f9 importanti accreditamenti presenti sul mercato. SinerVis Academy \u00e8 accreditata:<br \/><strong>\u2013\u00a0Test Center ufficiale Pearson Vue\u2028<\/strong><br \/><strong>\u2013\u00a0Microsoft Training Center\u2028<\/strong><br \/><strong>\u2013\u00a0Tesi Automazione\u2028<\/strong><br \/><strong>\u2013\u00a0Test Center ICDL\u2028<\/strong><br \/><strong>\u2013\u00a0Accreditamento Formatem<\/strong>p<\/p><p>Questi prestigiosi riconoscimenti ci consentono di\u00a0offrire formazione certificata a livello internazionale in tutti gli ambiti del mondo IT, potendo erogare direttamente, per nostri clienti, le certificazioni internazionali di tutti i pi\u00f9 importanti player Globali, oltre a permetterci di erogare qualsiasi tipo di formazione finanziata.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<div style=\"display: none;\">\n<p>Progettiamo i tuoi percorsi di formazione in base agli obiettivi e le richieste attuali del mondo del lavoro, attivando la tua motivazione attraverso un clima favorevole alla partecipazione e all\u2019interazione per aiutarti a costruire una professionalit\u00e0 solida e vincente. Dal 2003 siamo la migliore scuola di formazione informatica.<br \/>\nContattaci Progettiamo i tuoi percorsi di formazione in base agli obiettivi e le richieste attuali del mondo del lavoro, attivando la tua motivazione attraverso un clima favorevole alla partecipazione e all\u2019interazione per aiutarti a costruire una professionalit\u00e0 solida e vincente. Dal 2003 siamo la migliore scuola di formazione informatica: Pi\u00f9 di 100 corsi distinti a tua disposizione: informatica di base, programmazione, Cloud, Cyber security<br \/>\nOltre 40.000 ore di lezione in aula fisica e in Diretta Streaming Pi\u00f9 di 28.000 ore di formazione erogate presso le aziende<br \/>\nCERTIFICAZIONE ISO<br \/>\nCertificazione ISO 9001:2015<br \/>\nIn SinerVis ci impegniamo nel mettere a disposizione del cliente strumenti formativi di valore e garantiti, ed \u00e8 per questo motivo che abbiamo acquisito la Certificazione Internazionale ISO 9001:2015 per la qualit\u00e0 nella progettazione e nell\u2019erogazione dei percorsi formativi di informatica. Progettiamo ogni percorso didattico sempre con grande cura, e aggiorniamo periodicamente, secondo gli standard ISO, tutti i contenuti formativi sviluppati dal nostro team di docenti.<br \/>\nFLESSIBILIT\u00e0 Il ricco catalogo di corsi unito a un\u2019organizzazione agile, ci permette di offrirti percorsi formativi flessibili, personalizzati e altamente qualificanti COMPETENZE SinerVis non solo forma ma, con competenza e dedizione, interviene attivamente nelle aziende, offrendo consulenze specializzate e soluzioni ICT. ESPERIENZA Con pi\u00f9 di 20 anni di esperienza nella formazione, SinerVis Academy offre percorsi di apprendimento in linea con le esigenze del mercato lavorativo. privati e aziende<br \/>\nOrganizziamo corsi su misura che si adattano a te e ai tuoi obiettivi. Che tu preferisca un approccio individualizzato o desideri imparare in un contesto di gruppo, abbiamo l\u2019opzione giusta per te. I nostri corsi personalizzati sono progettati per rispondere alle tue specifiche esigenze e interessi, offrendo un\u2019esperienza di apprendimento unica e coinvolgente. Unisciti a noi per un percorso formativo fatto su misura per te, dove la tua crescita \u00e8 al centro di tutto quello che facciamo<\/p>\n<p>Informatica Base e Office<br \/>\nIntelligenza Artificiale<br \/>\nProgrammazione e Database<br \/>\nSistemistica e Cyber Security<br \/>\nSviluppo Web e Mobile<br \/>\nComunicazione e Marketing<br \/>\nGrafica e Design<\/p>\n<p>percorsi di formazione, scuola di formazione informatica, formazione informatica, corsi di formazione, percorsi formativi, percorsi formativi di informatica, corsi su misura, corsi per privati, corsi per aziende, percorso formativo, formazione professionale,<\/p>\n<p>percorsi di formazione di Intelligenza Artificiale, corsi di formazione di Intelligenza Artificiale, corsi di Intelligenza Artificiale,<\/p>\n<p>percorsi di formazione di Programmazione e Database , corsi di formazione di Programmazione e Database , corsi di Programmazione e Database ,<\/p>\n<p>percorsi di formazione di Sistemistica e Cyber Security, corsi di formazione di Sistemistica e Cyber Security, corsi di Sistemistica e Cyber Security,<\/p>\n<p>percorsi di formazione di Sviluppo Web, corsi di formazione di Sviluppo Web, corsi di Sviluppo Web,<\/p>\n<p>percorsi di formazione di Comunicazione e Marketing, corsi di formazione di Comunicazione e Marketing, corsi di Comunicazione e Marketing,<\/p>\n<p>percorsi di formazione di Grafica e Design, corsi di formazione di Grafica e Design, corsi di Grafica e Design,<\/p>\n<p>percorsi di formazione a Milano, scuola di formazione a Milano, formazione informatica a Milano, corsi di formazione a Milano, percorsi formativi a Milano, percorsi formativi di informatica a Milano, corsi su misura a Milano, corsi per privati a Milano, corsi per aziende a Milano, percorso formativo a Milano, formazione professionale a Milano,<\/p>\n<p>percorsi di formazione a Torino, scuola di formazione a Torino, formazione informatica a Torino, corsi di formazione a Torino, percorsi formativi a Torino, percorsi formativi di informatica a Torino, corsi su misura a Torino, corsi per privati a Torino, corsi per aziende a Torino, percorso formativo a Torino, formazione professionale a Torino,<\/p>\n<\/div>\n","protected":false},"featured_media":17986,"comment_status":"open","ping_status":"closed","template":"elementor_header_footer","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":""},"product_brand":[],"product_cat":[2589,3668,701,23],"product_tag":[3876,3589,3875,3878,3863,3866,3869,3872,3879,3864,3867,3870,3873,3860,3859,3858,3855,398,3853,3874,3877,3862,3865,3868,3871,3856,3857,3861,3854],"class_list":{"0":"post-17984","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-corsi-di-formazione-istruzione","7":"product_cat-corsi-di-informatica","8":"product_cat-corsi-online","9":"product_cat-istruzione","10":"product_tag-corsi-di-comunicazione-e-marketing","11":"product_tag-corsi-di-formazione","12":"product_tag-corsi-di-formazione-di-comunicazione-e-marketing","13":"product_tag-corsi-di-formazione-di-grafica-e-design","14":"product_tag-corsi-di-formazione-di-intelligenza-artificiale","15":"product_tag-corsi-di-formazione-di-programmazione-e-database","16":"product_tag-corsi-di-formazione-di-sistemistica-e-cyber-security","17":"product_tag-corsi-di-formazione-di-sviluppo-web","18":"product_tag-corsi-di-grafica-e-design","19":"product_tag-corsi-di-intelligenza-artificiale","20":"product_tag-corsi-di-programmazione-e-database","21":"product_tag-corsi-di-sistemistica-e-cyber-security","22":"product_tag-corsi-di-sviluppo-web","23":"product_tag-corsi-per-aziende","24":"product_tag-corsi-per-privati","25":"product_tag-corsi-su-misura","26":"product_tag-formazione-informatica","27":"product_tag-formazione-professionale","28":"product_tag-percorsi-di-formazione","29":"product_tag-percorsi-di-formazione-di-comunicazione-e-marketing","30":"product_tag-percorsi-di-formazione-di-grafica-e-design","31":"product_tag-percorsi-di-formazione-di-intelligenza-artificiale","32":"product_tag-percorsi-di-formazione-di-programmazione-e-database","33":"product_tag-percorsi-di-formazione-di-sistemistica-e-cyber-security","34":"product_tag-percorsi-di-formazione-di-sviluppo-web","35":"product_tag-percorsi-formativi","36":"product_tag-percorsi-formativi-di-informatica","37":"product_tag-percorso-formativo","38":"product_tag-scuola-di-formazione-informatica","40":"first","41":"instock","42":"shipping-taxable","43":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>SinerVis Academy - Cral Policlinico di Milano<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/sinervis-academy\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SinerVis Academy - Cral Policlinico di Milano\" \/>\n<meta property=\"og:description\" content=\"Progettiamo i tuoi percorsi di formazione in base agli obiettivi e le richieste attuali del mondo del lavoro, attivando la tua motivazione attraverso un clima favorevole alla partecipazione e all\u2019interazione per aiutarti a costruire una professionalit\u00e0 solida e vincente. Dal 2003 siamo la migliore scuola di formazione informatica. Contattaci Progettiamo i tuoi percorsi di formazione in base agli obiettivi e le richieste attuali del mondo del lavoro, attivando la tua motivazione attraverso un clima favorevole alla partecipazione e all\u2019interazione per aiutarti a costruire una professionalit\u00e0 solida e vincente. Dal 2003 siamo la migliore scuola di formazione informatica: Pi\u00f9 di 100 corsi distinti a tua disposizione: informatica di base, programmazione, Cloud, Cyber security Oltre 40.000 ore di lezione in aula fisica e in Diretta Streaming Pi\u00f9 di 28.000 ore di formazione erogate presso le aziende CERTIFICAZIONE ISO Certificazione ISO 9001:2015 In SinerVis ci impegniamo nel mettere a disposizione del cliente strumenti formativi di valore e garantiti, ed \u00e8 per questo motivo che abbiamo acquisito la Certificazione Internazionale ISO 9001:2015 per la qualit\u00e0 nella progettazione e nell\u2019erogazione dei percorsi formativi di informatica. Progettiamo ogni percorso didattico sempre con grande cura, e aggiorniamo periodicamente, secondo gli standard ISO, tutti i contenuti formativi sviluppati dal nostro team di docenti. FLESSIBILIT\u00e0 Il ricco catalogo di corsi unito a un\u2019organizzazione agile, ci permette di offrirti percorsi formativi flessibili, personalizzati e altamente qualificanti COMPETENZE SinerVis non solo forma ma, con competenza e dedizione, interviene attivamente nelle aziende, offrendo consulenze specializzate e soluzioni ICT. ESPERIENZA Con pi\u00f9 di 20 anni di esperienza nella formazione, SinerVis Academy offre percorsi di apprendimento in linea con le esigenze del mercato lavorativo. privati e aziende Organizziamo corsi su misura che si adattano a te e ai tuoi obiettivi. Che tu preferisca un approccio individualizzato o desideri imparare in un contesto di gruppo, abbiamo l\u2019opzione giusta per te. I nostri corsi personalizzati sono progettati per rispondere alle tue specifiche esigenze e interessi, offrendo un\u2019esperienza di apprendimento unica e coinvolgente. Unisciti a noi per un percorso formativo fatto su misura per te, dove la tua crescita \u00e8 al centro di tutto quello che facciamo  Informatica Base e Office Intelligenza Artificiale Programmazione e Database Sistemistica e Cyber Security Sviluppo Web e Mobile Comunicazione e Marketing Grafica e Design  percorsi di formazione, scuola di formazione informatica, formazione informatica, corsi di formazione, percorsi formativi, percorsi formativi di informatica, corsi su misura, corsi per privati, corsi per aziende, percorso formativo, formazione professionale,  percorsi di formazione di Intelligenza Artificiale, corsi di formazione di Intelligenza Artificiale, corsi di Intelligenza Artificiale,  percorsi di formazione di Programmazione e Database , corsi di formazione di Programmazione e Database , corsi di Programmazione e Database ,  percorsi di formazione di Sistemistica e Cyber Security, corsi di formazione di Sistemistica e Cyber Security, corsi di Sistemistica e Cyber Security,  percorsi di formazione di Sviluppo Web, corsi di formazione di Sviluppo Web, corsi di Sviluppo Web,  percorsi di formazione di Comunicazione e Marketing, corsi di formazione di Comunicazione e Marketing, corsi di Comunicazione e Marketing,  percorsi di formazione di Grafica e Design, corsi di formazione di Grafica e Design, corsi di Grafica e Design,  percorsi di formazione a Milano, scuola di formazione a Milano, formazione informatica a Milano, corsi di formazione a Milano, percorsi formativi a Milano, percorsi formativi di informatica a Milano, corsi su misura a Milano, corsi per privati a Milano, corsi per aziende a Milano, percorso formativo a Milano, formazione professionale a Milano,  percorsi di formazione a Torino, scuola di formazione a Torino, formazione informatica a Torino, corsi di formazione a Torino, percorsi formativi a Torino, percorsi formativi di informatica a Torino, corsi su misura a Torino, corsi per privati a Torino, corsi per aziende a Torino, percorso formativo a Torino, formazione professionale a Torino,\" \/>\n<meta property=\"og:url\" content=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/sinervis-academy\/\" \/>\n<meta property=\"og:site_name\" content=\"Cral Policlinico di Milano\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-29T12:26:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/03\/Logo-siti-sinervis-academy.png\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"9 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/sinervis-academy\/\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/sinervis-academy\/\",\"name\":\"SinerVis Academy - Cral Policlinico di Milano\",\"isPartOf\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/sinervis-academy\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/sinervis-academy\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/03\/Logo-siti-sinervis-academy.png\",\"datePublished\":\"2025-03-24T14:51:09+00:00\",\"dateModified\":\"2025-04-29T12:26:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/sinervis-academy\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/sinervis-academy\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/sinervis-academy\/#primaryimage\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/03\/Logo-siti-sinervis-academy.png\",\"contentUrl\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/03\/Logo-siti-sinervis-academy.png\",\"width\":300,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/sinervis-academy\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/negozio\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"SinerVis Academy\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/#website\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/\",\"name\":\"Cral Policlinico di Milano\",\"description\":\"Area Convenzioni\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SinerVis Academy - Cral Policlinico di Milano","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/sinervis-academy\/","og_locale":"it_IT","og_type":"article","og_title":"SinerVis Academy - Cral Policlinico di Milano","og_description":"Progettiamo i tuoi percorsi di formazione in base agli obiettivi e le richieste attuali del mondo del lavoro, attivando la tua motivazione attraverso un clima favorevole alla partecipazione e all\u2019interazione per aiutarti a costruire una professionalit\u00e0 solida e vincente. Dal 2003 siamo la migliore scuola di formazione informatica. Contattaci Progettiamo i tuoi percorsi di formazione in base agli obiettivi e le richieste attuali del mondo del lavoro, attivando la tua motivazione attraverso un clima favorevole alla partecipazione e all\u2019interazione per aiutarti a costruire una professionalit\u00e0 solida e vincente. Dal 2003 siamo la migliore scuola di formazione informatica: Pi\u00f9 di 100 corsi distinti a tua disposizione: informatica di base, programmazione, Cloud, Cyber security Oltre 40.000 ore di lezione in aula fisica e in Diretta Streaming Pi\u00f9 di 28.000 ore di formazione erogate presso le aziende CERTIFICAZIONE ISO Certificazione ISO 9001:2015 In SinerVis ci impegniamo nel mettere a disposizione del cliente strumenti formativi di valore e garantiti, ed \u00e8 per questo motivo che abbiamo acquisito la Certificazione Internazionale ISO 9001:2015 per la qualit\u00e0 nella progettazione e nell\u2019erogazione dei percorsi formativi di informatica. Progettiamo ogni percorso didattico sempre con grande cura, e aggiorniamo periodicamente, secondo gli standard ISO, tutti i contenuti formativi sviluppati dal nostro team di docenti. FLESSIBILIT\u00e0 Il ricco catalogo di corsi unito a un\u2019organizzazione agile, ci permette di offrirti percorsi formativi flessibili, personalizzati e altamente qualificanti COMPETENZE SinerVis non solo forma ma, con competenza e dedizione, interviene attivamente nelle aziende, offrendo consulenze specializzate e soluzioni ICT. ESPERIENZA Con pi\u00f9 di 20 anni di esperienza nella formazione, SinerVis Academy offre percorsi di apprendimento in linea con le esigenze del mercato lavorativo. privati e aziende Organizziamo corsi su misura che si adattano a te e ai tuoi obiettivi. Che tu preferisca un approccio individualizzato o desideri imparare in un contesto di gruppo, abbiamo l\u2019opzione giusta per te. I nostri corsi personalizzati sono progettati per rispondere alle tue specifiche esigenze e interessi, offrendo un\u2019esperienza di apprendimento unica e coinvolgente. Unisciti a noi per un percorso formativo fatto su misura per te, dove la tua crescita \u00e8 al centro di tutto quello che facciamo  Informatica Base e Office Intelligenza Artificiale Programmazione e Database Sistemistica e Cyber Security Sviluppo Web e Mobile Comunicazione e Marketing Grafica e Design  percorsi di formazione, scuola di formazione informatica, formazione informatica, corsi di formazione, percorsi formativi, percorsi formativi di informatica, corsi su misura, corsi per privati, corsi per aziende, percorso formativo, formazione professionale,  percorsi di formazione di Intelligenza Artificiale, corsi di formazione di Intelligenza Artificiale, corsi di Intelligenza Artificiale,  percorsi di formazione di Programmazione e Database , corsi di formazione di Programmazione e Database , corsi di Programmazione e Database ,  percorsi di formazione di Sistemistica e Cyber Security, corsi di formazione di Sistemistica e Cyber Security, corsi di Sistemistica e Cyber Security,  percorsi di formazione di Sviluppo Web, corsi di formazione di Sviluppo Web, corsi di Sviluppo Web,  percorsi di formazione di Comunicazione e Marketing, corsi di formazione di Comunicazione e Marketing, corsi di Comunicazione e Marketing,  percorsi di formazione di Grafica e Design, corsi di formazione di Grafica e Design, corsi di Grafica e Design,  percorsi di formazione a Milano, scuola di formazione a Milano, formazione informatica a Milano, corsi di formazione a Milano, percorsi formativi a Milano, percorsi formativi di informatica a Milano, corsi su misura a Milano, corsi per privati a Milano, corsi per aziende a Milano, percorso formativo a Milano, formazione professionale a Milano,  percorsi di formazione a Torino, scuola di formazione a Torino, formazione informatica a Torino, corsi di formazione a Torino, percorsi formativi a Torino, percorsi formativi di informatica a Torino, corsi su misura a Torino, corsi per privati a Torino, corsi per aziende a Torino, percorso formativo a Torino, formazione professionale a Torino,","og_url":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/sinervis-academy\/","og_site_name":"Cral Policlinico di Milano","article_modified_time":"2025-04-29T12:26:57+00:00","og_image":[{"width":300,"height":300,"url":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/03\/Logo-siti-sinervis-academy.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"9 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/sinervis-academy\/","url":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/sinervis-academy\/","name":"SinerVis Academy - Cral Policlinico di Milano","isPartOf":{"@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/#website"},"primaryImageOfPage":{"@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/sinervis-academy\/#primaryimage"},"image":{"@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/sinervis-academy\/#primaryimage"},"thumbnailUrl":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/03\/Logo-siti-sinervis-academy.png","datePublished":"2025-03-24T14:51:09+00:00","dateModified":"2025-04-29T12:26:57+00:00","breadcrumb":{"@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/sinervis-academy\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/sinervis-academy\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/sinervis-academy\/#primaryimage","url":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/03\/Logo-siti-sinervis-academy.png","contentUrl":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2025\/03\/Logo-siti-sinervis-academy.png","width":300,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/sinervis-academy\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/negozio\/"},{"@type":"ListItem","position":3,"name":"SinerVis Academy"}]},{"@type":"WebSite","@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/#website","url":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/","name":"Cral Policlinico di Milano","description":"Area Convenzioni","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/product\/17984","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/comments?post=17984"}],"version-history":[{"count":114,"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/product\/17984\/revisions"}],"predecessor-version":[{"id":19150,"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/product\/17984\/revisions\/19150"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/media\/17986"}],"wp:attachment":[{"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/media?parent=17984"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/product_brand?post=17984"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/product_cat?post=17984"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/product_tag?post=17984"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}