{"id":14638,"date":"2024-12-12T15:19:14","date_gmt":"2024-12-12T14:19:14","guid":{"rendered":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/?post_type=product&#038;p=14638"},"modified":"2024-12-13T09:39:38","modified_gmt":"2024-12-13T08:39:38","slug":"weplaylab-fun-care-music","status":"publish","type":"product","link":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/weplaylab-fun-care-music\/","title":{"rendered":"Weplaylab fun care &#038; music"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"14638\" class=\"elementor elementor-14638\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a0b1b6d e-flex e-con-boxed e-con e-parent\" data-id=\"a0b1b6d\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b99d03f elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"b99d03f\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" fetchpriority=\"high\" decoding=\"async\" width=\"3101\" height=\"773\" src=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2024\/12\/logo-jpeg2.png\" class=\"attachment-full size-full wp-image-14644\" alt=\"\" srcset=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2024\/12\/logo-jpeg2.png 3101w, https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2024\/12\/logo-jpeg2-1280x319.png 1280w, https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2024\/12\/logo-jpeg2-980x244.png 980w, https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2024\/12\/logo-jpeg2-480x120.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) and (max-width: 1280px) 1280px, (min-width: 1281px) 3101px, 100vw\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-048e2da elementor-hidden-mobile elementor-widget elementor-widget-text-editor\" data-id=\"048e2da\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Scuola di musica per adulti e bambini<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-48494cc elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-text-editor\" data-id=\"48494cc\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Scuola di musica <br \/>per adulti e bambini<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-55ee170 elementor-widget elementor-widget-text-editor\" data-id=\"55ee170\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Dal 2014 non insegniamo solo note musicali, ma anche come gestire le proprie emozioni.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5402a0c elementor-hidden-desktop e-flex e-con-boxed e-con e-parent\" data-id=\"5402a0c\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-247fc32 e-flex e-con-boxed e-con e-child\" data-id=\"247fc32\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-54fa3e4 elementor-hidden-mobile elementor-widget elementor-widget-text-editor\" data-id=\"54fa3e4\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Weplaylab fun care &amp; music<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-73941fa elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-text-editor\" data-id=\"73941fa\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Weplaylab<br \/>fun care &amp; music<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-27258c8 elementor-widget elementor-widget-text-editor\" data-id=\"27258c8\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u00e8 un luogo in cui, adulti e bambini imparano ad esprimersi attraverso la musica, la danza e l&#8217;arte.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bf7ac1d elementor-widget elementor-widget-text-editor\" data-id=\"bf7ac1d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Corsi per adulti e bambini di<br \/><strong>CANTO \u2022 CHITARRA \u2022 PIANOFORTE \u2022 TEATRO<\/strong><br \/><strong>YOGA \u2022 MEDITAZIONE \u2022 GESTIONE DELL\u2019ANSIA<\/strong><\/p><p>Per i bambini dai 10\/36 mesi e 3\/5 anni<br \/><strong>PROPEDEUTICA MUSICALE<\/strong><br \/><strong>DANZA \u2022 PSICOMOTRICIT\u00c0<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0a374d2 elementor-widget elementor-widget-text-editor\" data-id=\"0a374d2\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Per potenziare tutti gli aspetti della relazione affettiva.<\/p><p>Il focus \u00e8 sul &#8220;corpo del performer&#8221; e su come le nostre emozioni possono influenzare la nostra esibizione sul palco e nella vita.<\/p><p>Grazie ai nostri training di ultima generazione tutti possono imparare a commutare le emozioni in energia fluida e costruttiva.<br \/>Docenti titolati, solo corsi di qualit\u00e0.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-962d66a elementor-widget__width-inherit elementor-widget elementor-widget-image\" data-id=\"962d66a\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1246\" height=\"1260\" src=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2024\/12\/play.png\" class=\"attachment-full size-full wp-image-14662\" alt=\"\" srcset=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2024\/12\/play.png 1246w, https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2024\/12\/play-980x991.png 980w, https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2024\/12\/play-480x485.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1246px, 100vw\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3d34759 elementor-hidden-tablet elementor-hidden-mobile e-flex e-con-boxed e-con e-parent\" data-id=\"3d34759\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-2134ca4 e-con-full e-flex e-con e-child\" data-id=\"2134ca4\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0e545c2 elementor-hidden-mobile elementor-widget elementor-widget-text-editor\" data-id=\"0e545c2\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Weplaylab fun care &amp; music<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3599ea3 elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-text-editor\" data-id=\"3599ea3\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Weplaylab<br \/>fun care &amp; music<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-34656e1 elementor-widget elementor-widget-text-editor\" data-id=\"34656e1\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u00e8 un luogo in cui, adulti e bambini imparano ad esprimersi attraverso la musica, la danza e l&#8217;arte.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b1faf16 elementor-widget elementor-widget-text-editor\" data-id=\"b1faf16\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Corsi per adulti e bambini di<br \/><strong>CANTO \u2022 CHITARRA \u2022 PIANOFORTE \u2022 TEATRO<\/strong><br \/><strong>YOGA \u2022 MEDITAZIONE \u2022 GESTIONE DELL\u2019ANSIA<\/strong><\/p><p>Per i bambini dai 10\/36 mesi e 3\/5 anni<br \/><strong>PROPEDEUTICA MUSICALE<\/strong><br \/><strong>DANZA \u2022 PSICOMOTRICIT\u00c0<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ea7d14d elementor-widget elementor-widget-text-editor\" data-id=\"ea7d14d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Per potenziare tutti gli aspetti della relazione affettiva.<\/p><p>Il focus \u00e8 sul &#8220;corpo del performer&#8221; e su come le nostre emozioni possono influenzare la nostra esibizione sul palco e nella vita.<\/p><p>Grazie ai nostri training di ultima generazione tutti possono imparare a commutare le emozioni in energia fluida e costruttiva.<br \/>Docenti titolati, solo corsi di qualit\u00e0.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9e1f478 e-con-full e-flex e-con e-child\" data-id=\"9e1f478\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a248d7a elementor-widget__width-inherit elementor-widget elementor-widget-image\" data-id=\"a248d7a\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1246\" height=\"1260\" src=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2024\/12\/play.png\" class=\"attachment-full size-full wp-image-14662\" alt=\"\" srcset=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2024\/12\/play.png 1246w, https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2024\/12\/play-980x991.png 980w, https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2024\/12\/play-480x485.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1246px, 100vw\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6edfb5df elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6edfb5df\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-71a43a4b\" data-id=\"71a43a4b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5f10e529 elementor-widget elementor-widget-text-editor\" data-id=\"5f10e529\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Per gli associati<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c96d333 elementor-widget elementor-widget-text-editor\" data-id=\"c96d333\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u2022 Sconto del 10%<br \/>\u2022 Lezione prova gratuita per i corsi di musica e strumento<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-7b07d5b elementor-hidden-desktop e-flex e-con-boxed e-con e-parent\" data-id=\"7b07d5b\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-265f36c e-con-full e-flex e-con e-child\" data-id=\"265f36c\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ff62a94 elementor-widget elementor-widget-text-editor\" data-id=\"ff62a94\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Contatti<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c334343 elementor-widget elementor-widget-text-editor\" data-id=\"c334343\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Weplaylab fun care &amp; music<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a283502 elementor-widget elementor-widget-text-editor\" data-id=\"a283502\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #333333;\">Via Luigi Pirandello, 4\/A &#8211; 20144 Milano<\/span><br \/><span style=\"color: #333333;\"><strong>Tel: <\/strong>02 39401041<\/span><br \/><span style=\"color: #333333;\"><strong>WhatsApp: <\/strong>351 6608127<\/span><br \/><span style=\"color: #333333;\"><strong>Mail: <\/strong><a style=\"color: #333333;\" href=\"mailto:info@weplaylab.com\">info@weplaylab.com<\/a><\/span><br \/><span style=\"color: #333333;\"><strong>Sito web: <\/strong><a style=\"color: #333333;\" href=\"https:\/\/www.weplaylab.com\/\">www.weplaylab.com<\/a><\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e70e5fc elementor-shape-circle e-grid-align-left elementor-grid-0 elementor-widget elementor-widget-social-icons\" data-id=\"e70e5fc\" data-element_type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-whatsapp elementor-repeater-item-1539373\" href=\"https:\/\/api.whatsapp.com\/send?phone=393516608127\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Whatsapp<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-whatsapp\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M380.9 97.1C339 55.1 283.2 32 223.9 32c-122.4 0-222 99.6-222 222 0 39.1 10.2 77.3 29.6 111L0 480l117.7-30.9c32.4 17.7 68.9 27 106.1 27h.1c122.3 0 224.1-99.6 224.1-222 0-59.3-25.2-115-67.1-157zm-157 341.6c-33.2 0-65.7-8.9-94-25.7l-6.7-4-69.8 18.3L72 359.2l-4.4-7c-18.5-29.4-28.2-63.3-28.2-98.2 0-101.7 82.8-184.5 184.6-184.5 49.3 0 95.6 19.2 130.4 54.1 34.8 34.9 56.2 81.2 56.1 130.5 0 101.8-84.9 184.6-186.6 184.6zm101.2-138.2c-5.5-2.8-32.8-16.2-37.9-18-5.1-1.9-8.8-2.8-12.5 2.8-3.7 5.6-14.3 18-17.6 21.8-3.2 3.7-6.5 4.2-12 1.4-32.6-16.3-54-29.1-75.5-66-5.7-9.8 5.7-9.1 16.3-30.3 1.8-3.7.9-6.9-.5-9.7-1.4-2.8-12.5-30.1-17.1-41.2-4.5-10.8-9.1-9.3-12.5-9.5-3.2-.2-6.9-.2-10.6-.2-3.7 0-9.7 1.4-14.8 6.9-5.1 5.6-19.4 19-19.4 46.3 0 27.3 19.9 53.7 22.6 57.4 2.8 3.7 39.1 59.7 94.8 83.8 35.2 15.2 49 16.5 66.6 13.9 10.7-1.6 32.8-13.4 37.4-26.4 4.6-13 4.6-24.1 3.2-26.4-1.3-2.5-5-3.9-10.5-6.6z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9cbc4d4 elementor-widget elementor-widget-text-editor\" data-id=\"9cbc4d4\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><div id=\"gmw-single-location-wrapper-532\" class=\"gmw-element-wrapper gmw-single-location-wrapper gmw-sl-wrapper gmw-sl-single-post-wrapper post \" object_type=\"post\" object_id=\"14638\"  style=\"width:100%\"><div class=\"gmw-sl-map-wrapper gmw-sl-element\"><div id=\"gmw-map-wrapper-532\" class=\"gmw-map-wrapper  sl single_location \" style=\"width:100%;height:300px;\"> <span id=\"gmw-resize-map-toggle-532\" class=\"gmw-resize-map-toggle gmw-icon-resize-full\" style=\"display:none;\" title=\"Resize map\"><\/span> <div id=\"gmw-map-loader-532\" class=\"gmw-map-loader\"><\/div> <div id=\"gmw-map-532\" class=\"gmw-map sl single_location\" style=\"width:100%; height:100%\" data-map_id=\"532\" data-prefix=\"sl\" data-map_type=\"single_location\" data-icons_usage=\"global\"><\/div> <\/div><\/div><\/div><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-29045eb elementor-hidden-tablet elementor-hidden-mobile e-flex e-con-boxed e-con e-parent\" data-id=\"29045eb\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-5bb61d3 e-con-full e-flex e-con e-child\" data-id=\"5bb61d3\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-821365e elementor-widget elementor-widget-text-editor\" data-id=\"821365e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Contatti<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5760e91 elementor-widget elementor-widget-text-editor\" data-id=\"5760e91\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Weplaylab fun care &amp; music<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7b964d5 elementor-widget elementor-widget-text-editor\" data-id=\"7b964d5\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #333333;\">Via Luigi Pirandello, 4\/A &#8211; 20144 Milano<\/span><br \/><span style=\"color: #333333;\"><strong>Tel: <\/strong>02 39401041<\/span><br \/><span style=\"color: #333333;\"><strong>WhatsApp: <\/strong>351 6608127<\/span><br \/><span style=\"color: #333333;\"><strong>Mail: <\/strong><a style=\"color: #333333;\" href=\"mailto:info@weplaylab.com\">info@weplaylab.com<\/a><\/span><br \/><span style=\"color: #333333;\"><strong>Sito web: <\/strong><a style=\"color: #333333;\" href=\"https:\/\/www.weplaylab.com\/\">www.weplaylab.com<\/a><\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4b6230c elementor-shape-circle e-grid-align-left elementor-grid-0 elementor-widget elementor-widget-social-icons\" data-id=\"4b6230c\" data-element_type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-whatsapp elementor-repeater-item-1539373\" href=\"https:\/\/api.whatsapp.com\/send?phone=393516608127\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Whatsapp<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-whatsapp\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M380.9 97.1C339 55.1 283.2 32 223.9 32c-122.4 0-222 99.6-222 222 0 39.1 10.2 77.3 29.6 111L0 480l117.7-30.9c32.4 17.7 68.9 27 106.1 27h.1c122.3 0 224.1-99.6 224.1-222 0-59.3-25.2-115-67.1-157zm-157 341.6c-33.2 0-65.7-8.9-94-25.7l-6.7-4-69.8 18.3L72 359.2l-4.4-7c-18.5-29.4-28.2-63.3-28.2-98.2 0-101.7 82.8-184.5 184.6-184.5 49.3 0 95.6 19.2 130.4 54.1 34.8 34.9 56.2 81.2 56.1 130.5 0 101.8-84.9 184.6-186.6 184.6zm101.2-138.2c-5.5-2.8-32.8-16.2-37.9-18-5.1-1.9-8.8-2.8-12.5 2.8-3.7 5.6-14.3 18-17.6 21.8-3.2 3.7-6.5 4.2-12 1.4-32.6-16.3-54-29.1-75.5-66-5.7-9.8 5.7-9.1 16.3-30.3 1.8-3.7.9-6.9-.5-9.7-1.4-2.8-12.5-30.1-17.1-41.2-4.5-10.8-9.1-9.3-12.5-9.5-3.2-.2-6.9-.2-10.6-.2-3.7 0-9.7 1.4-14.8 6.9-5.1 5.6-19.4 19-19.4 46.3 0 27.3 19.9 53.7 22.6 57.4 2.8 3.7 39.1 59.7 94.8 83.8 35.2 15.2 49 16.5 66.6 13.9 10.7-1.6 32.8-13.4 37.4-26.4 4.6-13 4.6-24.1 3.2-26.4-1.3-2.5-5-3.9-10.5-6.6z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4e0324c e-con-full e-flex e-con e-child\" data-id=\"4e0324c\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0cfa7a7 elementor-widget elementor-widget-text-editor\" data-id=\"0cfa7a7\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><div id=\"gmw-single-location-wrapper-539\" class=\"gmw-element-wrapper gmw-single-location-wrapper gmw-sl-wrapper gmw-sl-single-post-wrapper post \" object_type=\"post\" object_id=\"14638\"  style=\"width:100%\"><div class=\"gmw-sl-map-wrapper gmw-sl-element\"><div id=\"gmw-map-wrapper-539\" class=\"gmw-map-wrapper  sl single_location \" style=\"width:100%;height:300px;\"> <span id=\"gmw-resize-map-toggle-539\" class=\"gmw-resize-map-toggle gmw-icon-resize-full\" style=\"display:none;\" title=\"Resize map\"><\/span> <div id=\"gmw-map-loader-539\" class=\"gmw-map-loader\"><\/div> <div id=\"gmw-map-539\" class=\"gmw-map sl single_location\" style=\"width:100%; height:100%\" data-map_id=\"539\" data-prefix=\"sl\" data-map_type=\"single_location\" data-icons_usage=\"global\"><\/div> <\/div><\/div><\/div><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-33a79767 elementor-section-content-middle elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"33a79767\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-caa32f5\" data-id=\"caa32f5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-426c7101 elementor-widget elementor-widget-text-editor\" data-id=\"426c7101\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tContatti\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-72c1fdab elementor-shape-circle e-grid-align-left elementor-grid-0 elementor-widget elementor-widget-social-icons\" data-id=\"72c1fdab\" data-element_type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-facebook elementor-repeater-item-1539373\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Facebook<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-facebook\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M504 256C504 119 393 8 256 8S8 119 8 256c0 123.78 90.69 226.38 209.25 245V327.69h-63V256h63v-54.64c0-62.15 37-96.48 93.67-96.48 27.14 0 55.52 4.84 55.52 4.84v61h-31.28c-30.8 0-40.41 19.12-40.41 38.73V256h68.78l-11 71.69h-57.78V501C413.31 482.38 504 379.78 504 256z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-twitter elementor-repeater-item-8913cb9\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Twitter<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-twitter\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M459.37 151.716c.325 4.548.325 9.097.325 13.645 0 138.72-105.583 298.558-298.558 298.558-59.452 0-114.68-17.219-161.137-47.106 8.447.974 16.568 1.299 25.34 1.299 49.055 0 94.213-16.568 130.274-44.832-46.132-.975-84.792-31.188-98.112-72.772 6.498.974 12.995 1.624 19.818 1.624 9.421 0 18.843-1.3 27.614-3.573-48.081-9.747-84.143-51.98-84.143-102.985v-1.299c13.969 7.797 30.214 12.67 47.431 13.319-28.264-18.843-46.781-51.005-46.781-87.391 0-19.492 5.197-37.36 14.294-52.954 51.655 63.675 129.3 105.258 216.365 109.807-1.624-7.797-2.599-15.918-2.599-24.04 0-57.828 46.782-104.934 104.934-104.934 30.213 0 57.502 12.67 76.67 33.137 23.715-4.548 46.456-13.32 66.599-25.34-7.798 24.366-24.366 44.833-46.132 57.827 21.117-2.273 41.584-8.122 60.426-16.243-14.292 20.791-32.161 39.308-52.628 54.253z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-youtube elementor-repeater-item-3255c55\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Youtube<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-youtube\" viewBox=\"0 0 576 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M549.655 124.083c-6.281-23.65-24.787-42.276-48.284-48.597C458.781 64 288 64 288 64S117.22 64 74.629 75.486c-23.497 6.322-42.003 24.947-48.284 48.597-11.412 42.867-11.412 132.305-11.412 132.305s0 89.438 11.412 132.305c6.281 23.65 24.787 41.5 48.284 47.821C117.22 448 288 448 288 448s170.78 0 213.371-11.486c23.497-6.321 42.003-24.171 48.284-47.821 11.412-42.867 11.412-132.305 11.412-132.305s0-89.438-11.412-132.305zm-317.51 213.508V175.185l142.739 81.205-142.739 81.201z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-4ad6e350\" data-id=\"4ad6e350\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-10267d3e elementor-widget elementor-widget-text-editor\" data-id=\"10267d3e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div id=\"gmw-single-location-wrapper-522\" class=\"gmw-element-wrapper gmw-single-location-wrapper gmw-sl-wrapper gmw-sl-single-post-wrapper post \" object_type=\"post\" object_id=\"14638\"  style=\"width:100%\"><div class=\"gmw-sl-map-wrapper gmw-sl-element\"><div id=\"gmw-map-wrapper-522\" class=\"gmw-map-wrapper  sl single_location \" style=\"width:100%;height:300px;\"> <span id=\"gmw-resize-map-toggle-522\" class=\"gmw-resize-map-toggle gmw-icon-resize-full\" style=\"display:none;\" title=\"Resize map\"><\/span> <div id=\"gmw-map-loader-522\" class=\"gmw-map-loader\"><\/div> <div id=\"gmw-map-522\" class=\"gmw-map sl single_location\" style=\"width:100%; height:100%\" data-map_id=\"522\" data-prefix=\"sl\" data-map_type=\"single_location\" data-icons_usage=\"global\"><\/div> <\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-efe3ba0 elementor-widget elementor-widget-text-editor\" data-id=\"efe3ba0\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><div id=\"gmw-single-object-locations-wrapper-243\" class=\"gmw-element-wrapper gmw-single-location-wrapper gmw-sl-wrapper gmw-sl-single-post-wrapper post gmw-sl-multiple-locations\" object_type=\"post\" object_id=\"\"  style=\"width:100%\"><div class=\"gmw-sl-map-wrapper\"><div id=\"gmw-map-wrapper-243\" class=\"gmw-map-wrapper  sl single_location \" style=\"width:100%;height:350px;\"> <span id=\"gmw-resize-map-toggle-243\" class=\"gmw-resize-map-toggle gmw-icon-resize-full\" style=\"display:none;\" title=\"Resize map\"><\/span> <div id=\"gmw-map-loader-243\" class=\"gmw-map-loader\"><\/div> <div id=\"gmw-map-243\" class=\"gmw-map sl single_location\" style=\"width:100%; height:100%\" data-map_id=\"243\" data-prefix=\"sl\" data-map_type=\"single_location\" data-icons_usage=\"global\"><\/div> <\/div><\/div><\/div><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<div style=\"display: none;\">\n<p>Dal 2014 non insegniamo solo note musicali, ma anche come gestire le proprie emozioni.<\/p>\n<p>Weplaylab fun care &amp; music \u00e8 un luogo in cui, adulti e bambini imparano ad esprimersi attraverso la musica, la danza e l&#8217;arte.<br \/>\nCorsi per adulti e bambini di<br \/>\nCANTO &#8211; CHITARRA &#8211; PIANOFORTE &#8211; TEATRO<br \/>\nYOGA &#8211; MEDITAZIONE \u2013 GESTIONE DELL\u2019ANSIA<br \/>\nPer i bambini dai 10\/36 mesi e 3\/5 anni<br \/>\nPROPEDEUTICA MUSICALE<br \/>\nDANZA \u2013 PSICOMOTRICITA\u2019<\/p>\n<p>per potenziare tutti gli aspetti della relazione affettiva<br \/>\nIl focus \u00e8 sul &#8220;corpo del performer&#8221; e su come le nostre emozioni possono influenzare la nostra esibizione sul palco e nella vita.<\/p>\n<p>Grazie ai nostri training di ultima generazione tutti possono imparare a commutare le emozioni in energia fluida e costruttiva.<br \/>\nDocenti titolati, solo corsi di qualit\u00e0.<\/p>\n<p>Music club, Scuola di musica, Corsi di Canto, Corsi di Violino, Corsi di Pianoforte, Corsi di Chitarra, Corsi di teatro, Corsi yoga, Corsi di meditazione, Corsi di gestione dell&#8217;ansia, Corsi di danza, corsi di song writing, corsi di Propedeutica musicale, Propedeutica alla danza, Danza propedeutica, Psicomotricit\u00e0, Yoga per bambini,<\/p>\n<p>Music club a Milano, Scuola di musica a Milano, Corsi di Canto a Milano, Corsi di Violino a Milano, Corsi di Pianoforte a Milano, Corsi di Chitarra a Milano, Corsi di teatro a Milano, Corsi di yoga a Milano, Corsi di meditazione a Milano, Corsi di gestione dell&#8217;ansia a Milano, Corsi di danza a Milano, corsi di song writing a Milano, corsi di Propedeutica musicale a Milano, Propedeutica alla danza a Milano, Danza propedeutica a Milano, Psicomotricit\u00e0 a Milano, Yoga per bambini a Milano,<\/p>\n<\/div>\n","protected":false},"featured_media":14639,"comment_status":"open","ping_status":"closed","template":"elementor_header_footer","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":""},"product_brand":[],"product_cat":[23,3005],"product_tag":[2993,2996,537,3000,2999,2995,3002,3001,2997,2994,2998,3004,2992,3003,2370,750,2932],"class_list":{"0":"post-14638","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-istruzione","7":"product_cat-scuola-di-musica","8":"product_tag-corsi-di-canto","9":"product_tag-corsi-di-chitarra","10":"product_tag-corsi-di-danza","11":"product_tag-corsi-di-gestione-dellansia","12":"product_tag-corsi-di-meditazione","13":"product_tag-corsi-di-pianoforte","14":"product_tag-corsi-di-propedeutica-musicale","15":"product_tag-corsi-di-song-writing","16":"product_tag-corsi-di-teatro","17":"product_tag-corsi-di-violino","18":"product_tag-corsi-yoga","19":"product_tag-danza-propedeutica","20":"product_tag-music-club","21":"product_tag-propedeutica-alla-danza","22":"product_tag-psicomotricita","23":"product_tag-scuola-di-musica","24":"product_tag-yoga-per-bambini","26":"first","27":"instock","28":"shipping-taxable","29":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Weplaylab fun care &amp; music - Cral Policlinico di Milano<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/weplaylab-fun-care-music\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Weplaylab fun care &amp; music - Cral Policlinico di Milano\" \/>\n<meta property=\"og:description\" content=\"Dal 2014 non insegniamo solo note musicali, ma anche come gestire le proprie emozioni.  Weplaylab fun care &amp; music \u00e8 un luogo in cui, adulti e bambini imparano ad esprimersi attraverso la musica, la danza e l&#039;arte. Corsi per adulti e bambini di CANTO - CHITARRA - PIANOFORTE - TEATRO YOGA - MEDITAZIONE \u2013 GESTIONE DELL\u2019ANSIA Per i bambini dai 10\/36 mesi e 3\/5 anni PROPEDEUTICA MUSICALE DANZA \u2013 PSICOMOTRICITA\u2019  per potenziare tutti gli aspetti della relazione affettiva Il focus \u00e8 sul &quot;corpo del performer&quot; e su come le nostre emozioni possono influenzare la nostra esibizione sul palco e nella vita.  Grazie ai nostri training di ultima generazione tutti possono imparare a commutare le emozioni in energia fluida e costruttiva. Docenti titolati, solo corsi di qualit\u00e0.  Music club, Scuola di musica, Corsi di Canto, Corsi di Violino, Corsi di Pianoforte, Corsi di Chitarra, Corsi di teatro, Corsi yoga, Corsi di meditazione, Corsi di gestione dell&#039;ansia, Corsi di danza, corsi di song writing, corsi di Propedeutica musicale, Propedeutica alla danza, Danza propedeutica, Psicomotricit\u00e0, Yoga per bambini,  Music club a Milano, Scuola di musica a Milano, Corsi di Canto a Milano, Corsi di Violino a Milano, Corsi di Pianoforte a Milano, Corsi di Chitarra a Milano, Corsi di teatro a Milano, Corsi di yoga a Milano, Corsi di meditazione a Milano, Corsi di gestione dell&#039;ansia a Milano, Corsi di danza a Milano, corsi di song writing a Milano, corsi di Propedeutica musicale a Milano, Propedeutica alla danza a Milano, Danza propedeutica a Milano, Psicomotricit\u00e0 a Milano, Yoga per bambini a Milano,\" \/>\n<meta property=\"og:url\" content=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/weplaylab-fun-care-music\/\" \/>\n<meta property=\"og:site_name\" content=\"Cral Policlinico di Milano\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-13T08:39:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2024\/12\/logo_Weplaylab.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/weplaylab-fun-care-music\/\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/weplaylab-fun-care-music\/\",\"name\":\"Weplaylab fun care & music - Cral Policlinico di Milano\",\"isPartOf\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/weplaylab-fun-care-music\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/weplaylab-fun-care-music\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2024\/12\/logo_Weplaylab.jpg\",\"datePublished\":\"2024-12-12T14:19:14+00:00\",\"dateModified\":\"2024-12-13T08:39:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/weplaylab-fun-care-music\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/weplaylab-fun-care-music\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/weplaylab-fun-care-music\/#primaryimage\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2024\/12\/logo_Weplaylab.jpg\",\"contentUrl\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2024\/12\/logo_Weplaylab.jpg\",\"width\":300,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/weplaylab-fun-care-music\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/negozio\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Weplaylab fun care &#038; music\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/#website\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/\",\"name\":\"Cral Policlinico di Milano\",\"description\":\"Area Convenzioni\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Weplaylab fun care & music - Cral Policlinico di Milano","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/weplaylab-fun-care-music\/","og_locale":"it_IT","og_type":"article","og_title":"Weplaylab fun care & music - Cral Policlinico di Milano","og_description":"Dal 2014 non insegniamo solo note musicali, ma anche come gestire le proprie emozioni.  Weplaylab fun care &amp; music \u00e8 un luogo in cui, adulti e bambini imparano ad esprimersi attraverso la musica, la danza e l'arte. Corsi per adulti e bambini di CANTO - CHITARRA - PIANOFORTE - TEATRO YOGA - MEDITAZIONE \u2013 GESTIONE DELL\u2019ANSIA Per i bambini dai 10\/36 mesi e 3\/5 anni PROPEDEUTICA MUSICALE DANZA \u2013 PSICOMOTRICITA\u2019  per potenziare tutti gli aspetti della relazione affettiva Il focus \u00e8 sul \"corpo del performer\" e su come le nostre emozioni possono influenzare la nostra esibizione sul palco e nella vita.  Grazie ai nostri training di ultima generazione tutti possono imparare a commutare le emozioni in energia fluida e costruttiva. Docenti titolati, solo corsi di qualit\u00e0.  Music club, Scuola di musica, Corsi di Canto, Corsi di Violino, Corsi di Pianoforte, Corsi di Chitarra, Corsi di teatro, Corsi yoga, Corsi di meditazione, Corsi di gestione dell'ansia, Corsi di danza, corsi di song writing, corsi di Propedeutica musicale, Propedeutica alla danza, Danza propedeutica, Psicomotricit\u00e0, Yoga per bambini,  Music club a Milano, Scuola di musica a Milano, Corsi di Canto a Milano, Corsi di Violino a Milano, Corsi di Pianoforte a Milano, Corsi di Chitarra a Milano, Corsi di teatro a Milano, Corsi di yoga a Milano, Corsi di meditazione a Milano, Corsi di gestione dell'ansia a Milano, Corsi di danza a Milano, corsi di song writing a Milano, corsi di Propedeutica musicale a Milano, Propedeutica alla danza a Milano, Danza propedeutica a Milano, Psicomotricit\u00e0 a Milano, Yoga per bambini a Milano,","og_url":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/weplaylab-fun-care-music\/","og_site_name":"Cral Policlinico di Milano","article_modified_time":"2024-12-13T08:39:38+00:00","og_image":[{"width":300,"height":300,"url":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2024\/12\/logo_Weplaylab.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/weplaylab-fun-care-music\/","url":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/weplaylab-fun-care-music\/","name":"Weplaylab fun care & music - Cral Policlinico di Milano","isPartOf":{"@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/#website"},"primaryImageOfPage":{"@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/weplaylab-fun-care-music\/#primaryimage"},"image":{"@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/weplaylab-fun-care-music\/#primaryimage"},"thumbnailUrl":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2024\/12\/logo_Weplaylab.jpg","datePublished":"2024-12-12T14:19:14+00:00","dateModified":"2024-12-13T08:39:38+00:00","breadcrumb":{"@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/weplaylab-fun-care-music\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/weplaylab-fun-care-music\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/weplaylab-fun-care-music\/#primaryimage","url":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2024\/12\/logo_Weplaylab.jpg","contentUrl":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2024\/12\/logo_Weplaylab.jpg","width":300,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/weplaylab-fun-care-music\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/negozio\/"},{"@type":"ListItem","position":3,"name":"Weplaylab fun care &#038; music"}]},{"@type":"WebSite","@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/#website","url":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/","name":"Cral Policlinico di Milano","description":"Area Convenzioni","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/product\/14638","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/comments?post=14638"}],"version-history":[{"count":31,"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/product\/14638\/revisions"}],"predecessor-version":[{"id":14679,"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/product\/14638\/revisions\/14679"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/media\/14639"}],"wp:attachment":[{"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/media?parent=14638"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/product_brand?post=14638"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/product_cat?post=14638"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/product_tag?post=14638"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}