{"id":12461,"date":"2024-10-08T16:18:01","date_gmt":"2024-10-08T14:18:01","guid":{"rendered":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/?post_type=product&#038;p=12461"},"modified":"2025-02-18T09:37:55","modified_gmt":"2025-02-18T08:37:55","slug":"family-district","status":"publish","type":"product","link":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/family-district\/","title":{"rendered":"Family District"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"12461\" class=\"elementor elementor-12461\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cc7d129 e-flex e-con-boxed e-con e-parent\" data-id=\"cc7d129\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f6df53a elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"f6df53a\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" fetchpriority=\"high\" decoding=\"async\" width=\"3000\" height=\"990\" src=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2024\/10\/familyDistrict_.png\" class=\"attachment-full size-full wp-image-16244\" alt=\"\" srcset=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2024\/10\/familyDistrict_.png 3000w, https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2024\/10\/familyDistrict_-1280x422.png 1280w, https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2024\/10\/familyDistrict_-980x323.png 980w, https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2024\/10\/familyDistrict_-480x158.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) and (max-width: 1280px) 1280px, (min-width: 1281px) 3000px, 100vw\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e213171 elementor-hidden-desktop e-flex e-con-boxed e-con e-parent\" data-id=\"e213171\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-1fdf658 e-con-full e-flex e-con e-child\" data-id=\"1fdf658\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-06177f8 elementor-widget elementor-widget-text-editor\" data-id=\"06177f8\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #7ca4b4;\">Chi<\/span> siamo<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-835e290 elementor-widget elementor-widget-text-editor\" data-id=\"835e290\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Family District \u00e8 Nido Scuola bilingue per bambini dai 3 mesi ai 6 anni e Centro polifunzionale, punto di riferimento per famiglie, coppie in attesa e neogenitori.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-99da752 elementor-widget elementor-widget-text-editor\" data-id=\"99da752\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Situato in Porta Romana, questo angolo di citt\u00e0 accompagna piccoli e adulti nel loro percorso di crescita e scoperta.<\/p><p>La proposta educativa della scuola segue un approccio play-based e offre un bilinguismo immersivo, dove le lingue sono parte integrante dell\u2019ambiente di apprendimento.<\/p><p>Il centro \u00e8 dotato di una piscina interna, aperta anche a bambini esterni e mamme in attesa per corsi di acquaticit\u00e0. Tra le attivit\u00e0 extra scolastiche sono previsti anche corsi per bambini, serate a tema, feste di compleanno e campus estivi.<\/p><p>Family District arricchisce la sua offerta grazie alla collaborazione di Novepassi, che da oltre dieci anni offre servizi per la gravidanza. Puericultrici, ostetriche, psicologi, educatori e parent coach collaborano insieme per garantire un supporto completo alle famiglie con una vasta gamma di servizi.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-265408a elementor-widget__width-inherit elementor-widget elementor-widget-image\" data-id=\"265408a\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1280\" height=\"853\" src=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2024\/10\/07A5093-copia.jpg\" class=\"attachment-full size-full wp-image-16241\" alt=\"\" srcset=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2024\/10\/07A5093-copia.jpg 1280w, https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2024\/10\/07A5093-copia-980x653.jpg 980w, https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2024\/10\/07A5093-copia-480x320.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1280px, 100vw\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b361c20 elementor-widget__width-inherit elementor-widget elementor-widget-image\" data-id=\"b361c20\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1280\" height=\"853\" src=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2024\/10\/07A5147-copia.jpg\" class=\"attachment-full size-full wp-image-16242\" alt=\"\" srcset=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2024\/10\/07A5147-copia.jpg 1280w, https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2024\/10\/07A5147-copia-980x653.jpg 980w, https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2024\/10\/07A5147-copia-480x320.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1280px, 100vw\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1989dc8 elementor-hidden-tablet elementor-hidden-mobile e-flex e-con-boxed e-con e-parent\" data-id=\"1989dc8\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-3faea8f e-con-full e-flex e-con e-child\" data-id=\"3faea8f\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2be9c81 elementor-widget__width-inherit elementor-widget elementor-widget-image\" data-id=\"2be9c81\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1280\" height=\"853\" src=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2024\/10\/07A5093-copia.jpg\" class=\"attachment-full size-full wp-image-16241\" alt=\"\" srcset=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2024\/10\/07A5093-copia.jpg 1280w, https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2024\/10\/07A5093-copia-980x653.jpg 980w, https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2024\/10\/07A5093-copia-480x320.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1280px, 100vw\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9e526f1 elementor-widget__width-inherit elementor-widget elementor-widget-image\" data-id=\"9e526f1\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1280\" height=\"853\" src=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2024\/10\/07A5147-copia.jpg\" class=\"attachment-full size-full wp-image-16242\" alt=\"\" srcset=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2024\/10\/07A5147-copia.jpg 1280w, https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2024\/10\/07A5147-copia-980x653.jpg 980w, https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2024\/10\/07A5147-copia-480x320.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1280px, 100vw\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5242a7c e-con-full e-flex e-con e-child\" data-id=\"5242a7c\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c4a0141 elementor-widget elementor-widget-text-editor\" data-id=\"c4a0141\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #7ca4b4;\">Chi<\/span> siamo<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-364ebd4 elementor-widget elementor-widget-text-editor\" data-id=\"364ebd4\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Family District \u00e8 Nido Scuola bilingue per bambini dai 3 mesi ai 6 anni e Centro polifunzionale, punto di riferimento per famiglie, coppie in attesa e neogenitori.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ef22723 elementor-widget elementor-widget-text-editor\" data-id=\"ef22723\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Situato in Porta Romana, questo angolo di citt\u00e0 accompagna piccoli e adulti nel loro percorso di crescita e scoperta.<\/p><p>La proposta educativa della scuola segue un approccio play-based e offre un bilinguismo immersivo, dove le lingue sono parte integrante dell\u2019ambiente di apprendimento.<\/p><p>Il centro \u00e8 dotato di una piscina interna, aperta anche a bambini esterni e mamme in attesa per corsi di acquaticit\u00e0. Tra le attivit\u00e0 extra scolastiche sono previsti anche corsi per bambini, serate a tema, feste di compleanno e campus estivi.<\/p><p>Family District arricchisce la sua offerta grazie alla collaborazione di Novepassi, che da oltre dieci anni offre servizi per la gravidanza.\u00a0<span style=\"font-size: 14px;\">Puericultrici, ostetriche, psicologi, educatori e parent coach collaborano insieme per garantire un supporto completo alle famiglie con una vasta gamma di servizi.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-320f5e57 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"320f5e57\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ce536ff\" data-id=\"ce536ff\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-43076f8a elementor-widget elementor-widget-text-editor\" data-id=\"43076f8a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Agevolazioni riservate agli associati<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-d2bf84e elementor-hidden-desktop e-flex e-con-boxed e-con e-parent\" data-id=\"d2bf84e\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-30b5442 e-con-full e-flex e-con e-child\" data-id=\"30b5442\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c0374be elementor-widget__width-initial elementor-hidden-tablet elementor-widget elementor-widget-image\" data-id=\"c0374be\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" fetchpriority=\"high\" decoding=\"async\" width=\"3000\" height=\"990\" src=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2024\/10\/familyDistrict_.png\" class=\"attachment-full size-full wp-image-16244\" alt=\"\" srcset=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2024\/10\/familyDistrict_.png 3000w, https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2024\/10\/familyDistrict_-1280x422.png 1280w, https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2024\/10\/familyDistrict_-980x323.png 980w, https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2024\/10\/familyDistrict_-480x158.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) and (max-width: 1280px) 1280px, (min-width: 1281px) 3000px, 100vw\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-656ffb8 elementor-widget elementor-widget-text-editor\" data-id=\"656ffb8\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Contatti<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-358a97b elementor-widget elementor-widget-text-editor\" data-id=\"358a97b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #333333;\">Via Orti, 18 &#8211; Via privata della Braida, 7 &#8211; 20122 Milano<\/span><br \/><span style=\"color: #333333;\"><strong>Tel:<\/strong> <a style=\"color: #333333;\" href=\"tel:+393200553998\">320 0553998<\/a><\/span><br \/><span style=\"color: #333333;\"><strong>Mail:<\/strong> <a style=\"color: #333333;\" href=\"mailto:info@familydistrict.it\">info@familydistrict.it<\/a><\/span><br \/><span style=\"color: #333333;\"><strong>Mail: <\/strong><a style=\"color: #333333;\" href=\"mailto:novepassi@familydistrict.it\">novepassi@familydistrict.it<\/a><\/span><br \/><span style=\"color: #333333;\"><strong>Sito Family District:<\/strong> <a style=\"color: #333333;\" href=\"https:\/\/www.familydistrict.it\/\">www.familydistrict.it<\/a><\/span><br \/><span style=\"color: #333333;\"><strong>Sito Nove Passi:<\/strong> <a style=\"color: #333333;\" href=\"http:\/\/www.novepassi.it\/\">www.novepassi.it<\/a><\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d090e40 elementor-widget elementor-widget-text-editor\" data-id=\"d090e40\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><div id=\"gmw-single-location-wrapper-117\" class=\"gmw-element-wrapper gmw-single-location-wrapper gmw-sl-wrapper gmw-sl-single-post-wrapper post \" object_type=\"post\" object_id=\"12461\"  style=\"width:100%\"><div class=\"gmw-sl-map-wrapper gmw-sl-element\"><div id=\"gmw-map-wrapper-117\" class=\"gmw-map-wrapper  sl single_location \" style=\"width:100%;height:300px;\"> <span id=\"gmw-resize-map-toggle-117\" class=\"gmw-resize-map-toggle gmw-icon-resize-full\" style=\"display:none;\" title=\"Resize map\"><\/span> <div id=\"gmw-map-loader-117\" class=\"gmw-map-loader\"><\/div> <div id=\"gmw-map-117\" class=\"gmw-map sl single_location\" style=\"width:100%; height:100%\" data-map_id=\"117\" data-prefix=\"sl\" data-map_type=\"single_location\" data-icons_usage=\"global\"><\/div> <\/div><\/div><\/div><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-247af72 elementor-hidden-tablet elementor-hidden-mobile e-flex e-con-boxed e-con e-parent\" data-id=\"247af72\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-8972346 e-con-full e-flex e-con e-child\" data-id=\"8972346\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-95c6e87 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"95c6e87\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" fetchpriority=\"high\" decoding=\"async\" width=\"3000\" height=\"990\" src=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2024\/10\/familyDistrict_.png\" class=\"attachment-full size-full wp-image-16244\" alt=\"\" srcset=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2024\/10\/familyDistrict_.png 3000w, https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2024\/10\/familyDistrict_-1280x422.png 1280w, https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2024\/10\/familyDistrict_-980x323.png 980w, https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2024\/10\/familyDistrict_-480x158.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) and (max-width: 1280px) 1280px, (min-width: 1281px) 3000px, 100vw\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e45ecff elementor-widget elementor-widget-text-editor\" data-id=\"e45ecff\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Contatti<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9ed3bbd elementor-widget elementor-widget-text-editor\" data-id=\"9ed3bbd\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #333333;\">Via Orti, 18 &#8211; Via privata della Braida, 7 &#8211; 20122 Milano<\/span><br \/><span style=\"color: #333333;\"><strong>Tel:<\/strong> <a style=\"color: #333333;\" href=\"tel:+393200553998\">320 0553998<\/a><\/span><br \/><span style=\"color: #333333;\"><strong>Mail:<\/strong> <a style=\"color: #333333;\" href=\"mailto:info@familydistrict.it\">info@familydistrict.it<\/a><\/span><br \/><span style=\"color: #333333;\"><strong>Mail: <\/strong><a style=\"color: #333333;\" href=\"mailto:novepassi@familydistrict.it\">novepassi@familydistrict.it<\/a><\/span><br \/><span style=\"color: #333333;\"><strong>Sito Family District:<\/strong> <a style=\"color: #333333;\" href=\"https:\/\/www.familydistrict.it\/\">www.familydistrict.it<\/a><\/span><br \/><span style=\"color: #333333;\"><strong>Sito Nove Passi:<\/strong> <a style=\"color: #333333;\" href=\"http:\/\/www.novepassi.it\/\">www.novepassi.it<\/a><\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-331b149 e-con-full e-flex e-con e-child\" data-id=\"331b149\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2d1a4b0 elementor-widget elementor-widget-text-editor\" data-id=\"2d1a4b0\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><div id=\"gmw-single-location-wrapper-237\" class=\"gmw-element-wrapper gmw-single-location-wrapper gmw-sl-wrapper gmw-sl-single-post-wrapper post \" object_type=\"post\" object_id=\"12461\"  style=\"width:100%\"><div class=\"gmw-sl-map-wrapper gmw-sl-element\"><div id=\"gmw-map-wrapper-237\" class=\"gmw-map-wrapper  sl single_location \" style=\"width:100%;height:300px;\"> <span id=\"gmw-resize-map-toggle-237\" class=\"gmw-resize-map-toggle gmw-icon-resize-full\" style=\"display:none;\" title=\"Resize map\"><\/span> <div id=\"gmw-map-loader-237\" class=\"gmw-map-loader\"><\/div> <div id=\"gmw-map-237\" class=\"gmw-map sl single_location\" style=\"width:100%; height:100%\" data-map_id=\"237\" data-prefix=\"sl\" data-map_type=\"single_location\" data-icons_usage=\"global\"><\/div> <\/div><\/div><\/div><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-77cc4409 elementor-section-content-middle elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"77cc4409\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-4137f8be\" data-id=\"4137f8be\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-24cd1992 elementor-widget elementor-widget-text-editor\" data-id=\"24cd1992\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tContatti\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4fc417c elementor-shape-circle e-grid-align-left elementor-grid-0 elementor-widget elementor-widget-social-icons\" data-id=\"4fc417c\" data-element_type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-facebook elementor-repeater-item-1539373\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Facebook<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-facebook\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M504 256C504 119 393 8 256 8S8 119 8 256c0 123.78 90.69 226.38 209.25 245V327.69h-63V256h63v-54.64c0-62.15 37-96.48 93.67-96.48 27.14 0 55.52 4.84 55.52 4.84v61h-31.28c-30.8 0-40.41 19.12-40.41 38.73V256h68.78l-11 71.69h-57.78V501C413.31 482.38 504 379.78 504 256z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-twitter elementor-repeater-item-8913cb9\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Twitter<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-twitter\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M459.37 151.716c.325 4.548.325 9.097.325 13.645 0 138.72-105.583 298.558-298.558 298.558-59.452 0-114.68-17.219-161.137-47.106 8.447.974 16.568 1.299 25.34 1.299 49.055 0 94.213-16.568 130.274-44.832-46.132-.975-84.792-31.188-98.112-72.772 6.498.974 12.995 1.624 19.818 1.624 9.421 0 18.843-1.3 27.614-3.573-48.081-9.747-84.143-51.98-84.143-102.985v-1.299c13.969 7.797 30.214 12.67 47.431 13.319-28.264-18.843-46.781-51.005-46.781-87.391 0-19.492 5.197-37.36 14.294-52.954 51.655 63.675 129.3 105.258 216.365 109.807-1.624-7.797-2.599-15.918-2.599-24.04 0-57.828 46.782-104.934 104.934-104.934 30.213 0 57.502 12.67 76.67 33.137 23.715-4.548 46.456-13.32 66.599-25.34-7.798 24.366-24.366 44.833-46.132 57.827 21.117-2.273 41.584-8.122 60.426-16.243-14.292 20.791-32.161 39.308-52.628 54.253z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-youtube elementor-repeater-item-3255c55\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Youtube<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-youtube\" viewBox=\"0 0 576 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M549.655 124.083c-6.281-23.65-24.787-42.276-48.284-48.597C458.781 64 288 64 288 64S117.22 64 74.629 75.486c-23.497 6.322-42.003 24.947-48.284 48.597-11.412 42.867-11.412 132.305-11.412 132.305s0 89.438 11.412 132.305c6.281 23.65 24.787 41.5 48.284 47.821C117.22 448 288 448 288 448s170.78 0 213.371-11.486c23.497-6.321 42.003-24.171 48.284-47.821 11.412-42.867 11.412-132.305 11.412-132.305s0-89.438-11.412-132.305zm-317.51 213.508V175.185l142.739 81.205-142.739 81.201z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-48549d7e\" data-id=\"48549d7e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6e61c1d3 elementor-widget elementor-widget-text-editor\" data-id=\"6e61c1d3\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div id=\"gmw-single-location-wrapper-210\" class=\"gmw-element-wrapper gmw-single-location-wrapper gmw-sl-wrapper gmw-sl-single-post-wrapper post \" object_type=\"post\" object_id=\"12461\"  style=\"width:100%\"><div class=\"gmw-sl-map-wrapper gmw-sl-element\"><div id=\"gmw-map-wrapper-210\" class=\"gmw-map-wrapper  sl single_location \" style=\"width:100%;height:300px;\"> <span id=\"gmw-resize-map-toggle-210\" class=\"gmw-resize-map-toggle gmw-icon-resize-full\" style=\"display:none;\" title=\"Resize map\"><\/span> <div id=\"gmw-map-loader-210\" class=\"gmw-map-loader\"><\/div> <div id=\"gmw-map-210\" class=\"gmw-map sl single_location\" style=\"width:100%; height:100%\" data-map_id=\"210\" data-prefix=\"sl\" data-map_type=\"single_location\" data-icons_usage=\"global\"><\/div> <\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-60adf887 elementor-widget elementor-widget-text-editor\" data-id=\"60adf887\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><div id=\"gmw-single-object-locations-wrapper-272\" class=\"gmw-element-wrapper gmw-single-location-wrapper gmw-sl-wrapper gmw-sl-single-post-wrapper post gmw-sl-multiple-locations\" object_type=\"post\" object_id=\"\"  style=\"width:100%\"><div class=\"gmw-sl-map-wrapper\"><div id=\"gmw-map-wrapper-272\" class=\"gmw-map-wrapper  sl single_location \" style=\"width:100%;height:350px;\"> <span id=\"gmw-resize-map-toggle-272\" class=\"gmw-resize-map-toggle gmw-icon-resize-full\" style=\"display:none;\" title=\"Resize map\"><\/span> <div id=\"gmw-map-loader-272\" class=\"gmw-map-loader\"><\/div> <div id=\"gmw-map-272\" class=\"gmw-map sl single_location\" style=\"width:100%; height:100%\" data-map_id=\"272\" data-prefix=\"sl\" data-map_type=\"single_location\" data-icons_usage=\"global\"><\/div> <\/div><\/div><\/div><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<div style=\"display: none;\">\n<p>Family District \u00e8 Nido Scuola bilingue per bambini dai 3 mesi ai 6 anni e Centro polifunzionale, punto di riferimento per famiglie, coppie in attesa e neogenitori. Situato in Porta Romana, questo angolo di citt\u00e0 accompagna piccoli e adulti nel loro<br \/>\npercorso di crescita e scoperta. La proposta educativa della scuola segue un approccio play-based e offre un bilinguismo immersivo, dove le lingue sono parte integrante dell\u2019ambiente di apprendimento. Il centro \u00e8 dotato di una piscina interna, aperta anche a bambini esterni e mamme in attesa per corsi di acquaticit\u00e0. Tra le attivit\u00e0 extra scolastiche sono previsti anche corsi per bambini, serate a tema, feste di compleanno e campus estivi.<br \/>\nFamily District arricchisce la sua offerta grazie alla collaborazione di Novepassi, che da oltre dieci anni offre servizi per la gravidanza. Puericultrici, ostetriche, psicologi, educatori e parent coach collaborano insieme per garantire un supporto completo e una vasta gamma di servizi.<\/p>\n<p>Scuola bilingue per bambini, Nido bilingue per bambini, Centro polifunzionale, corsi di acquaticit\u00e0, Acquaticit\u00e0 neonatale, Corsi di Acquaticit\u00e0 per Bambini, Corsi di Nuoto per Bambini, corsi di acquaticit\u00e0 per mamme in attesa, corsi di acquaticit\u00e0 donne in gravidanza, corsi per bambini, serate a tema per bambini, feste di compleanno, campus estivi per bambini, servizi per la gravidanza, Puericultrici, ostetriche, psicologi, educatori, parent coach,<\/p>\n<p>Scuola bilingue per bambini a Milano, Nido bilingue per bambini a Milano, Centro polifunzionale a Milano, corsi di acquaticit\u00e0 a Milano, Acquaticit\u00e0 neonatale a Milano, Corsi di Acquaticit\u00e0 per Bambini a Milano, Corsi di Nuoto per Bambini a Milano, corsi di acquaticit\u00e0 per mamme in attesa a Milano, corsi di acquaticit\u00e0 donne in gravidanza a Milano, corsi per bambini a Milano, serate a tema per bambini a Milano, feste di compleanno a Milano, campus estivi per bambini a Milano, servizi per la gravidanza a Milano, Puericultrici a Milano, ostetriche a Milano, psicologi a Milano, educatori a Milano, parent coach a Milano,<\/p>\n<\/div>\n","protected":false},"featured_media":12462,"comment_status":"open","ping_status":"closed","template":"elementor_header_footer","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":""},"product_brand":[],"product_cat":[98,23,97],"product_tag":[3303,3310,886,3302,3307,3304,3306,3305,3308,3314,565,3301,3313,3315,1854,3312,3300,3309,3311],"class_list":{"0":"post-12461","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-asili-nido","7":"product_cat-istruzione","8":"product_cat-scuole-dinfanzia","9":"product_tag-acquaticita-neonatale","10":"product_tag-campus-estivi-per-bambini","11":"product_tag-centro-polifunzionale","12":"product_tag-corsi-di-acquaticita","13":"product_tag-corsi-di-acquaticita-donne-in-gravidanza","14":"product_tag-corsi-di-acquaticita-per-bambini","15":"product_tag-corsi-di-acquaticita-per-mamme-in-attesa","16":"product_tag-corsi-di-nuoto-per-bambini","17":"product_tag-corsi-per-bambini","18":"product_tag-educatori","19":"product_tag-feste-di-compleanno","20":"product_tag-nido-bilingue-per-bambini","21":"product_tag-ostetriche","22":"product_tag-parent-coach","23":"product_tag-psicologi","24":"product_tag-puericultrici","25":"product_tag-scuola-bilingue-per-bambini","26":"product_tag-serate-a-tema-per-bambini","27":"product_tag-servizi-per-la-gravidanza","29":"first","30":"instock","31":"shipping-taxable","32":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Family District - Cral Policlinico di Milano<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/family-district\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Family District - Cral Policlinico di Milano\" \/>\n<meta property=\"og:description\" content=\"Family District \u00e8 Nido Scuola bilingue per bambini dai 3 mesi ai 6 anni e Centro polifunzionale, punto di riferimento per famiglie, coppie in attesa e neogenitori. Situato in Porta Romana, questo angolo di citt\u00e0 accompagna piccoli e adulti nel loro percorso di crescita e scoperta. La proposta educativa della scuola segue un approccio play-based e offre un bilinguismo immersivo, dove le lingue sono parte integrante dell\u2019ambiente di apprendimento. Il centro \u00e8 dotato di una piscina interna, aperta anche a bambini esterni e mamme in attesa per corsi di acquaticit\u00e0. Tra le attivit\u00e0 extra scolastiche sono previsti anche corsi per bambini, serate a tema, feste di compleanno e campus estivi. Family District arricchisce la sua offerta grazie alla collaborazione di Novepassi, che da oltre dieci anni offre servizi per la gravidanza. Puericultrici, ostetriche, psicologi, educatori e parent coach collaborano insieme per garantire un supporto completo e una vasta gamma di servizi.  Scuola bilingue per bambini, Nido bilingue per bambini, Centro polifunzionale, corsi di acquaticit\u00e0, Acquaticit\u00e0 neonatale, Corsi di Acquaticit\u00e0 per Bambini, Corsi di Nuoto per Bambini, corsi di acquaticit\u00e0 per mamme in attesa, corsi di acquaticit\u00e0 donne in gravidanza, corsi per bambini, serate a tema per bambini, feste di compleanno, campus estivi per bambini, servizi per la gravidanza, Puericultrici, ostetriche, psicologi, educatori, parent coach,  Scuola bilingue per bambini a Milano, Nido bilingue per bambini a Milano, Centro polifunzionale a Milano, corsi di acquaticit\u00e0 a Milano, Acquaticit\u00e0 neonatale a Milano, Corsi di Acquaticit\u00e0 per Bambini a Milano, Corsi di Nuoto per Bambini a Milano, corsi di acquaticit\u00e0 per mamme in attesa a Milano, corsi di acquaticit\u00e0 donne in gravidanza a Milano, corsi per bambini a Milano, serate a tema per bambini a Milano, feste di compleanno a Milano, campus estivi per bambini a Milano, servizi per la gravidanza a Milano, Puericultrici a Milano, ostetriche a Milano, psicologi a Milano, educatori a Milano, parent coach a Milano,\" \/>\n<meta property=\"og:url\" content=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/family-district\/\" \/>\n<meta property=\"og:site_name\" content=\"Cral Policlinico di Milano\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-18T08:37:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2024\/10\/Logo-siti-family-district.png\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/family-district\/\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/family-district\/\",\"name\":\"Family District - Cral Policlinico di Milano\",\"isPartOf\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/family-district\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/family-district\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2024\/10\/Logo-siti-family-district.png\",\"datePublished\":\"2024-10-08T14:18:01+00:00\",\"dateModified\":\"2025-02-18T08:37:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/family-district\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/family-district\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/family-district\/#primaryimage\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2024\/10\/Logo-siti-family-district.png\",\"contentUrl\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2024\/10\/Logo-siti-family-district.png\",\"width\":300,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/family-district\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/negozio\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Family District\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/#website\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/\",\"name\":\"Cral Policlinico di Milano\",\"description\":\"Area Convenzioni\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Family District - Cral Policlinico di Milano","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/family-district\/","og_locale":"it_IT","og_type":"article","og_title":"Family District - Cral Policlinico di Milano","og_description":"Family District \u00e8 Nido Scuola bilingue per bambini dai 3 mesi ai 6 anni e Centro polifunzionale, punto di riferimento per famiglie, coppie in attesa e neogenitori. Situato in Porta Romana, questo angolo di citt\u00e0 accompagna piccoli e adulti nel loro percorso di crescita e scoperta. La proposta educativa della scuola segue un approccio play-based e offre un bilinguismo immersivo, dove le lingue sono parte integrante dell\u2019ambiente di apprendimento. Il centro \u00e8 dotato di una piscina interna, aperta anche a bambini esterni e mamme in attesa per corsi di acquaticit\u00e0. Tra le attivit\u00e0 extra scolastiche sono previsti anche corsi per bambini, serate a tema, feste di compleanno e campus estivi. Family District arricchisce la sua offerta grazie alla collaborazione di Novepassi, che da oltre dieci anni offre servizi per la gravidanza. Puericultrici, ostetriche, psicologi, educatori e parent coach collaborano insieme per garantire un supporto completo e una vasta gamma di servizi.  Scuola bilingue per bambini, Nido bilingue per bambini, Centro polifunzionale, corsi di acquaticit\u00e0, Acquaticit\u00e0 neonatale, Corsi di Acquaticit\u00e0 per Bambini, Corsi di Nuoto per Bambini, corsi di acquaticit\u00e0 per mamme in attesa, corsi di acquaticit\u00e0 donne in gravidanza, corsi per bambini, serate a tema per bambini, feste di compleanno, campus estivi per bambini, servizi per la gravidanza, Puericultrici, ostetriche, psicologi, educatori, parent coach,  Scuola bilingue per bambini a Milano, Nido bilingue per bambini a Milano, Centro polifunzionale a Milano, corsi di acquaticit\u00e0 a Milano, Acquaticit\u00e0 neonatale a Milano, Corsi di Acquaticit\u00e0 per Bambini a Milano, Corsi di Nuoto per Bambini a Milano, corsi di acquaticit\u00e0 per mamme in attesa a Milano, corsi di acquaticit\u00e0 donne in gravidanza a Milano, corsi per bambini a Milano, serate a tema per bambini a Milano, feste di compleanno a Milano, campus estivi per bambini a Milano, servizi per la gravidanza a Milano, Puericultrici a Milano, ostetriche a Milano, psicologi a Milano, educatori a Milano, parent coach a Milano,","og_url":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/family-district\/","og_site_name":"Cral Policlinico di Milano","article_modified_time":"2025-02-18T08:37:55+00:00","og_image":[{"width":300,"height":300,"url":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2024\/10\/Logo-siti-family-district.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/family-district\/","url":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/family-district\/","name":"Family District - Cral Policlinico di Milano","isPartOf":{"@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/#website"},"primaryImageOfPage":{"@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/family-district\/#primaryimage"},"image":{"@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/family-district\/#primaryimage"},"thumbnailUrl":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2024\/10\/Logo-siti-family-district.png","datePublished":"2024-10-08T14:18:01+00:00","dateModified":"2025-02-18T08:37:55+00:00","breadcrumb":{"@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/family-district\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/family-district\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/family-district\/#primaryimage","url":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2024\/10\/Logo-siti-family-district.png","contentUrl":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2024\/10\/Logo-siti-family-district.png","width":300,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/family-district\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/negozio\/"},{"@type":"ListItem","position":3,"name":"Family District"}]},{"@type":"WebSite","@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/#website","url":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/","name":"Cral Policlinico di Milano","description":"Area Convenzioni","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/product\/12461","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/comments?post=12461"}],"version-history":[{"count":46,"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/product\/12461\/revisions"}],"predecessor-version":[{"id":16482,"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/product\/12461\/revisions\/16482"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/media\/12462"}],"wp:attachment":[{"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/media?parent=12461"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/product_brand?post=12461"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/product_cat?post=12461"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/product_tag?post=12461"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}