{"id":10612,"date":"2024-07-10T10:55:48","date_gmt":"2024-07-10T08:55:48","guid":{"rendered":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/?post_type=product&#038;p=10612"},"modified":"2024-11-04T15:34:25","modified_gmt":"2024-11-04T14:34:25","slug":"gioiello-inn","status":"publish","type":"product","link":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/gioiello-inn\/","title":{"rendered":"Gioiello Inn"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"10612\" class=\"elementor elementor-10612\">\n\t\t\t\t<div class=\"elementor-element elementor-element-015181e e-flex e-con-boxed e-con e-parent\" data-id=\"015181e\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-32eeebc elementor-widget elementor-widget-image\" data-id=\"32eeebc\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" fetchpriority=\"high\" decoding=\"async\" width=\"2000\" height=\"1333\" src=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2024\/07\/GioielloIn-6-luglio-169.jpg\" class=\"attachment-full size-full wp-image-10618\" alt=\"\" srcset=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2024\/07\/GioielloIn-6-luglio-169.jpg 2000w, https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2024\/07\/GioielloIn-6-luglio-169-1280x853.jpg 1280w, https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2024\/07\/GioielloIn-6-luglio-169-980x653.jpg 980w, https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2024\/07\/GioielloIn-6-luglio-169-480x320.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) and (max-width: 1280px) 1280px, (min-width: 1281px) 2000px, 100vw\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c52604c elementor-widget elementor-widget-image\" data-id=\"c52604c\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1210\" height=\"512\" src=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2024\/07\/logo-nero.png\" class=\"attachment-full size-full wp-image-10616\" alt=\"\" srcset=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2024\/07\/logo-nero.png 1210w, https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2024\/07\/logo-nero-980x415.png 980w, https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2024\/07\/logo-nero-480x203.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1210px, 100vw\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-edc65a4 e-flex e-con-boxed e-con e-parent\" data-id=\"edc65a4\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-f446e87 e-con-full e-flex e-con e-child\" data-id=\"f446e87\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-007f247 elementor-widget elementor-widget-text-editor\" data-id=\"007f247\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Benvenuti a <strong>Gioiello Inn<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-034a12c elementor-widget elementor-widget-text-editor\" data-id=\"034a12c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>la gioielleria nel cuore di Milano, situata nella zona di Crocetta. Siamo orgogliosi di essere parte integrante del panorama gioielliero della citt\u00e0 da molti anni, e di avere una clientela fedele e appassionata.<\/p><p>Da Gioiello Inn, ci impegniamo a offrire un\u2019esperienza di shopping unica e indimenticabile a tutti i nostri clienti. La nostra vasta selezione di gioielli \u00e8 studiata per soddisfare ogni gusto e desiderio, con diverse fasce di prezzo che si adattano a tutte le esigenze.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d4e1698 e-con-full elementor-hidden-desktop e-flex e-con e-parent\" data-id=\"d4e1698\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-86fa274 e-flex e-con-boxed e-con e-child\" data-id=\"86fa274\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c4c4232 elementor-widget elementor-widget-text-editor\" data-id=\"c4c4232\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Variet\u00e0 e professionalit\u00e0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1b4a50b elementor-widget elementor-widget-text-editor\" data-id=\"1b4a50b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Presso la nostra gioielleria, troverete una variet\u00e0 di pezzi unici e raffinati, realizzati con maestria artigianale e materiali pregiati. Dalle eleganti collane ai luccicanti anelli, passando per i brillanti orecchini e i sofisticati braccialetti, la nostra collezione abbraccia diversi stili e design, garantendo una scelta adatta a ogni occasione.<\/p><p>Siamo particolarmente orgogliosi di offrire una vasta gamma di gioielli con diamanti di alta qualit\u00e0. La nostra selezione di diamanti \u00e8 curata con estrema attenzione, garantendo la bellezza e la brillantezza che solo queste gemme possono offrire.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b41cf0d elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"b41cf0d\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-gem\" viewBox=\"0 0 576 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M464 0H112c-4 0-7.8 2-10 5.4L2 152.6c-2.9 4.4-2.6 10.2.7 14.2l276 340.8c4.8 5.9 13.8 5.9 18.6 0l276-340.8c3.3-4.1 3.6-9.8.7-14.2L474.1 5.4C471.8 2 468.1 0 464 0zm-19.3 48l63.3 96h-68.4l-51.7-96h56.8zm-202.1 0h90.7l51.7 96H191l51.6-96zm-111.3 0h56.8l-51.7 96H68l63.3-96zm-43 144h51.4L208 352 88.3 192zm102.9 0h193.6L288 435.3 191.2 192zM368 352l68.2-160h51.4L368 352z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9f81086 elementor-widget elementor-widget-text-editor\" data-id=\"9f81086\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tVoi al primo posto\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-740888b elementor-widget elementor-widget-text-editor\" data-id=\"740888b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Ci preoccupiamo anche di rendere l\u2019esperienza di acquisto dei nostri clienti il pi\u00f9 piacevole possibile. Il nostro personale esperto e cortese \u00e8 sempre disponibile per guidarvi nella scelta del gioiello perfetto, fornendo consigli personalizzati e assistenza professionale.<\/p><p>La soddisfazione dei nostri clienti \u00e8 la nostra priorit\u00e0 assoluta e ci impegniamo a garantire la qualit\u00e0 dei nostri prodotti e dei nostri servizi. Ogni gioiello venduto da Gioiello Inn \u00e8 accompagnato da un certificato di autenticit\u00e0, che testimonia l\u2019originalit\u00e0 e l\u2019eccellenza artigianale di ogni pezzo.<\/p><p>Siamo lieti di accogliervi presso Gioiello Inn, dove il fascino dei gioielli incontra la professionalit\u00e0 e l\u2019ospitalit\u00e0. Venite a trovarci e scoprite la gioia di possedere un gioiello unico e di pregio, che porterete con orgoglio e che sar\u00e0 per voi un tesoro prezioso nel corso degli anni.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3d233fa e-flex e-con-boxed e-con e-child\" data-id=\"3d233fa\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;slideshow&quot;,&quot;background_slideshow_gallery&quot;:[{&quot;id&quot;:10626,&quot;url&quot;:&quot;https:\\\/\\\/convenzioni.cralnetwork.it\\\/cralmangiagalli\\\/wp-content\\\/uploads\\\/sites\\\/30\\\/2024\\\/07\\\/ContactPage-Hero-BG-img_1-3.png&quot;},{&quot;id&quot;:10617,&quot;url&quot;:&quot;https:\\\/\\\/convenzioni.cralnetwork.it\\\/cralmangiagalli\\\/wp-content\\\/uploads\\\/sites\\\/30\\\/2024\\\/07\\\/HomePage-Hero-BG-img_2-3.png&quot;},{&quot;id&quot;:10621,&quot;url&quot;:&quot;https:\\\/\\\/convenzioni.cralnetwork.it\\\/cralmangiagalli\\\/wp-content\\\/uploads\\\/sites\\\/30\\\/2024\\\/07\\\/foto-orecchini-10-scaled.jpg.png&quot;},{&quot;id&quot;:10623,&quot;url&quot;:&quot;https:\\\/\\\/convenzioni.cralnetwork.it\\\/cralmangiagalli\\\/wp-content\\\/uploads\\\/sites\\\/30\\\/2024\\\/07\\\/foto-orecchini-6-scaled.jpg.png&quot;},{&quot;id&quot;:10620,&quot;url&quot;:&quot;https:\\\/\\\/convenzioni.cralnetwork.it\\\/cralmangiagalli\\\/wp-content\\\/uploads\\\/sites\\\/30\\\/2024\\\/07\\\/foto-orecchini-11-scaled.jpg.png&quot;},{&quot;id&quot;:10625,&quot;url&quot;:&quot;https:\\\/\\\/convenzioni.cralnetwork.it\\\/cralmangiagalli\\\/wp-content\\\/uploads\\\/sites\\\/30\\\/2024\\\/07\\\/rubino3-2.jpg.png&quot;},{&quot;id&quot;:10624,&quot;url&quot;:&quot;https:\\\/\\\/convenzioni.cralnetwork.it\\\/cralmangiagalli\\\/wp-content\\\/uploads\\\/sites\\\/30\\\/2024\\\/07\\\/foto-anello-5-scaled.jpg.png&quot;},{&quot;id&quot;:10627,&quot;url&quot;:&quot;https:\\\/\\\/convenzioni.cralnetwork.it\\\/cralmangiagalli\\\/wp-content\\\/uploads\\\/sites\\\/30\\\/2024\\\/07\\\/DSC00541-scaled-1.png&quot;},{&quot;id&quot;:10635,&quot;url&quot;:&quot;https:\\\/\\\/convenzioni.cralnetwork.it\\\/cralmangiagalli\\\/wp-content\\\/uploads\\\/sites\\\/30\\\/2024\\\/07\\\/DSC00488_vert-scaled.jpg.png&quot;},{&quot;id&quot;:10629,&quot;url&quot;:&quot;https:\\\/\\\/convenzioni.cralnetwork.it\\\/cralmangiagalli\\\/wp-content\\\/uploads\\\/sites\\\/30\\\/2024\\\/07\\\/foto-bracciale-4-scaled.jpg.png&quot;},{&quot;id&quot;:10631,&quot;url&quot;:&quot;https:\\\/\\\/convenzioni.cralnetwork.it\\\/cralmangiagalli\\\/wp-content\\\/uploads\\\/sites\\\/30\\\/2024\\\/07\\\/foto-anello-4-scaled.jpg.png&quot;},{&quot;id&quot;:10630,&quot;url&quot;:&quot;https:\\\/\\\/convenzioni.cralnetwork.it\\\/cralmangiagalli\\\/wp-content\\\/uploads\\\/sites\\\/30\\\/2024\\\/07\\\/foto-anello-scaled.jpg.png&quot;},{&quot;id&quot;:10628,&quot;url&quot;:&quot;https:\\\/\\\/convenzioni.cralnetwork.it\\\/cralmangiagalli\\\/wp-content\\\/uploads\\\/sites\\\/30\\\/2024\\\/07\\\/HomePage-AboutSection-1.png&quot;},{&quot;id&quot;:10633,&quot;url&quot;:&quot;https:\\\/\\\/convenzioni.cralnetwork.it\\\/cralmangiagalli\\\/wp-content\\\/uploads\\\/sites\\\/30\\\/2024\\\/07\\\/foto-anello-3-scaled.jpg.png&quot;},{&quot;id&quot;:10622,&quot;url&quot;:&quot;https:\\\/\\\/convenzioni.cralnetwork.it\\\/cralmangiagalli\\\/wp-content\\\/uploads\\\/sites\\\/30\\\/2024\\\/07\\\/foto-orecchini-8-scaled.jpg.png&quot;},{&quot;id&quot;:10634,&quot;url&quot;:&quot;https:\\\/\\\/convenzioni.cralnetwork.it\\\/cralmangiagalli\\\/wp-content\\\/uploads\\\/sites\\\/30\\\/2024\\\/07\\\/foto-anello-2-scaled.jpg.png&quot;}],&quot;background_slideshow_slide_duration&quot;:4000,&quot;background_slideshow_transition_duration&quot;:350,&quot;background_slideshow_loop&quot;:&quot;yes&quot;,&quot;background_slideshow_slide_transition&quot;:&quot;fade&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cd04790 elementor-widget elementor-widget-spacer\" data-id=\"cd04790\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4647548 e-con-full elementor-hidden-tablet elementor-hidden-mobile e-flex e-con e-parent\" data-id=\"4647548\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-ce9f0d7 e-con-full e-flex e-con e-child\" data-id=\"ce9f0d7\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ca4b048 elementor-widget elementor-widget-text-editor\" data-id=\"ca4b048\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Variet\u00e0 e professionalit\u00e0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7e61daf elementor-widget elementor-widget-text-editor\" data-id=\"7e61daf\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Presso la nostra gioielleria, troverete una variet\u00e0 di pezzi unici e raffinati, realizzati con maestria artigianale e materiali pregiati. Dalle eleganti collane ai luccicanti anelli, passando per i brillanti orecchini e i sofisticati braccialetti, la nostra collezione abbraccia diversi stili e design, garantendo una scelta adatta a ogni occasione.<\/p><p>Siamo particolarmente orgogliosi di offrire una vasta gamma di gioielli con diamanti di alta qualit\u00e0. La nostra selezione di diamanti \u00e8 curata con estrema attenzione, garantendo la bellezza e la brillantezza che solo queste gemme possono offrire.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4af829f elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"4af829f\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-gem\" viewBox=\"0 0 576 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M464 0H112c-4 0-7.8 2-10 5.4L2 152.6c-2.9 4.4-2.6 10.2.7 14.2l276 340.8c4.8 5.9 13.8 5.9 18.6 0l276-340.8c3.3-4.1 3.6-9.8.7-14.2L474.1 5.4C471.8 2 468.1 0 464 0zm-19.3 48l63.3 96h-68.4l-51.7-96h56.8zm-202.1 0h90.7l51.7 96H191l51.6-96zm-111.3 0h56.8l-51.7 96H68l63.3-96zm-43 144h51.4L208 352 88.3 192zm102.9 0h193.6L288 435.3 191.2 192zM368 352l68.2-160h51.4L368 352z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bf23451 elementor-widget elementor-widget-text-editor\" data-id=\"bf23451\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tVoi al primo posto\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-41fcb56 elementor-widget elementor-widget-text-editor\" data-id=\"41fcb56\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Ci preoccupiamo anche di rendere l\u2019esperienza di acquisto dei nostri clienti il pi\u00f9 piacevole possibile. Il nostro personale esperto e cortese \u00e8 sempre disponibile per guidarvi nella scelta del gioiello perfetto, fornendo consigli personalizzati e assistenza professionale.<\/p><p>La soddisfazione dei nostri clienti \u00e8 la nostra priorit\u00e0 assoluta e ci impegniamo a garantire la qualit\u00e0 dei nostri prodotti e dei nostri servizi. Ogni gioiello venduto da Gioiello Inn \u00e8 accompagnato da un certificato di autenticit\u00e0, che testimonia l\u2019originalit\u00e0 e l\u2019eccellenza artigianale di ogni pezzo.<\/p><p>Siamo lieti di accogliervi presso Gioiello Inn, dove il fascino dei gioielli incontra la professionalit\u00e0 e l\u2019ospitalit\u00e0. Venite a trovarci e scoprite la gioia di possedere un gioiello unico e di pregio, che porterete con orgoglio e che sar\u00e0 per voi un tesoro prezioso nel corso degli anni.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b8da968 e-con-full e-flex e-con e-child\" data-id=\"b8da968\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;slideshow&quot;,&quot;background_slideshow_gallery&quot;:[{&quot;id&quot;:10626,&quot;url&quot;:&quot;https:\\\/\\\/convenzioni.cralnetwork.it\\\/cralmangiagalli\\\/wp-content\\\/uploads\\\/sites\\\/30\\\/2024\\\/07\\\/ContactPage-Hero-BG-img_1-3.png&quot;},{&quot;id&quot;:10617,&quot;url&quot;:&quot;https:\\\/\\\/convenzioni.cralnetwork.it\\\/cralmangiagalli\\\/wp-content\\\/uploads\\\/sites\\\/30\\\/2024\\\/07\\\/HomePage-Hero-BG-img_2-3.png&quot;},{&quot;id&quot;:10621,&quot;url&quot;:&quot;https:\\\/\\\/convenzioni.cralnetwork.it\\\/cralmangiagalli\\\/wp-content\\\/uploads\\\/sites\\\/30\\\/2024\\\/07\\\/foto-orecchini-10-scaled.jpg.png&quot;},{&quot;id&quot;:10623,&quot;url&quot;:&quot;https:\\\/\\\/convenzioni.cralnetwork.it\\\/cralmangiagalli\\\/wp-content\\\/uploads\\\/sites\\\/30\\\/2024\\\/07\\\/foto-orecchini-6-scaled.jpg.png&quot;},{&quot;id&quot;:10620,&quot;url&quot;:&quot;https:\\\/\\\/convenzioni.cralnetwork.it\\\/cralmangiagalli\\\/wp-content\\\/uploads\\\/sites\\\/30\\\/2024\\\/07\\\/foto-orecchini-11-scaled.jpg.png&quot;},{&quot;id&quot;:10625,&quot;url&quot;:&quot;https:\\\/\\\/convenzioni.cralnetwork.it\\\/cralmangiagalli\\\/wp-content\\\/uploads\\\/sites\\\/30\\\/2024\\\/07\\\/rubino3-2.jpg.png&quot;},{&quot;id&quot;:10624,&quot;url&quot;:&quot;https:\\\/\\\/convenzioni.cralnetwork.it\\\/cralmangiagalli\\\/wp-content\\\/uploads\\\/sites\\\/30\\\/2024\\\/07\\\/foto-anello-5-scaled.jpg.png&quot;},{&quot;id&quot;:10627,&quot;url&quot;:&quot;https:\\\/\\\/convenzioni.cralnetwork.it\\\/cralmangiagalli\\\/wp-content\\\/uploads\\\/sites\\\/30\\\/2024\\\/07\\\/DSC00541-scaled-1.png&quot;},{&quot;id&quot;:10635,&quot;url&quot;:&quot;https:\\\/\\\/convenzioni.cralnetwork.it\\\/cralmangiagalli\\\/wp-content\\\/uploads\\\/sites\\\/30\\\/2024\\\/07\\\/DSC00488_vert-scaled.jpg.png&quot;},{&quot;id&quot;:10629,&quot;url&quot;:&quot;https:\\\/\\\/convenzioni.cralnetwork.it\\\/cralmangiagalli\\\/wp-content\\\/uploads\\\/sites\\\/30\\\/2024\\\/07\\\/foto-bracciale-4-scaled.jpg.png&quot;},{&quot;id&quot;:10631,&quot;url&quot;:&quot;https:\\\/\\\/convenzioni.cralnetwork.it\\\/cralmangiagalli\\\/wp-content\\\/uploads\\\/sites\\\/30\\\/2024\\\/07\\\/foto-anello-4-scaled.jpg.png&quot;},{&quot;id&quot;:10630,&quot;url&quot;:&quot;https:\\\/\\\/convenzioni.cralnetwork.it\\\/cralmangiagalli\\\/wp-content\\\/uploads\\\/sites\\\/30\\\/2024\\\/07\\\/foto-anello-scaled.jpg.png&quot;},{&quot;id&quot;:10628,&quot;url&quot;:&quot;https:\\\/\\\/convenzioni.cralnetwork.it\\\/cralmangiagalli\\\/wp-content\\\/uploads\\\/sites\\\/30\\\/2024\\\/07\\\/HomePage-AboutSection-1.png&quot;},{&quot;id&quot;:10633,&quot;url&quot;:&quot;https:\\\/\\\/convenzioni.cralnetwork.it\\\/cralmangiagalli\\\/wp-content\\\/uploads\\\/sites\\\/30\\\/2024\\\/07\\\/foto-anello-3-scaled.jpg.png&quot;},{&quot;id&quot;:10622,&quot;url&quot;:&quot;https:\\\/\\\/convenzioni.cralnetwork.it\\\/cralmangiagalli\\\/wp-content\\\/uploads\\\/sites\\\/30\\\/2024\\\/07\\\/foto-orecchini-8-scaled.jpg.png&quot;},{&quot;id&quot;:10634,&quot;url&quot;:&quot;https:\\\/\\\/convenzioni.cralnetwork.it\\\/cralmangiagalli\\\/wp-content\\\/uploads\\\/sites\\\/30\\\/2024\\\/07\\\/foto-anello-2-scaled.jpg.png&quot;}],&quot;background_slideshow_slide_duration&quot;:4000,&quot;background_slideshow_transition_duration&quot;:350,&quot;background_slideshow_loop&quot;:&quot;yes&quot;,&quot;background_slideshow_slide_transition&quot;:&quot;fade&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-70ed611 elementor-widget elementor-widget-spacer\" data-id=\"70ed611\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4ffda99 e-flex e-con-boxed e-con e-parent\" data-id=\"4ffda99\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-748e83c e-con-full e-flex e-con e-child\" data-id=\"748e83c\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c19371a elementor-widget elementor-widget-text-editor\" data-id=\"c19371a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>AGEVOLAZIONI RISERVATE AGLI ASSOCIATI<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-de564b6 elementor-widget elementor-widget-spacer\" data-id=\"de564b6\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0efc3d6 elementor-widget elementor-widget-text-editor\" data-id=\"0efc3d6\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tVieni a trovarci, a due passi da Crocetta\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-af13f73 e-flex e-con-boxed e-con e-child\" data-id=\"af13f73\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1014b3c elementor-widget__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"1014b3c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Via Alfonso Lamarmora, 2<br \/>20122 Milano (MI)<\/p><p><strong>Mar &#8211; Sab:<\/strong><br \/>10.00 &#8211; 13.00 \/ 14.30 &#8211; 19.00<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b7caa7d elementor-widget__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"b7caa7d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Chiamaci<\/strong><br \/><span style=\"color: #9ccaff;\"><a style=\"color: #9ccaff;\" href=\"tel:+39025511618\">02 551 1618<\/a><\/span><\/p><p><strong>Scrivici una mail<\/strong><br \/><span style=\"color: #9ccaff;\"><a style=\"color: #9ccaff;\" href=\"mailto:info@gioielloinn.it\">info@gioielloinn.it<\/a><\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-bd5e6b0 e-flex e-con-boxed e-con e-child\" data-id=\"bd5e6b0\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d796f4b elementor-widget__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"d796f4b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Visita il sito\u00a0<br \/><span style=\"color: #9ccaff;\"><a style=\"color: #9ccaff;\" href=\"https:\/\/gioielloinn.it\/\"><strong>gioielloinn.it<\/strong><\/a><\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9f85412 elementor-shape-circle e-grid-align-left elementor-grid-0 elementor-widget elementor-widget-social-icons\" data-id=\"9f85412\" data-element_type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-facebook elementor-repeater-item-74dda79\" href=\"https:\/\/www.facebook.com\/gioielloin\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Facebook<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-facebook\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M504 256C504 119 393 8 256 8S8 119 8 256c0 123.78 90.69 226.38 209.25 245V327.69h-63V256h63v-54.64c0-62.15 37-96.48 93.67-96.48 27.14 0 55.52 4.84 55.52 4.84v61h-31.28c-30.8 0-40.41 19.12-40.41 38.73V256h68.78l-11 71.69h-57.78V501C413.31 482.38 504 379.78 504 256z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-instagram elementor-repeater-item-db66474\" href=\"https:\/\/www.instagram.com\/gioiello.in\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Instagram<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-instagram\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.1 141c-63.6 0-114.9 51.3-114.9 114.9s51.3 114.9 114.9 114.9S339 319.5 339 255.9 287.7 141 224.1 141zm0 189.6c-41.1 0-74.7-33.5-74.7-74.7s33.5-74.7 74.7-74.7 74.7 33.5 74.7 74.7-33.6 74.7-74.7 74.7zm146.4-194.3c0 14.9-12 26.8-26.8 26.8-14.9 0-26.8-12-26.8-26.8s12-26.8 26.8-26.8 26.8 12 26.8 26.8zm76.1 27.2c-1.7-35.9-9.9-67.7-36.2-93.9-26.2-26.2-58-34.4-93.9-36.2-37-2.1-147.9-2.1-184.9 0-35.8 1.7-67.6 9.9-93.9 36.1s-34.4 58-36.2 93.9c-2.1 37-2.1 147.9 0 184.9 1.7 35.9 9.9 67.7 36.2 93.9s58 34.4 93.9 36.2c37 2.1 147.9 2.1 184.9 0 35.9-1.7 67.7-9.9 93.9-36.2 26.2-26.2 34.4-58 36.2-93.9 2.1-37 2.1-147.8 0-184.8zM398.8 388c-7.8 19.6-22.9 34.7-42.6 42.6-29.5 11.7-99.5 9-132.1 9s-102.7 2.6-132.1-9c-19.6-7.8-34.7-22.9-42.6-42.6-11.7-29.5-9-99.5-9-132.1s-2.6-102.7 9-132.1c7.8-19.6 22.9-34.7 42.6-42.6 29.5-11.7 99.5-9 132.1-9s102.7-2.6 132.1 9c19.6 7.8 34.7 22.9 42.6 42.6 11.7 29.5 9 99.5 9 132.1s2.7 102.7-9 132.1z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1fbc579 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"1fbc579\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9df795a\" data-id=\"9df795a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d2955ea elementor-widget elementor-widget-text-editor\" data-id=\"d2955ea\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><div id=\"gmw-single-location-wrapper-502\" class=\"gmw-element-wrapper gmw-single-location-wrapper gmw-sl-wrapper gmw-sl-single-post-wrapper post \" object_type=\"post\" object_id=\"10612\"  style=\"width:100%\"><div class=\"gmw-sl-map-wrapper gmw-sl-element\"><div id=\"gmw-map-wrapper-502\" class=\"gmw-map-wrapper  sl single_location \" style=\"width:100%;height:300px;\"> <span id=\"gmw-resize-map-toggle-502\" class=\"gmw-resize-map-toggle gmw-icon-resize-full\" style=\"display:none;\" title=\"Resize map\"><\/span> <div id=\"gmw-map-loader-502\" class=\"gmw-map-loader\"><\/div> <div id=\"gmw-map-502\" class=\"gmw-map sl single_location\" style=\"width:100%; height:100%\" data-map_id=\"502\" data-prefix=\"sl\" data-map_type=\"single_location\" data-icons_usage=\"global\"><\/div> <\/div><\/div><\/div><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7ae770c1 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7ae770c1\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-588b7303\" data-id=\"588b7303\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-217cd83a elementor-widget elementor-widget-text-editor\" data-id=\"217cd83a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>CONTATTI<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-39d32d7e elementor-widget elementor-widget-text-editor\" data-id=\"39d32d7e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-1b8e5cdc\" data-id=\"1b8e5cdc\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d523314 elementor-widget elementor-widget-text-editor\" data-id=\"d523314\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>AGEVOLAZIONI RISERVATE AGLI ASSOCIATI<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-49630ae0 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"49630ae0\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">VISUALIZZA L'ULTIMA PROMO<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-125ad82e\" data-id=\"125ad82e\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2ae09176 elementor-widget elementor-widget-text-editor\" data-id=\"2ae09176\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Clicca sul bottone<br \/>per visualizzare tutti<br \/>i nostri prodotti<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3ffd391d elementor-shape-circle elementor-grid-0 e-grid-align-center elementor-widget elementor-widget-social-icons\" data-id=\"3ffd391d\" data-element_type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-facebook elementor-repeater-item-74dda79\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Facebook<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-facebook\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M504 256C504 119 393 8 256 8S8 119 8 256c0 123.78 90.69 226.38 209.25 245V327.69h-63V256h63v-54.64c0-62.15 37-96.48 93.67-96.48 27.14 0 55.52 4.84 55.52 4.84v61h-31.28c-30.8 0-40.41 19.12-40.41 38.73V256h68.78l-11 71.69h-57.78V501C413.31 482.38 504 379.78 504 256z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-twitter elementor-repeater-item-0f6eab1\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Twitter<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-twitter\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M459.37 151.716c.325 4.548.325 9.097.325 13.645 0 138.72-105.583 298.558-298.558 298.558-59.452 0-114.68-17.219-161.137-47.106 8.447.974 16.568 1.299 25.34 1.299 49.055 0 94.213-16.568 130.274-44.832-46.132-.975-84.792-31.188-98.112-72.772 6.498.974 12.995 1.624 19.818 1.624 9.421 0 18.843-1.3 27.614-3.573-48.081-9.747-84.143-51.98-84.143-102.985v-1.299c13.969 7.797 30.214 12.67 47.431 13.319-28.264-18.843-46.781-51.005-46.781-87.391 0-19.492 5.197-37.36 14.294-52.954 51.655 63.675 129.3 105.258 216.365 109.807-1.624-7.797-2.599-15.918-2.599-24.04 0-57.828 46.782-104.934 104.934-104.934 30.213 0 57.502 12.67 76.67 33.137 23.715-4.548 46.456-13.32 66.599-25.34-7.798 24.366-24.366 44.833-46.132 57.827 21.117-2.273 41.584-8.122 60.426-16.243-14.292 20.791-32.161 39.308-52.628 54.253z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-youtube elementor-repeater-item-db66474\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Youtube<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-youtube\" viewBox=\"0 0 576 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M549.655 124.083c-6.281-23.65-24.787-42.276-48.284-48.597C458.781 64 288 64 288 64S117.22 64 74.629 75.486c-23.497 6.322-42.003 24.947-48.284 48.597-11.412 42.867-11.412 132.305-11.412 132.305s0 89.438 11.412 132.305c6.281 23.65 24.787 41.5 48.284 47.821C117.22 448 288 448 288 448s170.78 0 213.371-11.486c23.497-6.321 42.003-24.171 48.284-47.821 11.412-42.867 11.412-132.305 11.412-132.305s0-89.438-11.412-132.305zm-317.51 213.508V175.185l142.739 81.205-142.739 81.201z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7f546b59 elementor-widget elementor-widget-text-editor\" data-id=\"7f546b59\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><div id=\"gmw-single-location-wrapper-193\" class=\"gmw-element-wrapper gmw-single-location-wrapper gmw-sl-wrapper gmw-sl-single-post-wrapper post \" object_type=\"post\" object_id=\"10612\"  style=\"width:100%\"><div class=\"gmw-sl-map-wrapper gmw-sl-element\"><div id=\"gmw-map-wrapper-193\" class=\"gmw-map-wrapper  sl single_location \" style=\"width:100%;height:300px;\"> <span id=\"gmw-resize-map-toggle-193\" class=\"gmw-resize-map-toggle gmw-icon-resize-full\" style=\"display:none;\" title=\"Resize map\"><\/span> <div id=\"gmw-map-loader-193\" class=\"gmw-map-loader\"><\/div> <div id=\"gmw-map-193\" class=\"gmw-map sl single_location\" style=\"width:100%; height:100%\" data-map_id=\"193\" data-prefix=\"sl\" data-map_type=\"single_location\" data-icons_usage=\"global\"><\/div> <\/div><\/div><\/div><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-54e57ba4 elementor-widget elementor-widget-text-editor\" data-id=\"54e57ba4\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><div id=\"gmw-single-object-locations-wrapper-418\" class=\"gmw-element-wrapper gmw-single-location-wrapper gmw-sl-wrapper gmw-sl-single-post-wrapper post gmw-sl-multiple-locations\" object_type=\"post\" object_id=\"\"  style=\"width:100%\"><div class=\"gmw-sl-map-wrapper\"><div id=\"gmw-map-wrapper-418\" class=\"gmw-map-wrapper  sl single_location \" style=\"width:100%;height:350px;\"> <span id=\"gmw-resize-map-toggle-418\" class=\"gmw-resize-map-toggle gmw-icon-resize-full\" style=\"display:none;\" title=\"Resize map\"><\/span> <div id=\"gmw-map-loader-418\" class=\"gmw-map-loader\"><\/div> <div id=\"gmw-map-418\" class=\"gmw-map sl single_location\" style=\"width:100%; height:100%\" data-map_id=\"418\" data-prefix=\"sl\" data-map_type=\"single_location\" data-icons_usage=\"global\"><\/div> <\/div><\/div><\/div><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-52df8560 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"52df8560\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">VAI ALLO SHOP ONLINE<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<div style= \"display: none\">\n<p>La bottega dei pensieri preziosi<br \/>\nNel cuore di Milano, a due passi dalla M3 Crocetta<br \/>\nOgni gioiello che vendiamo \u00e8 intriso di significato e emozione. Ogni pezzo \u00e8 concepito con cura artigianale, come un pensiero prezioso che si materializza in oro, argento e pietre preziose. I nostri gioielli raccontano storie uniche, custodendo ricordi, desideri e sentimenti profondi. Siamo l\u00ec per catturare l\u2019essenza delle emozioni pi\u00f9 preziose, offrendo pezzi unici che diventano simboli di amore, felicit\u00e0 e bellezza. Benvenuti nella Bottega dei Pensieri Preziosi, dove i vostri sogni prendono forma e diventano realt\u00e0.<br \/>\nBenvenuti a Gioiello In, la gioielleria nel cuore di Milano, situata nella zona di Crocetta. Siamo orgogliosi di essere parte integrante del panorama gioielliero della citt\u00e0 da molti anni, e di avere una clientela fedele e appassionata.<br \/>\nDa Gioiello In, ci impegniamo a offrire un\u2019esperienza di shopping unica e indimenticabile a tutti i nostri clienti. La nostra vasta selezione di gioielli \u00e8 studiata per soddisfare ogni gusto e desiderio, con diverse fasce di prezzo che si adattano a tutte le esigenze.<br \/>\nVariet\u00e0 e professionalit\u00e0<br \/>\nPresso la nostra gioielleria, troverete una variet\u00e0 di pezzi unici e raffinati, realizzati con maestria artigianale e materiali pregiati. Dalle eleganti collane ai luccicanti anelli, passando per i brillanti orecchini e i sofisticati braccialetti, la nostra collezione abbraccia diversi stili e design, garantendo una scelta adatta a ogni occasione.<br \/>\nSiamo particolarmente orgogliosi di offrire una vasta gamma di gioielli con diamanti di alta qualit\u00e0. La nostra selezione di diamanti \u00e8 curata con estrema attenzione, garantendo la bellezza e la brillantezza che solo queste gemme possono offrire.<br \/>\nVoi al primo posto<br \/>\nCi preoccupiamo anche di rendere l\u2019esperienza di acquisto dei nostri clienti il pi\u00f9 piacevole possibile. Il nostro personale esperto e cortese \u00e8 sempre disponibile per guidarvi nella scelta del gioiello perfetto, fornendo consigli personalizzati e assistenza professionale.<br \/>\nLa soddisfazione dei nostri clienti \u00e8 la nostra priorit\u00e0 assoluta e ci impegniamo a garantire la qualit\u00e0 dei nostri prodotti e dei nostri servizi. Ogni gioiello venduto da Gioiello In \u00e8 accompagnato da un certificato di autenticit\u00e0, che testimonia l\u2019originalit\u00e0 e l\u2019eccellenza artigianale di ogni pezzo.<br \/>\nSiamo lieti di accogliervi presso Gioiello In, dove il fascino dei gioielli incontra la professionalit\u00e0 e l\u2019ospitalit\u00e0. Venite a trovarci e scoprite la gioia di possedere un gioiello unico e di pregio, che porterete con orgoglio e che sar\u00e0 per voi un tesoro prezioso nel corso degli anni.<\/p>\n<p>gioiello, gioielli, gioielli oro, gioielli d&#8217;argento, gioielli con pietre preziose, gioielleria , gioiellerie, collane, anelli, orecchini , braccialetti, diamanti , negozio di gioielli, vendita di gioielli, vendita di collane, vendita di anelli, vendita di orecchini , vendita di braccialetti, gioielli d&#8217;oro, <\/p>\n<p>gioielli a Milano, gioielli oro a Milano, gioielli d&#8217;oro a Milano, gioielli d&#8217;argento a Milano, gioielli con pietre preziose a Milano, gioielleria a Milano , gioiellerie a Milano, collane a Milano, anelli a Milano, orecchini a Milano , braccialetti a Milano, diamanti a Milano , negozio di gioielli a Milano, vendita di gioielli a Milano, vendita di collane a Milano, vendita di anelli a Milano, vendita di orecchini a Milano , vendita di braccialetti a Milano, <\/p>\n<\/div>\n","protected":false},"featured_media":10613,"comment_status":"open","ping_status":"closed","template":"elementor_header_footer","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":""},"product_brand":[],"product_cat":[246,28],"product_tag":[1103,2580,1104,2581,1097,1102,1098,2579,2578,2588,2577,2574,2582,1106,2585,2587,2584,2583,2586],"class_list":{"0":"post-10612","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-gioiellerie-oreficerie","7":"product_cat-shopping","8":"product_tag-anelli","9":"product_tag-braccialetti","10":"product_tag-collane","11":"product_tag-diamanti","12":"product_tag-gioielleria","13":"product_tag-gioiellerie","14":"product_tag-gioielli","15":"product_tag-gioielli-con-pietre-preziose","16":"product_tag-gioielli-dargento","17":"product_tag-gioielli-doro","18":"product_tag-gioielli-oro","19":"product_tag-gioiello","20":"product_tag-negozio-di-gioielli","21":"product_tag-orecchini","22":"product_tag-vendita-di-anelli","23":"product_tag-vendita-di-braccialetti","24":"product_tag-vendita-di-collane","25":"product_tag-vendita-di-gioielli","26":"product_tag-vendita-di-orecchini","28":"first","29":"instock","30":"shipping-taxable","31":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Gioiello Inn - Cral Policlinico di Milano<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/gioiello-inn\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gioiello Inn - Cral Policlinico di Milano\" \/>\n<meta property=\"og:description\" content=\"La bottega dei pensieri preziosi Nel cuore di Milano, a due passi dalla M3 Crocetta Ogni gioiello che vendiamo \u00e8 intriso di significato e emozione. Ogni pezzo \u00e8 concepito con cura artigianale, come un pensiero prezioso che si materializza in oro, argento e pietre preziose. I nostri gioielli raccontano storie uniche, custodendo ricordi, desideri e sentimenti profondi. Siamo l\u00ec per catturare l\u2019essenza delle emozioni pi\u00f9 preziose, offrendo pezzi unici che diventano simboli di amore, felicit\u00e0 e bellezza. Benvenuti nella Bottega dei Pensieri Preziosi, dove i vostri sogni prendono forma e diventano realt\u00e0. Benvenuti a Gioiello In, la gioielleria nel cuore di Milano, situata nella zona di Crocetta. Siamo orgogliosi di essere parte integrante del panorama gioielliero della citt\u00e0 da molti anni, e di avere una clientela fedele e appassionata. Da Gioiello In, ci impegniamo a offrire un\u2019esperienza di shopping unica e indimenticabile a tutti i nostri clienti. La nostra vasta selezione di gioielli \u00e8 studiata per soddisfare ogni gusto e desiderio, con diverse fasce di prezzo che si adattano a tutte le esigenze. Variet\u00e0 e professionalit\u00e0 Presso la nostra gioielleria, troverete una variet\u00e0 di pezzi unici e raffinati, realizzati con maestria artigianale e materiali pregiati. Dalle eleganti collane ai luccicanti anelli, passando per i brillanti orecchini e i sofisticati braccialetti, la nostra collezione abbraccia diversi stili e design, garantendo una scelta adatta a ogni occasione. Siamo particolarmente orgogliosi di offrire una vasta gamma di gioielli con diamanti di alta qualit\u00e0. La nostra selezione di diamanti \u00e8 curata con estrema attenzione, garantendo la bellezza e la brillantezza che solo queste gemme possono offrire. Voi al primo posto Ci preoccupiamo anche di rendere l\u2019esperienza di acquisto dei nostri clienti il pi\u00f9 piacevole possibile. Il nostro personale esperto e cortese \u00e8 sempre disponibile per guidarvi nella scelta del gioiello perfetto, fornendo consigli personalizzati e assistenza professionale. La soddisfazione dei nostri clienti \u00e8 la nostra priorit\u00e0 assoluta e ci impegniamo a garantire la qualit\u00e0 dei nostri prodotti e dei nostri servizi. Ogni gioiello venduto da Gioiello In \u00e8 accompagnato da un certificato di autenticit\u00e0, che testimonia l\u2019originalit\u00e0 e l\u2019eccellenza artigianale di ogni pezzo. Siamo lieti di accogliervi presso Gioiello In, dove il fascino dei gioielli incontra la professionalit\u00e0 e l\u2019ospitalit\u00e0. Venite a trovarci e scoprite la gioia di possedere un gioiello unico e di pregio, che porterete con orgoglio e che sar\u00e0 per voi un tesoro prezioso nel corso degli anni.     gioiello, gioielli, gioielli oro, gioielli d&#039;argento, gioielli con pietre preziose, gioielleria , gioiellerie, collane, anelli, orecchini , braccialetti, diamanti , negozio di gioielli, vendita di gioielli, vendita di collane, vendita di anelli, vendita di orecchini , vendita di braccialetti, gioielli d&#039;oro,     gioielli a Milano, gioielli oro a Milano, gioielli d&#039;oro a Milano, gioielli d&#039;argento a Milano, gioielli con pietre preziose a Milano, gioielleria a Milano , gioiellerie a Milano, collane a Milano, anelli a Milano, orecchini a Milano , braccialetti a Milano, diamanti a Milano , negozio di gioielli a Milano, vendita di gioielli a Milano, vendita di collane a Milano, vendita di anelli a Milano, vendita di orecchini a Milano , vendita di braccialetti a Milano,\" \/>\n<meta property=\"og:url\" content=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/gioiello-inn\/\" \/>\n<meta property=\"og:site_name\" content=\"Cral Policlinico di Milano\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-04T14:34:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2024\/07\/logo_Gioiello-Inn_.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/gioiello-inn\/\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/gioiello-inn\/\",\"name\":\"Gioiello Inn - Cral Policlinico di Milano\",\"isPartOf\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/gioiello-inn\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/gioiello-inn\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2024\/07\/logo_Gioiello-Inn_.jpg\",\"datePublished\":\"2024-07-10T08:55:48+00:00\",\"dateModified\":\"2024-11-04T14:34:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/gioiello-inn\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/gioiello-inn\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/gioiello-inn\/#primaryimage\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2024\/07\/logo_Gioiello-Inn_.jpg\",\"contentUrl\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2024\/07\/logo_Gioiello-Inn_.jpg\",\"width\":300,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/gioiello-inn\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/negozio\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Gioiello Inn\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/#website\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/\",\"name\":\"Cral Policlinico di Milano\",\"description\":\"Area Convenzioni\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gioiello Inn - Cral Policlinico di Milano","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/gioiello-inn\/","og_locale":"it_IT","og_type":"article","og_title":"Gioiello Inn - Cral Policlinico di Milano","og_description":"La bottega dei pensieri preziosi Nel cuore di Milano, a due passi dalla M3 Crocetta Ogni gioiello che vendiamo \u00e8 intriso di significato e emozione. Ogni pezzo \u00e8 concepito con cura artigianale, come un pensiero prezioso che si materializza in oro, argento e pietre preziose. I nostri gioielli raccontano storie uniche, custodendo ricordi, desideri e sentimenti profondi. Siamo l\u00ec per catturare l\u2019essenza delle emozioni pi\u00f9 preziose, offrendo pezzi unici che diventano simboli di amore, felicit\u00e0 e bellezza. Benvenuti nella Bottega dei Pensieri Preziosi, dove i vostri sogni prendono forma e diventano realt\u00e0. Benvenuti a Gioiello In, la gioielleria nel cuore di Milano, situata nella zona di Crocetta. Siamo orgogliosi di essere parte integrante del panorama gioielliero della citt\u00e0 da molti anni, e di avere una clientela fedele e appassionata. Da Gioiello In, ci impegniamo a offrire un\u2019esperienza di shopping unica e indimenticabile a tutti i nostri clienti. La nostra vasta selezione di gioielli \u00e8 studiata per soddisfare ogni gusto e desiderio, con diverse fasce di prezzo che si adattano a tutte le esigenze. Variet\u00e0 e professionalit\u00e0 Presso la nostra gioielleria, troverete una variet\u00e0 di pezzi unici e raffinati, realizzati con maestria artigianale e materiali pregiati. Dalle eleganti collane ai luccicanti anelli, passando per i brillanti orecchini e i sofisticati braccialetti, la nostra collezione abbraccia diversi stili e design, garantendo una scelta adatta a ogni occasione. Siamo particolarmente orgogliosi di offrire una vasta gamma di gioielli con diamanti di alta qualit\u00e0. La nostra selezione di diamanti \u00e8 curata con estrema attenzione, garantendo la bellezza e la brillantezza che solo queste gemme possono offrire. Voi al primo posto Ci preoccupiamo anche di rendere l\u2019esperienza di acquisto dei nostri clienti il pi\u00f9 piacevole possibile. Il nostro personale esperto e cortese \u00e8 sempre disponibile per guidarvi nella scelta del gioiello perfetto, fornendo consigli personalizzati e assistenza professionale. La soddisfazione dei nostri clienti \u00e8 la nostra priorit\u00e0 assoluta e ci impegniamo a garantire la qualit\u00e0 dei nostri prodotti e dei nostri servizi. Ogni gioiello venduto da Gioiello In \u00e8 accompagnato da un certificato di autenticit\u00e0, che testimonia l\u2019originalit\u00e0 e l\u2019eccellenza artigianale di ogni pezzo. Siamo lieti di accogliervi presso Gioiello In, dove il fascino dei gioielli incontra la professionalit\u00e0 e l\u2019ospitalit\u00e0. Venite a trovarci e scoprite la gioia di possedere un gioiello unico e di pregio, che porterete con orgoglio e che sar\u00e0 per voi un tesoro prezioso nel corso degli anni.     gioiello, gioielli, gioielli oro, gioielli d'argento, gioielli con pietre preziose, gioielleria , gioiellerie, collane, anelli, orecchini , braccialetti, diamanti , negozio di gioielli, vendita di gioielli, vendita di collane, vendita di anelli, vendita di orecchini , vendita di braccialetti, gioielli d'oro,     gioielli a Milano, gioielli oro a Milano, gioielli d'oro a Milano, gioielli d'argento a Milano, gioielli con pietre preziose a Milano, gioielleria a Milano , gioiellerie a Milano, collane a Milano, anelli a Milano, orecchini a Milano , braccialetti a Milano, diamanti a Milano , negozio di gioielli a Milano, vendita di gioielli a Milano, vendita di collane a Milano, vendita di anelli a Milano, vendita di orecchini a Milano , vendita di braccialetti a Milano,","og_url":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/gioiello-inn\/","og_site_name":"Cral Policlinico di Milano","article_modified_time":"2024-11-04T14:34:25+00:00","og_image":[{"width":300,"height":300,"url":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2024\/07\/logo_Gioiello-Inn_.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/gioiello-inn\/","url":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/gioiello-inn\/","name":"Gioiello Inn - Cral Policlinico di Milano","isPartOf":{"@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/#website"},"primaryImageOfPage":{"@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/gioiello-inn\/#primaryimage"},"image":{"@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/gioiello-inn\/#primaryimage"},"thumbnailUrl":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2024\/07\/logo_Gioiello-Inn_.jpg","datePublished":"2024-07-10T08:55:48+00:00","dateModified":"2024-11-04T14:34:25+00:00","breadcrumb":{"@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/gioiello-inn\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/gioiello-inn\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/gioiello-inn\/#primaryimage","url":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2024\/07\/logo_Gioiello-Inn_.jpg","contentUrl":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2024\/07\/logo_Gioiello-Inn_.jpg","width":300,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/gioiello-inn\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/negozio\/"},{"@type":"ListItem","position":3,"name":"Gioiello Inn"}]},{"@type":"WebSite","@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/#website","url":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/","name":"Cral Policlinico di Milano","description":"Area Convenzioni","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/product\/10612","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/comments?post=10612"}],"version-history":[{"count":56,"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/product\/10612\/revisions"}],"predecessor-version":[{"id":10692,"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/product\/10612\/revisions\/10692"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/media\/10613"}],"wp:attachment":[{"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/media?parent=10612"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/product_brand?post=10612"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/product_cat?post=10612"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/product_tag?post=10612"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}